{"id":23203,"date":"2020-12-11T22:07:36","date_gmt":"2020-12-11T21:07:36","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=23203"},"modified":"2020-12-22T11:16:19","modified_gmt":"2020-12-22T10:16:19","slug":"staatsunabhaengige-theologische-hochschule-basel-sth-basel-3","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/ru\/listings\/staatsunabhaengige-theologische-hochschule-basel-sth-basel-3\/","title":{"rendered":"Staatsunabh\u00e4ngige Theologische Hochschule Basel (STH Basel)"},"content":{"rendered":"<div class=\"elementor-element elementor-element-5af28da elementor-widget elementor-widget-heading\" data-id=\"5af28da\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h1 class=\"elementor-heading-title elementor-size-default\">Studienprofil<\/h1>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-06b0f35 elementor-widget elementor-widget-text-editor\" data-id=\"06b0f35\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p><strong>Die STH Basel ist eine universit\u00e4r akkreditierte, theologische Hochschule. Sie<\/strong><strong>\u00a0bietet Studierenden eine theologisch-wissenschaftliche Ausbildung zum Pfarr- bzw. Pastorenberuf\u00a0in einer Landes- oder Freikirche sowie die M\u00f6glichkeit eines Forschungsstudiums mit Promotion.<\/strong><\/p>\n<p>Ihre Studieng\u00e4nge Bachelor und Master in Theologie sind vom Schweizerischen Akkreditierungsrat akkreditiert. Das Studium ist bez\u00fcglich der Lerninhalte und Anforderungen mit demjenigen theologischer Fakult\u00e4ten staatlicher Universit\u00e4ten vergleichbar. Internationale Kooperationen mit Universit\u00e4ten und Hochschulen im In- und Ausland sowie Forschungsprojekte, internationale Tagungen, Studientage und Gastvorlesungen er\u00f6ffnen unseren Studentinnen und Studenten breite Perspektiven f\u00fcr ihre berufliche und akademische Weiterbildung.<\/p>\n<\/div>\n<div class=\"elementor-element elementor-element-75eedcbb elementor-widget elementor-widget-heading\" data-id=\"75eedcbb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h1 class=\"elementor-heading-title elementor-size-default\">Die STH Basel \u2013 eine akkreditierte universit\u00e4re Institution<\/h1>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-3911b0b8 elementor-widget elementor-widget-text-editor\" data-id=\"3911b0b8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p><strong>Die STH Basel ist eine private Hochschule f\u00fcr evangelische Theologie und bietet ein akademisches Theologiestudium an. Sie ist als universit\u00e4re Institution sowie der Bachelor- und der Masterstudiengang in Theologie akkreditiert. Ebenso besteht die M\u00f6glichkeit eines weiterf\u00fchrenden Forschungsstudiums mit Promotion zum Doktor der Theologie.<\/strong><\/p>\n<\/div>\n<div class=\"elementor-element elementor-element-3a3cd382 elementor-widget elementor-widget-heading\" data-id=\"3a3cd382\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h1 class=\"elementor-heading-title elementor-size-default\">Organisation &amp; Ansprechpartner<\/h1>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-56f1dac7 elementor-widget elementor-widget-text-editor\" data-id=\"56f1dac7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p><strong>Tr\u00e4gerin der STH Basel ist die Immanuel-Stiftung. Sie ist f\u00fcr die Bereitstellung der finanziellen Mittel f\u00fcr den Hochschulbetrieb besorgt. Der Hochschulrat beaufsichtigt die Lehre und Forschung an der STH Basel. Auf der operativen Ebene untersteht dem Rektor als Leiter des gesamten Hochschulbetriebs das wissenschaftliche Personal f\u00fcr Lehre und Forschung einerseits und das administrative Personal andererseits.<\/strong><\/p>\n<p>Die Organisation der STH Basel ist in ihrem Statut dargelegt.<\/p>\n<\/div>\n<p>Kernaufgaben der STH Basel<br \/>\nDie Kernaufgaben der STH Basel sind Forschung und Lehre auf universit\u00e4rem Niveau im Bereich der evangelischen Theologie.<br \/>\nDie theologische Forschung der STH Basel kn\u00fcpft am jeweiligen Stand des Wissens in den einzelnen Forschungszweigen der Theologie an. Die Freiheit von Forschung und Lehre ist gew\u00e4hrleistet.<br \/>\nDie STH Basel bildet Studierende unterschiedlicher Denominationen und Konfessionen f\u00fcr eine<br \/>\nqualifizierte theologische T\u00e4tigkeit aus, vermittelt das notwendige methodische Wissen, f\u00f6rdert<br \/>\ndie sozialen Kompetenzen der Studierenden sowie deren pers\u00f6nliche Spiritualit\u00e4t.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"M\u00fchlestiegrain 50 4125 Riehen\/Basel Schweiz","_company_website":"https:\/\/sthbasel.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[158,157,414],"job-categories":[226],"job-types":[228],"class_list":{"0":"post-23203","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-basel-land","6":"job_listing_region-basel-stadt","7":"job_listing_region-basel-stadt-land","8":"job_listing_category-hoehere-fachschule","9":"job_listing_type-tertiaerausbildung","11":"job-type-tertiarausbildung"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Staatsunabh\u00e4ngige Theologische Hochschule Basel (STH Basel) - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"description\" content=\"Die STH Basel ist eine private Hochschule f\u00fcr evangelische Theologie und bietet ein akademisches Theologiestudium an\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/ru\/listings\/staatsunabhaengige-theologische-hochschule-basel-sth-basel-3\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Staatsunabh\u00e4ngige Theologische Hochschule Basel (STH Basel)\" \/>\n<meta property=\"og:description\" content=\"Die STH Basel ist eine private Hochschule f\u00fcr evangelische Theologie und bietet ein akademisches Theologiestudium an\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/ru\/listings\/staatsunabhaengige-theologische-hochschule-basel-sth-basel-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-22T10:16:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/STH_Logo_50_komplett-oo1tve4g9c7sp14f1k6qvfu264df7dh4s36294ubiu.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/STH_Logo_50_komplett-oo1tve4g9c7sp14f1k6qvfu264df7dh4s36294ubiu.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 \u043c\u0438\u043d\u0443\u0442\u044b\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/staatsunabhaengige-theologische-hochschule-basel-sth-basel-3\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/staatsunabhaengige-theologische-hochschule-basel-sth-basel-3\\\/\",\"name\":\"Staatsunabh\u00e4ngige Theologische Hochschule Basel (STH Basel) - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\"},\"datePublished\":\"2020-12-11T21:07:36+00:00\",\"dateModified\":\"2020-12-22T10:16:19+00:00\",\"description\":\"Die STH Basel ist eine private Hochschule f\u00fcr evangelische Theologie und bietet ein akademisches Theologiestudium an\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/staatsunabhaengige-theologische-hochschule-basel-sth-basel-3\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/staatsunabhaengige-theologische-hochschule-basel-sth-basel-3\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/staatsunabhaengige-theologische-hochschule-basel-sth-basel-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Staatsunabh\u00e4ngige Theologische Hochschule Basel (STH Basel)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Staatsunabh\u00e4ngige Theologische Hochschule Basel (STH Basel) - Privatschul Verzeichnis und Beratung","description":"Die STH Basel ist eine private Hochschule f\u00fcr evangelische Theologie und bietet ein akademisches Theologiestudium an","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/ru\/listings\/staatsunabhaengige-theologische-hochschule-basel-sth-basel-3\/","og_locale":"ru_RU","og_type":"article","og_title":"Staatsunabh\u00e4ngige Theologische Hochschule Basel (STH Basel)","og_description":"Die STH Basel ist eine private Hochschule f\u00fcr evangelische Theologie und bietet ein akademisches Theologiestudium an","og_url":"https:\/\/schoolaboo.com\/ru\/listings\/staatsunabhaengige-theologische-hochschule-basel-sth-basel-3\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-12-22T10:16:19+00:00","og_image":[{"url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/STH_Logo_50_komplett-oo1tve4g9c7sp14f1k6qvfu264df7dh4s36294ubiu.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/STH_Logo_50_komplett-oo1tve4g9c7sp14f1k6qvfu264df7dh4s36294ubiu.jpg","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"2 \u043c\u0438\u043d\u0443\u0442\u044b"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/ru\/listings\/staatsunabhaengige-theologische-hochschule-basel-sth-basel-3\/","url":"https:\/\/schoolaboo.com\/ru\/listings\/staatsunabhaengige-theologische-hochschule-basel-sth-basel-3\/","name":"Staatsunabh\u00e4ngige Theologische Hochschule Basel (STH Basel) - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/ru\/#website"},"datePublished":"2020-12-11T21:07:36+00:00","dateModified":"2020-12-22T10:16:19+00:00","description":"Die STH Basel ist eine private Hochschule f\u00fcr evangelische Theologie und bietet ein akademisches Theologiestudium an","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/ru\/listings\/staatsunabhaengige-theologische-hochschule-basel-sth-basel-3\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/ru\/listings\/staatsunabhaengige-theologische-hochschule-basel-sth-basel-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/ru\/listings\/staatsunabhaengige-theologische-hochschule-basel-sth-basel-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/ru\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/ru\/angebote\/"},{"@type":"ListItem","position":3,"name":"Staatsunabh\u00e4ngige Theologische Hochschule Basel (STH Basel)"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/ru\/#website","url":"https:\/\/schoolaboo.com\/ru\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/ru\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings\/23203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/comments?post=23203"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/media?parent=23203"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job_listing_region?post=23203"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-categories?post=23203"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-types?post=23203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}