{"id":23065,"date":"2020-11-06T23:10:42","date_gmt":"2020-11-06T22:10:42","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=23065"},"modified":"2020-11-06T23:10:42","modified_gmt":"2020-11-06T22:10:42","slug":"montessori-kindergarten-zug","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/ru\/listings\/montessori-kindergarten-zug\/","title":{"rendered":"Montessori Kindergarten Zug"},"content":{"rendered":"<h1>Herzlich willkommen<\/h1>\n<p>&nbsp;<\/p>\n<p>Sie suchen eine Ganztagesbetreuung in deutscher und englischer Sprache, in der Ihr Kind selbst\u00e4ndig lernt,\u00a0individuell gef\u00f6rdert und begleitet wird und sich so zu einer\u00a0eigenst\u00e4ndigen Pers\u00f6nlichkeit entwickeln kann.\u00a0Als Eltern wollen Sie kompetente Unterst\u00fctzung bei der Erziehung, F\u00f6rderung und Betreuung Ihres Kindes. Unsere\u00a0altersgemischten Gruppen sind die ideale Umgebung, um Toleranz, Selbst\u00e4ndigkeit und Teamgeist zu erfahren sowie zu f\u00f6rdern. Mit unseren Unterrichtsmaterialien lernt Ihr Kind in deutscher und englischer Sprache spielerisch und\u00a0im eigenen Tempo sich und die Umwelt kennen. Aber\u00a0bei uns kommt auch das Spielen, Geniessen und Einfach-nur-Kind-Sein nicht zu kurz, denn Ihr Kind soll sich bei uns\u00a0aufgehoben, verstanden und wohl f\u00fchlen.<\/p>\n<h4>Zielgruppe \/ \u00d6ffnungszeiten<code><br \/>\n<\/code><\/h4>\n<p>&nbsp;<\/p>\n<p>Wir sind eine familienerg\u00e4nzende, zweisprachige Kindertagesst\u00e4tte (Krippe und Kindergarten) f\u00fcr Kinder im Alter von 18 Monaten bis zum Eintritt in die erste Primarklasse. Wir nehmen Kinder aller Nationen und Konfessionen auf und sind politisch neutral.<\/p>\n<p>Bei Geschwistern nehmen wir Kinder bereits ab 3 Monaten auf.<\/p>\n<p>&nbsp;<\/p>\n<p><span lang=\"EN-US\">Die \u00d6ffnungszeiten sind Montag bis Freitag von 07:30 bis 18:30 Uhr. Die Morgenbetreuung beinhaltet die Zeit von 07:30 Uhr bis 11:30 Uhr, die Nachmittagsbetreuung die Zeit von 14:00 Uhr bis 18:30 Uhr.<\/span><\/p>\n<p><span lang=\"EN-US\">De<\/span><span lang=\"EN-US\">r MoZ bleibt zwei Wochen \u00fcber Weihnachten\/Neujahr, die letzte Woche im Juli und die erste Woche im August sowie an folgenden Feier- und Br\u00fcckentagen geschlossen: Karfreitag, Ostermontag, Auffahrt, Freitag nach Auffahrt, Pfingstmontag, Fronleichnam, Freitag nach Fronleichnam, Maria Himmelfahrt, Allerheiligen, Maria Empf\u00e4ngnis sowie an maximal drei weiteren Tagen.<\/span><\/p>\n<p><span lang=\"EN-US\">Vor den Ferienwochen und Feiertagen schliesst der Kindergarten bereits um 16:00 Uhr.<\/span><\/p>\n<p><span lang=\"DE-CH\">W\u00e4hrend den beiden Wochen vor den Sommerferien sind die \u00d6ffnungszeiten von 08:30 bis 17:30.<\/span><\/p>\n<h4><\/h4>\n<h4>Ein-\/Austritte<\/h4>\n<p>&nbsp;<\/p>\n<p>Der Eintritt ist grunds\u00e4tzlich jederzeit m\u00f6glich. Der Austritt erfolgt jeweils zum Ende eines Schulqartals (31.1., 30.4., 31.7., 31.10.) mit dreimonatiger K\u00fcndigungsfrist.<\/p>\n<h4><\/h4>\n<h4>Mindestbetreuungszeit<\/h4>\n<p>&nbsp;<\/p>\n<p><span lang=\"EN-US\">Zur Sicherstellung der Integration des Kindes besteht eine obligatorische Mindestbetreuung von w\u00f6chentlich 40%. Ein Aufenthalt von 60% pro Woche wird aus p\u00e4dagogischer Sicht empfohlen.<\/span><\/p>\n<p><span lang=\"EN-US\">Kinder im obligatorischen Kindergartenjahr mit Wohnsitz im Kanton Zug m\u00fcssen gem\u00e4ss beh\u00f6rdlichen Vorgaben mindestens an vier Vormittagen und zwei Nachmittagen anwesend sein.<\/span><\/p>\n<p><span lang=\"EN-US\">Der ausschliessliche Bezug von Halbtagen ist nicht m\u00f6glich.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h4>Zusammensetzung Kindergruppen<\/h4>\n<p>Altersgemischte Kindergruppen mit wechselnder Spiel-\/Lerngruppengr\u00f6sse und Zusammensetzung erm\u00f6glichen aus gruppendynamischer Sicht die optimale Umsetzung des Konzepts der Montessori-P\u00e4dagogik. Die Gruppe pr\u00e4gt entscheidend die M\u00f6glichkeiten des Kindes zu Eigenaktivit\u00e4t, Eigent\u00e4tigkeit und sozialem Lernen.<br \/>\nDie Gruppenzusammensetzung ist bei uns daher flexibel und durch die Kinder und deren Bed\u00fcrfnisse und Vorlieben mitgepr\u00e4gt. Die Kinder werden dabei je nach Aktivit\u00e4t von p\u00e4dagogisch qualifizierten Betreuerinnen und Betreuern, spezialisierten internen und externen Fachpersonen und Personen in Ausbildung betreut. Die Hauptverantwortung f\u00fcr das ganze Programm eines Kindes\u00a0tr\u00e4gt jeweils sein(e) Key-Teacher(in), welche(r) auch die Hauptansprechperson f\u00fcr die Eltern ist.<\/p>\n<p>F\u00fcr Kinder von 3 bis ca. 18 Monaten findet\u00a0nur eine beschr\u00e4nkte Integration in die \u00fcbrigen Gruppen statt.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Oberm\u00fchle 8, 6340 Baar, Schweiz","_company_website":"https:\/\/www.montessorizug.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[154],"job-categories":[103],"job-types":[90],"class_list":{"0":"post-23065","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-zug","6":"job_listing_category-kindergarten","7":"job_listing_type-kindergarten","9":"job-type-kindergarten-4-6-jahre"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Montessori Kindergarten Zug - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/ru\/listings\/montessori-kindergarten-zug\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Montessori Kindergarten Zug\" \/>\n<meta property=\"og:description\" content=\"Herzlich willkommen &nbsp; Sie suchen eine Ganztagesbetreuung in deutscher und englischer Sprache, in der Ihr Kind selbst\u00e4ndig lernt,\u00a0individuell gef\u00f6rdert und begleitet wird und sich so zu einer\u00a0eigenst\u00e4ndigen Pers\u00f6nlichkeit entwickeln kann.\u00a0Als Eltern wollen Sie kompetente Unterst\u00fctzung bei der Erziehung, F\u00f6rderung und Betreuung Ihres Kindes. Unsere\u00a0altersgemischten Gruppen sind die ideale Umgebung, um Toleranz, Selbst\u00e4ndigkeit und Teamgeist zu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/ru\/listings\/montessori-kindergarten-zug\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/logo-text.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/logo-text.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 \u043c\u0438\u043d\u0443\u0442\u044b\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/montessori-kindergarten-zug\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/montessori-kindergarten-zug\\\/\",\"name\":\"Montessori Kindergarten Zug - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\"},\"datePublished\":\"2020-11-06T22:10:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/montessori-kindergarten-zug\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/montessori-kindergarten-zug\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/montessori-kindergarten-zug\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Montessori Kindergarten Zug\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Montessori Kindergarten Zug - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/ru\/listings\/montessori-kindergarten-zug\/","og_locale":"ru_RU","og_type":"article","og_title":"Montessori Kindergarten Zug","og_description":"Herzlich willkommen &nbsp; Sie suchen eine Ganztagesbetreuung in deutscher und englischer Sprache, in der Ihr Kind selbst\u00e4ndig lernt,\u00a0individuell gef\u00f6rdert und begleitet wird und sich so zu einer\u00a0eigenst\u00e4ndigen Pers\u00f6nlichkeit entwickeln kann.\u00a0Als Eltern wollen Sie kompetente Unterst\u00fctzung bei der Erziehung, F\u00f6rderung und Betreuung Ihres Kindes. Unsere\u00a0altersgemischten Gruppen sind die ideale Umgebung, um Toleranz, Selbst\u00e4ndigkeit und Teamgeist zu [&hellip;]","og_url":"https:\/\/schoolaboo.com\/ru\/listings\/montessori-kindergarten-zug\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/logo-text.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/logo-text.png","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"2 \u043c\u0438\u043d\u0443\u0442\u044b"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/ru\/listings\/montessori-kindergarten-zug\/","url":"https:\/\/schoolaboo.com\/ru\/listings\/montessori-kindergarten-zug\/","name":"Montessori Kindergarten Zug - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/ru\/#website"},"datePublished":"2020-11-06T22:10:42+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/ru\/listings\/montessori-kindergarten-zug\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/ru\/listings\/montessori-kindergarten-zug\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/ru\/listings\/montessori-kindergarten-zug\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/ru\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/ru\/angebote\/"},{"@type":"ListItem","position":3,"name":"Montessori Kindergarten Zug"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/ru\/#website","url":"https:\/\/schoolaboo.com\/ru\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/ru\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings\/23065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/comments?post=23065"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/media?parent=23065"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job_listing_region?post=23065"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-categories?post=23065"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-types?post=23065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}