{"id":22852,"date":"2020-11-06T09:22:17","date_gmt":"2020-11-06T08:22:17","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=22852"},"modified":"2020-11-06T09:22:17","modified_gmt":"2020-11-06T08:22:17","slug":"nbw-betriebswirtschaftliche-weiterbildung-zuerich","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/ru\/listings\/nbw-betriebswirtschaftliche-weiterbildung-zuerich\/","title":{"rendered":"NBW Betriebswirtschaftliche Weiterbildung Z\u00fcrich"},"content":{"rendered":"<div class=\"row-fluid\">\n<div class=\"span15\">\n<p class=\"intro\">Wir setzen auf die anerkannten eidgen\u00f6ssischen Fachausweise und Diplome, die solide F\u00e4higkeiten sowie theoretische Kenntnisse nachweisen und in der Wirtschaft einen ausgezeichneten Ruf geniessen.<\/p>\n<\/div>\n<\/div>\n<div class=\"row-fluid\">\n<div id=\"section1\" class=\"span24\">\n<div class=\"row-fluid stretch-sep\">\n<div class=\"span8 vertical-sep\">\n<div class=\"sparte hidden-phone\">Zertifikat<\/div>\n<div class=\"l11\">\n<h3>ASSISTENTIN \/ ASSISTENT MARKETING UND VERKAUF NBW<\/h3>\n<p><span class=\"desc\">4 Monate<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1 vertical-sep\">\n<div class=\"sparte hidden-phone\">Fachausweis<\/div>\n<div class=\"l21\">\n<h3>MARKETINGFACHFRAU \/<br \/>\nMARKETINGFACHMANN<\/h3>\n<p><span class=\"desc\">mit eidg. Fachausweis<br \/>\n2 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1\">\n<div class=\"sparte hidden-phone\">Diplom<\/div>\n<div class=\"l31\">\n<h3>EIDG. DIPL. MARKETINGLEITERIN \/<br \/>\nMARKETINGLEITER<\/h3>\n<p><span class=\"desc\">2 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row-fluid stretch-sep\">\n<div class=\"span8 vertical-sep hidden-phone\"><\/div>\n<div class=\"span7 offset1 vertical-sep\">\n<div class=\"l22\">\n<h3>VERKAUFSFACHFRAU \/<br \/>\nVERKAUFSFACHMANN<\/h3>\n<p><span class=\"desc\">mit eidg. Fachausweis<br \/>\n2 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1\">\n<div class=\"l32\">\n<h3>EIDG. DIPL. VERKAUFSLEITERIN \/<br \/>\nVERKAUFSLEITER<\/h3>\n<p><span class=\"desc\">Vertiefungsrichtungen &#171;Verkaufsleitung&#187; oder &#171;Key-Account-Management&#187;<br \/>\n2 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row-fluid\">\n<div id=\"section2\" class=\"span24\">\n<div class=\"row-fluid stretch-sep\">\n<div class=\"span8 vertical-sep\">\n<div class=\"sparte hidden-phone\">Zertifikat<\/div>\n<div class=\"l14\">\n<h3>LEADERSHIP NBW \/ SVF<\/h3>\n<p><span class=\"desc\">1 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1 vertical-sep\">\n<div class=\"sparte hidden-phone\">Fachausweis<\/div>\n<div class=\"l23\">\n<h3>TECHNISCHE KAUFFRAU \/<br \/>\nTECHNISCHER KAUFMANN<\/h3>\n<p><span class=\"desc\">mit eidg. Fachausweis<br \/>\n3 oder 4 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row-fluid stretch-sep\">\n<div class=\"span8 vertical-sep hidden-phone\"><\/div>\n<div class=\"span7 offset1 vertical-sep\">\n<div class=\"l24\">\n<h3>F\u00dcHRUNGSFACHFRAU \/<br \/>\n-FACHMANN<\/h3>\n<p><span class=\"desc\">mit eidg. Fachausweis<br \/>\n4 Monate<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1 hidden-phone\"><\/div>\n<\/div>\n<div class=\"row-fluid stretch-sep\">\n<div class=\"span8 vertical-sep\">\n<div class=\"l17\">\n<h3>MANAGEMENTJAHRESKURS NBW<\/h3>\n<p><span class=\"desc\">mit SVF-Anerkennung<br \/>\n2 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1 vertical-sep\">\n<div class=\"l25\">\n<h3>SPEZIALISTIN \/ SPEZIALIST<br \/>\nIN UNTERNEHMENSORGANISATION<\/h3>\n<p><span class=\"desc\">mit eidg. Fachausweis<br \/>\n2 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row-fluid stretch-sep\">\n<div class=\"span8 vertical-sep hidden-phone\"><\/div>\n<div class=\"span7 offset1 vertical-sep\">\n<div class=\"l25\">\n<h3>DIREKTIONSASSISTENTIN \/<br \/>\nDIREKTIONSASSISTENT<\/h3>\n<p><span class=\"desc\">mit eidg. Fachausweis<br \/>\n2 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row-fluid\">\n<div id=\"section3\" class=\"span24\">\n<div class=\"row-fluid stretch-sep\">\n<div class=\"span8 vertical-sep\">\n<div class=\"sparte hidden-phone\">Zertifikat<\/div>\n<div class=\"l18\">\n<h3>PERSONALASSISTENTIN \/<br \/>\nPERSONALASSISTENT NBW<\/h3>\n<p><span class=\"desc\">mit HRSE-Anerkennung<br \/>\n1 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1 vertical-sep\">\n<div class=\"sparte hidden-phone\">Fachausweis<\/div>\n<div class=\"l27\">\n<h3>HR-FACHFRAU \/<br \/>\nHR-FACHMANN<\/h3>\n<p><span class=\"desc\">mit eidg. Fachausweis (Fachrichtungen A, B und C)<br \/>\n2 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1\">\n<div class=\"sparte hidden-phone\">Diplom<\/div>\n<div class=\"l37\">\n<h3>LEITERIN \/ LEITER HUMAN RESOURCES<\/h3>\n<p><span class=\"desc\">mit eidgen\u00f6ssischem Diplom<br \/>\n2 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row-fluid stretch-sep\">\n<div class=\"span8 vertical-sep\">\n<div class=\"l12\">\n<h3>PERSONALASSISTENTIN \/<br \/>\nPERSONALASSISTENT NBW (INTENSIVKURS)<\/h3>\n<p><span class=\"desc\">mit HRSE-Anerkennung<br \/>\n6 Wochen<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1 hidden-phone\"><\/div>\n<\/div>\n<div class=\"row-fluid stretch-sep\">\n<div class=\"span8 vertical-sep\">\n<div class=\"l112\">\n<h3>PAYROLL-SPEZIALISTIN \/<br \/>\n-SPEZIALIST NBW<\/h3>\n<p><span class=\"desc\">1 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1 hidden-phone\"><\/div>\n<\/div>\n<div class=\"row-fluid stretch-sep\">\n<div class=\"span8 vertical-sep\">\n<div class=\"l112\">\n<h3>SPEZIALISTIN \/ SPEZIALIST INTERNATIONALES HR-MANAGEMENT NBW<\/h3>\n<p><span class=\"desc\">1 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1 hidden-phone\"><\/div>\n<\/div>\n<div class=\"row-fluid stretch-sep\">\n<div class=\"span8 vertical-sep\">\n<div class=\"l113\">\n<h3>RECRUITING-SPEZIALISTIN \/ RECRUITING-SPEZIALIST NBW<\/h3>\n<p><span class=\"desc\">1 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1 hidden-phone\"><\/div>\n<\/div>\n<div class=\"row-fluid stretch-sep\">\n<div class=\"span8 vertical-sep\">\n<div class=\"l19\">\n<h3>SACHBEARBEITERIN \/ SACHBEARBEITER<br \/>\nSOZIALVERSICHERUNGEN NBW<\/h3>\n<p><span class=\"desc\">1 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1 vertical-sep\">\n<div class=\"l29\">\n<h3>SOZIALVERSICHERUNGS-FACH-<br \/>\nFRAU \/ -FACHMANN<\/h3>\n<p><span class=\"desc\">mit eidg. Fachausweis<br \/>\n2 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row-fluid\">\n<div id=\"section4\" class=\"span24\">\n<div class=\"row-fluid stretch-sep\">\n<div class=\"span8 vertical-sep\">\n<div class=\"sparte hidden-phone\">Zertifikat<\/div>\n<div class=\"l15\">\n<h3>FINANZ- UND RECHNUNGSWESEN, STUFE 1<\/h3>\n<p><span class=\"desc\">10 Abende oder 5 Schulungstage<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1 hidden-phone\"><\/div>\n<\/div>\n<div class=\"row-fluid stretch-sep\">\n<div class=\"span8 vertical-sep\">\n<div class=\"l110\">\n<h3>SACHBEARBEITERIN \/ SACHBEARBEITER<br \/>\nRECHNUNGSWESEN NBW<\/h3>\n<p><span class=\"desc\">1 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1 vertical-sep\">\n<div class=\"l29\">\n<h3>FACHFRAU \/ FACHMANN<br \/>\nIM FINANZ- UND RECHNUNGSWESEN<\/h3>\n<p><span class=\"desc\">mit eidg. Fachausweis<br \/>\n3 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1\">\n<div class=\"l39\">\n<h3>EIDG. DIPL. EXPERTIN \/ EXPERTE<br \/>\nIN RECHNUNGSLEGUNG UND CONTROLLING<\/h3>\n<p><span class=\"desc\">4 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row-fluid stretch-sep\">\n<div class=\"span8 vertical-sep\">\n<div class=\"l110\">\n<h3>SACHBEARBEITERIN \/ SACHBEARBEITER<br \/>\nSTEUERPRAXIS NBW<\/h3>\n<p><span class=\"desc\">1 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1 hidden-phone\"><\/div>\n<\/div>\n<div class=\"row-fluid stretch-sep\">\n<div class=\"span8 vertical-sep\">\n<div class=\"l110\">\n<h3>SPEZIALISTIN \/ SPEZIALIST STEUERWESEN NBW<\/h3>\n<p><span class=\"desc\">1 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row-fluid\">\n<div id=\"section9\" class=\"span24\">\n<div class=\"row-fluid stretch-sep\">\n<div class=\"span8 vertical-sep\">\n<div class=\"sparte hidden-phone\">Zertifikat<\/div>\n<div class=\"l13\">\n<h3>KAUFM\u00c4NNISCHE SACHBEARBEITERIN \/<br \/>\nSACHBEARBEITER NBW<\/h3>\n<p><span class=\"desc\">2 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1 hidden-phone\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row-fluid\">\n<div id=\"section11\" class=\"span24\">\n<div class=\"row-fluid stretch-sep\">\n<div class=\"span8 vertical-sep\">\n<div class=\"sparte hidden-phone\">Zertifikat<\/div>\n<div class=\"l113\">\n<h3>SACHBEARBEITERIN \/ SACHBEARBEITER<br \/>\nEINKAUF NBW<\/h3>\n<p><span class=\"desc\">1 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1 vertical-sep\">\n<div class=\"sparte hidden-phone\">Fachausweis<\/div>\n<div class=\"l210\">\n<h3>EINKAUFSFACHFRAU \/<br \/>\nEINKAUFSFACHMANN<\/h3>\n<p><span class=\"desc\">mit eidg. Fachausweis<br \/>\n2 Semester<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"span7 offset1\">\n<div class=\"sparte hidden-phone\">Diplom<\/div>\n<div class=\"l310\">\n<h3>EINKAUFSLEITERIN \/<br \/>\nEINKAUFSLEITER<\/h3>\n<p><span class=\"desc\">mit eidgen\u00f6ssischem Diplom<br \/>\n3 Semester <\/span>von Praxisproblemen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Hohlstrasse 550, 8048 Z\u00fcrich, Schweiz","_company_website":"https:\/\/nbw.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[153],"job-categories":[226],"job-types":[228],"class_list":{"0":"post-22852","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-zuerich","6":"job_listing_category-hoehere-fachschule","7":"job_listing_type-tertiaerausbildung","9":"job-type-tertiarausbildung"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>NBW Betriebswirtschaftliche Weiterbildung Z\u00fcrich - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/ru\/listings\/nbw-betriebswirtschaftliche-weiterbildung-zuerich\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NBW Betriebswirtschaftliche Weiterbildung Z\u00fcrich\" \/>\n<meta property=\"og:description\" content=\"Wir setzen auf die anerkannten eidgen\u00f6ssischen Fachausweise und Diplome, die solide F\u00e4higkeiten sowie theoretische Kenntnisse nachweisen und in der Wirtschaft einen ausgezeichneten Ruf geniessen. Zertifikat ASSISTENTIN \/ ASSISTENT MARKETING UND VERKAUF NBW 4 Monate Fachausweis MARKETINGFACHFRAU \/ MARKETINGFACHMANN mit eidg. Fachausweis 2 Semester Diplom EIDG. DIPL. MARKETINGLEITERIN \/ MARKETINGLEITER 2 Semester VERKAUFSFACHFRAU \/ VERKAUFSFACHMANN mit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/ru\/listings\/nbw-betriebswirtschaftliche-weiterbildung-zuerich\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/og-image.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/og-image.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u043c\u0438\u043d\u0443\u0442\u0430\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/nbw-betriebswirtschaftliche-weiterbildung-zuerich\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/nbw-betriebswirtschaftliche-weiterbildung-zuerich\\\/\",\"name\":\"NBW Betriebswirtschaftliche Weiterbildung Z\u00fcrich - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\"},\"datePublished\":\"2020-11-06T08:22:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/nbw-betriebswirtschaftliche-weiterbildung-zuerich\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/nbw-betriebswirtschaftliche-weiterbildung-zuerich\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/nbw-betriebswirtschaftliche-weiterbildung-zuerich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"NBW Betriebswirtschaftliche Weiterbildung Z\u00fcrich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NBW Betriebswirtschaftliche Weiterbildung Z\u00fcrich - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/ru\/listings\/nbw-betriebswirtschaftliche-weiterbildung-zuerich\/","og_locale":"ru_RU","og_type":"article","og_title":"NBW Betriebswirtschaftliche Weiterbildung Z\u00fcrich","og_description":"Wir setzen auf die anerkannten eidgen\u00f6ssischen Fachausweise und Diplome, die solide F\u00e4higkeiten sowie theoretische Kenntnisse nachweisen und in der Wirtschaft einen ausgezeichneten Ruf geniessen. Zertifikat ASSISTENTIN \/ ASSISTENT MARKETING UND VERKAUF NBW 4 Monate Fachausweis MARKETINGFACHFRAU \/ MARKETINGFACHMANN mit eidg. Fachausweis 2 Semester Diplom EIDG. DIPL. MARKETINGLEITERIN \/ MARKETINGLEITER 2 Semester VERKAUFSFACHFRAU \/ VERKAUFSFACHMANN mit [&hellip;]","og_url":"https:\/\/schoolaboo.com\/ru\/listings\/nbw-betriebswirtschaftliche-weiterbildung-zuerich\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/og-image.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/og-image.jpg","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"1 \u043c\u0438\u043d\u0443\u0442\u0430"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/ru\/listings\/nbw-betriebswirtschaftliche-weiterbildung-zuerich\/","url":"https:\/\/schoolaboo.com\/ru\/listings\/nbw-betriebswirtschaftliche-weiterbildung-zuerich\/","name":"NBW Betriebswirtschaftliche Weiterbildung Z\u00fcrich - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/ru\/#website"},"datePublished":"2020-11-06T08:22:17+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/ru\/listings\/nbw-betriebswirtschaftliche-weiterbildung-zuerich\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/ru\/listings\/nbw-betriebswirtschaftliche-weiterbildung-zuerich\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/ru\/listings\/nbw-betriebswirtschaftliche-weiterbildung-zuerich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/ru\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/ru\/angebote\/"},{"@type":"ListItem","position":3,"name":"NBW Betriebswirtschaftliche Weiterbildung Z\u00fcrich"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/ru\/#website","url":"https:\/\/schoolaboo.com\/ru\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/ru\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings\/22852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/comments?post=22852"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/media?parent=22852"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job_listing_region?post=22852"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-categories?post=22852"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-types?post=22852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}