{"id":22236,"date":"2020-11-02T16:33:43","date_gmt":"2020-11-02T15:33:43","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=22236"},"modified":"2020-11-02T16:33:43","modified_gmt":"2020-11-02T15:33:43","slug":"freies-gymnasium-zuerich","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/ru\/listings\/freies-gymnasium-zuerich\/","title":{"rendered":"Freies Gymnasium Z\u00fcrich"},"content":{"rendered":"<h2 class=\"header header2 header-default \">Ein breites und hoch stehendes Angebot<\/h2>\n<div class=\"csc-textpic-text\">\n<p class=\"bodytext\">Das Angebot des Freien Gymnasiums Z\u00fcrich umfasst drei Vorbereitungsklassen, eine progymnasiale und eine gymnasiale Unterstufe sowie ein Kurzgymnasium mit staatlich anerkannter Hausmaturit\u00e4t.<\/p>\n<p>Im Gymnasium k\u00f6nnen vier Profile gew\u00e4hlt werden: das altsprachliche, das neusprachliche, das mathematisch-naturwissenschaftliche mit zwei Schwerpunktsrichtungen und das wirtschaftlich-rechtliche.<\/p>\n<p>F\u00fcr die gymnasialen Lehrg\u00e4nge ist das eidgen\u00f6ssische Maturit\u00e4tsanerkennungs-Reglement (MAR), f\u00fcr die Vorbereitungsklassen und die progymnasiale Unterstufe der kantonale Lehrplan verbindlich.<\/p>\n<\/div>\n<p class=\"bodytext\"><b>Pionier in der echt zweisprachigen Ausbildung<\/b><br \/>\nBilingualer Unterricht ist die Antwort auf eine globalisierte Welt. Die zweisprachigen Ausbildungsg\u00e4nge am Freien Gymnasium Z\u00fcrich tragen dieser Tatsache mit ihrem bilingualen Angebot Rechnung. Als erste Schule im Kanton bot das Freie Gymnasium Z\u00fcrich bereits im Jahr 2000 eine bilinguale progymnasiale Unterstufe an, dies in Zusammenarbeit mit der Lakeside School (K\u00fcsnacht). Damit wurde eine Br\u00fccke zwischen der echt zweisprachigen Ausbildung an der Primarstufe und dem Kurzgymnasium gebaut und im Kanton Z\u00fcrich Pionierarbeit auf dem Gebiet der zweisprachigen Ausbildung geleistet.<\/p>\n<p>Bereits 1997 hatte das Freie Gymnasium Z\u00fcrich den Englischunterricht in die ersten Klassen der gymnasialen und der progymnasialen Unterstufe vorverlegt. Drei Jahre sp\u00e4ter f\u00fchrte unsere Schule als erstes Gymnasium im Kanton das Profil \u201eWirtschaft und Recht\u201c auch zweisprachig ein.<\/p>\n<p><b>Muttersprachliche Lehrpersonen<\/b><br \/>\nDas Freie Gymnasium Z\u00fcrich bietet die folgenden zweisprachigen Ausbildungen an:<\/p>\n<ul>\n<li>Gymnasiale Unterstufe (1. und 2. Klasse)<\/li>\n<li>Progymnasiale Unterstufe (1. und 2. Klasse, ohne Latein)<\/li>\n<li>Kurzgymnasium (3. &#8212; 6. Klasse)<\/li>\n<\/ul>\n<p class=\"bodytext\">Die Lehrpersonen sind in den deutschsprachigen F\u00e4chern deutscher, in den englischsprachigen Einheiten englischer Muttersprache.<\/p>\n<p><b>Hohe Anforderungen an die Sch\u00fclerinnen und Sch\u00fcler<\/b><br \/>\nDie Ausbildung ist gepr\u00e4gt von Qualit\u00e4t und Innovation. Der Unterricht erfolgt im Fachlehrer-System und ist f\u00fcr Sch\u00fclerinnen und Sch\u00fcler ausgelegt, die \u00fcber sehr gute Englisch- und Deutschkenntnisse verf\u00fcgen, so dass sie einem Unterricht auf muttersprachlichem Niveau problemlos folgen k\u00f6nnen. Unsere Sch\u00fclerinnen und Sch\u00fcler haben sich die Maturit\u00e4t zum Ziel gesetzt.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"bodytext\">Das FGZ ist eine liberale und weltoffene Schule in\u00a0 der\u00a0 Tradition\u00a0 christlich\u2010humanistischer Menschenbildung. Es wurde 1888 als Privatschule gegr\u00fcndet.<\/p>\n<p class=\"bodytext\">Unser Angebot\u00a0 umfasst\u00a0 drei Vorbereitungsklassen,\u00a0 eine\u00a0 ein- und zweisprachige Sekundarabteilung\u00a0 A\u00a0 auf\u00a0 progymnasialem Niveau, sowie ein Lang-\u00ad und Kurzgymnasium mit bilingualen Ausbildungsg\u00e4ngen und staatlich anerkannter Hausmatur.<\/p>\n<p>Im Gymnasium k\u00f6nnen vier Profile gew\u00e4hlt werden: ein altsprachliches, ein neusprachliches, ein mathematisch-naturwissenschaftliches mit zwei Schwerpunktsrichtungen und ein\u00a0 wirtschaftlich-\u00adrechtliches.<\/p>\n<p>F\u00fcr die gymnasialen Lehrg\u00e4nge ist das eidgen\u00f6ssische Maturit\u00e4tsanerkennungsreglement (MAR), f\u00fcr die Vorbereitungsklassen und die Sekundarschule der kantonale Lehrplan verbindlich.<\/p>\n<p>Die Schule wird nach privatwirtschaftlichen, aber nicht gewinnorientierten Grunds\u00e4tzen gef\u00fchrt. Tr\u00e4ger ist ein Schulverein, sein oberstes F\u00fchrungsorgan der Vorstand.<\/p>\n<p>Rektor bzw. Rektorin und Prorektoren bzw. Prorektorinnen leiten die Schule. In den Klassen \u00fcbernehmen die Klassen-\u00ad und die Fachlehrpersonen die ihnen zukommenden F\u00fchrungsaufgaben.<\/p>\n<p>Ein kooperativer F\u00fchrungsstil sorgt\u00a0 f\u00fcr\u00a0 eine\u00a0 solide\u00a0 Abst\u00fctzung\u00a0 der\u00a0 Schulpolitik\u00a0 bei\u00a0 Sch\u00fclerschaft,\u00a0 Eltern und\u00a0 Mitarbeitenden.<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"header header2 header-default \">Eine lange Tradition<\/h2>\n<div class=\"csc-textpic-text\">\n<p class=\"bodytext\">1888 als Privatgymnasium gegr\u00fcndet, ist das Freie Gymnasium Z\u00fcrich eines der \u00e4ltesten und traditionsreichsten Gymnasien in Z\u00fcrich.<br \/>\nIn unserer weltoffenen Schule, die sowohl der humanistischen Tradition als auch der christlichen Grundhaltung verpflichtet ist, begleiten wir unsere Sch\u00fclerinnen und Sch\u00fcler auf dem Weg zur Maturit\u00e4t und in die Selbstst\u00e4ndigkeit. Dabei unterst\u00fctzen wir sie in der Entwicklung ihrer Pers\u00f6nlichkeit und bei der \u00dcbernahme von Verantwortung<\/p>\n<\/div>\n<h2 class=\"header header2 header-default \">Aufgabenbetreuung und Einzelf\u00f6rderung<\/h2>\n<div class=\"csc-textpic-text\">\n<p class=\"bodytext\">In Erg\u00e4nzung zum Unterricht h\u00e4lt das FGZ ein F\u00f6rder- und Betreuungsangebot bereit, das auf die individuellen Bed\u00fcrfnisse der Sch\u00fclerinnen und Sch\u00fcler abgestimmt ist. Das Angebot umfasst die Gef\u00e4sse Aufgabenbetreuung, Einzelf\u00f6rderung und Einzelcoaching sowie einen beaufsichtigten stillen Arbeitsraum in der Bibliothek, in welchem die Sch\u00fclerinnen und Sch\u00fcler konzentriert lernen und ihre Hausaufgaben erledigen k\u00f6nnen.<\/p>\n<\/div>\n<p class=\"bodytext\">Das Freie Gymnasium Z\u00fcrich f\u00fchrt folgende Ausbildungswege:<\/p>\n<ul>\n<li>\u00a0Vorbereitungsklasse 5 im Anschluss an die 4. Primarklasse<\/li>\n<li>\u00a0Vorbereitungsklasse 6 im Anschluss an die 5. Primarklasse<\/li>\n<li>\u00a0Progymnasiale Unterstufe: einsprachig und zweisprachig<\/li>\n<li>\u00a0Gymnasiale Unterstufe: einsprachig und zweisprachig<\/li>\n<li>\u00a0Kurzgymnasium: einsprachig und zweisprachig<\/li>\n<\/ul>\n<p class=\"bodytext\">Ein vielf\u00e4ltiges Angebot von Schwerpunkt- und Erg\u00e4nzungsf\u00e4chern besteht auf der Stufe des<br \/>\nGymnasiums. Es k\u00f6nnen vier verschiedene Ausbildungsprofile gew\u00e4hlt werde:<\/p>\n<ul>\n<li>\u00a0Altsprachliches Profil mit Schwerpunktfach Latein, kombiniert mit Englisch oder Griechisch<\/li>\n<li>\u00a0Neusprachliches Profil mit Schwerpunktfach Italienisch<\/li>\n<li>\u00a0Wirtschaftlich-rechtliches Profil mit Schwerpunktfach \u00abWirtschaft und Recht\u00bb<\/li>\n<li>\u00a0Mathematisch-naturwissenschaftliches Profil mit Schwerpunktfach \u00abBiologie und Chemie\u00bb<br \/>\noder \u00abAnwendungen der Mathematik und Physik\u00bb<\/li>\n<\/ul>\n<p class=\"bodytext\">Jedes Profil bieten wir ein- oder zweisprachig an.<\/p>\n<p class=\"align-justify\">Die Hausmaturit\u00e4t des Freien Gymnasiums Z\u00fcrich ist in allen Profilen eidgen\u00f6ssisch<br \/>\nanerkannt. Unsere Lehrerinnen und Lehrer stellen die Aufgaben, korrigieren die Pr\u00fcfungen<br \/>\nund bewerten diese.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Arbenzstrasse 19, 8008 Z\u00fcrich, Schweiz","_company_website":"https:\/\/www.fgz.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[153],"job-categories":[119,132,99,140,76,102],"job-types":[5,92,93],"class_list":{"0":"post-22236","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-zuerich","6":"job_listing_category-bilingualer-abschluss","7":"job_listing_category-gymnasium","8":"job_listing_category-primarschule","9":"job_listing_category-schweizer-maturitaet","10":"job_listing_category-sekundarstufe_1","11":"job_listing_category-sekundarstufe_2","12":"job_listing_type-primarschule","13":"job_listing_type-sekundarstufe_1","14":"job_listing_type-sekundarstufe_2","16":"job-type-primarschule-7-12jahre","17":"job-type-sekundarstufe-1-13-16-jahre","18":"job-type-sekundarstufe-2-16-19-jahre"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Freies Gymnasium Z\u00fcrich - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/ru\/listings\/freies-gymnasium-zuerich\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Freies Gymnasium Z\u00fcrich\" \/>\n<meta property=\"og:description\" content=\"Ein breites und hoch stehendes Angebot Das Angebot des Freien Gymnasiums Z\u00fcrich umfasst drei Vorbereitungsklassen, eine progymnasiale und eine gymnasiale Unterstufe sowie ein Kurzgymnasium mit staatlich anerkannter Hausmaturit\u00e4t. Im Gymnasium k\u00f6nnen vier Profile gew\u00e4hlt werden: das altsprachliche, das neusprachliche, das mathematisch-naturwissenschaftliche mit zwei Schwerpunktsrichtungen und das wirtschaftlich-rechtliche. F\u00fcr die gymnasialen Lehrg\u00e4nge ist das eidgen\u00f6ssische Maturit\u00e4tsanerkennungs-Reglement [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/ru\/listings\/freies-gymnasium-zuerich\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/1905_01_CF052518.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/1905_01_CF052518.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 \u043c\u0438\u043d\u0443\u0442\u044b\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/freies-gymnasium-zuerich\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/freies-gymnasium-zuerich\\\/\",\"name\":\"Freies Gymnasium Z\u00fcrich - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\"},\"datePublished\":\"2020-11-02T15:33:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/freies-gymnasium-zuerich\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/freies-gymnasium-zuerich\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/freies-gymnasium-zuerich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Freies Gymnasium Z\u00fcrich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Freies Gymnasium Z\u00fcrich - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/ru\/listings\/freies-gymnasium-zuerich\/","og_locale":"ru_RU","og_type":"article","og_title":"Freies Gymnasium Z\u00fcrich","og_description":"Ein breites und hoch stehendes Angebot Das Angebot des Freien Gymnasiums Z\u00fcrich umfasst drei Vorbereitungsklassen, eine progymnasiale und eine gymnasiale Unterstufe sowie ein Kurzgymnasium mit staatlich anerkannter Hausmaturit\u00e4t. Im Gymnasium k\u00f6nnen vier Profile gew\u00e4hlt werden: das altsprachliche, das neusprachliche, das mathematisch-naturwissenschaftliche mit zwei Schwerpunktsrichtungen und das wirtschaftlich-rechtliche. F\u00fcr die gymnasialen Lehrg\u00e4nge ist das eidgen\u00f6ssische Maturit\u00e4tsanerkennungs-Reglement [&hellip;]","og_url":"https:\/\/schoolaboo.com\/ru\/listings\/freies-gymnasium-zuerich\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/1905_01_CF052518.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/1905_01_CF052518.jpg","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"4 \u043c\u0438\u043d\u0443\u0442\u044b"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/ru\/listings\/freies-gymnasium-zuerich\/","url":"https:\/\/schoolaboo.com\/ru\/listings\/freies-gymnasium-zuerich\/","name":"Freies Gymnasium Z\u00fcrich - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/ru\/#website"},"datePublished":"2020-11-02T15:33:43+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/ru\/listings\/freies-gymnasium-zuerich\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/ru\/listings\/freies-gymnasium-zuerich\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/ru\/listings\/freies-gymnasium-zuerich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/ru\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/ru\/angebote\/"},{"@type":"ListItem","position":3,"name":"Freies Gymnasium Z\u00fcrich"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/ru\/#website","url":"https:\/\/schoolaboo.com\/ru\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/ru\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings\/22236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/comments?post=22236"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/media?parent=22236"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job_listing_region?post=22236"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-categories?post=22236"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-types?post=22236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}