{"id":21561,"date":"2020-11-02T21:25:51","date_gmt":"2020-11-02T20:25:51","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=21561"},"modified":"2020-11-02T21:25:51","modified_gmt":"2020-11-02T20:25:51","slug":"f-f","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/ru\/listings\/f-f\/","title":{"rendered":"F + F"},"content":{"rendered":"<div class=\"grid-item dynamic-box \" data-page-part-id=\"181\">\n<div class=\"title-subtitle hyphenate\">\n<div class=\"title\">Die offene Kunst- und Gestaltungsschule. Seit 1971 \u2013 Vermittlung von Kunst und Design.<\/div>\n<\/div>\n<div class=\"text hyphenate\">\n<p><strong>Wenn du die spannende Design- und Kunstwelt f\u00fcr dich entdecken oder einen gestalterischen Beruf erlernen m\u00f6chtest, bist du bei der F+F genau an der richtigen Adresse: Denn als gr\u00f6sste unabh\u00e4ngie Kunst- und Gestlatungschule der Schweiz die F+F Schule f\u00fcr Kunst und Design bereits seit 1971 hervorragende Gestaltung und fundiertes Kunstwissen.<\/strong><\/p>\n<p>Die F+F bringt nicht nur mehr Form und Farbe in dein Leben, sondern sch\u00e4rft auch deine kreativen Sinne und tr\u00e4gt im Austausch mit Mitstudierenden und Dozierenden zur Entwicklung deiner eigenen gestalterischen Pers\u00f6nlichkeit bei.<\/p>\n<div title=\"Page 3\">\n<div>\n<div>\n<p>An der F+F begegnen sich alle, die sich mit Leidenschaft dem Gestalten in Theorie und Praxis oder der Vermittlung von Kunst und Design verschrieben haben. F\u00fcr eine Ausbildung an der gr\u00f6ssten privaten Kunst- und Gestaltungsschule\u00a0der Schweiz brauchst du keine Matur und auch keine ECTS-Punkte zu sammeln.<\/p>\n<div title=\"Page 3\">\n<div>\n<div>\n<p>Ein offener und praxisnaher Austausch in den Ausbildungen und Kursen pr\u00e4gt das Klima dieser einzigartigen Schule. Der Unterricht findet in \u00fcberschaubaren Klassen statt, unterrichtet wird von Leuten aus der Praxis.\u00a0Die F+F bietet dir Raum und Zeit, dich im Austausch mit Mitstudierenden und Dozierenden kri- tisch mit allem Gegenw\u00e4rtigen auseinanderzusetzen, deine Sinne zu sch\u00e4rfen und so deine gestalterische Pers\u00f6nlichkeit weiterzuentwickeln.<\/p>\n<p>Als \u00e4lteste Kunstausbildungsst\u00e4tte der Deutschschweiz bietet die F+F einen reichen Erfahrungsschatz in der Vermittlung von Gestaltung und Kunstwissen und entwickelt sich dabei immer weiter:<\/p>\n<ul>\n<li>Seit Herbst 2016\u00a0k\u00f6nnen 11- bis 16-J\u00e4hrige Ferien- und Semesterkurse besuchen und so in einem professionellen Umfeld die ersten Schritte in die Gestaltung und Kunst unternehmen. Die Jugendkurse schliessen endlich diese Bildungsl\u00fccke der Volksschule und die F+F ist Mitglied in der\u00a0Konferenz Bildschulen Schweiz.<\/li>\n<li>Seit Schuljahr 2017\/18 kann an der F+F als einziger Schule der Deutschschweiz eine vier-j\u00e4hrige Berufsausbildung zum Fotograf\/zur Fotografin EFZ absolviert werden. Wir sind davon \u00fcberzeugt, dass das fotografische Handwerk heute noch immer Relevanz besitzt und dass eine schulische Ausbildung junge Leute ideal f\u00fcr die heutige visuelle Welt vorbereiten kann.<\/li>\n<\/ul>\n<p>Die F+F hat sich immer als soziale Institution begriffen, dies wird in mehrfacher Hinsicht deutlich.<\/p>\n<ul>\n<li>Mit der Kulturlegi der Caritas k\u00f6nnen alle Kurse f\u00fcr Jugendliche und Erwachsene\u00a0mit 30 % Rabatt besucht werden.<\/li>\n<li>Seit 2016\/17 offeriert die F+F in enger Zusammenarbeit mit der Autonomen Schule Z\u00fcrich Gefl\u00fcchteten die M\u00f6glichkeit einer kostenlosen Ausbildung, dem \u00abStipendium Welcome\u00bb.<\/li>\n<li>Der Stipendienfonds der F+F erm\u00f6glicht finanziell bed\u00fcrftigen Sch\u00fcler_innen und Student_innen der F+F\u00a0Unterst\u00fctzungsbeitr\u00e4ge.<\/li>\n<\/ul>\n<p>Die F+F entstand 1971 aus der Abspaltung der Kunstklasse Form &amp; Farbe von der damaligen Kunstgewerbeschule Z\u00fcrich. Die beiden \u00abF\u00bb beziehen sich auf das bis heute bei uns gelehrte Fach Form &amp; Farbe \u2013 die Grundelemente jeder visuellen Kommunikation. Gegr\u00fcndet als\u00a0<em>F+F Schule f\u00fcr experimentelle Gestaltung<\/em>\u00a0stand f\u00fcr die Gr\u00fcndergeneration die Entwicklung einer unabh\u00e4ngigen und zeitgem\u00e4ssen Kunstausbildung im Zentrum. Gleichzeitig wurde mit der \u00abAbendschule\u00bb schon fr\u00fch ein Kursprogramm etabliert, das offen f\u00fcr alle war. Der einj\u00e4hrige gestalterische Vorkurs wurde ebenfalls in den Anfangsjahren aufgebaut und er ist heute der zweit\u00e4lteste Vorkurs der Schweiz, der sich durch ein pr\u00e4zises und dichtes Curriculum auszeichnet. In den letzten Jahrzehnten wurde das Ausbildungsangebot in Richtung Gestaltung kontinuierlich ausgebaut: inzwischen ist die F+F die gr\u00f6sste Schule mit HF-Studieng\u00e4ngen der Schweiz.<\/p>\n<p>Als Mitglied bei\u00a0<em>swiss design schools<\/em>, der Direktorenkonferenz der Schweizer Schulen f\u00fcr Gestaltung und der\u00a0<em>Schweizerischen Konferenz der H\u00f6heren Fachschulen\u00a0<\/em>und der\u00a0<em>Konferenz Bildschulen Schweiz<\/em>\u00a0ist die Schule bestens etabliert, alle ihre Berufsausbildungen sind staatlich anerkannt (damit sind unsere Studierenden in allen Kantonen und im F\u00fcrstentum Lichtenstein stipendienberechtigt).\u00a0Mit dem Swiss European Mobility-Programme von\u00a0Movetia\u00a0sind Praktika und Austauschsemester im Ausland m\u00f6glich.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"file\">\n<div class=\"tool download-tool\"><\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"social-media-buttons\">\n<div class=\"clear\"><\/div>\n<\/div>\n<\/div>\n<div class=\"grid-item dynamic-box \" data-page-part-id=\"149\">\n<div class=\"title-contexts\">\n<div class=\"title-context\">\n<div>Portrait<\/div>\n<\/div>\n<\/div>\n<div class=\"title-subtitle hyphenate\">\n<div class=\"title\">F+F Bildungsangebot<\/div>\n<\/div>\n<div class=\"text hyphenate\">\n<p><strong>Das F+F-Bildungsangebot<\/strong><\/p>\n<p>Die F+F bietet staatlich anerkannte Studieng\u00e4nge in\u00a0Film,\u00a0Fotografie, \u00a0Modedesign\u00a0und\u00a0Visueller Gestaltung\u00a0mit Abschluss der H\u00f6heren Fachschule (HF) an. Zum Angebot geh\u00f6ren weiter die beiden Fachklassen\u00a0Fotografie\u00a0und\u00a0Grafik\u00a0mit EFZ-Lehrabschluss und der\u00a0Vorkurs\/Prop\u00e4deutikum\u00a0und der\u00a0berufsbgeleitende Vorkurs. Das breite\u00a0gestalterische Weiterbildungskursangebot\u00a0und die\u00a0Jugendkurse\u00a0stehen allen Interessierten offen.<\/p>\n<p>&nbsp;<\/p>\n<div title=\"Page 4\">\n<div>\n<div>\n<div title=\"Page 6\">\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div title=\"Page 4\">\n<div>\n<div><\/div>\n<\/div>\n<\/div>\n<p><strong>Fachklassen:\u00a0Fotografie EFZ\/BM\u00a0und\u00a0Grafik EFZ\/BM<\/strong><\/p>\n<div title=\"Page 6\">\n<div>\n<div>Die staatlich anerkannten, vier Jahre dauernden Fachklassen Fotografie EFZ\/BM und Grafik EFZ\/BM k\u00f6nnen als berufliche Grundausbildung nach Abschluss eines gestalterischen Vorkurses absolviert werden. Die Fachklassen sind als Vollzeitausbildung auf der Sekundarstufe II angesiedelt und stellen eine Alternative zum dualen System mit Lehrstelle und Berufsschule dar. Die Fachklassen werden mit dem Eidgen\u00f6ssischen F\u00e4higkeitszeugnis (EFZ) abgeschlossen. Es besteht die M\u00f6glichkeit, w\u00e4hrend der Ausbildung die gestalterische Berufsmaturit\u00e4tsschule Z\u00fcrich (BMS) zu besuchen.<\/div>\n<\/div>\n<\/div>\n<p><strong>Studieng\u00e4nge HF<\/strong><\/p>\n<div title=\"Page 4\">\n<div title=\"Page 7\">Die Vollzeit-Studieng\u00e4nge in den Vertiefungsrichtungen Kunst, Fotografie, Modedesign und Visuelle Gestaltung dauern sechs, der berufsbegleitende Studiengang Film acht Semester. Alle Studieng\u00e4nge sind staatlich anerkannt und Studierende damit grunds\u00e4tzlich in ihrem Herkunftskanton stipendienberechtigt.<\/div>\n<div title=\"Page 7\"><\/div>\n<\/div>\n<div title=\"Page 7\">\n<div>\n<div><strong>Studiengang Film HF berufsbegleitend<\/strong><br \/>\nDer berufsbegleitende Studiengang Film vermittelt alle Kompetenzen, um Filme und Videos produzieren zu k\u00f6nnen. W\u00e4hrend des acht Semester dauernden Studiengangs eignen sich die Studierenden das technische Knowhow f\u00fcr Regie, der Kamera-, Licht- und Tontechnik an. Sie lernen die Regeln des Drehbuchschreibens und der Schauspielf\u00fchrung kennen, schneiden eigene Filme und entwickeln inspirierende Vermarktungskonzepte. Diese sind Teil des R\u00fcstzeugs, das sie sich im Studiengang aneignen, um in der Filmbranche bestehen zu k\u00f6nnen.<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div title=\"Page 7\">\n<div>\n<div><strong>Studiengang Fotografie HF<\/strong><br \/>\nDas dreij\u00e4hrige Fotografie-Studium ist das einzige Vollzeitstudium auf Stufe H\u00f6here Fachschule in der Deutschschweiz. Die Studierenden befassen sich im Studiengang sowohl mit inhaltlichen als auch mit gestalterischen Prozessen. Hochqualifizierte Dozent*innen f\u00f6rdern individuelles und projektbezogenes Arbeiten ebenso wie spannende Kooperationen. Damit tragen sie zu einem zeitgem\u00e4ssen Bildverst\u00e4ndnis bei. Die St\u00e4rke dieses Bildungsganges liegt in seiner Praxisn\u00e4he, durch die sich fortlaufend berufliche Netzwerke bilden. Vielf\u00e4ltige Diskurse werden m\u00f6glich.<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div title=\"Page 7\">\n<div>\n<div><strong>Studiengang Kunst HF<\/strong><br \/>\nDer Studiengang Kunst HF unterst\u00fctzt K\u00fcnstler*innen, selbstst\u00e4ndig Projekte zu realisieren, die eine ganz eigene k\u00fcnstlerische Sprache sprechen. Und im Studium erfahren die Studierenden, wie die daraus resultierenden unverwechselbaren Werke im Kunstsystem entsprechend vermittelt werden k\u00f6nnen<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div title=\"Page 7\">\n<div>\n<div><strong>Studiengang Modedesign HF<\/strong><br \/>\nDie Studierenden erhalten im Studiengang Modedesign HF eine fundierte handwerkliche, technische und gestalterische Grundlage f\u00fcr ihre k\u00fcnftige Berufsaus\u00fcbung als Fashiondesigner*in. In der praxisorientierten Ausbildung werden sowohl konzeptionelles Denken als auch kreatives Schaffen gef\u00f6rdert. Die Studierenden erlangen F\u00e4higkeiten, fr\u00fchzeitig Trends und Stiltendenzen auszumachen und originelle, eigenst\u00e4ndige Entwurfsarbeiten zu entwickeln. Die aktuellsten Entwicklungen aus Mode, Wirtschaft und Gesellschaft fliessen stets ins Studium ein \u2013 kein Hinderungsgrund, sich im Studium nicht auch mit kulturhistorischen Zusammenh\u00e4ngen zu befassen.<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div title=\"Page 7\">\n<div>\n<div><strong>Studiengang Visuelle Gestaltung HF<\/strong><br \/>\nIm Studiengang Visuelle Gestaltung HF erwerben die Studierenden alle Kompetenzen, um eigene grafische L\u00f6sungen zu entwickeln. Sie lernen alle Schritte, die f\u00fcr die Erf\u00fcllung von grafischen Auftr\u00e4gen n\u00f6tig sind \u2013 von der Konzeption \u00fcber die Planung und den Entwurf bis zur Realisation. Die Konfrontation mit realen Auftr\u00e4gen l\u00e4sst die Studierenden praxisnah den Umgang mit den Anspr\u00fcchen von Kunden und Kundinnen erproben und ihre Arbeiten selbstbewusst zu vertreten.<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<p><strong>Weiterbildung Modedesign f\u00fcr Bekleidungsgestalter*innen EFZ<\/strong><\/p>\n<div title=\"Page 4\">\n<div>\n<div>\n<div title=\"Page 7\">\n<div>\n<div>Die Weiterbildung wird berufsbegleitend w\u00e4hrend einem Jahr in f\u00fcnf aufeinanderfolgenden Modulen absolviert. Die erfolgreich abgeschlossene berufsorientierte Weiterbildung bietet Bekleidungsgestalter*innen mit EFZ-Abschluss die M\u00f6glichkeit, direkt in das 3. Semester des Studiengangs Modedesign HF einzusteigen.<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Gestalterische Weiterbildungskurse<\/strong><\/p>\n<div title=\"Page 4\">\n<div title=\"Page 7\">Mit den Weiterbildungskursen macht die F+F ihren Wissenspool allen Interessierten zug\u00e4nglich. Die praxisnahen Kurse in den Bereichen Kunst, Gestaltung und Kunsttheorie starten viermal j\u00e4hrlich. Insbesondere f\u00fcr Berufst\u00e4tige ideal ist, dass die Kurse an Abenden, die Tageskurse am Freitag oder Samstag stattfinden. Jeweils im Juli und Februar gehen die einw\u00f6chigen\u00a0Winter- und Sommerateliers\u00a0\u00fcber die B\u00fchne. Die F+F bietet auch Kunstreisen an und sie f\u00fchrt externe Projektwochen durch.<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Flurstrasse 89 8047 Z\u00fcrich","_company_website":"https:\/\/ffzh.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[153],"job-categories":[76,102],"job-types":[93,228],"class_list":{"0":"post-21561","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-zuerich","6":"job_listing_category-sekundarstufe_1","7":"job_listing_category-sekundarstufe_2","8":"job_listing_type-sekundarstufe_2","9":"job_listing_type-tertiaerausbildung","11":"job-type-sekundarstufe-2-16-19-jahre","12":"job-type-tertiarausbildung"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>F + F - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/ru\/listings\/f-f\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F + F\" \/>\n<meta property=\"og:description\" content=\"Die offene Kunst- und Gestaltungsschule. Seit 1971 \u2013 Vermittlung von Kunst und Design. Wenn du die spannende Design- und Kunstwelt f\u00fcr dich entdecken oder einen gestalterischen Beruf erlernen m\u00f6chtest, bist du bei der F+F genau an der richtigen Adresse: Denn als gr\u00f6sste unabh\u00e4ngie Kunst- und Gestlatungschule der Schweiz die F+F Schule f\u00fcr Kunst und Design [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/ru\/listings\/f-f\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/Download-4-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/Download-4-1.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/f-f\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/f-f\\\/\",\"name\":\"F + F - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\"},\"datePublished\":\"2020-11-02T20:25:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/f-f\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/f-f\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/f-f\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"F + F\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"F + F - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/ru\/listings\/f-f\/","og_locale":"ru_RU","og_type":"article","og_title":"F + F","og_description":"Die offene Kunst- und Gestaltungsschule. Seit 1971 \u2013 Vermittlung von Kunst und Design. Wenn du die spannende Design- und Kunstwelt f\u00fcr dich entdecken oder einen gestalterischen Beruf erlernen m\u00f6chtest, bist du bei der F+F genau an der richtigen Adresse: Denn als gr\u00f6sste unabh\u00e4ngie Kunst- und Gestlatungschule der Schweiz die F+F Schule f\u00fcr Kunst und Design [&hellip;]","og_url":"https:\/\/schoolaboo.com\/ru\/listings\/f-f\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/Download-4-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/Download-4-1.png","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"7 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/ru\/listings\/f-f\/","url":"https:\/\/schoolaboo.com\/ru\/listings\/f-f\/","name":"F + F - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/ru\/#website"},"datePublished":"2020-11-02T20:25:51+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/ru\/listings\/f-f\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/ru\/listings\/f-f\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/ru\/listings\/f-f\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/ru\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/ru\/angebote\/"},{"@type":"ListItem","position":3,"name":"F + F"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/ru\/#website","url":"https:\/\/schoolaboo.com\/ru\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/ru\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings\/21561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/comments?post=21561"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/media?parent=21561"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job_listing_region?post=21561"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-categories?post=21561"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-types?post=21561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}