{"id":20903,"date":"2020-11-02T18:04:54","date_gmt":"2020-11-02T17:04:54","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=20903"},"modified":"2020-11-02T18:04:54","modified_gmt":"2020-11-02T17:04:54","slug":"swimac-swiss-marketing-academy-gmbh","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/ru\/listings\/swimac-swiss-marketing-academy-gmbh\/","title":{"rendered":"SWIMAC swiss marketing academy GmbH"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-8\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h2>Marketing \u2013 How to market things \u2026<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-4\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-8\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>SWISS MARKETING ACADEMY wurde 2002 von Brigitte Oertli und Hansruedi Kn\u00f6pfli gegr\u00fcndet. Wer h\u00e4tte das gedacht; schon bald werden wir uns Gedanken machen d\u00fcrfen, wie wir das 20-j\u00e4hrige Bestehen zelebrieren d\u00fcrfen.<\/p>\n<p>&nbsp;<\/p>\n<p>SWISS MARKETING ACADEMY ist seit 2007 Marktf\u00fchrer bei Marketing- und Verkaufsausbildungen auf dem zweiten Bildungsweg. Wir wissen, wovon wir reden \u2013 kein anderes Bildungsinstitut hat seit 2007 mehr Student|innen erfolgreich durch die Pr\u00fcfung f\u00fcr Marketing- und Verkaufsfachleute mit eidg. Fachausweis begleiten d\u00fcrfen. Dies ist ein gnadenloser Erfolg f\u00fcr ein kleines, feines Familienunternehmen.<\/p>\n<p>&nbsp;<\/p>\n<p>Seit 2010 sind wir H\u00f6here Fachschule Marketing und seit 2012 auch H\u00f6here Fachschule Wirtschaft. Die Marktf\u00fchrerschaft untermauert SWISS MARKETING ACADEMY aber auch als Treiber f\u00fcr Pr\u00fcfungsreformen und Entwickler neuster Ausbildungen in den Bereichen von Marketing, Verkauf, Kommunikation und Event\/Sponsoring.<\/p>\n<p>&nbsp;<\/p>\n<p>Dieses Engagement f\u00fchrte dazu, dass SWISS MARKETING ACADEMY nicht nur der dominante Bildungspartner f\u00fcr die f\u00fchrenden Berufsverb\u00e4nde wurde, sondern auch Marktleader.<\/p>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-8\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h2>Digitales Marketing<\/h2>\n<h3>Von Grund auf Lernen und Verstehen<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-4\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-8\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>SWISS MARKETING ACADEMY war schon oft Pionier. Wir w\u00e4ren das aber gerne noch mehr. Da wir leider (oder GottseiDank?) nicht ein vom Staat (und somit von Ihnen, den Steuerzahlern) finanziertes Institut sind, m\u00fcssen wir erst mal kleine Br\u00f6tchen backen.<\/p>\n<p>&nbsp;<\/p>\n<p>Unsere Referenten in diesen Lehrg\u00e4ngen m\u00fcssen folgenden Kriterien erf\u00fcllen:<br \/>\n\u2013 Selbstst\u00e4ndige Unternehmer oder Firmeninhaber, mind. 3 Jahre<br \/>\n\u2013 Unterrichtserfahrung auf Stufe H\u00d6HERE FACHSCHULE WIRTSCHAFT oder<\/p>\n<p>&nbsp;<\/p>\n<p>MARKETING<br \/>\n\u2013 Haupts\u00e4chliches Bestreiten des Lebensunterhaltes, mit dem was sie Dozieren<\/p>\n<p>\u2026somit haben wir die jetzt massig auftretenden 3.+4. Reihespeaker, wie sie an w\u00f6chentlichen Networking-Anl\u00e4ssen inflation\u00e4r daher schwadronieren \u201edraussen\u201c gelassen. Und diese \u201eBerater, Speaker, Coaches\u2026\u201c und wie sie sich alle gerne selbsbelobhudeln\u2026 sie bleiben \u201edraussen\u201c.<\/p>\n<p>&nbsp;<\/p>\n<p>Die beiden Ausbildungen Dipl. Online-Marketingplaner OMP und die Ausbildung Dipl. Digital Marketing Manager DMM erhalten bei 100% Kursanwesenheit ein EMK-Zertifikat, welches den jeweiligen Titel tr\u00e4gt. Der Dipl. Online-Marketingplaner OMP ist zu 100% Online \u2013 bequem von zu Hause aus besuchbar.<br \/>\nDer Dipl. Digital Marketing Manager DMM findet sowohl online (Freitagskurs) als auch offline (Samstagskurs) statt.<\/p>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-8\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h2>Betriebswirtschaftslehre<\/h2>\n<h3>Modullos und v\u00f6llig losgel\u00f6st\u2026 dies Basis bis zum mittleren Wissensstand<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-4\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-8\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>SWISS MARKETING ACADEMY vereint seit Jahren alle Inhalte, welche zur Betriebswirtschaftslehre geh\u00f6ren. Dies aus verschiedenen Betrachtungsblickwinkeln. Nat\u00fcrlich sind wir nicht nur in den mathematischen und statistischen Disziplinen stark positioniert, sondern durch die Ausbildungsrichtungen in Marketing, Verkauf und Kommunikation auch im Bereich der F\u00fchrung und Organisation.<\/p>\n<p>&nbsp;<\/p>\n<p>Ab Fr\u00fchjahr 2020 bieten wir zwei weitere Lehrg\u00e4nge an, welche sich modular bestens vernetzen lassen und die Grundlage f\u00fcr ein sp\u00e4teres Studium eignet. Als H\u00d6HERE FACHSCHULE WIRTSCHAFT und H\u00d6HERE FACHSCHULE MARKETING vereinen und vernetzen wir Theorie und Praxis wie kaum jemand sonst.<\/p>\n<\/div>\n<p>Unser Programme scheinen so gut zu sein, dass diese zum Teil von den Fachhochschule einfach kopiert und \u00fcbernommen wurden. Und als CAS verkauft werden. Insofern k\u00f6nnen wir nicht nur mit Fug und Recht behaupten die Pioniere in diesem Genre zu sein, sondern auch die Basis vieler weitere Unterlagen \u2013 im praktischen, wie auch wissenschaftlichen Sinne.<\/p>\n<p>&nbsp;<\/p>\n<p>Was bei all den Kopierereien nie gelang \u2013 die echte Praxisn\u00e4he. Nicht nur auf dem Papier.<br \/>\nDas k\u00f6nnen wir. Das sind wir\u2026<\/p>\n<p>&nbsp;<\/p>\n<p>Einige 100 Student\/innen absolvierten unsere Event- und Sponsoring-Ausbildungen \u2013 dies seit 2004. SWISS MARKETING ACADEMY wurde von Hansruedi Kn\u00f6pfli und Brigitte Oertli 2002 gegr\u00fcndet und was lag mehr auf der Hand, als die Beziehungen die die Beiden hatten zu nutzen.<\/p>\n<p>&nbsp;<\/p>\n<p>Brigitte Oertli zum einen als Skirennfahrerin (2 Olympia-Medaillen, X-Weltcupsiege\u2026) und Hansruedi Kn\u00f6pfli welcher f\u00fcr die Bierindustrie 15 Jahre Marketing, Events und Sales leitete. Mit dem Abschluss beim damalig gr\u00f6ssten Wein- und Spirituosen-Importeur. Dies war eine Plattform von Hunderten von Events \u2013 aus welchen man die Lehren ziehen konnte.<\/p>\n<p>&nbsp;<\/p>\n<p>Und so entstand dann auch bald schon der theoretische Boden \u2013 wissenschaftliche Erkennt-nisse rund um das Thema Event und Sponsoring wurden erschaffen. Und so wuchs diese Abteilung \u00fcber die Jahre. Bis hin zum eidg. anerkannten Abschluss \u201eEvent- und Promotion-manager NDS HF\u201c \u2013 was allerdings gewisse Zulassungskriterien erfordert.<\/p>\n<p>&nbsp;<\/p>\n<p>Wir empfehlen Ihnen aus einer der folgenden Ausbildungen auszuw\u00e4hlen:<\/p>\n<p>\u2013\u00a0Dipl. Event- und Sponsoringplaner (mit Diplom EMK-Zertifikatspr\u00fcfung)<br \/>\n\u2013\u00a0eidg. anerkanntes Nachdiplomstudium HF \u201eEvent- und Promotionmanager\u201c<br \/>\n\u2013\u00a0Dipl. Online-Marketingplaner (mit Zertifikat EMK-Zertifikatspr\u00fcfung)\u00a0\u2013 dies f\u00fcr Personen, welche schon Event- und Sponsoring-Erfahrung mitbringen, dies aber noch im Online-Bereich erg\u00e4nzen m\u00f6chten.<\/p>\n<p>Nat\u00fcrlich bieten wir unsere Erlebniswelten allen Student\/innen \u00fcber unser Alumni-Netzwerk \u201eRICHTIG &amp; WICHTIG\u201c an\u2026<\/p>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\" data-ls_id=\"#kommandobruecke\">\n<div class=\"wpb_column vc_column_container vc_col-sm-8\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h1>Die Kommandobr\u00fccke<\/h1>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-4\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-8\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Wir \u2013 Hansruedi \u201ekn\u00f6\u201c Kn\u00f6pfli und Brigitte Oertli \u2013 gr\u00fcndeten swiss marketing academy 2002. Und somit ist eigentlich auch schon klar, wer da am Beginn der Geschichte auf der Kommandobr\u00fccke stand und immer \u201evolle Kraft\u201c voraus Kurs auf zu neuen Ufern hielt.<\/p>\n<p>\u200b<\/p>\n<p>Nat\u00fcrlich geht\u2019s nicht ohne eine gut besetzte Kommandobr\u00fccke \u2013 welche immer genau weiss, wo was wann zu tun ist, damit der Dampfer kr\u00e4ftig durch die Wellen stampft. Und so gehen wir seit \u00fcber 10 Jahren keinem Sturm aus dem Weg. Bei rauher See f\u00fchlen wir uns wohl. Weil wir wissen, dass auf den Rest der Besatzung Verlass ist.<\/p>\n<p>\u200b<\/p>\n<h4>Folgende Vakanzen gibt\u2019s aktuell bei SWISS MARKETING ACADEMY:<\/h4>\n<p>Bisher haben s\u00e4mtliche Auszubildenden von SWISS MARKETING ACADEMY die kaufm\u00e4nnische Ausbildung im ersten Durchgang geschafft. Ein lebendiger Ausbildungsplatz \u2013 in einem lebendigen Dienstleistungbetrieb.<\/p>\n<ul>\n<li>Auszubildende\/r am Standort Z\u00fcrich\/Winterthur | f\u00fcr eine kaufm\u00e4nnische Ausbildung beginnend im Sommer 2020<\/li>\n<li>Praktikant\/in ab sofort als Assistenz des Schulleiters\u2026 vergeben seit 01.12.2019 bis Herbst 2020<\/li>\n<\/ul>\n<p>\u200b<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Hardturmstrasse 161, 8005 Z\u00fcrich, Schweiz","_company_website":"https:\/\/swissmarketingacademy.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[153],"job-categories":[226],"job-types":[228],"class_list":{"0":"post-20903","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-zuerich","6":"job_listing_category-hoehere-fachschule","7":"job_listing_type-tertiaerausbildung","9":"job-type-tertiarausbildung"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SWIMAC swiss marketing academy GmbH - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/ru\/listings\/swimac-swiss-marketing-academy-gmbh\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SWIMAC swiss marketing academy GmbH\" \/>\n<meta property=\"og:description\" content=\"Marketing \u2013 How to market things \u2026 SWISS MARKETING ACADEMY wurde 2002 von Brigitte Oertli und Hansruedi Kn\u00f6pfli gegr\u00fcndet. Wer h\u00e4tte das gedacht; schon bald werden wir uns Gedanken machen d\u00fcrfen, wie wir das 20-j\u00e4hrige Bestehen zelebrieren d\u00fcrfen. &nbsp; SWISS MARKETING ACADEMY ist seit 2007 Marktf\u00fchrer bei Marketing- und Verkaufsausbildungen auf dem zweiten Bildungsweg. Wir [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/ru\/listings\/swimac-swiss-marketing-academy-gmbh\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/swiss-marketing-academy.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/swiss-marketing-academy.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/swimac-swiss-marketing-academy-gmbh\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/swimac-swiss-marketing-academy-gmbh\\\/\",\"name\":\"SWIMAC swiss marketing academy GmbH - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\"},\"datePublished\":\"2020-11-02T17:04:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/swimac-swiss-marketing-academy-gmbh\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/swimac-swiss-marketing-academy-gmbh\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/swimac-swiss-marketing-academy-gmbh\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SWIMAC swiss marketing academy GmbH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SWIMAC swiss marketing academy GmbH - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/ru\/listings\/swimac-swiss-marketing-academy-gmbh\/","og_locale":"ru_RU","og_type":"article","og_title":"SWIMAC swiss marketing academy GmbH","og_description":"Marketing \u2013 How to market things \u2026 SWISS MARKETING ACADEMY wurde 2002 von Brigitte Oertli und Hansruedi Kn\u00f6pfli gegr\u00fcndet. Wer h\u00e4tte das gedacht; schon bald werden wir uns Gedanken machen d\u00fcrfen, wie wir das 20-j\u00e4hrige Bestehen zelebrieren d\u00fcrfen. &nbsp; SWISS MARKETING ACADEMY ist seit 2007 Marktf\u00fchrer bei Marketing- und Verkaufsausbildungen auf dem zweiten Bildungsweg. Wir [&hellip;]","og_url":"https:\/\/schoolaboo.com\/ru\/listings\/swimac-swiss-marketing-academy-gmbh\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/swiss-marketing-academy.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/swiss-marketing-academy.jpg","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"5 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/ru\/listings\/swimac-swiss-marketing-academy-gmbh\/","url":"https:\/\/schoolaboo.com\/ru\/listings\/swimac-swiss-marketing-academy-gmbh\/","name":"SWIMAC swiss marketing academy GmbH - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/ru\/#website"},"datePublished":"2020-11-02T17:04:54+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/ru\/listings\/swimac-swiss-marketing-academy-gmbh\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/ru\/listings\/swimac-swiss-marketing-academy-gmbh\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/ru\/listings\/swimac-swiss-marketing-academy-gmbh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/ru\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/ru\/angebote\/"},{"@type":"ListItem","position":3,"name":"SWIMAC swiss marketing academy GmbH"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/ru\/#website","url":"https:\/\/schoolaboo.com\/ru\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/ru\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings\/20903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/comments?post=20903"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/media?parent=20903"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job_listing_region?post=20903"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-categories?post=20903"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-types?post=20903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}