{"id":20023,"date":"2020-09-09T22:53:23","date_gmt":"2020-09-09T20:53:23","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=20023"},"modified":"2020-10-14T20:51:36","modified_gmt":"2020-10-14T18:51:36","slug":"ifm-universite-institut-de-finance-et-de-management-sa","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/ru\/listings\/ifm-universite-institut-de-finance-et-de-management-sa\/","title":{"rendered":"IFM Universit\u00e9 &#8212; Institut de Finance et de Management SA"},"content":{"rendered":"<div class=\"col-xs-12 col-md-6 lead\">\n<p class=\"\">Die IFM-Universit\u00e4t &#8212; Institut f\u00fcr Finanzen und Management wurde 1971 gegr\u00fcndet und ist eine akkreditierte Business School im Herzen von Genf, Schweiz.\u00a0Bei IFM konzentrieren wir uns auf die kaufm\u00e4nnische Ausbildung und unsere betriebswirtschaftlichen Abschl\u00fcsse bieten einen erstaunlichen Wert.\u00a0Wir sind darauf spezialisiert, Studenten dabei zu helfen, ihre Ziele zu erreichen und eine erfolgreiche Karriere zu erreichen &#8212; unsere Erfahrung aus einem halben Jahrhundert Ausbildung und Wirtschaft ist ein Beweis daf\u00fcr.\u00a0Ein wegweisender Lehrplan, der von Experten unter Einbeziehung von F\u00fchrungskr\u00e4ften aus der Wirtschaft entwickelt wurde, verschafft den Karrieren unserer Absolventen einen echten Wettbewerbsvorteil.<\/p>\n<\/div>\n<div class=\"col-xs-12 col-md-6 lead\">\n<p class=\"\">Unsere Leidenschaft f\u00fcr Innovation spiegelt sich in unserem einzigartigen realen Lehransatz wider: eine Kombination aus akademischer Exzellenz, die von einer erstklassigen Fakult\u00e4t erbracht wird, wesentlichen F\u00e4higkeiten, die mit praktischen Werkzeugen entwickelt wurden, und einer digitalen Denkweise.\u00a0Unsere Transformationsprogramme umfassen alle wichtigen Managementf\u00e4higkeiten, die moderne Unternehmen ben\u00f6tigen, und bieten gleichzeitig eine karrieref\u00f6rdernde globale Perspektive.\u00a0Die herausragenden Leistungen von IFM in der betriebswirtschaftlichen Ausbildung werden von drei gro\u00dfen Akkreditierungsstellen sowie von Rankings und zwei Innovationspreisen anerkannt.\u00a0Durch die Zugeh\u00f6rigkeit zu renommierten Verb\u00e4nden auf der ganzen Welt genie\u00dfen wir bei Personalvermittlern einen soliden Ruf.<\/p>\n<p>Das moderne Campusgeb\u00e4ude befindet sich im Herzen von Genf, im Bezirk der Universit\u00e4ten und der Kultur.\u00a0IFM befindet sich im Viertel Quartier des Bains, einem lebhaften, trendigen Viertel, das f\u00fcr seine zahlreichen zeitgen\u00f6ssischen Galerien und Museen bekannt ist.\u00a0Der IFM-Campus bietet modernste Technologie und Annehmlichkeiten.<\/p>\n<p>W\u00e4hrend ihres Studiums profitieren IFM-Studenten von der zentralen Lage des Genfer Standorts, wenn sie exklusive Branchenbesuche bei f\u00fchrenden Unternehmen, Fabriken, Herstellern, Banken und internationalen Organisationen durchf\u00fchren.\u00a0Genf ist eine internationale Stadt, die eine hervorragende Lebensqualit\u00e4t bietet.\u00a0Kultur spielt auch in Genf eine gro\u00dfe Rolle.\u00a0Unser Computerraum ist mit iMacs mit Multimedia-Technologie ausgestattet, um das Lernen zu unterst\u00fctzen.\u00a0Wir bieten auch eine Glasfaser-Webverbindung f\u00fcr das Hochgeschwindigkeitssurfen.\u00a0Unsere Bibliothek und unsere digitale Plattform bieten aktuelle B\u00fccher zu den w\u00e4hrend des Studiums behandelten Themen.\u00a0Wenn es Zeit ist, eine Pause einzulegen, k\u00f6nnen die Sch\u00fcler in der Studentenlounge oder in den G\u00e4rten entspannen.<\/p>\n<p>Der Bachelor of Business Administration (BBA) des IFM bereitet Sie auf die Herausforderungen der modernen Gesch\u00e4ftswelt vor.\u00a0Unser Bachelor vermittelt Ihnen eine praktische kaufm\u00e4nnische Ausbildung und die wesentlichen F\u00e4higkeiten f\u00fcr den Erfolg.\u00a0Sie entwickeln eine unternehmerische, innovative und digitale Denkweise.<\/p>\n<p>IFM MBA bietet eine intensive Transformationserfahrung, bietet neue Perspektiven, \u00e4ndert Ihre Denkweise und bereitet Sie auf die Herausforderungen der modernen Gesch\u00e4ftswelt vor.\u00a0Dieses Programm ist praxisrelevant, flexibel und konzentriert sich auf Ihren Erfolg.<\/p>\n<p>nser Executive MBA bietet eine intensive Transformationserfahrung, bietet neue Perspektiven, \u00e4ndert Ihre Denkweise, f\u00f6rdert Karrieren und bereitet Sie auf die Herausforderungen der modernen Gesch\u00e4ftswelt vor.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"rue des Bains 35, 1205 Genf Schweiz","_company_website":"https:\/\/www.ifm.ch\/index-en.html","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[172],"job-categories":[226],"job-types":[228],"class_list":{"0":"post-20023","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-genf","6":"job_listing_category-hoehere-fachschule","7":"job_listing_type-tertiaerausbildung","9":"job-type-tertiarausbildung"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>IFM Universit\u00e9 - Institut de Finance et de Management SA - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/ru\/listings\/ifm-universite-institut-de-finance-et-de-management-sa\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IFM Universit\u00e9 - Institut de Finance et de Management SA\" \/>\n<meta property=\"og:description\" content=\"Die IFM-Universit\u00e4t &#8212; Institut f\u00fcr Finanzen und Management wurde 1971 gegr\u00fcndet und ist eine akkreditierte Business School im Herzen von Genf, Schweiz.\u00a0Bei IFM konzentrieren wir uns auf die kaufm\u00e4nnische Ausbildung und unsere betriebswirtschaftlichen Abschl\u00fcsse bieten einen erstaunlichen Wert.\u00a0Wir sind darauf spezialisiert, Studenten dabei zu helfen, ihre Ziele zu erreichen und eine erfolgreiche Karriere zu erreichen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/ru\/listings\/ifm-universite-institut-de-finance-et-de-management-sa\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-14T18:51:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/Download-2.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/Download-2.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 \u043c\u0438\u043d\u0443\u0442\u044b\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/ifm-universite-institut-de-finance-et-de-management-sa\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/ifm-universite-institut-de-finance-et-de-management-sa\\\/\",\"name\":\"IFM Universit\u00e9 - Institut de Finance et de Management SA - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\"},\"datePublished\":\"2020-09-09T20:53:23+00:00\",\"dateModified\":\"2020-10-14T18:51:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/ifm-universite-institut-de-finance-et-de-management-sa\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/ifm-universite-institut-de-finance-et-de-management-sa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/ifm-universite-institut-de-finance-et-de-management-sa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IFM Universit\u00e9 &#8211; Institut de Finance et de Management SA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"IFM Universit\u00e9 - Institut de Finance et de Management SA - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/ru\/listings\/ifm-universite-institut-de-finance-et-de-management-sa\/","og_locale":"ru_RU","og_type":"article","og_title":"IFM Universit\u00e9 - Institut de Finance et de Management SA","og_description":"Die IFM-Universit\u00e4t &#8212; Institut f\u00fcr Finanzen und Management wurde 1971 gegr\u00fcndet und ist eine akkreditierte Business School im Herzen von Genf, Schweiz.\u00a0Bei IFM konzentrieren wir uns auf die kaufm\u00e4nnische Ausbildung und unsere betriebswirtschaftlichen Abschl\u00fcsse bieten einen erstaunlichen Wert.\u00a0Wir sind darauf spezialisiert, Studenten dabei zu helfen, ihre Ziele zu erreichen und eine erfolgreiche Karriere zu erreichen [&hellip;]","og_url":"https:\/\/schoolaboo.com\/ru\/listings\/ifm-universite-institut-de-finance-et-de-management-sa\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-10-14T18:51:36+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/Download-2.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/Download-2.png","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"2 \u043c\u0438\u043d\u0443\u0442\u044b"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/ru\/listings\/ifm-universite-institut-de-finance-et-de-management-sa\/","url":"https:\/\/schoolaboo.com\/ru\/listings\/ifm-universite-institut-de-finance-et-de-management-sa\/","name":"IFM Universit\u00e9 - Institut de Finance et de Management SA - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/ru\/#website"},"datePublished":"2020-09-09T20:53:23+00:00","dateModified":"2020-10-14T18:51:36+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/ru\/listings\/ifm-universite-institut-de-finance-et-de-management-sa\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/ru\/listings\/ifm-universite-institut-de-finance-et-de-management-sa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/ru\/listings\/ifm-universite-institut-de-finance-et-de-management-sa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/ru\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/ru\/angebote\/"},{"@type":"ListItem","position":3,"name":"IFM Universit\u00e9 &#8211; Institut de Finance et de Management SA"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/ru\/#website","url":"https:\/\/schoolaboo.com\/ru\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/ru\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings\/20023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/comments?post=20023"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/media?parent=20023"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job_listing_region?post=20023"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-categories?post=20023"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-types?post=20023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}