{"id":20021,"date":"2020-09-09T22:53:23","date_gmt":"2020-09-09T20:53:23","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=20021"},"modified":"2020-12-22T11:16:41","modified_gmt":"2020-12-22T10:16:41","slug":"hso-wirtschafts-und-informatikschule-aarau","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/ru\/listings\/hso-wirtschafts-und-informatikschule-aarau\/","title":{"rendered":"HSO Wirtschafts- und Informatikschule Aarau"},"content":{"rendered":"<p>Die erste HSO Schule wurde von Camille A. Bise gegr\u00fcndet und im Fr\u00fchjahr 1954 im\u00a0Z\u00fcrcher\u00a0Stadtteil\u00a0Oerlikon\u00a0als\u00a0<i>Handelsschule\u00a0Oerlikon<\/i>\u00a0er\u00f6ffnet. Der erste Lehrgang f\u00fchrte angehende Kaufleute in das Maschinenschreiben ein.<sup id=\"cite_ref-1\" class=\"reference\"><\/sup><\/p>\n<p>1959 entstand daraus eine Tageshandelsschule mit einem vollen KV-Lehrprogramm.\u00a0<i>\u201eKV\u201c<\/i>\u00a0(nach \u201eKaufm\u00e4nnischer Verband\u201c) steht in der Schweiz synonym f\u00fcr kaufm\u00e4nnische Themen und Ausbildung. Sp\u00e4ter wandelte sie sich zum Bildungszentrum \u201eHSO Handels- und Kaderschule Oerlikon Z\u00fcrich\u201c. 2004, 10 Jahre nach der \u00dcbernahme der Unternehmensleitung der HSO durch den heutigen Vize Verwaltungsratspr\u00e4sidenten Beat N\u00e4gelin, hatte die HSO 1.500\u00a0Studierende in verschiedenen Ausbildungsg\u00e4ngen, darunter Kommunikation, Informatik, Handelsschule, KV College und Kaderschulung. 2007 begann die HSO gesamtschweizerisch zu expandieren und heisst heute \u201eHSO Wirtschafts- und Informatikschule\u201c. Bildungszentren gibt es in verschiedenen Schweizer St\u00e4dten.<\/p>\n<p>Die HSO verf\u00fcgte 2020 \u00fcber 3\u2019800 Studierende und einen Lehrk\u00f6rper mit 450 Mitarbeitenden und Dozenten. Die Aus- und Weiterbildung umfasst 40 verschiedene Lehrg\u00e4nge. Diese reichen von eidgen\u00f6ssischen Diplomen und Nachdiplomen \u00fcber europ\u00e4isch anerkannte Bachelorprogramme bis hin zu global akkreditierten Masterprogrammen. Dazu geh\u00f6ren die kaufm\u00e4nnische Grundausbildung und verschiedene Berufspr\u00fcfungen bis zur\u00a0H\u00f6heren Fachschule\u00a0und\u00a0Fachhochschule, sowie weiterf\u00fchrende Studien bis zum Executive Master of Business Administration (EMBA).<\/p>\n<p>Die HSO Wirtschafts- und Informatikschule geh\u00f6rt zu den f\u00fchrenden Wirtschaftsschulen der Schweiz. Sie ist konsequent auf die Bed\u00fcrfnisse des Marktes ausgerichtet. Seit der Gr\u00fcndung 1954 in Z\u00fcrich-Oerlikon hat sich die HSO Wirtschafts- und Informatikschule mit aktuell elf Standorten und mit mehr als 3500 Studierenden zu einem der bedeutendsten privaten Bildungsanbieter in der Schweiz entwickelt. Alle elf Standorte befinden sich an zentraler Lage und sind in maximal zehn Minuten zu Fuss vom jeweiligen Bahnhof aus erreichbar. So gew\u00e4hrleisten wir, dass alle den Standort einfach erreichen k\u00f6nnen. Dank der breiten Pr\u00e4senz in vielen Regionen der Schweiz besteht auch die M\u00f6glichkeit, w\u00e4hrend der Weiterbildung den Standort zu wechseln und am neuen Ort mit dem Lehrgang fortzufahren.<\/p>\n<p>Die HSO Wirtschafts-\u00ad und Informatikschule bietet Ihnen maximale Flexibilit\u00e4t bei der zeitlichen und inhaltlichen Gestaltung einer berufsbegleitenden Weiterbildung. Dank konsequenter Modularisierung und einer klaren Dispensationsregelung studieren Sie an der HSO effizient und individuell nach Ihren Bed\u00fcrfnissen.<\/p>\n<p>Die HSO gliedert das zu erwerbende Wissen in unterschiedliche, aber in sich geschlossene Lerneinheiten. Dabei sind die Module inhaltlich so gestaltet, dass sie stufen-\u00ad und zielgruppengerecht eingesetzt werden k\u00f6nnen. Um Ihnen die Planung zu erleichtern, ist innerhalb jedes Lehrgangsmoduls zudem genau festgelegt, welche Inhalte Sie durch Unterrichtspr\u00e4senz und welche Sie durch selbstst\u00e4ndiges Lernen erwerben.<\/p>\n<p><strong>Flexible Grundmodule f\u00fcr Flexibilit\u00e4t und aktiven Austausch<\/strong><br \/>\nDie Grundmodule sind so konzipiert, dass sie nicht nur f\u00fcr einen einzigen Abschluss anrechenbar sind, sondern Teil mehrerer Abschl\u00fcsse darstellen k\u00f6nnen. Damit haben Sie nicht nur eine gr\u00f6ssere Auswahl an Ausbildungswegen, sondern Sie erwerben das Basiswissen in heterogene Klassenverb\u00e4nden. Das f\u00f6rdert und fordert den aktiven Austausch unter angehenden Spezialisten und Generalisten und Sie entwickeln eine f\u00e4cher\u00fcbergreifende Betrachtungsweise von betriebswirtschaftlichen Problemstellungen. Im weiteren Verlauf der Studieng\u00e4nge werden die Klassen dann aufgrund des zielgruppenspezifischen Unterrichtes immer fokussierter und damit auch homogener.<\/p>\n<p><strong>Keine Doppelspurigkeiten dank klarer Dispensationsregelung<\/strong><br \/>\nWenn Sie den entsprechenden Nachweis erbringen, k\u00f6nnen Sie f\u00fcr einzelne Themenbereiche, ganze Module oder sogar Semester vom Unterricht dispensiert werden. So sparen Sie wertvolle Zeit und gelangen effizienter an Ihr Studienziel. Die Pr\u00fcfungen f\u00fcr einen angestrebten Abschluss m\u00fcssen in der Regel jedoch auch von Studierenden mit Dispens abgelegt werden.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Bahnhofpl. 3h, 5000 Aarau, Schweiz","_company_website":"https:\/\/www.hso.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[155,157,414,160,151,162,167,159,154,153],"job-categories":[114,226],"job-types":[228],"class_list":{"0":"post-20021","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-aargau","6":"job_listing_region-basel-stadt","7":"job_listing_region-basel-stadt-land","8":"job_listing_region-bern","9":"job_listing_region-graubuenden","10":"job_listing_region-luzern","11":"job_listing_region-solothurn","12":"job_listing_region-st-gallen","13":"job_listing_region-zug","14":"job_listing_region-zuerich","15":"job_listing_category-fachmittelschule","16":"job_listing_category-hoehere-fachschule","17":"job_listing_type-tertiaerausbildung","19":"job-type-tertiarausbildung"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>HSO Wirtschafts- und Informatikschule Aarau - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/ru\/listings\/hso-wirtschafts-und-informatikschule-aarau\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HSO Wirtschafts- und Informatikschule Aarau\" \/>\n<meta property=\"og:description\" content=\"Die erste HSO Schule wurde von Camille A. Bise gegr\u00fcndet und im Fr\u00fchjahr 1954 im\u00a0Z\u00fcrcher\u00a0Stadtteil\u00a0Oerlikon\u00a0als\u00a0Handelsschule\u00a0Oerlikon\u00a0er\u00f6ffnet. Der erste Lehrgang f\u00fchrte angehende Kaufleute in das Maschinenschreiben ein. 1959 entstand daraus eine Tageshandelsschule mit einem vollen KV-Lehrprogramm.\u00a0\u201eKV\u201c\u00a0(nach \u201eKaufm\u00e4nnischer Verband\u201c) steht in der Schweiz synonym f\u00fcr kaufm\u00e4nnische Themen und Ausbildung. Sp\u00e4ter wandelte sie sich zum Bildungszentrum \u201eHSO Handels- und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/ru\/listings\/hso-wirtschafts-und-informatikschule-aarau\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-22T10:16:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/alstetten-standort-hso-zuerich.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/alstetten-standort-hso-zuerich.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 \u043c\u0438\u043d\u0443\u0442\u044b\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/hso-wirtschafts-und-informatikschule-aarau\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/hso-wirtschafts-und-informatikschule-aarau\\\/\",\"name\":\"HSO Wirtschafts- und Informatikschule Aarau - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\"},\"datePublished\":\"2020-09-09T20:53:23+00:00\",\"dateModified\":\"2020-12-22T10:16:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/hso-wirtschafts-und-informatikschule-aarau\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/hso-wirtschafts-und-informatikschule-aarau\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/hso-wirtschafts-und-informatikschule-aarau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HSO Wirtschafts- und Informatikschule Aarau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"HSO Wirtschafts- und Informatikschule Aarau - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/ru\/listings\/hso-wirtschafts-und-informatikschule-aarau\/","og_locale":"ru_RU","og_type":"article","og_title":"HSO Wirtschafts- und Informatikschule Aarau","og_description":"Die erste HSO Schule wurde von Camille A. Bise gegr\u00fcndet und im Fr\u00fchjahr 1954 im\u00a0Z\u00fcrcher\u00a0Stadtteil\u00a0Oerlikon\u00a0als\u00a0Handelsschule\u00a0Oerlikon\u00a0er\u00f6ffnet. Der erste Lehrgang f\u00fchrte angehende Kaufleute in das Maschinenschreiben ein. 1959 entstand daraus eine Tageshandelsschule mit einem vollen KV-Lehrprogramm.\u00a0\u201eKV\u201c\u00a0(nach \u201eKaufm\u00e4nnischer Verband\u201c) steht in der Schweiz synonym f\u00fcr kaufm\u00e4nnische Themen und Ausbildung. Sp\u00e4ter wandelte sie sich zum Bildungszentrum \u201eHSO Handels- und [&hellip;]","og_url":"https:\/\/schoolaboo.com\/ru\/listings\/hso-wirtschafts-und-informatikschule-aarau\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-12-22T10:16:41+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/alstetten-standort-hso-zuerich.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/alstetten-standort-hso-zuerich.jpg","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"3 \u043c\u0438\u043d\u0443\u0442\u044b"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/ru\/listings\/hso-wirtschafts-und-informatikschule-aarau\/","url":"https:\/\/schoolaboo.com\/ru\/listings\/hso-wirtschafts-und-informatikschule-aarau\/","name":"HSO Wirtschafts- und Informatikschule Aarau - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/ru\/#website"},"datePublished":"2020-09-09T20:53:23+00:00","dateModified":"2020-12-22T10:16:41+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/ru\/listings\/hso-wirtschafts-und-informatikschule-aarau\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/ru\/listings\/hso-wirtschafts-und-informatikschule-aarau\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/ru\/listings\/hso-wirtschafts-und-informatikschule-aarau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/ru\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/ru\/angebote\/"},{"@type":"ListItem","position":3,"name":"HSO Wirtschafts- und Informatikschule Aarau"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/ru\/#website","url":"https:\/\/schoolaboo.com\/ru\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/ru\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings\/20021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/comments?post=20021"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/media?parent=20021"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job_listing_region?post=20021"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-categories?post=20021"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-types?post=20021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}