{"id":20003,"date":"2020-09-09T22:53:24","date_gmt":"2020-09-09T20:53:24","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=20003"},"modified":"2020-10-14T19:07:24","modified_gmt":"2020-10-14T17:07:24","slug":"geneva-english-school","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/ru\/listings\/geneva-english-school\/","title":{"rendered":"Geneva English School"},"content":{"rendered":"<p class=\"fs_style_24\">Die Geneva English School wurde 1961 von einer kleinen Gruppe von Eltern gegr\u00fcndet, die eine britische Ausbildung f\u00fcr ihre Kinder w\u00fcnschten.\u00a0Ein Gemeindesaal in der Rue Baulacre 14 in Genf wurde angemietet, ein Lehrer eingestellt und die Schule begann zu wachsen.<\/p>\n<p class=\"Tableanswers\">Bis 1963 war die Zahl der Sch\u00fcler auf 40 angewachsen, und die Schule zog in gr\u00f6\u00dfere R\u00e4umlichkeiten an der Ecole Migros in der Rue du Prince um.\u00a0Da die Nachfrage nach Pl\u00e4tzen weiter zunahm, zog die Schule in ein gro\u00dfes Haus an der 39 bis route de Malagnou und 1967 in das leere Schulgel\u00e4nde des Dorfes in V\u00e9senaz.<\/p>\n<p class=\"Tableanswers\">1972 wurde Denis Unsworth zum Leiter ernannt.\u00a0Er blieb bis zu seiner Pensionierung im Jahr 2007. Eine lange und schwierige Suche nach neuen R\u00e4umlichkeiten in den fr\u00fchen 1980er Jahren f\u00fchrte schlie\u00dflich zur Identifizierung des pr\u00e4chtigen Standortes \u201ePetit Malagny\u201c in Genthod auf der gegen\u00fcberliegenden Seite des Sees.\u00a0Insgesamt wurden rund sechs Jahre f\u00fcr die Aushandlung des endg\u00fcltigen Kaufs, die Sicherung des Darlehens, die Genehmigung f\u00fcr die Nutzung des Geb\u00e4udes als Schule, die Vereinbarung von Sanierungspl\u00e4nen und zus\u00e4tzlichen Geb\u00e4uden sowie die Durchf\u00fchrung der Bauarbeiten aufgewendet.\u00a01989 zog die Schule zu Beginn des Sommersemesters nach Genthod und wurde am Sporttag offiziell er\u00f6ffnet.<\/p>\n<p class=\"Tableanswers\">Ein viertes Geb\u00e4ude, das\u00a0<em>Sal\u00e8ve<\/em>\u00a0, wurde im April 2013 er\u00f6ffnet und bietet zus\u00e4tzlich zu den Klassenzimmern, die f\u00fcr eine Erweiterung auf zwei Klassen pro Jahr erforderlich sind, einen Speisesaal und ein Tanzstudio.<\/p>\n<p class=\"p1\">Unser\u00a0sekund\u00e4rer Campus\u00a0\u00a0wurde im September 2017 in einer neuen, hochmodernen Einrichtung in Versoix er\u00f6ffnet, nur wenige Minuten vom prim\u00e4ren Standort entfernt.\u00a0Die Sekundarschule w\u00e4chst von Jahr zu Jahr organisch und hat derzeit Sch\u00fcler in den Klassen 7 bis 9, wobei die 10. Klasse im September 2019 er\u00f6ffnet wird.<\/p>\n<h1 class=\"fsPageTitle\">Wo wir sind<\/h1>\n<div id=\"fsEl_1075\" class=\"fsPageLayout fsLayout fsOneColumnLayout fsStyleAutoclear\" data-use-new=\"true\">\n<div id=\"fsEl_1076\" class=\" fsDiv fsStyleAutoclear\">\n<div id=\"fsEl_2587\" class=\"fsElement fsContent\" data-use-new=\"true\">\n<div class=\"fsElementContent\">\n<p>GES Primary<a href=\"https:\/\/www.geschool.ch\/primary\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a0<\/a>befindet sich in einer wundersch\u00f6nen Parklandschaft in der Gemeinde Genthod, weniger als 10 km vom Zentrum von Genf entfernt.<\/p>\n<p class=\"Tableanswers\">Die Schule besteht aus einem eleganten, historischen, denkmalgesch\u00fctzten Hauptgeb\u00e4ude und drei weiteren Geb\u00e4uden, von denen zwei gebaut wurden, als die Schule 1989 &#8216;Le Petit Malagny&#8217; erwarb. Unser neuestes Geb\u00e4ude wurde im April 2013 er\u00f6ffnet. Die Schule und ihr Gel\u00e4nde bieten einen atemberaubenden Blick L\u00e9man-See in Richtung Mont Blanc.<\/p>\n<\/div>\n<\/div>\n<div id=\"fsEl_2588\" class=\"fsElement fsContent\" data-use-new=\"true\">\n<div class=\"fsElementContent\">\n<p><span class=\"fs_style_26\">GES Secondary<a href=\"https:\/\/www.geschool.ch\/secondary\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a0<\/a>nimmt einen bedeutenden Teil des Erdgeschosses und des Gel\u00e4ndes des neu errichteten Modulis-Geb\u00e4udes in der N\u00e4he des Sees in Versoix ein, nur wenige Minuten vom Hauptcampus entfernt.<\/span><\/p>\n<p>Das helle Innere dieses hochmodernen Geb\u00e4udes bietet die perfekte leere Leinwand, um eine innovative, miteinander verbundene Lernumgebung zu schaffen, die f\u00fcr die Bildung des 21. Jahrhunderts geeignet ist.\u00a0Die g\u00fcnstige Lage bietet zahlreiche M\u00f6glichkeiten, sich mit der Gemeinde zu verbinden und lokale Annehmlichkeiten zu nutzen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Route de Malagny 36 1294 Genthod \/ Genf Schweiz","_company_website":"https:\/\/www.geschool.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[172],"job-categories":[109,99,76,131],"job-types":[5,92],"class_list":{"0":"post-20003","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-genf","6":"job_listing_category-englisches-schulprogramm-gce-a-level","7":"job_listing_category-primarschule","8":"job_listing_category-sekundarstufe_1","9":"job_listing_category-unterrichtssprache-englisch","10":"job_listing_type-primarschule","11":"job_listing_type-sekundarstufe_1","13":"job-type-primarschule-7-12jahre","14":"job-type-sekundarstufe-1-13-16-jahre"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Geneva English School - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/ru\/listings\/geneva-english-school\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geneva English School\" \/>\n<meta property=\"og:description\" content=\"Die Geneva English School wurde 1961 von einer kleinen Gruppe von Eltern gegr\u00fcndet, die eine britische Ausbildung f\u00fcr ihre Kinder w\u00fcnschten.\u00a0Ein Gemeindesaal in der Rue Baulacre 14 in Genf wurde angemietet, ein Lehrer eingestellt und die Schule begann zu wachsen. Bis 1963 war die Zahl der Sch\u00fcler auf 40 angewachsen, und die Schule zog in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/ru\/listings\/geneva-english-school\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-14T17:07:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/maxresdefault-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/maxresdefault-1.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 \u043c\u0438\u043d\u0443\u0442\u044b\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/geneva-english-school\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/geneva-english-school\\\/\",\"name\":\"Geneva English School - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\"},\"datePublished\":\"2020-09-09T20:53:24+00:00\",\"dateModified\":\"2020-10-14T17:07:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/geneva-english-school\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/geneva-english-school\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/geneva-english-school\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Geneva English School\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Geneva English School - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/ru\/listings\/geneva-english-school\/","og_locale":"ru_RU","og_type":"article","og_title":"Geneva English School","og_description":"Die Geneva English School wurde 1961 von einer kleinen Gruppe von Eltern gegr\u00fcndet, die eine britische Ausbildung f\u00fcr ihre Kinder w\u00fcnschten.\u00a0Ein Gemeindesaal in der Rue Baulacre 14 in Genf wurde angemietet, ein Lehrer eingestellt und die Schule begann zu wachsen. Bis 1963 war die Zahl der Sch\u00fcler auf 40 angewachsen, und die Schule zog in [&hellip;]","og_url":"https:\/\/schoolaboo.com\/ru\/listings\/geneva-english-school\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-10-14T17:07:24+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/maxresdefault-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/maxresdefault-1.jpg","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"2 \u043c\u0438\u043d\u0443\u0442\u044b"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/ru\/listings\/geneva-english-school\/","url":"https:\/\/schoolaboo.com\/ru\/listings\/geneva-english-school\/","name":"Geneva English School - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/ru\/#website"},"datePublished":"2020-09-09T20:53:24+00:00","dateModified":"2020-10-14T17:07:24+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/ru\/listings\/geneva-english-school\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/ru\/listings\/geneva-english-school\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/ru\/listings\/geneva-english-school\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/ru\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/ru\/angebote\/"},{"@type":"ListItem","position":3,"name":"Geneva English School"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/ru\/#website","url":"https:\/\/schoolaboo.com\/ru\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/ru\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings\/20003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/comments?post=20003"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/media?parent=20003"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job_listing_region?post=20003"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-categories?post=20003"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-types?post=20003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}