{"id":19913,"date":"2020-09-09T22:53:52","date_gmt":"2020-09-09T20:53:52","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=19913"},"modified":"2021-06-18T14:33:52","modified_gmt":"2021-06-18T12:33:52","slug":"ecole-alpine-internationale-prefleuri","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/ru\/listings\/ecole-alpine-internationale-prefleuri\/","title":{"rendered":"Ecole Alpine Internationale &#8212; Pr\u00e9fleuri"},"content":{"rendered":"<div class=\"summary\">\n<p>Die Internationale Alpenschule Pr\u00e9fleuri befindet sich in den Schweizer Alpen auf einer H\u00f6he von 1200 Metern \u00fcber dem Meeresspiegel in der N\u00e4he des bekannten Skigebiets Villars-sur-Ollon. Pr\u00e9fleuri befindet sich in einer au\u00dfergew\u00f6hnlichen Umgebung und bietet eine herrliche Aussicht. <span style=\"color: inherit; font-family: inherit; font-size: inherit;\">Die Schule liegt auf 2 Hektar Land, umgeben von W\u00e4ldern und Wiesen, auf denen noch immer Eichh\u00f6rnchen, Hirsche und F\u00fcchse herumtollen.<\/span><\/p>\n<\/div>\n<p>Wir begr\u00fc\u00dfen Jungen und M\u00e4dchen im Alter von 3 bis 13 Jahren aus aller Welt als Internatssch\u00fcler oder Tagessch\u00fcler, f\u00fcr das akademische Schuljahr oder f\u00fcr Sport- und Studienferien.<\/p>\n<p>Wir bieten qualitativ hochwertige Bildung auf der Grundlage der Achtung traditioneller Werte und der Vertrauensw\u00fcrdigkeit und sind stolz darauf, dies seit unserer Gr\u00fcndung im Jahr 1948 getan zu haben.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"summary\">\n<h4><strong>Ausbildung von h\u00f6chster Qualit\u00e4t\u2026<\/strong><\/h4>\n<p>Unser Ziel ist es, eine Ausbildung anzubieten, die dem offiziellen nationalen Schullehrplan entspricht und an das Tempo Ihres Kindes angepasst ist.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p><span style=\"font-size: 1.125rem; font-weight: bold; letter-spacing: 1px; text-transform: uppercase; font-family: inherit;\">Unsere Unterrichtsphilosophie basiert auf:<\/span><\/p>\n<ul>\n<li>Kleine Klassen, um eine individuelle Nachverfolgung zu erm\u00f6glichen, die an die F\u00e4higkeiten des Kindes angepasst ist.<\/li>\n<li>Unsere Lehrer und Erzieher arbeiten zusammen, um die Bem\u00fchungen des Kindes zu f\u00f6rdern und zu belohnen.<\/li>\n<li>Unsere humanistische Ethik des Respekts und der Aufmerksamkeit, die zur Entwicklung einer selbstbewussten und ausgeglichenen Pers\u00f6nlichkeit beitr\u00e4gt.<\/li>\n<li>Unser Erfordernis der Disziplin in der Arbeit sowohl der Kinder als auch der Lehrer.<\/li>\n<\/ul>\n<p>Die Schule unterh\u00e4lt enge Beziehungen zu den Eltern und f\u00f6rdert gemeinsame Aktivit\u00e4ten mit Eltern und Kindern.<\/p>\n<p>Weihnachtsworkshops, Themenmahlzeiten und Herausforderungen beim Orientierungslauf sind M\u00f6glichkeiten f\u00fcr gemeinsames Gl\u00fcck.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Chemin de Curnaux 32 CH 1885 Chesi\u00e8res","_company_website":"http:\/\/www.prefleuri.ch\/en\/content\/contact","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[177],"job-categories":[119,103,99,115],"job-types":[90,5],"class_list":{"0":"post-19913","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-wallis","6":"job_listing_category-bilingualer-abschluss","7":"job_listing_category-kindergarten","8":"job_listing_category-primarschule","9":"job_listing_category-tagesschule","10":"job_listing_type-kindergarten","11":"job_listing_type-primarschule","13":"job-type-kindergarten-4-6-jahre","14":"job-type-primarschule-7-12jahre"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ecole Alpine Internationale - Pr\u00e9fleuri - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/ru\/listings\/ecole-alpine-internationale-prefleuri\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecole Alpine Internationale - Pr\u00e9fleuri\" \/>\n<meta property=\"og:description\" content=\"Die Internationale Alpenschule Pr\u00e9fleuri befindet sich in den Schweizer Alpen auf einer H\u00f6he von 1200 Metern \u00fcber dem Meeresspiegel in der N\u00e4he des bekannten Skigebiets Villars-sur-Ollon. Pr\u00e9fleuri befindet sich in einer au\u00dfergew\u00f6hnlichen Umgebung und bietet eine herrliche Aussicht. Die Schule liegt auf 2 Hektar Land, umgeben von W\u00e4ldern und Wiesen, auf denen noch immer Eichh\u00f6rnchen, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/ru\/listings\/ecole-alpine-internationale-prefleuri\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-18T12:33:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/07\/carousel_chalet01.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/07\/carousel_chalet01.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 \u043c\u0438\u043d\u0443\u0442\u044b\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/ecole-alpine-internationale-prefleuri\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/ecole-alpine-internationale-prefleuri\\\/\",\"name\":\"Ecole Alpine Internationale - Pr\u00e9fleuri - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\"},\"datePublished\":\"2020-09-09T20:53:52+00:00\",\"dateModified\":\"2021-06-18T12:33:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/ecole-alpine-internationale-prefleuri\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/ecole-alpine-internationale-prefleuri\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/listings\\\/ecole-alpine-internationale-prefleuri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ecole Alpine Internationale &#8212; Pr\u00e9fleuri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ecole Alpine Internationale - Pr\u00e9fleuri - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/ru\/listings\/ecole-alpine-internationale-prefleuri\/","og_locale":"ru_RU","og_type":"article","og_title":"Ecole Alpine Internationale - Pr\u00e9fleuri","og_description":"Die Internationale Alpenschule Pr\u00e9fleuri befindet sich in den Schweizer Alpen auf einer H\u00f6he von 1200 Metern \u00fcber dem Meeresspiegel in der N\u00e4he des bekannten Skigebiets Villars-sur-Ollon. Pr\u00e9fleuri befindet sich in einer au\u00dfergew\u00f6hnlichen Umgebung und bietet eine herrliche Aussicht. Die Schule liegt auf 2 Hektar Land, umgeben von W\u00e4ldern und Wiesen, auf denen noch immer Eichh\u00f6rnchen, [&hellip;]","og_url":"https:\/\/schoolaboo.com\/ru\/listings\/ecole-alpine-internationale-prefleuri\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2021-06-18T12:33:52+00:00","og_image":[{"url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/07\/carousel_chalet01.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/07\/carousel_chalet01.jpg","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"2 \u043c\u0438\u043d\u0443\u0442\u044b"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/ru\/listings\/ecole-alpine-internationale-prefleuri\/","url":"https:\/\/schoolaboo.com\/ru\/listings\/ecole-alpine-internationale-prefleuri\/","name":"Ecole Alpine Internationale - Pr\u00e9fleuri - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/ru\/#website"},"datePublished":"2020-09-09T20:53:52+00:00","dateModified":"2021-06-18T12:33:52+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/ru\/listings\/ecole-alpine-internationale-prefleuri\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/ru\/listings\/ecole-alpine-internationale-prefleuri\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/ru\/listings\/ecole-alpine-internationale-prefleuri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/ru\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/ru\/angebote\/"},{"@type":"ListItem","position":3,"name":"Ecole Alpine Internationale &#8212; Pr\u00e9fleuri"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/ru\/#website","url":"https:\/\/schoolaboo.com\/ru\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/ru\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings\/19913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/comments?post=19913"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/media?parent=19913"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job_listing_region?post=19913"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-categories?post=19913"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/ru\/wp-json\/wp\/v2\/job-types?post=19913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}