{"id":29310,"date":"2022-02-04T13:10:39","date_gmt":"2022-02-04T12:10:39","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=29310"},"modified":"2026-04-26T08:39:09","modified_gmt":"2026-04-26T06:39:09","slug":"rudolf-steiner-schule-zuerich-oberland","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/it\/listings\/rudolf-steiner-schule-zuerich-oberland\/","title":{"rendered":"Rudolf Steiner Schule Z\u00fcrich Oberland"},"content":{"rendered":"<p><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-29311 size-full\" src=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2022\/02\/Rudolf-Steiner-Schule-Zuerich-Oberland-Logo.png\" alt=\"\" width=\"363\" height=\"139\" \/><\/span><\/p>\n<h3>Wer wir sind<\/h3>\n<p>Wir sind eine politisch und konfessionell neutrale Gesamtschule in privater Tr\u00e4gerschaft. 300 Kinder, 200 Familien, 34 Lehrpersonen und weitere Mitarbeitende, alles Menschen, die versuchen, vieles zu reflektieren und bewusst zu handeln, bzw. Kinder und Jugendliche, die zu innerer Freiheit erzogen und gebildet werden wollen. Menschen, die das Unm\u00f6gliche m\u00f6glich zu machen versuchen, die Schule als Lern- und Begegnungsort f\u00fchren und weiterentwickeln und damit in die Zukunft wirken wollen. Wir sind ein soziales Lernfeld \u2013 nicht nur f\u00fcr die Kinder und Jugendlichen.<\/p>\n<h3>Wir nehmen die Individualit\u00e4t des Kindes ernst<\/h3>\n<p>In jedem Kind offenbart sich ein individuelles Wesen, das sich leiblich, seelisch und geistig-spirituell zum Ausdruck bringen will. Es tr\u00e4gt sein Lebensziel in sich selbst und weiss \u2013 allerdings zun\u00e4chst noch unbewusst \u2013 was es f\u00fcr seinen Lebensweg bedarf.<\/p>\n<p>Der altersgerechte Unterricht orientiert sich an der Entwicklung des Kindes. Er erm\u00f6glicht es ihm, seine individuellen Anlagen zu entfalten, freudig zu lernen und eine Pers\u00f6nlichkeit heranzubilden, die Standhaftigkeit und Beweglichkeit verbindet.<\/p>\n<p>Hier geht es zu einer virtuellen Tour:\u00a0<a href=\"http:\/\/vtour.rsszo.ch\/vtour.html\" target=\"_blank\" rel=\"noopener\">http:\/\/vtour.rsszo.ch\/vtour.html<\/a><\/p>\n<div class=\"jetpack-video-wrapper\"><iframe loading=\"lazy\" title=\"Rudolf Steiner Schule Z\u00fcrcher Oberland\" width=\"1050\" height=\"591\" src=\"https:\/\/www.youtube.com\/embed\/v_mE21xyIRg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n","protected":false},"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Usterstrasse 1 8620 Wetzikon","_company_website":"https:\/\/rsszo.ch","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":1,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[153],"job-categories":[103,99,76,115],"job-types":[90,5,92],"class_list":{"0":"post-29310","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-zuerich","6":"job_listing_category-kindergarten","7":"job_listing_category-primarschule","8":"job_listing_category-sekundarstufe_1","9":"job_listing_category-tagesschule","10":"job_listing_type-kindergarten","11":"job_listing_type-primarschule","12":"job_listing_type-sekundarstufe_1","14":"job-type-kindergarten-4-6-jahre","15":"job-type-primarschule-7-12jahre","16":"job-type-sekundarstufe-1-13-16-jahre","17":"job_position_featured"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rudolf Steiner Schule Z\u00fcrich Oberland - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"description\" content=\"ganzheitliche, auf die individuellen Bed\u00fcrfnisse des Kindes ausgerichtete Schule. Kindergarten Primarschule und Sekundarschule Tagesschule\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/it\/listings\/rudolf-steiner-schule-zuerich-oberland\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rudolf Steiner Schule Z\u00fcrich Oberland\" \/>\n<meta property=\"og:description\" content=\"ganzheitliche, auf die individuellen Bed\u00fcrfnisse des Kindes ausgerichtete Schule. Kindergarten Primarschule und Sekundarschule Tagesschule\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/it\/listings\/rudolf-steiner-schule-zuerich-oberland\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-26T06:39:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2022\/02\/steiner_schule_zh_oberland.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2022\/02\/steiner_schule_zh_oberland.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/rudolf-steiner-schule-zuerich-oberland\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/rudolf-steiner-schule-zuerich-oberland\\\/\",\"name\":\"Rudolf Steiner Schule Z\u00fcrich Oberland - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/rudolf-steiner-schule-zuerich-oberland\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/rudolf-steiner-schule-zuerich-oberland\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Rudolf-Steiner-Schule-Zuerich-Oberland-Logo.png\",\"datePublished\":\"2022-02-04T12:10:39+00:00\",\"dateModified\":\"2026-04-26T06:39:09+00:00\",\"description\":\"ganzheitliche, auf die individuellen Bed\u00fcrfnisse des Kindes ausgerichtete Schule. Kindergarten Primarschule und Sekundarschule Tagesschule\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/rudolf-steiner-schule-zuerich-oberland\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/rudolf-steiner-schule-zuerich-oberland\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/rudolf-steiner-schule-zuerich-oberland\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Rudolf-Steiner-Schule-Zuerich-Oberland-Logo.png\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Rudolf-Steiner-Schule-Zuerich-Oberland-Logo.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/rudolf-steiner-schule-zuerich-oberland\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rudolf Steiner Schule Z\u00fcrich Oberland\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rudolf Steiner Schule Z\u00fcrich Oberland - Privatschul Verzeichnis und Beratung","description":"ganzheitliche, auf die individuellen Bed\u00fcrfnisse des Kindes ausgerichtete Schule. Kindergarten Primarschule und Sekundarschule Tagesschule","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/it\/listings\/rudolf-steiner-schule-zuerich-oberland\/","og_locale":"it_IT","og_type":"article","og_title":"Rudolf Steiner Schule Z\u00fcrich Oberland","og_description":"ganzheitliche, auf die individuellen Bed\u00fcrfnisse des Kindes ausgerichtete Schule. Kindergarten Primarschule und Sekundarschule Tagesschule","og_url":"https:\/\/schoolaboo.com\/it\/listings\/rudolf-steiner-schule-zuerich-oberland\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2026-04-26T06:39:09+00:00","og_image":[{"url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2022\/02\/steiner_schule_zh_oberland.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2022\/02\/steiner_schule_zh_oberland.jpg","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/it\/listings\/rudolf-steiner-schule-zuerich-oberland\/","url":"https:\/\/schoolaboo.com\/it\/listings\/rudolf-steiner-schule-zuerich-oberland\/","name":"Rudolf Steiner Schule Z\u00fcrich Oberland - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoolaboo.com\/it\/listings\/rudolf-steiner-schule-zuerich-oberland\/#primaryimage"},"image":{"@id":"https:\/\/schoolaboo.com\/it\/listings\/rudolf-steiner-schule-zuerich-oberland\/#primaryimage"},"thumbnailUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2022\/02\/Rudolf-Steiner-Schule-Zuerich-Oberland-Logo.png","datePublished":"2022-02-04T12:10:39+00:00","dateModified":"2026-04-26T06:39:09+00:00","description":"ganzheitliche, auf die individuellen Bed\u00fcrfnisse des Kindes ausgerichtete Schule. Kindergarten Primarschule und Sekundarschule Tagesschule","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/it\/listings\/rudolf-steiner-schule-zuerich-oberland\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/it\/listings\/rudolf-steiner-schule-zuerich-oberland\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/schoolaboo.com\/it\/listings\/rudolf-steiner-schule-zuerich-oberland\/#primaryimage","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2022\/02\/Rudolf-Steiner-Schule-Zuerich-Oberland-Logo.png","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2022\/02\/Rudolf-Steiner-Schule-Zuerich-Oberland-Logo.png"},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/it\/listings\/rudolf-steiner-schule-zuerich-oberland\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/it\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/it\/angebote\/"},{"@type":"ListItem","position":3,"name":"Rudolf Steiner Schule Z\u00fcrich Oberland"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/it\/#website","url":"https:\/\/schoolaboo.com\/it\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/it\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/schoolaboo.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-listings\/29310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/comments?post=29310"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/media?parent=29310"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job_listing_region?post=29310"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-categories?post=29310"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-types?post=29310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}