{"id":26012,"date":"2021-02-10T18:27:43","date_gmt":"2021-02-10T17:27:43","guid":{"rendered":"https:\/\/schoolaboo.ch\/listings\/liceo-immensee\/"},"modified":"2021-08-09T13:00:45","modified_gmt":"2021-08-09T11:00:45","slug":"liceo-immensee","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/it\/listings\/liceo-immensee\/","title":{"rendered":"Liceo Immensee"},"content":{"rendered":"<h1>Liceo Immensee<\/h1>\n<h2>Scuola di maturit\u00e0 con mandato di servizio pubblico<\/h2>\n<p>&nbsp;<\/p>\n<p>Il liceo Immensee con <strong>giorno di scuola<\/strong> e <strong>internat<\/strong> \u00e8 riconosciuto da molti anni per la sua cura di alta qualit\u00e0 e il suo concetto educativo innovativo. Accompagniamo i nostri studenti con attenzione e attenzione nel loro cammino verso una<strong> maturit\u00e0<\/strong> di successo e quindi allo studio delle <strong>capacit\u00e0 in tutte le aree disciplinari<\/strong>. Inoltre, li supportiamo nel trovare risposte alle loro domande esistenziali.<\/p>\n<p>Chiunque sia andato a scuola al liceo Immensee ha imparato a condurre<strong> una vita autodeterminata e orientata al futuro<\/strong> nell&#8217;era digitale. L&#8217;Immenseer Matura apre le porte allo studio in tutte le universit\u00e0 e college svizzeri e internazionali.<\/p>\n<p>Sebbene sia una scuola relativamente piccola e quindi familiare, la scuola di grammatica Immensee ha una vasta gamma e forme di apprendimento di successo, combinate con <strong>strutture chiare<\/strong>:<\/p>\n<ul>\n<li>7 soggetti principali, 13 soggetti supplementari, offerte latine<\/li>\n<li>Lezioni bilingue (&#8220;immersione&#8221;)<\/li>\n<li>Supporto completo, supporto competente<\/li>\n<li>Strutture chiare che forniscono supporto e allo stesso tempo sono aperte allo sviluppo personale individuale<\/li>\n<li>Chiedere e sostenere l&#8217;apprendimento auto-organizzato (SOL) e quindi una preparazione ottimale per gli studi<\/li>\n<li>Eccellente supporto individuale e un ambiente personale<\/li>\n<li>Una comunit\u00e0 che si sostiene a vicenda<\/li>\n<\/ul>\n<p>Chunnsch au ins Gymi?<\/p>\n<div class=\"jetpack-video-wrapper\"><iframe loading=\"lazy\" title=\"Chunsch au is Gymi Matura\" width=\"1050\" height=\"591\" src=\"https:\/\/www.youtube.com\/embed\/DN9SPH_awSo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Bethlehemweg 12, 6405 Immensee","_company_website":"https:\/\/www.gymnasium-immensee.ch\/","_company_tagline":"Privates Gymnasium","_company_twitter":"","_filled":0,"_featured":1,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[388],"job-categories":[537,570,542,566,571,538,530,535],"job-types":[533,531,532],"class_list":{"0":"post-26012","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-svitto","6":"job_listing_category-collegio","7":"job_listing_category-corsi-di-recupero","8":"job_listing_category-insegnamento-plurilingue","9":"job_listing_category-liceo","10":"job_listing_category-maturita-svizzera","11":"job_listing_category-scuola-diurna","12":"job_listing_category-scuola-media-13-15","13":"job_listing_category-scuola-media-superiore-16-19","14":"job_listing_type-collegio","15":"job_listing_type-scuola-media-13-15","16":"job_listing_type-scuola-media-superiore-16-19","18":"job-type-collegio","19":"job-type-scuola-media-13-15","20":"job-type-scuola-media-superiore-16-19","21":"job_position_featured"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Liceo Immensee - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"description\" content=\"Il liceo Immensee con scuola materna e collegio \u00e8 riconosciuto da molti anni per la sua cura di alta qualit\u00e0 e il suo concetto educativo innovativo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/it\/listings\/liceo-immensee\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liceo Immensee\" \/>\n<meta property=\"og:description\" content=\"Il liceo Immensee con scuola materna e collegio \u00e8 riconosciuto da molti anni per la sua cura di alta qualit\u00e0 e il suo concetto educativo innovativo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/it\/listings\/liceo-immensee\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-09T11:00:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2015\/10\/1280px-Gymnasium_Immensee.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2015\/10\/1280px-Gymnasium_Immensee.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/liceo-immensee\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/liceo-immensee\\\/\",\"name\":\"Liceo Immensee - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#website\"},\"datePublished\":\"2021-02-10T17:27:43+00:00\",\"dateModified\":\"2021-08-09T11:00:45+00:00\",\"description\":\"Il liceo Immensee con scuola materna e collegio \u00e8 riconosciuto da molti anni per la sua cura di alta qualit\u00e0 e il suo concetto educativo innovativo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/liceo-immensee\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/liceo-immensee\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/liceo-immensee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Liceo Immensee\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Liceo Immensee - Privatschul Verzeichnis und Beratung","description":"Il liceo Immensee con scuola materna e collegio \u00e8 riconosciuto da molti anni per la sua cura di alta qualit\u00e0 e il suo concetto educativo innovativo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/it\/listings\/liceo-immensee\/","og_locale":"it_IT","og_type":"article","og_title":"Liceo Immensee","og_description":"Il liceo Immensee con scuola materna e collegio \u00e8 riconosciuto da molti anni per la sua cura di alta qualit\u00e0 e il suo concetto educativo innovativo.","og_url":"https:\/\/schoolaboo.com\/it\/listings\/liceo-immensee\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2021-08-09T11:00:45+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2015\/10\/1280px-Gymnasium_Immensee.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2015\/10\/1280px-Gymnasium_Immensee.jpg","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/it\/listings\/liceo-immensee\/","url":"https:\/\/schoolaboo.com\/it\/listings\/liceo-immensee\/","name":"Liceo Immensee - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/it\/#website"},"datePublished":"2021-02-10T17:27:43+00:00","dateModified":"2021-08-09T11:00:45+00:00","description":"Il liceo Immensee con scuola materna e collegio \u00e8 riconosciuto da molti anni per la sua cura di alta qualit\u00e0 e il suo concetto educativo innovativo.","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/it\/listings\/liceo-immensee\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/it\/listings\/liceo-immensee\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/it\/listings\/liceo-immensee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/it\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/it\/angebote\/"},{"@type":"ListItem","position":3,"name":"Liceo Immensee"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/it\/#website","url":"https:\/\/schoolaboo.com\/it\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/it\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/schoolaboo.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-listings\/26012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/comments?post=26012"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/media?parent=26012"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job_listing_region?post=26012"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-categories?post=26012"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-types?post=26012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}