{"id":23482,"date":"2020-12-14T17:33:11","date_gmt":"2020-12-14T16:33:11","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=23482"},"modified":"2021-08-03T11:52:38","modified_gmt":"2021-08-03T09:52:38","slug":"zauberfloete-kita-kiga","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/it\/listings\/zauberfloete-kita-kiga\/","title":{"rendered":"Zauberfl\u00f6te, KiTa &#038; KiGa"},"content":{"rendered":"","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Zugerstrasse 5 8805 Richterswil","_company_website":"https:\/\/schoolaboo.com","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[153],"job-categories":[103,229],"job-types":[90,230],"class_list":{"0":"post-23482","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-zuerich","6":"job_listing_category-kindergarten","7":"job_listing_category-vorkindergarten","8":"job_listing_type-kindergarten","9":"job_listing_type-vorkindergarten","11":"job-type-kindergarten-4-6-jahre","12":"job-type-vorkindergarten"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Zauberfl\u00f6te, KiTa &amp; KiGa - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"description\" content=\"Die Kita und Kiga Zauberfl\u00f6te in der n\u00e4he von Pf\u00e4ffikon bietet aufenthalt f\u00fcr Kinder im altervon 4-6 Jahren - Mehr Infos auf schoolaboo.com\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/it\/listings\/zauberfloete-kita-kiga\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zauberfl\u00f6te, KiTa &amp; KiGa\" \/>\n<meta property=\"og:description\" content=\"Die Kita und Kiga Zauberfl\u00f6te in der n\u00e4he von Pf\u00e4ffikon bietet aufenthalt f\u00fcr Kinder im altervon 4-6 Jahren - Mehr Infos auf schoolaboo.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/it\/listings\/zauberfloete-kita-kiga\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-03T09:52:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/kz-new-logo.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/kz-new-logo.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/zauberfloete-kita-kiga\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/zauberfloete-kita-kiga\\\/\",\"name\":\"Zauberfl\u00f6te, KiTa & KiGa - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#website\"},\"datePublished\":\"2020-12-14T16:33:11+00:00\",\"dateModified\":\"2021-08-03T09:52:38+00:00\",\"description\":\"Die Kita und Kiga Zauberfl\u00f6te in der n\u00e4he von Pf\u00e4ffikon bietet aufenthalt f\u00fcr Kinder im altervon 4-6 Jahren - Mehr Infos auf schoolaboo.com\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/zauberfloete-kita-kiga\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/zauberfloete-kita-kiga\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/zauberfloete-kita-kiga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zauberfl\u00f6te, KiTa &#038; KiGa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Zauberfl\u00f6te, KiTa & KiGa - Privatschul Verzeichnis und Beratung","description":"Die Kita und Kiga Zauberfl\u00f6te in der n\u00e4he von Pf\u00e4ffikon bietet aufenthalt f\u00fcr Kinder im altervon 4-6 Jahren - Mehr Infos auf schoolaboo.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/it\/listings\/zauberfloete-kita-kiga\/","og_locale":"it_IT","og_type":"article","og_title":"Zauberfl\u00f6te, KiTa & KiGa","og_description":"Die Kita und Kiga Zauberfl\u00f6te in der n\u00e4he von Pf\u00e4ffikon bietet aufenthalt f\u00fcr Kinder im altervon 4-6 Jahren - Mehr Infos auf schoolaboo.com","og_url":"https:\/\/schoolaboo.com\/it\/listings\/zauberfloete-kita-kiga\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2021-08-03T09:52:38+00:00","og_image":[{"url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/kz-new-logo.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/kz-new-logo.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/it\/listings\/zauberfloete-kita-kiga\/","url":"https:\/\/schoolaboo.com\/it\/listings\/zauberfloete-kita-kiga\/","name":"Zauberfl\u00f6te, KiTa & KiGa - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/it\/#website"},"datePublished":"2020-12-14T16:33:11+00:00","dateModified":"2021-08-03T09:52:38+00:00","description":"Die Kita und Kiga Zauberfl\u00f6te in der n\u00e4he von Pf\u00e4ffikon bietet aufenthalt f\u00fcr Kinder im altervon 4-6 Jahren - Mehr Infos auf schoolaboo.com","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/it\/listings\/zauberfloete-kita-kiga\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/it\/listings\/zauberfloete-kita-kiga\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/it\/listings\/zauberfloete-kita-kiga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/it\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/it\/angebote\/"},{"@type":"ListItem","position":3,"name":"Zauberfl\u00f6te, KiTa &#038; KiGa"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/it\/#website","url":"https:\/\/schoolaboo.com\/it\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/it\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/schoolaboo.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-listings\/23482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/comments?post=23482"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/media?parent=23482"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job_listing_region?post=23482"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-categories?post=23482"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-types?post=23482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}