{"id":21913,"date":"2020-11-01T14:14:34","date_gmt":"2020-11-01T13:14:34","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=21913"},"modified":"2020-11-02T17:14:21","modified_gmt":"2020-11-02T16:14:21","slug":"sco-schuelerin-co-gmbh","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/it\/listings\/sco-schuelerin-co-gmbh\/","title":{"rendered":"S&#038;CO. (Sch\u00fclerIn &#038; Co. GmbH)"},"content":{"rendered":"<p>Suchen Sie eine Schule, an der sich Ihr Kind ernst genommen f\u00fchlt und erfolgreich lernen kann? N\u00e4hrboden daf\u00fcr ist eine wertsch\u00e4tzende sowie aufrichtige Beziehung zwischen allen Beteiligten. Um diese aufzubauen, pflegen wir den regelm\u00e4ssigen\u00a0Dialog zwischen dem Kind, den Lehrpersonen und den Eltern.<\/p>\n<p>Bei uns lernt Ihr Kind, sich entschlossen und mit Hingabe f\u00fcr eine Idee einzusetzen.\u00a0Entscheidend dabei ist, den individuell abgestimmten und vereinbarten Zielen im\u00a0Schulalltag verbindlich und konsequent nachzugehen \u2013 auch in schwierigen Momenten.\u00a0Wir begleiten und unterst\u00fctzen Ihr Kind systematisch in seinen Wachstumsprozessen,\u00a0arbeiten an der Selbstmotivation, dr\u00fccken Wertsch\u00e4tzung aus und loben\u00a0gute Leistungen. Zudem sprechen wir Unzul\u00e4nglichkeiten klar an, damit Ihr Kind die\u00a0Chance packen kann, sich zu verbessern.<\/p>\n<p>Wir wollen, dass sich Ihr Kind bei uns wohl und sicher f\u00fchlt. Es\u00a0soll Vertrauen zu Menschen aufbauen und\u00a0Beziehungen pflegen. So st\u00e4rkt sich das Selbstbewusstsein wie auch Selbstwertgef\u00fchl Ihres Kindes und w\u00e4chst\u00a0nachhaltig.\u00a0Erstklassige Lehrpersonen und eine exzellente Unterrichtsqualit\u00e4t sind f\u00fcr uns\u00a0selbstverst\u00e4ndlich. Interne und externe Evaluationen und der f\u00f6rderliche Kontakt zu\u00a0p\u00e4dagogisch wichtigen Institutionen geben uns und Ihnen die Garantie, dass wir uns\u00a0stets weiterentwickeln, um den sich schnell \u00e4ndernden Anforderungen unserer Gesellschaft gerecht zu werden.<\/p>\n<p>&nbsp;<\/p>\n<table class=\"wsite-multicol-table\">\n<tbody class=\"wsite-multicol-tbody\">\n<tr class=\"wsite-multicol-tr\">\n<td class=\"wsite-multicol-col\"><\/td>\n<td class=\"wsite-multicol-col\">\n<h2 class=\"wsite-content-title\">Wie wir den Schulalltag gestalten<\/h2>\n<div class=\"paragraph\">Besonders wichtig ist uns eine friedliche,\u00a0 respektvolle sowie famili\u00e4re Schulgemeinschaft.\u00a0 Zentrales Element hierf\u00fcr ist die Mitwirkung und Mitbestimmung aller Schulbeteiligten.\u00a0Der Schulalltag folgt einer klaren Tages-\/Wochenstruktur. Leitplanke ist dabei unser Motto<span style=\"color: #515151;\">\u00a0\u00abStark durch Pakt\u00bb<\/span>\u00a0\u2013 hier handelt es sich um 10 Grundregeln, welche einen wertsch\u00e4tzenden Umgang sowie ein gutes Zusammenleben unterst\u00fctzen. Diese Vereinbarungen sind sowohl f\u00fcr die Sch\u00fclerinnen und Sch\u00fcler als auch f\u00fcr das gesamte Schulteam verbindlich.<\/div>\n<div>\n<div><\/div>\n<p><span class=\"wsite-button-inner\">ZUM SCHULALLTAG<\/span><\/p>\n<div><\/div>\n<\/div>\n<\/td>\n<td class=\"wsite-multicol-col\">\n<h2 class=\"wsite-content-title\">Lebendige Schulkultur<\/h2>\n<div class=\"paragraph\">Die S&amp;CO. ist mehr als eine Schule \u2013 n\u00e4mlich ein Ort zum Wohlf\u00fchlen, Zusammensein, Entdecken, Ausprobieren, Erleben, Gl\u00fccklichsein und Verweilen. Dem ganzheitlichen Lernen geben wir einen ganz besonderen Stellenwert: Dies bedeutet, als Mensch mit nat\u00fcrlichem Bewegungsdrang, individuellen Interessen, vielf\u00e4ltigen Sinnen und Gef\u00fchlen ernst genommen und gef\u00f6rdert zu werden. Damit wir dem gerecht werden k\u00f6nnen, sind unsere Exkursionen, Kreativ-Workshops, sportliche Aktivit\u00e4ten, Proben und Konzerte mit der Sch\u00fclerband etc. fester Bestandteil unseres Schulprogramms.<\/div>\n<div><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<div>\n<div><\/div>\n<div>\n<h2 class=\"wsite-content-title\">Primarstufe 3. bis 6. Klasse<\/h2>\n<div class=\"paragraph\">Jedes Kind hat unterschiedlich ausgepr\u00e4gte F\u00e4higkeiten, Begabungen und Interessen. Diese zu erkennen geh\u00f6rt zu unseren wichtigsten Aufgaben. Im\u00a0<strong>altersdurchmischten Lernen<\/strong>\u00a0<strong>begleiten\u00a0<\/strong>wir unsere J\u00fcngsten\u00a0<strong>sorgf\u00e4ltig und\u00a0<\/strong><strong>individuell<\/strong>,\u00a0<strong>trainieren<\/strong>\u00a0mit ihnen die\u00a0<strong>Grundfertigkeiten<\/strong>,\u00a0<strong>arbeiten allf\u00e4llige L\u00fccken auf\u00a0<\/strong>und\u00a0<strong>f\u00f6rdern gezielt\u00a0<\/strong>ihre\u00a0<strong>St\u00e4rken<\/strong>, damit der \u00dcbertritt in die Sekundarstufe oder ans Gymnasium wunschgem\u00e4ss gelingt. Zudem setzen wird uns daf\u00fcr ein, dass die Kinder in unserem Haus\u00a0<strong>eine gl\u00fcckliche und unbeschwerte Schulzeit erleben<\/strong><strong>\u00a0d\u00fcrfen\u00a0<\/strong>sowie mit Freude, Begeisterung und Engagement an ihren Zielen arbeiten k\u00f6nnen.<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div>\n<h2 class=\"wsite-content-title\">Sekundarstufe I \u200bNiveaus A, B und C<\/h2>\n<div class=\"paragraph\">Im\u00a0<strong>jahrgangs\u00fcbergreifenden Unterricht<\/strong>\u00a0unserer Sekundarstufe werden die Jugendlichen mittels individualisierten Lehrpl\u00e4nen auf das Berufsleben oder den \u00dcbertritt an weiterf\u00fchrende Schulen vorbereitet. Dabei steht der\u00a0<strong>gezielte Aufbau der personalen\u00a0<\/strong>(z.B. Selbst\u00e4ndigkeit),\u00a0<strong>sozialen<\/strong>\u00a0(z.B. Konfliktf\u00e4higkeit),\u00a0<strong>methodischen<\/strong>\u00a0(z.B. Lerntechniken) sowie\u00a0<strong>fachlichen Kompetenzen<\/strong>\u00a0im Zentrum. Ein eng begleitetes\u00a0<strong>Coaching der Jugendlichen\u00a0<\/strong>durch unsere erfahrenen Lehrpersonen sowie unser\u00a0<strong>Berufsfindungsprogramm<\/strong>\u00a0(u.a. Stellwerktest, Berufswahlpraktika) unterst\u00fctzen dieses Vorhaben. Niveauwechsel sind semesterweise m\u00f6glich.<\/div>\n<div><\/div>\n<div>\n<h2 class=\"wsite-content-title\">10. Schuljahr\/\u200bFokusjahr<\/h2>\n<div class=\"paragraph\">Noch keine Lehrstelle? Die Aufnahme in die Fachmittelschule nicht geschafft? Im 10. Schuljahr\/Fokusjahr bieten wir den jungen Erwachsenen ein\u00a0<strong>massgeschneidertes Programm<\/strong>\u00a0an, welches vollumf\u00e4nglich auf deren Bed\u00fcrfnisse und Zielsetzungen ausgerichtet ist. Mit diesem\u00a0zus\u00e4tzlichen Jahr er\u00f6ffnet sich f\u00fcr die Jugendlichen die Chance, mehr Zeit f\u00fcr den Berufswahlentscheid zu erhalten, pers\u00f6nlichen Interessen nachzugehen, Lerninhalte zu vertiefen, Wissensl\u00fccken zu schliessen und den\u00a0Schulstoff zu festigen. So k\u00f6nnen Basistests, Eignungstests oder Aufnahmepr\u00fcfungen erfolgreich abgeschlossen werden.<\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<div>\n<div class=\"wsite-multicol\">\n<div class=\"wsite-multicol-table-wrap\"><\/div>\n<\/div>\n<\/div>\n<div>\n<h2 class=\"wsite-content-title\">Sport &amp; Musik &amp; Gestalten<\/h2>\n<div class=\"paragraph\"><strong>Ganzheitliches Lernen\u00a0<\/strong>hat an unserer Schule einen hohen Stellenwert und bedeutet f\u00fcr uns, als Mensch mit nat\u00fcrlichem Bewegungsdrang, individuellen Interessen, vielf\u00e4ltigen Sinnen und Gef\u00fchlen ernst genommen und gef\u00f6rdert zu werden. Im Rahmen unserer\u00a0<strong>Sportprogramme, Sch\u00fclerbands und Kreativ-Workshops<\/strong>\u00a0entdecken und entfalten die Lernenden ihre Talente. Sportliche, musikalische und gestalterische T\u00e4tigkeiten wirken sich \u00e4usserst positiv auf Kreativit\u00e4t, Konzentration, Wille und Selbstbewusstsein aus \u2013 alles F\u00e4higkeiten, die auch in anderen F\u00e4chern (z.B. Mathematik) oder Lebenssituationen gefragt sind.<\/div>\n<div><\/div>\n<\/div>\n<div>\n<h2 class=\"wsite-content-title\">Umfassendes Betreuungsangebot<\/h2>\n<div class=\"paragraph\">\n<p>Als\u00a0<strong>Privatschule\/<\/strong><strong>Tagesschule\u00a0<\/strong><strong>mit \u00fcber 40 Jahren Erfahrung<\/strong>\u00a0in diesem Bereich sind wir eine ideale L\u00f6sung f\u00fcr Kinder und Jugendliche von berufst\u00e4tigen Eltern. Wir bieten folgende Betreuungselemente an:<\/p>\n<ul>\n<li><strong>Begleitetes Fr\u00fch- und Sp\u00e4tstudium\u00a0<\/strong>(kann f\u00fcr das L\u00f6sen von Hausaufgaben genutzt werden)<\/li>\n<li><strong>Gemeinsamer Mittagstisch<\/strong>\u00a0mit einem t\u00e4glich frisch zubereiteten Men\u00fc<\/li>\n<li><strong>Individuelle Beratungs- und F\u00f6rdergespr\u00e4che<\/strong><br \/>\n<h2 class=\"wsite-content-title\"><\/h2>\n<h2 class=\"wsite-content-title\">Lehrplan 21<\/h2>\n<div class=\"paragraph\">Die F\u00e4cher und Fachinhalte entsprechen den\u00a0Lehrpl\u00e4nen des Kantons Luzern. Damit gew\u00e4hrleisten\u00a0wir die Kompatibilit\u00e4t zu den \u00f6ffentlichen Schulen.<\/div>\n<\/li>\n<\/ul>\n<h2 class=\"wsite-content-title\">Individuelle Lernbegleitung<\/h2>\n<div class=\"paragraph\">Alle Sch\u00fclerinnen und Sch\u00fcler arbeiten mit einem\u00a0<strong>individuellen, auf ihr Lern- und Entwicklungsniveau abgestimmten Lehrplan<\/strong>. Zu Schuljahresbeginn werden im Rahmen eines Gespr\u00e4chs zwischen den Beteiligten (Sch\u00fcler\/-in, Eltern, Lehrperson)\u00a0<strong>Zielvereinbarungen\u00a0<\/strong>vorgenommen. Bei Bedarf wird eine Lernstanderfassungen durchgef\u00fchrt. Wichtig ist, dass die vereinbarten\u00a0<strong>individuellen Lernziele<\/strong>\u00a0<strong>auf die Leistungsf\u00e4higkeit<\/strong>\u00a0der einzelnen Kinder beziehungsweise Jugendlichen\u00a0<strong>abgestimmt<\/strong>\u00a0sind. Die Lernziele sollen erreichbar sein und gleichzeitig eine echte Herausforderung darstellen. Darauf aufbauend erstellen die Lehrpersonen eine\u00a0<strong>F\u00f6rderplanung\u00a0<\/strong>und organisieren entsprechende\u00a0<strong>Lehr- und Lernarrangements<\/strong>. In regelm\u00e4ssig stattfinden\u00a0<strong>F\u00f6rder- und Beratungsgespr\u00e4chen<\/strong>\u00a0mit der Sch\u00fcler\/-innen werden die Lernfortschritte besprochen und gegebenenfalls neue Ziele gesetzt.<\/div>\n<div><\/div>\n<\/div>\n<div>\n<h2 class=\"wsite-content-title\">Elternkontakt und -information<\/h2>\n<div class=\"paragraph\">\n<p>Das Wohl unserer Sch\u00fclerinnen und Sch\u00fcler steht im Zentrum unserer p\u00e4dagogischen Arbeit. Dabei spielt die Kommunikation, der Kontakt und die Beziehung zwischen den Beteiligten eine entscheidende Rolle. In diesem Sinne sind wir bestrebt, die Eltern jeweils umgehend und transparent zu informieren: Unsere \u00ab<strong>360\u00b0-Kommunikation\u00bb<\/strong>\u00a0(Elternabende, Elternrundtische, Elterngespr\u00e4che, Lernjournal, Zwischenberichte, Schulanl\u00e4sse, Telefon, E-Mail) bietet eine ideale Basis f\u00fcr einen bestm\u00f6glichen Informationsaustausch. Diese vielf\u00e4ltigen Angebote tragen dazu bei, dass die Eltern stets mit uns im Gespr\u00e4ch bleiben k\u00f6nnen.<\/p>\n<p>Die Kinder und Jugendlichen erhalten im\u00a0<strong>9-Wochen-Rhythmus<\/strong>\u00a0einen\u00a0<strong>Zwischenbericht<\/strong>, welcher ihren aktuellen fachlichen sowie \u00fcberfachlichen Leistungsstand aufzeigt. Dieser wird auch den Eltern zugestellt.<\/p>\n<\/div>\n<div>\n<h2 class=\"wsite-content-title\">Aktivit\u00e4ten und Anl\u00e4sse<\/h2>\n<div class=\"paragraph\">\n<p>In unserer Jahresagenda fest eingerichtete Treffpunkte und Aktivit\u00e4ten:<\/p>\n<ul>\n<li>Elternabende<\/li>\n<li>Elternrundtische<\/li>\n<li><span style=\"color: #3f3f3f;\">Exkursionen<\/span><\/li>\n<li>Herbstwanderung<\/li>\n<li><span style=\"color: #3f3f3f;\">Sportanl\u00e4sse<\/span><\/li>\n<li><span style=\"color: #3f3f3f;\">Kreativ-Workshops<\/span><\/li>\n<li><span style=\"color: #3f3f3f;\">Adventsanl\u00e4sse<\/span><\/li>\n<li><span style=\"color: #3f3f3f;\">Samichlaus<\/span><\/li>\n<li><span style=\"color: #3f3f3f;\">Weinachtsessen<\/span><\/li>\n<li><span style=\"color: #3f3f3f;\">Sch\u00fcler\/-innen kochen f\u00fcr Sch\u00fcler\/-innen<\/span><\/li>\n<li><span style=\"color: #3f3f3f;\">Schneetag<\/span><\/li>\n<li><span style=\"color: #3f3f3f;\">Tage der offenen T\u00fcren<\/span><\/li>\n<li>Werkausstellung<\/li>\n<li>Sommerfest mit Sch\u00fclerband-Konzert<\/li>\n<li>Projektpr\u00e4sentationen<\/li>\n<li>Abschlussfeier der 3. Sek.<\/li>\n<li>Abschlussreise der 3. Sek.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Schachenstrasse 11, 6030 Ebikon, Schweiz","_company_website":"https:\/\/s-co.ch\/index.html","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[162],"job-categories":[141,76],"job-types":[5,92],"class_list":{"0":"post-21913","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-luzern","6":"job_listing_category-brueckenangebot","7":"job_listing_category-sekundarstufe_1","8":"job_listing_type-primarschule","9":"job_listing_type-sekundarstufe_1","11":"job-type-primarschule-7-12jahre","12":"job-type-sekundarstufe-1-13-16-jahre"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>S&amp;CO. (Sch\u00fclerIn &amp; Co. GmbH) - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/it\/listings\/sco-schuelerin-co-gmbh\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S&amp;CO. (Sch\u00fclerIn &amp; Co. GmbH)\" \/>\n<meta property=\"og:description\" content=\"Suchen Sie eine Schule, an der sich Ihr Kind ernst genommen f\u00fchlt und erfolgreich lernen kann? N\u00e4hrboden daf\u00fcr ist eine wertsch\u00e4tzende sowie aufrichtige Beziehung zwischen allen Beteiligten. Um diese aufzubauen, pflegen wir den regelm\u00e4ssigen\u00a0Dialog zwischen dem Kind, den Lehrpersonen und den Eltern. Bei uns lernt Ihr Kind, sich entschlossen und mit Hingabe f\u00fcr eine Idee [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/it\/listings\/sco-schuelerin-co-gmbh\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-02T16:14:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/s-co-logo-mit-rgb_1-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/s-co-logo-mit-rgb_1-1.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/sco-schuelerin-co-gmbh\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/sco-schuelerin-co-gmbh\\\/\",\"name\":\"S&CO. (Sch\u00fclerIn & Co. GmbH) - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#website\"},\"datePublished\":\"2020-11-01T13:14:34+00:00\",\"dateModified\":\"2020-11-02T16:14:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/sco-schuelerin-co-gmbh\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/sco-schuelerin-co-gmbh\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/sco-schuelerin-co-gmbh\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S&#038;CO. (Sch\u00fclerIn &#038; Co. GmbH)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"S&CO. (Sch\u00fclerIn & Co. GmbH) - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/it\/listings\/sco-schuelerin-co-gmbh\/","og_locale":"it_IT","og_type":"article","og_title":"S&CO. (Sch\u00fclerIn & Co. GmbH)","og_description":"Suchen Sie eine Schule, an der sich Ihr Kind ernst genommen f\u00fchlt und erfolgreich lernen kann? N\u00e4hrboden daf\u00fcr ist eine wertsch\u00e4tzende sowie aufrichtige Beziehung zwischen allen Beteiligten. Um diese aufzubauen, pflegen wir den regelm\u00e4ssigen\u00a0Dialog zwischen dem Kind, den Lehrpersonen und den Eltern. Bei uns lernt Ihr Kind, sich entschlossen und mit Hingabe f\u00fcr eine Idee [&hellip;]","og_url":"https:\/\/schoolaboo.com\/it\/listings\/sco-schuelerin-co-gmbh\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-11-02T16:14:21+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/s-co-logo-mit-rgb_1-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/s-co-logo-mit-rgb_1-1.jpg","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/it\/listings\/sco-schuelerin-co-gmbh\/","url":"https:\/\/schoolaboo.com\/it\/listings\/sco-schuelerin-co-gmbh\/","name":"S&CO. (Sch\u00fclerIn & Co. GmbH) - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/it\/#website"},"datePublished":"2020-11-01T13:14:34+00:00","dateModified":"2020-11-02T16:14:21+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/it\/listings\/sco-schuelerin-co-gmbh\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/it\/listings\/sco-schuelerin-co-gmbh\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/it\/listings\/sco-schuelerin-co-gmbh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/it\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/it\/angebote\/"},{"@type":"ListItem","position":3,"name":"S&#038;CO. (Sch\u00fclerIn &#038; Co. GmbH)"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/it\/#website","url":"https:\/\/schoolaboo.com\/it\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/it\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/schoolaboo.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-listings\/21913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/comments?post=21913"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/media?parent=21913"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job_listing_region?post=21913"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-categories?post=21913"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-types?post=21913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}