{"id":19988,"date":"2020-09-09T22:53:24","date_gmt":"2020-09-09T20:53:24","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=19988"},"modified":"2020-10-14T19:12:47","modified_gmt":"2020-10-14T17:12:47","slug":"externat-catholique-des-glacis","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/it\/listings\/externat-catholique-des-glacis\/","title":{"rendered":"Externat Catholique des Glacis"},"content":{"rendered":"<div class=\"elementor-element elementor-element-4dcf9e8 elementor-widget elementor-widget-heading\" data-id=\"4dcf9e8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h2 class=\"elementor-heading-title elementor-size-default\">Pr\u00e4sentation<\/h2>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-90d9cce elementor-widget elementor-widget-text-editor\" data-id=\"90d9cce\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p>Die katholische Tagesschule ist eine Grundschule, die 1927 gegr\u00fcndet wurde und in einem Herrenhaus aus dem 19. Jahrhundert etwa 200 Sch\u00fcler aller Glaubensrichtungen und Herkunft zusammenbringt.<\/p>\n<p>Nach einem hochwertigen Lehrplan f\u00fcr Franz\u00f6sisch bietet die Glacis Day School strenges und anspruchsvolles Lernen, insbesondere in Franz\u00f6sisch und Mathematik.<\/p>\n<p>Basierend auf dem Plan d&#8217;Etudes Romand und erg\u00e4nzt durch Begriffe der franz\u00f6sischen nationalen Bildung wird das angebotene Programm so studiert, dass die Sch\u00fcler am Ende der Grundschule nat\u00fcrlich auch im \u00f6ffentlichen Genfer Kreis ihr Studium fortsetzen k\u00f6nnen oder privat, als im franz\u00f6sischen System.\u00a0Es ist angereichert mit wesentlichen Erg\u00e4nzungen zur zeitgen\u00f6ssischen Bildung: Englisch vom Beginn der Schulpflicht an, Deutsch und IT.<br \/>\nWir vergessen auch nicht unsere Wurzeln, da alle Sch\u00fcler des letzten Grundschuljahres einer Einweihung in Latein folgen.<\/p>\n<p>Die solide Lernumgebung und die zahlreichen au\u00dferschulischen Aktivit\u00e4ten f\u00f6rdern die Entwicklung und Erf\u00fcllung unserer Sch\u00fcler nach dem alten Sprichwort &#8221;\u00a0<em>Mens Sana in Corpore Sano<\/em>\u00a0&#8220;.<\/p>\n<p>Um die Kinder bei ihrer Arbeit zu unterst\u00fctzen und ihnen beizubringen, sich selbst zu organisieren, bietet die Glacis Day School ihren Sch\u00fclern ein System von betreuten Studien an, das von Lehrern der Schule geleitet wird.\u00a0Parallel zu den j\u00fcngsten Sch\u00fclern bietet die Einrichtung vom Ende des Unterrichts bis 17.30 Uhr eine abendliche Kindertagesst\u00e4tte an.<\/p>\n<p>Die geringe Gr\u00f6\u00dfe der Schule f\u00f6rdert eine famili\u00e4re Atmosph\u00e4re, die dem Zuh\u00f6ren der Sch\u00fcler und einem Gef\u00fchl der Sicherheit f\u00f6rderlich ist.\u00a0Dieser \u201eFamiliengeist\u201c ist wichtig f\u00fcr das Vertrauensverh\u00e4ltnis zwischen Lehrern, Kindern und Eltern.<\/p>\n<p>Die Glacis Day School ist eine gemeinn\u00fctzige Vereinigung, die sich aus einem Ausschuss und einer Generalversammlung zusammensetzt.\u00a0Die Schule ist Teil des Schweizerischen Verbandes der Privatschulen (FSEP) und des Genfer Verbands der Privatschulen (AGEP).\u00a0Es hat auch ein Qualit\u00e4tszertifikat (Swiss School Impulse).<\/p>\n<section class=\"elementor-element elementor-element-3973d1d elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"3973d1d\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-row\">\n<div class=\"elementor-element elementor-element-80aa45d elementor-column elementor-col-50 elementor-top-column\" data-id=\"80aa45d\" data-element_type=\"column\">\n<div class=\"elementor-column-wrap elementor-element-populated\">\n<div class=\"elementor-widget-wrap\">\n<div class=\"elementor-element elementor-element-9a6c961 elementor-widget elementor-widget-heading\" data-id=\"9a6c961\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h2 class=\"elementor-heading-title elementor-size-default\">Das Trench-Viertel und die Glacis Day School<\/h2>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-621cb30 elementor-widget elementor-widget-text-editor\" data-id=\"621cb30\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p>Im Laufe der Jahrhunderte wurde Genf mehrfach angegriffen, und seine befestigte Altstadt spielt die Rolle eines echten Schutzschildes gegen die Angreifer (wir werden uns an den ber\u00fchmten Versuch von Herzog Charles-Emmanuel von Savoyen im Jahr 1602 erinnern, dessen Flucht noch immer gefeiert wird). .\u00a0Dieser Zustand hielt bis zur Mitte des 19. Jahrhunderts an.<\/p>\n<p>Dann, nach der &#8220;radikalen Revolution&#8221; vom Oktober 1846, wollte die neue Genfer Verfassung von 1847 Genf zu einer offenen Stadt mit gro\u00dfen Entwicklungsr\u00e4umen machen.<\/p>\n<p>Im Jahr 1848 stimmte der damalige Staatsrat James Fazy im Rahmen der von Genf ben\u00f6tigten Entwicklung, dem Abriss der Stadtbefestigungen, ab.\u00a0Dies beginnt sofort und weicht gro\u00dfen Boulevards, neuen Geb\u00e4uden und Promenaden, die heute noch sichtbar sind.\u00a0Anschlie\u00dfend ermutigte er die Patrizierfamilien, im Bezirk der Gr\u00e4ben auf dem Gel\u00e4nde, das von den alten Mauern, Schanzen und Bastionen frei gelassen wurde, opulente Geb\u00e4ude, oft Villen, die von privaten G\u00e4rten umgeben sind, zu bauen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-ca0d8ef elementor-widget elementor-widget-heading\" data-id=\"ca0d8ef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h2 class=\"elementor-heading-title elementor-size-default\">Geb\u00e4ude<\/h2>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-a73e6c2 elementor-widget elementor-widget-text-editor\" data-id=\"a73e6c2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p>Unter diesen Geb\u00e4uden befindet sich das Geb\u00e4ude, in dem sich unsere 1881 errichtete Schule befindet. Der erste Besitzer ist ein wohlhabender Genfer, Herr Louis-Alfred Bertrand, der der Stadt Genf den gleichnamigen Park vermacht hat.<\/p>\n<p>Dann, 1917, verkaufte er dieses Geb\u00e4ude an Frau Anne de Planta, die es 1936 an Herrn Fran\u00e7ois Rossiaud verkaufte, der in der Schule, die er einige Jahre zuvor gegr\u00fcndet hatte, eng war 1927 in der Rue des Glacis de Rive. Schlie\u00dflich, 1980, einige Zeit vor seinem Verschwinden, vermachte seine letzte Tochter, Lucie, ledig, dieses Geb\u00e4ude der r\u00f6misch-katholischen Kirche in Genf, unter der ausdr\u00fccklichen Bedingung, dass er f\u00fcr immer eine Schule, seine Schule, beherbergen k\u00f6nnte: Tagesschule Glacis.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section class=\"elementor-element elementor-element-1ae9055 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"1ae9055\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-row\">\n<div class=\"elementor-element elementor-element-9eac899 elementor-column elementor-col-50 elementor-top-column\" data-id=\"9eac899\" data-element_type=\"column\">\n<div class=\"elementor-column-wrap elementor-element-populated\">\n<div class=\"elementor-widget-wrap\">\n<div class=\"elementor-element elementor-element-063cbc6 elementor-widget elementor-widget-image\" data-id=\"063cbc6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-image\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-2d2adb5 elementor-column elementor-col-50 elementor-top-column\" data-id=\"2d2adb5\" data-element_type=\"column\">\n<div class=\"elementor-column-wrap elementor-element-populated\">\n<div class=\"elementor-widget-wrap\">\n<div class=\"elementor-element elementor-element-fc2b650 elementor-widget elementor-widget-heading\" data-id=\"fc2b650\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h2 class=\"elementor-heading-title elementor-size-default\">Schule<\/h2>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-0f4057b elementor-widget elementor-widget-text-editor\" data-id=\"0f4057b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p>1927 begann das Abenteuer der von der Familie Rossiaud gegr\u00fcndeten und geleiteten Schule, die sich zun\u00e4chst in der Rue des Glacis de Rive befand.\u00a0Die Anf\u00e4nge sind bescheiden, da es nur vier Studenten hat.\u00a0Sp\u00e4ter, nachdem die Zahl der Sch\u00fcler erheblich zugenommen hatte, zog die Schule f\u00fcr kurze Zeit in die Rue T\u00f6pffer und integrierte schlie\u00dflich die Mauern der Rue Munier-Romilly 2, wobei der Name der Tagesschule &#8220;Glacis&#8221; beibehalten wurde erinnere dich an seine erste Adresse.<br \/>\nSeit ihrer Gr\u00fcndung hat die Glacis Day School eine famili\u00e4re Berufung und eine Philosophie, die sich grundlegend auf die Entwicklung des Kindes konzentriert.\u00a0In Genf ist diese Schule die erste, die Kindern im Primarbereich die deutsche Sprache beibringt.<\/p>\n<p>1980 machte die damals 84-j\u00e4hrige Miss Lucie Rossiaud ihre Schule zu einem \u201egemeinn\u00fctzigen Verein\u201c, der jetzt von einer Generalversammlung geleitet wird, die das p\u00e4dagogische Management an einen Direktor delegiert.<\/p>\n<p>Seit seiner Gr\u00fcndung kennt L&#8217;Externat des Glacis drei Direktoren:<br \/>\n\u2022 von 1927 bis 1980 Miss Lucie Rossiaud (1896-1983)<br \/>\n\u2022 von 1980 bis 2002 Miss Madeleine Courlet (1935-2004)<br \/>\n\u2022 seit 2002 Herrn Alexandre Odier (1964).<\/p>\n<\/div>\n<p>Wenn ich gebeten werde, die\u00a0<strong>Glacis Day School<\/strong>\u00a0zu qualifizieren\u00a0, m\u00f6chte ich sagen, dass es sich um einen kostbaren Fall handelt, der einen Fluss kleiner Diamanten enth\u00e4lt, von denen jeder sch\u00f6ner und wertvoller ist als der n\u00e4chste.\u00a0und ich bin gl\u00fccklich, der Garant f\u00fcr diesen unsch\u00e4tzbaren Schatz zu sein.<\/p>\n<p>Als ausgebildeter Latinist mag ich traditionelle Werte wie Respekt, Toleranz, Disziplin, Liebe zu einer gut gemachten Arbeit, intellektuelle Neugier und die Aus\u00fcbung von Sport, wie bereits von Juvenal mit seiner ber\u00fchmten \u201eMens Sana\u201c vertreten in corpore sano \u201c, um ein vern\u00fcnftiges Gleichgewicht zwischen K\u00f6rper und Geist herzustellen.<\/p>\n<p>Ich bin dennoch ein Mann, der fest in seiner Zeit verwurzelt ist, und ich m\u00f6chte, dass die Kinder, die uns heute anvertraut werden, bereit sind f\u00fcr die Herausforderungen, die sie morgen erwarten.\u00a0Aus diesem Grund erscheint es mir wichtig, ihnen die M\u00f6glichkeit zu bieten, Sprachen wie Englisch und Deutsch zu lernen &#8211; mit einem Hauch von Latein -, Computerwerkzeuge zu beherrschen, die K\u00fcnste zu entdecken und d &#8221; erwerben die F\u00e4higkeit, frei zu argumentieren.<\/p>\n<p>Als P\u00e4dagoge ist es mein Ziel, dass jeder Sch\u00fcler des\u00a0<strong>Externat des Glacis<\/strong>\u00a0\u00a0in diesem wundersch\u00f6nen Herrenhaus aus dem 19. Jahrhundert die Freude am Lernen, die Freude, lebenslange Freunde zu finden und die Freude am Teilen mit ihnen findet seine Kameraden und seine Lehrer unvergessliche Momente.\u00a0Ich hoffe, dass alle unsere Sch\u00fcler in der\u00a0<strong>Glacis Day School<\/strong>\u00a0\u00a0ein privilegiertes Universum\u00a0finden, in dem\u00a0eine Familie und ein wohlwollender Geist herrschen, in dem jedes Kind noch das Recht hat, ein Kind zu sein.<\/p>\n<p><em>Alexandre Odier<br \/>\nRegisseur<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Rue Munier-Romilly 2 1206 Genf","_company_website":"https:\/\/externat-glacis.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[172],"job-categories":[110,103,99,76],"job-types":[90,5,92],"class_list":{"0":"post-19988","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-genf","6":"job_listing_category-franzoesisches-schulprogramm-baccalaureat","7":"job_listing_category-kindergarten","8":"job_listing_category-primarschule","9":"job_listing_category-sekundarstufe_1","10":"job_listing_type-kindergarten","11":"job_listing_type-primarschule","12":"job_listing_type-sekundarstufe_1","14":"job-type-kindergarten-4-6-jahre","15":"job-type-primarschule-7-12jahre","16":"job-type-sekundarstufe-1-13-16-jahre"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Externat Catholique des Glacis - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/it\/listings\/externat-catholique-des-glacis\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Externat Catholique des Glacis\" \/>\n<meta property=\"og:description\" content=\"Pr\u00e4sentation Die katholische Tagesschule ist eine Grundschule, die 1927 gegr\u00fcndet wurde und in einem Herrenhaus aus dem 19. Jahrhundert etwa 200 Sch\u00fcler aller Glaubensrichtungen und Herkunft zusammenbringt. Nach einem hochwertigen Lehrplan f\u00fcr Franz\u00f6sisch bietet die Glacis Day School strenges und anspruchsvolles Lernen, insbesondere in Franz\u00f6sisch und Mathematik. Basierend auf dem Plan d&#8217;Etudes Romand und erg\u00e4nzt [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/it\/listings\/externat-catholique-des-glacis\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-14T17:12:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/Externat-Catholique-des-Glacis.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/Externat-Catholique-des-Glacis.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/externat-catholique-des-glacis\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/externat-catholique-des-glacis\\\/\",\"name\":\"Externat Catholique des Glacis - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#website\"},\"datePublished\":\"2020-09-09T20:53:24+00:00\",\"dateModified\":\"2020-10-14T17:12:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/externat-catholique-des-glacis\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/externat-catholique-des-glacis\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/externat-catholique-des-glacis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Externat Catholique des Glacis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Externat Catholique des Glacis - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/it\/listings\/externat-catholique-des-glacis\/","og_locale":"it_IT","og_type":"article","og_title":"Externat Catholique des Glacis","og_description":"Pr\u00e4sentation Die katholische Tagesschule ist eine Grundschule, die 1927 gegr\u00fcndet wurde und in einem Herrenhaus aus dem 19. Jahrhundert etwa 200 Sch\u00fcler aller Glaubensrichtungen und Herkunft zusammenbringt. Nach einem hochwertigen Lehrplan f\u00fcr Franz\u00f6sisch bietet die Glacis Day School strenges und anspruchsvolles Lernen, insbesondere in Franz\u00f6sisch und Mathematik. Basierend auf dem Plan d&#8217;Etudes Romand und erg\u00e4nzt [&hellip;]","og_url":"https:\/\/schoolaboo.com\/it\/listings\/externat-catholique-des-glacis\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-10-14T17:12:47+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/Externat-Catholique-des-Glacis.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/Externat-Catholique-des-Glacis.jpg","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/it\/listings\/externat-catholique-des-glacis\/","url":"https:\/\/schoolaboo.com\/it\/listings\/externat-catholique-des-glacis\/","name":"Externat Catholique des Glacis - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/it\/#website"},"datePublished":"2020-09-09T20:53:24+00:00","dateModified":"2020-10-14T17:12:47+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/it\/listings\/externat-catholique-des-glacis\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/it\/listings\/externat-catholique-des-glacis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/it\/listings\/externat-catholique-des-glacis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/it\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/it\/angebote\/"},{"@type":"ListItem","position":3,"name":"Externat Catholique des Glacis"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/it\/#website","url":"https:\/\/schoolaboo.com\/it\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/it\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/schoolaboo.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-listings\/19988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/comments?post=19988"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/media?parent=19988"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job_listing_region?post=19988"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-categories?post=19988"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-types?post=19988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}