{"id":19911,"date":"2020-09-09T22:53:52","date_gmt":"2020-09-09T20:53:52","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=19911"},"modified":"2020-10-08T21:36:18","modified_gmt":"2020-10-08T19:36:18","slug":"ecole-alphalif","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/it\/listings\/ecole-alphalif\/","title":{"rendered":"Ecole Alphalif"},"content":{"rendered":"<h3>Wer sind wir ?<\/h3>\n<p>Eine familienorientierte Schule, die 1986 in Lausanne gegr\u00fcndet wurde.\u00a0Wir sind spezialisiert auf die Vorbereitung auf offizielle Pr\u00fcfungen und Nachhilfeunterricht, von der High School bis zum Studium.<\/p>\n<h3>Was ist die Philosophie der Schule?<\/h3>\n<p>Bereits seit 30 Jahren geben wir uns die Aufgabe, unsere Kunden durch\u00a0<strong>einwandfreie und personalisierte Schulungen<\/strong>\u00a0sowohl in akademischer als auch in intellektueller und menschlicher\u00a0<strong>Hinsicht<\/strong> zufrieden zu stellen . Wir bem\u00fchen uns, die Integration jedes einzelnen Studenten in die Berufswelt zu erleichtern und den Erwerb von\u00a0<strong>Wissen<\/strong>\u00a0,\u00a0<strong>F\u00e4higkeiten<\/strong>\u00a0und\u00a0<strong>Reife<\/strong>\u00a0sicherzustellen\u00a0,\u00a0ohne die sie\u00a0in einer modernen Gesellschaft\u00a0nicht\u00a0<strong>gedeihen<\/strong>\u00a0w\u00fcrden\u00a0. immer komplexer.<\/p>\n<p>Um dieses Ziel zu erreichen, bieten wir einen anderen Bildungsstil an, der eine\u00a0<strong>besondere Beziehung<\/strong>\u00a0zum Sch\u00fcler\u00a0schafft\u00a0und einen\u00a0lernf\u00f6rderlichen\u00a0<strong>Rahmen<\/strong>\u00a0garantiert\u00a0.\u00a0Die entspannte Atmosph\u00e4re in unserer Schule erm\u00f6glicht es dem Sch\u00fcler, sich angeh\u00f6rt, gef\u00fchrt und\u00a0<strong>gesch\u00e4tzt<\/strong>\u00a0zu f\u00fchlen und\u00a0so den\u00a0<strong>Dialog zu<\/strong>\u00a0f\u00f6rdern\u00a0.\u00a0Angeregt und ermutigt, seine Schwierigkeiten auszudr\u00fccken,\u00a0<strong>gewinnt<\/strong>\u00a0dieser\u00a0<strong>(wieder) Vertrauen<\/strong>\u00a0in sich.<\/p>\n<p>Die\u00a0<strong>strenge \u00dcberwachung<\/strong>\u00a0und\u00a0<strong>Ermutigung<\/strong>\u00a0wird durch\u00a0<strong>geringe Zahlen erm\u00f6glicht<\/strong>\u00a0.\u00a0Die Erfahrung, das Engagement und die Verf\u00fcgbarkeit unseres Teams &#8211; bestehend aus\u00a0<strong>qualifizierten und zertifizierten P\u00e4dagogen<\/strong>\u00a0in ihrem Bildungsbereich &#8211; erm\u00f6glichen es wiederum, Demotivierungen des Sch\u00fclers zu erkennen und zu beseitigen.\u00a0Allm\u00e4hlich lernt er,\u00a0<strong>selbst\u00e4ndig<\/strong>\u00a0zu arbeiten,\u00a0und er interessiert sich\u00a0<strong>f\u00fcr<\/strong>\u00a0sein Interesse\u00a0<strong>f\u00fcr das Studium,<\/strong>\u00a0w\u00e4hrend er seine\u00a0<strong>Kreativit\u00e4t entwickelt<\/strong>\u00a0.\u00a0Er kann somit sein volles akademisches Potenzial erreichen.<\/p>\n<h3>Zusammenfassend ist die Alphalif-Schule:<\/h3>\n<ul>\n<li>ein\u00a0\u00a0<strong>qualitativ hochwertiges Coaching\u00a0<\/strong>\u00a0mit einem Team erfahrener Trainer, dynamisch und engagiert;<\/li>\n<li>von\u00a0\u00a0<strong>engen Kontakten\u00a0<\/strong>\u00a0zwischen Bildungsleitern und Lernenden und ihren Eltern f\u00fcr eine direkte und effektive Information;<\/li>\n<li>eine\u00a0\u00a0<strong>personalisierte Verfolgung\u00a0<\/strong>\u00a0genau und regelm\u00e4\u00dfig f\u00fcr sichtbare Fortschritte schnell;<\/li>\n<li>das\u00a0\u00a0<strong>begrenzte Personal\u00a0<\/strong>\u00a0in einem freundlichen und harmonischen, um (wieder) einen Vorgeschmack auf die Studie zu geben;<\/li>\n<li>eine\u00a0<strong>hohe Erfolgsquote<\/strong>\u00a0seit 30 Jahren.<\/li>\n<\/ul>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Rue Pichard 18-20, 1003 Lausanne, Schweiz","_company_website":"https:\/\/www.alphalif.ch\/enseignants\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[174],"job-categories":[141,132,76,102],"job-types":[92],"class_list":{"0":"post-19911","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-vaud","6":"job_listing_category-brueckenangebot","7":"job_listing_category-gymnasium","8":"job_listing_category-sekundarstufe_1","9":"job_listing_category-sekundarstufe_2","10":"job_listing_type-sekundarstufe_1","12":"job-type-sekundarstufe-1-13-16-jahre"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ecole Alphalif - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/it\/listings\/ecole-alphalif\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecole Alphalif\" \/>\n<meta property=\"og:description\" content=\"Wer sind wir ? Eine familienorientierte Schule, die 1986 in Lausanne gegr\u00fcndet wurde.\u00a0Wir sind spezialisiert auf die Vorbereitung auf offizielle Pr\u00fcfungen und Nachhilfeunterricht, von der High School bis zum Studium. Was ist die Philosophie der Schule? Bereits seit 30 Jahren geben wir uns die Aufgabe, unsere Kunden durch\u00a0einwandfreie und personalisierte Schulungen\u00a0sowohl in akademischer als auch [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/it\/listings\/ecole-alphalif\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-08T19:36:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/10_logo.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/10_logo.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/ecole-alphalif\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/ecole-alphalif\\\/\",\"name\":\"Ecole Alphalif - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#website\"},\"datePublished\":\"2020-09-09T20:53:52+00:00\",\"dateModified\":\"2020-10-08T19:36:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/ecole-alphalif\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/ecole-alphalif\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/listings\\\/ecole-alphalif\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ecole Alphalif\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ecole Alphalif - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/it\/listings\/ecole-alphalif\/","og_locale":"it_IT","og_type":"article","og_title":"Ecole Alphalif","og_description":"Wer sind wir ? Eine familienorientierte Schule, die 1986 in Lausanne gegr\u00fcndet wurde.\u00a0Wir sind spezialisiert auf die Vorbereitung auf offizielle Pr\u00fcfungen und Nachhilfeunterricht, von der High School bis zum Studium. Was ist die Philosophie der Schule? Bereits seit 30 Jahren geben wir uns die Aufgabe, unsere Kunden durch\u00a0einwandfreie und personalisierte Schulungen\u00a0sowohl in akademischer als auch [&hellip;]","og_url":"https:\/\/schoolaboo.com\/it\/listings\/ecole-alphalif\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-10-08T19:36:18+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/10_logo.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/10_logo.jpg","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/it\/listings\/ecole-alphalif\/","url":"https:\/\/schoolaboo.com\/it\/listings\/ecole-alphalif\/","name":"Ecole Alphalif - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/it\/#website"},"datePublished":"2020-09-09T20:53:52+00:00","dateModified":"2020-10-08T19:36:18+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/it\/listings\/ecole-alphalif\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/it\/listings\/ecole-alphalif\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/it\/listings\/ecole-alphalif\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/it\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/it\/angebote\/"},{"@type":"ListItem","position":3,"name":"Ecole Alphalif"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/it\/#website","url":"https:\/\/schoolaboo.com\/it\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/it\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/schoolaboo.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-listings\/19911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/comments?post=19911"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/media?parent=19911"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job_listing_region?post=19911"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-categories?post=19911"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/it\/wp-json\/wp\/v2\/job-types?post=19911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}