{"id":30717,"date":"2024-05-02T10:42:29","date_gmt":"2024-05-02T08:42:29","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=30717"},"modified":"2026-04-26T08:39:08","modified_gmt":"2026-04-26T06:39:08","slug":"lze-immersive-learning-space","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/fr\/listings\/lze-immersive-learning-space\/","title":{"rendered":"LzE Immersive Learning Space"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2024\/05\/65af67e4dee707424676f73b_Screenshot-2024-01-23-082316.jpg\" width=\"117\" height=\"116\" \/><br \/>\nLzE Immersive Learning Space<\/h2>\n<p>&nbsp;<\/p>\n<p>Die junge Privatschule verfolgt einen einzigartigen Bildungsansatz, der akademische Exzellenz mit erfahrungsbasiertem Lernen verbindet. Die Studierenden tauchen durch praktische Erfahrungen in verschiedene Themen ein und gewinnen damit ein tieferes Verst\u00e4ndnis und eine lebenslange Leidenschaft f\u00fcr das Lernen.<\/p>\n<p>Der LzE bietet einen umfassenden internationalen Lehrplan mit Schwerpunkt auf Sprachen (Vermittlung dreier Fremdsprachen ab dem ersten Schuljahr), MINT-F\u00e4chern, Kunst und Sport, sowie \u00d6konomie, welche \u00fcber reale und praxisnahe Projekte vermittelt werden. Diese Vielfalt stellt sicher, dass F\u00e4higkeiten aus verschiedenen Perspektiven und in ihrer Ganzheitlichkeit vermittelt werden und die Sch\u00fcler weltweit wettbewerbsf\u00e4hig sind.<\/p>\n<h3>Unser Konzept<\/h3>\n<p class=\"centered-heading-3\">Unser Konzept steht auf drei S\u00e4ulen, die jeweils darauf abzielen, eine ganzheitliche und <strong>herzzentrierte\u00a0<\/strong>Bildungserfahrung zu bieten:<\/p>\n<ol>\n<li><strong>Akademische Exzellenz: <\/strong>Wir f\u00f6rdern eine starke Grundlage akademischen Wissens. Unser Lehrplan ist darauf ausgelegt, die Sch\u00fcler individuell und st\u00e4rkenorientiert herauszufordern und zu inspirieren, um kritisches Denken, Probleml\u00f6sungskompetenz und ein tiefes Verst\u00e4ndnis der Kernf\u00e4cher zu f\u00f6rdern.<\/li>\n<li><strong>Unternehmerschule:<\/strong> In der sich schnell ver\u00e4ndernden Welt von heute sind unternehmerische F\u00e4higkeiten wichtiger denn je. Unsere Sch\u00fcler tauchen in reale Projekte ein und wenden so ihr Wissen schon fr\u00fch in der Praxis an. Dar\u00fcber hinaus haben sie die M\u00f6glichkeit, auf die Gr\u00fcndung ihrer ersten Unternehmen hinzuarbeiten und so schon in jungen Jahren Eigeninitiative und Kreativit\u00e4t auszuleben.<\/li>\n<li><strong>Innovationsschule:<\/strong> Die Einf\u00fchrung neuer Lernmethoden ist f\u00fcr die Vorbereitung der Sch\u00fcler auf die Zukunft von entscheidender Bedeutung. Als Innovationsschule sind wir bestrebt, diese Methoden zu erforschen und umzusetzen, um sicherzustellen, dass unsere Sch\u00fcler bei <strong>Nutzung aller Sinne<\/strong> umfassende F\u00e4higkeiten entwickeln, die \u00fcber traditionelle Bildungsmodelle hinausgehen<\/li>\n<\/ol>\n<section class=\"section-9\">\n<h3 class=\"display-2\">Unsere Schwerpunkte<\/h3>\n<\/section>\n<section class=\"section-8\">\n<div class=\"div-block-27\">\n<div id=\"w-node-_41a4a130-5694-c114-e2f3-1a349f8852c6-4db0d176\" class=\"div-block-6\">\n<p><strong class=\"bold-text-15\">Freiheit des Lernens<br \/>\n<\/strong>Wir geben den Kindern Raum zur Entfaltung ihrer individuellen Interessen und Talente. Unser Fokus liegt auf intrinsischer Motivation und der Entwicklung einer lebenslangen Lernbereitschaft.<\/p>\n<\/div>\n<div id=\"w-node-_08cc9889-4314-52d4-a820-59637bc537df-4db0d176\">\n<div><strong class=\"bold-text-15\">Ganzheitliche Bildung<\/strong><\/div>\n<p class=\"paragraph-36\">Neben den akademischen F\u00e4chern f\u00f6rdern wir kreatives Denken, soziale Kompetenzen und praktische Fertigkeiten. Wir legen Wert auf eine umfassende Entwicklung und auf eigenverantwortliches Lernen.<\/p>\n<\/div>\n<div id=\"w-node-e48f9f23-2fe7-d687-2337-f2aa62d8e58e-4db0d176\">\n<div><strong class=\"bold-text-15\">Lehrplan 21-konform<\/strong><\/div>\n<p class=\"paragraph-37\">Unser Lehrplan ist staatlich bewilligt und gew\u00e4hrleistet eine solide Grundlage f\u00fcr den \u00dcbergang in weiterf\u00fchrende Bildungseinrichtungen oder den Berufseinstieg.<\/p>\n<\/div>\n<div id=\"w-node-cbe2c024-8b8f-1a27-2029-afe91d749970-4db0d176\">\n<div><strong class=\"bold-text-15\">Individualisierte Betreuung<\/strong><\/div>\n<p class=\"paragraph-41\">In unseren kleinen Lerngruppen bieten wir eine pers\u00f6nliche und unterst\u00fctzende Lernumgebung. Jedes Kind wird individuell gef\u00f6rdert und in seinem eigenen Tempo begleitet.<\/p>\n<\/div>\n<div id=\"w-node-_4389bc84-a6cc-6391-ed1c-aed25e14db0e-4db0d176\">\n<div><strong class=\"bold-text-15\">Praxisnahe Erfahrungen<\/strong><\/div>\n<p class=\"paragraph-40\">Regelm\u00e4ssige Exkursionen, Praktika und Projekte erm\u00f6glichen es den Sch\u00fclern, das Gelernte in realen Situationen anzuwenden. Dadurch entstehen ein tieferes Verst\u00e4ndnis und eine st\u00e4rkere Verbindung zum k\u00fcnftigen Leben.<\/p>\n<\/div>\n<div id=\"w-node-f4089d7b-4de9-40fb-cb7f-d06b90506aaa-4db0d176\">\n<div><strong class=\"bold-text-15\">Respektvolles Miteinander<\/strong><\/div>\n<p class=\"paragraph-39\">Bei uns steht ein wertsch\u00e4tzendes und respektvolles Umfeld im Vordergrund. Wir f\u00f6rdern die soziale Kompetenz, Teamarbeit und Empathie, um eine positive Gemeinschaft zu scha\ufb00en.<\/p>\n<\/div>\n<div id=\"w-node-_79b05b69-a846-2a4c-e6c7-cfc3bb5bbbdc-4db0d176\">\n<div><strong class=\"bold-text-15\">Vorbereitung auf die Zukunft \u2028<\/strong><\/div>\n<p class=\"paragraph-43\">Unser Ziel ist es, die Sch\u00fcler auf ein erf\u00fclltes Leben und den schwierigen Arbeitsmarkt vorzubereiten. Wir legen Wert auf die Entwicklung von lebenspraktischen F\u00e4higkeiten, kritischem Denken und Eigenverantwortung \u2013 auch mit dem Ziel der Gr\u00fcndung eines eigenen Unternehmens gem\u00e4ss der individuellen Passion.<\/p>\n<\/div>\n<div id=\"w-node-a5de9841-b368-1de1-3039-1835242d6a22-4db0d176\">\n<div><strong class=\"bold-text-15\">Mehrsprachigkeit\/ Internationalit\u00e4t<\/strong><\/div>\n<p class=\"paragraph-42\">Wir erlernen Fremdsprachen (Englisch, Franz\u00f6sisch, Spanisch) bereits ab der ersten Klasse \u00fcber die Immersionsmethode. Bei dieser Methode ist die neue Sprache Arbeitssprache \u00fcber einen gewissen Zeitraum hinweg und erlaubt den Sch\u00fclern spielerisch\/ nat\u00fcrlich ihr Vokabular aufzubauen.<\/p>\n<p><a href=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2024\/05\/Brochure_ImmersiveLearningSpace_new.pdf\" target=\"_blank\" rel=\"noopener\">Informationsflyer<\/a><\/p>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"featured_media":30750,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Uznach","_company_website":"https:\/\/www.immersivelearningspace.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":1,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[159],"job-categories":[871,103,229,139,99,76],"job-types":[90,5,92,230],"class_list":{"0":"post-30717","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"has-post-thumbnail","5":"hentry","6":"job_listing_region-st-gallen","7":"job_listing_category-bilingual","8":"job_listing_category-kindergarten","9":"job_listing_category-vorkindergarten","10":"job_listing_category-mehrsprachiger-unterricht","11":"job_listing_category-primarschule","12":"job_listing_category-sekundarstufe_1","13":"job_listing_type-kindergarten","14":"job_listing_type-primarschule","15":"job_listing_type-sekundarstufe_1","16":"job_listing_type-vorkindergarten","18":"job-type-kindergarten-4-6-jahre","19":"job-type-primarschule-7-12jahre","20":"job-type-sekundarstufe-1-13-16-jahre","21":"job-type-vorkindergarten","22":"job_position_featured"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>LzE Immersive Learning Space - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"description\" content=\"vereint Konzepte von Schulen aus der Schweiz, Deutschland, Japan, Russland, Neuseeland, England, D\u00e4nemark und den USA in einer Privatschule\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/fr\/listings\/lze-immersive-learning-space\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LzE Immersive Learning Space\" \/>\n<meta property=\"og:description\" content=\"vereint Konzepte von Schulen aus der Schweiz, Deutschland, Japan, Russland, Neuseeland, England, D\u00e4nemark und den USA in einer Privatschule\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/fr\/listings\/lze-immersive-learning-space\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-26T06:39:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2024\/05\/Uznach-4-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/lze-immersive-learning-space\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/lze-immersive-learning-space\\\/\",\"name\":\"LzE Immersive Learning Space - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/lze-immersive-learning-space\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/lze-immersive-learning-space\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Uznach-4-1.jpg\",\"datePublished\":\"2024-05-02T08:42:29+00:00\",\"dateModified\":\"2026-04-26T06:39:08+00:00\",\"description\":\"vereint Konzepte von Schulen aus der Schweiz, Deutschland, Japan, Russland, Neuseeland, England, D\u00e4nemark und den USA in einer Privatschule\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/lze-immersive-learning-space\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/lze-immersive-learning-space\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/lze-immersive-learning-space\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Uznach-4-1.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Uznach-4-1.jpg\",\"width\":500,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/lze-immersive-learning-space\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LzE Immersive Learning Space\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"LzE Immersive Learning Space - Privatschul Verzeichnis und Beratung","description":"vereint Konzepte von Schulen aus der Schweiz, Deutschland, Japan, Russland, Neuseeland, England, D\u00e4nemark und den USA in einer Privatschule","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/fr\/listings\/lze-immersive-learning-space\/","og_locale":"fr_FR","og_type":"article","og_title":"LzE Immersive Learning Space","og_description":"vereint Konzepte von Schulen aus der Schweiz, Deutschland, Japan, Russland, Neuseeland, England, D\u00e4nemark und den USA in einer Privatschule","og_url":"https:\/\/schoolaboo.com\/fr\/listings\/lze-immersive-learning-space\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2026-04-26T06:39:08+00:00","og_image":[{"width":500,"height":375,"url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2024\/05\/Uznach-4-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/fr\/listings\/lze-immersive-learning-space\/","url":"https:\/\/schoolaboo.com\/fr\/listings\/lze-immersive-learning-space\/","name":"LzE Immersive Learning Space - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoolaboo.com\/fr\/listings\/lze-immersive-learning-space\/#primaryimage"},"image":{"@id":"https:\/\/schoolaboo.com\/fr\/listings\/lze-immersive-learning-space\/#primaryimage"},"thumbnailUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2024\/05\/Uznach-4-1.jpg","datePublished":"2024-05-02T08:42:29+00:00","dateModified":"2026-04-26T06:39:08+00:00","description":"vereint Konzepte von Schulen aus der Schweiz, Deutschland, Japan, Russland, Neuseeland, England, D\u00e4nemark und den USA in einer Privatschule","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/fr\/listings\/lze-immersive-learning-space\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/fr\/listings\/lze-immersive-learning-space\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/schoolaboo.com\/fr\/listings\/lze-immersive-learning-space\/#primaryimage","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2024\/05\/Uznach-4-1.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2024\/05\/Uznach-4-1.jpg","width":500,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/fr\/listings\/lze-immersive-learning-space\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/fr\/angebote\/"},{"@type":"ListItem","position":3,"name":"LzE Immersive Learning Space"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/fr\/#website","url":"https:\/\/schoolaboo.com\/fr\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/fr\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/schoolaboo.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job-listings\/30717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/comments?post=30717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/media\/30750"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/media?parent=30717"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job_listing_region?post=30717"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job-categories?post=30717"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job-types?post=30717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}