{"id":20256,"date":"2020-09-09T22:52:33","date_gmt":"2020-09-09T20:52:33","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=20256"},"modified":"2020-12-22T11:15:43","modified_gmt":"2020-12-22T10:15:43","slug":"rudolf-steiner-schule-muenchenstein","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/fr\/listings\/rudolf-steiner-schule-muenchenstein\/","title":{"rendered":"Rudolf Steiner Schule M\u00fcnchenstein"},"content":{"rendered":"<p>Wir sind ein vielf\u00e4ltiges, internationales und qualifiziertes Kollegium, das mit Leidenschaft, grossem Engagement und einer Portion Idealismus eine hohe Unterrichtsqualit\u00e4t verantwortet. Wir bilden uns laufend weiter, die Beziehungspflege ist uns in der Arbeit mit den Sch\u00fclerinnen und Sch\u00fclern wichtig. Im Team leben wir eine gegenseitig unterst\u00fctzende Zusammenarbeit. Alle Mitarbeitenden \u00fcbernehmen Verantwortung in Schulf\u00fchrung, Schulgestaltung und Schulentwicklung. So schaffen wir einen optimalen Rahmen f\u00fcr die p\u00e4dagogische Arbeit mit den Sch\u00fclerinnen und Sch\u00fclern.<\/p>\n<p>Uns leitet das Kind<br \/>\nUreigen, in sich selbst bestimmt<br \/>\nEntwicklungsraum fordernd<br \/>\nBeziehung suchend und schenkend<br \/>\nUnterwegs \u2013 die Welt zu erkennen, zu lieben, zu gestalten<br \/>\nUns leitet Rudolf Steiners P\u00e4dagogik<br \/>\nLeitbild der Rudolf Steiner Schule M\u00fcnchenstein<br \/>\nEine Schule f\u00fcr unsere Kinder<br \/>\n\u2022 Unsere Schule bildet den Raum zur Entwicklung der Kinder. Hier k\u00f6nnen die Kinder eine gesunde<br \/>\nBeziehung zu sich selbst, zu ihrem Leib und zu ihrer Umwelt finden.<br \/>\n\u2022 Es geht uns um die Bildung des ganzen Menschen, er ist einzigartig und sucht seinen Weg individuell<br \/>\nsowie in der Gemeinschaft.<br \/>\n\u2022 Lernen bedeutet f\u00fcr uns das Aufstrahlen der Zukunft im gegenw\u00e4rtigen kindlichen Erleben, die<br \/>\nlebendige Begegnung von dem, was war, mit dem, was werden will.<br \/>\nEine Schule von forschenden Lehrpersonen<br \/>\n\u2022 Der individuellen Entwicklung des Kindes sind unsere liebevolle Aufmerksamkeit und unser Wirken<br \/>\ngewidmet.<br \/>\n\u2022 Die Lehrpersonen entwickeln sich weiter, um stetig den Raum zu schaffen, in dem die Kinder sich<br \/>\nselbst erziehen lernen.<br \/>\n\u2022 Im Mittelpunkt unseres p\u00e4dagogischen Forschens steht die Bem\u00fchung, den fortw\u00e4hrenden<br \/>\nVer\u00e4nderungen der kindlichen Umwelt gerecht zu werden.<br \/>\nEine Schule als Gemeinschaft<br \/>\n\u2022 Beziehungen sind der Grundstein unseres p\u00e4dagogischen Handelns.<br \/>\n\u2022 Alle Lehrpersonen und alle Sch\u00fclerinnen und Sch\u00fcler kennen sich und arbeiten klassen- und<br \/>\nf\u00e4cher\u00fcbergreifend zusammen.<br \/>\n\u2022 Jahresfeste, k\u00fcnstlerische Anl\u00e4sse und gegenseitiger Austausch erm\u00f6glichen das gemeinsame Erleben<br \/>\nder Schulgemeinschaft.<br \/>\nEine Schule des Zusammenwirkens<br \/>\n\u2022 Eltern und Lehrpersonen tragen zusammen die Verantwortung f\u00fcr die Schule.<br \/>\n\u2022 Lehrpersonen und Eltern gehen eine p\u00e4dagogische Partnerschaft ein, zum Wohl des Kindes.<br \/>\n\u2022 Die Lehrpersonen f\u00fchren die Schule gemeinschaftlich in Selbstverwaltung.<br \/>\nEine Schule, flexibel und innovativ<br \/>\n\u2022 Die Gr\u00f6sse der Schule erm\u00f6glicht uns die gegenseitige Wahrnehmung innerhalb des ganzen<br \/>\nOrganismus.<br \/>\n\u2022 Wir gehen mutig Schulentwicklung und Erneuerungen an, ohne die Kernaufgabe aus den Augen zu<br \/>\nverlieren.<br \/>\n\u2022 Auf Forderungen der Gegenwart erarbeiten wir passende Konzepte im Sinne einer modernen<br \/>\nAuslegung der P\u00e4dagogik Rudolf Steiners.<br \/>\nEine Schule, geborgen im Hof, offen f\u00fcr die Welt<br \/>\n\u2022 Wir sch\u00e4tzen echte Erfahrungen als Gegengewicht zur Begegnung mit der virtuellen Welt.<br \/>\n\u2022 Wir f\u00f6rdern die Beziehung der Kinder zur Natur, zu Pflanzen und Tieren.<br \/>\n\u2022 Wir pflegen die Sprache, die Bildhaftigkeit und die Kunst.<\/p>\n<section class=\"content-col1\">\n<h1 class=\"green\">Organisation<\/h1>\n<div>\n<hr \/>\n<p>Wir sind eine Privatschule in der Region Basel, die Kindern aus allen Bev\u00f6lkerungskreisen offensteht und seit 1989 besteht. Unsere Schule wird von Eltern und Mitarbeitenden gemeinsam gef\u00fchrt. Sie ist ein Ort der Begegnung. Feste, Theaterauff\u00fchrungen, Konzerte und Veranstaltungen bereichern das Schulleben. Wir sind vernetzt mit den Steinerschulen in der Region, in der Schweiz und den \u00fcber 1\u2019000 Steinerschulen weltweit.<\/p>\n<\/div>\n<div><\/div>\n<div>\n<h2 class=\"green\">Vertrauenskreis<\/h2>\n<p>Im Vertrauenskreis besteht eine niederschwellige Anlaufstelle f\u00fcr alle Mitglieder der Schulgemeinschaft, die bei einem Konflikt Beratung oder Unterst\u00fctzung w\u00fcnschen.<\/p>\n<\/div>\n<\/section>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Rudolf Steiner Schule M\u00fcnchenstein Gutenbergstrasse 1 4142 M\u00fcnchenstein","_company_website":"https:\/\/rssm.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[158,414],"job-categories":[103,99],"job-types":[92],"class_list":{"0":"post-20256","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-basel-land","6":"job_listing_region-basel-stadt-land","7":"job_listing_category-kindergarten","8":"job_listing_category-primarschule","9":"job_listing_type-sekundarstufe_1","11":"job-type-sekundarstufe-1-13-16-jahre"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rudolf Steiner Schule M\u00fcnchenstein - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/fr\/listings\/rudolf-steiner-schule-muenchenstein\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rudolf Steiner Schule M\u00fcnchenstein\" \/>\n<meta property=\"og:description\" content=\"Wir sind ein vielf\u00e4ltiges, internationales und qualifiziertes Kollegium, das mit Leidenschaft, grossem Engagement und einer Portion Idealismus eine hohe Unterrichtsqualit\u00e4t verantwortet. Wir bilden uns laufend weiter, die Beziehungspflege ist uns in der Arbeit mit den Sch\u00fclerinnen und Sch\u00fclern wichtig. Im Team leben wir eine gegenseitig unterst\u00fctzende Zusammenarbeit. Alle Mitarbeitenden \u00fcbernehmen Verantwortung in Schulf\u00fchrung, Schulgestaltung und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/fr\/listings\/rudolf-steiner-schule-muenchenstein\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-22T10:15:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/images-2.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/images-2.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/rudolf-steiner-schule-muenchenstein\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/rudolf-steiner-schule-muenchenstein\\\/\",\"name\":\"Rudolf Steiner Schule M\u00fcnchenstein - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#website\"},\"datePublished\":\"2020-09-09T20:52:33+00:00\",\"dateModified\":\"2020-12-22T10:15:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/rudolf-steiner-schule-muenchenstein\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/rudolf-steiner-schule-muenchenstein\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/rudolf-steiner-schule-muenchenstein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rudolf Steiner Schule M\u00fcnchenstein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rudolf Steiner Schule M\u00fcnchenstein - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/fr\/listings\/rudolf-steiner-schule-muenchenstein\/","og_locale":"fr_FR","og_type":"article","og_title":"Rudolf Steiner Schule M\u00fcnchenstein","og_description":"Wir sind ein vielf\u00e4ltiges, internationales und qualifiziertes Kollegium, das mit Leidenschaft, grossem Engagement und einer Portion Idealismus eine hohe Unterrichtsqualit\u00e4t verantwortet. Wir bilden uns laufend weiter, die Beziehungspflege ist uns in der Arbeit mit den Sch\u00fclerinnen und Sch\u00fclern wichtig. Im Team leben wir eine gegenseitig unterst\u00fctzende Zusammenarbeit. Alle Mitarbeitenden \u00fcbernehmen Verantwortung in Schulf\u00fchrung, Schulgestaltung und [&hellip;]","og_url":"https:\/\/schoolaboo.com\/fr\/listings\/rudolf-steiner-schule-muenchenstein\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-12-22T10:15:43+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/images-2.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/images-2.jpg","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/fr\/listings\/rudolf-steiner-schule-muenchenstein\/","url":"https:\/\/schoolaboo.com\/fr\/listings\/rudolf-steiner-schule-muenchenstein\/","name":"Rudolf Steiner Schule M\u00fcnchenstein - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/fr\/#website"},"datePublished":"2020-09-09T20:52:33+00:00","dateModified":"2020-12-22T10:15:43+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/fr\/listings\/rudolf-steiner-schule-muenchenstein\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/fr\/listings\/rudolf-steiner-schule-muenchenstein\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/fr\/listings\/rudolf-steiner-schule-muenchenstein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/fr\/angebote\/"},{"@type":"ListItem","position":3,"name":"Rudolf Steiner Schule M\u00fcnchenstein"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/fr\/#website","url":"https:\/\/schoolaboo.com\/fr\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/fr\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/schoolaboo.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job-listings\/20256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/comments?post=20256"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/media?parent=20256"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job_listing_region?post=20256"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job-categories?post=20256"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job-types?post=20256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}