{"id":20244,"date":"2020-09-09T22:52:33","date_gmt":"2020-09-09T20:52:33","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=20244"},"modified":"2020-10-14T17:42:57","modified_gmt":"2020-10-14T15:42:57","slug":"curaviva-hsl-hoehere-fachschule-fuer-sozialpaedagogik","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/fr\/listings\/curaviva-hsl-hoehere-fachschule-fuer-sozialpaedagogik\/","title":{"rendered":"Curaviva Hsl &#8211; H\u00f6here Fachschule f\u00fcr Sozialp\u00e4dagogik"},"content":{"rendered":"<div class=\"container struktur title\">\n<header>\n<h1 class=\"wwsticky-stick-to\">\u00dcber uns<\/h1>\n<\/header>\n<\/div>\n<div class=\"container struktur\">\n<p>Die H\u00f6here Fachschule f\u00fcr Sozialp\u00e4dagogik Luzern (hsl) ist eine privatrechtlich getragene Institution. Die hsl ist von Bund und Kantonen anerkannt und \u00fcberregional ausgerichtet. Sie entstand 1959 als Heimhelferinnenkurs und entwickelte sich kontinuierlich zur heute bestehenden H\u00f6heren Fachschule f\u00fcr Sozialp\u00e4dagogik. Bis Ende 2002 war der Verband Christlicher Institutionen vci Tr\u00e4ger der hsl. Dieser fusionierte 2003 mit dem Heimverband Schweiz HVS zu CURAVIVA Schweiz. Heute ist die hsl Teil des Gesch\u00e4ftsbereichs Bildung von CURAVIVA Schweiz. Der Bildungsbereich von CURAVIVA Schweiz und die H\u00f6here Fachschule f\u00fcr Sozialp\u00e4dagogik Luzern sind eduQua und ISO zertifiziert.<\/p>\n<\/div>\n<p>Die hsl ist eine renommierte Ausbildungsst\u00e4tte f\u00fcr angehende diplomierte Sozialp\u00e4dagoginnen und Sozialp\u00e4dagogen HF. Sie orientiert sich an einem ganzheitlichen Bildungsprofil und bietet eine praxisbezogene, fachlich fundierte und kreativ-musische Ausbildung. Die vermittelten Berufskompetenzen bef\u00e4higen die Absolventinnen und Absolventen der hsl zur erfolgreichen T\u00e4tigkeit\u00a0 in unterschiedlichen Feldern der sozialen Arbeit.\u00a0An der\u00a0hsl gibt es drei verschiedene Ausbildungswege. Alle drei f\u00fchren zum eidgen\u00f6ssisch anerkannten Abschluss diplomierte Sozialp\u00e4dagogin HF \/ diplomierter Sozialp\u00e4dagoge HF.<\/p>\n<div class=\"container struktur title\">\n<header>\n<h1 class=\"wwsticky-stick-to\">Sozialp\u00e4dagogik<\/h1>\n<\/header>\n<\/div>\n<div class=\"container struktur\">\n<div class=\"lead\">\n<p>Ein Beruf mit vielen Facetten<\/p>\n<\/div>\n<p><a id=\"Beruf\" name=\"beruf-0\"><\/a>Sozialp\u00e4dagogik begleitet Menschen aller Altersstufen, Familien oder Gruppen in Krisen und schwierigen Lebenssituationen. Kennzeichnend ist, dass sie ihren Alltag nicht mehr selbstst\u00e4ndig bew\u00e4ltigen k\u00f6nnen. Ohne Hilfe von aussen droht ihnen der Ausschluss aus der Gesellschaft. Die Sozialp\u00e4dagogik \u00fcbernimmt somit eine bedeutsame Integrationsaufgabe. Sie wirkt vorbeugend, unterst\u00fctzend und erg\u00e4nzend. Im Zentrum steht die intensive Beziehungsarbeit. Ziele sind die Optimierung der Lebensqualit\u00e4t und die gr\u00f6sstm\u00f6gliche Autonomie der Betroffenen.<\/p>\n<h3>Vielf\u00e4ltige Arbeitsfelder<\/h3>\n<article>Sozialp\u00e4dagoginnen und Sozialp\u00e4dagogen sind prim\u00e4r dort im Einsatz, wo Menschen in ihrem sozialen Umfeld zu wenig Halt und Unterst\u00fctzung finden, Kinder, Jugendliche und Erwachsene von ihrer Umwelt ausgegrenzt werden, die schwierige Situation eines Menschen seine Familie, sein Arbeitsumfeld und seinen Freundeskreis \u00fcberfordert.Sozialp\u00e4dagoginnen und Sozialp\u00e4dagogen sind in Institutionen des Erziehungs-, Gesundheits- und Sozialwesens t\u00e4tig, wie<\/p>\n<ul>\n<li>Sonderschulheime, Behinderteneinrichtungen, Therapieheime<\/li>\n<li>Wohngemeinschaften, z. B. f\u00fcr psychisch Kranke, Behinderte, Mutter und Kind, Alterswohngruppen<\/li>\n<li>Sozialp\u00e4dagogische Familienbegleitung; heil und sozialp\u00e4dagogische Grossfamilien<\/li>\n<li>Horte, Tagesheime, Internate<\/li>\n<li>Schulen (Schulsozialp\u00e4dagogik\/arbeit)<\/li>\n<li>Notschlafstellen, Krankenzimmer<\/li>\n<li>Frauenh\u00e4user, Jugendh\u00e4user, Freizeitzentren<\/li>\n<li>Institutionen zur Wiedereingliederung von Drogen und Alkoholkranken<\/li>\n<li>Eingliederungs und Rehabilitationszentren, z. B. Werkst\u00e4tten mit besonderem sozialp\u00e4dagogischem Auftrag<\/li>\n<li>Multikulturelle Vermittlungsarbeit<\/li>\n<li>Institutionen des Strafvollzugs<\/li>\n<li>Projekte verschiedenster Auspr\u00e4gung, z. B. f\u00fcr Langzeiterwerbslose, Obdachlose usw.<\/li>\n<li>Institutionen f\u00fcr Asylsuchende und Fl\u00fcchtlinge<\/li>\n<\/ul>\n<\/article>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"CURAVIVA hsl Abendweg 1 6000 Luzern 6","_company_website":"https:\/\/www.hsl-luzern.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[162],"job-categories":[226],"job-types":[228],"class_list":{"0":"post-20244","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-luzern","6":"job_listing_category-hoehere-fachschule","7":"job_listing_type-tertiaerausbildung","9":"job-type-tertiarausbildung"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Curaviva Hsl - H\u00f6here Fachschule f\u00fcr Sozialp\u00e4dagogik - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/fr\/listings\/curaviva-hsl-hoehere-fachschule-fuer-sozialpaedagogik\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curaviva Hsl - H\u00f6here Fachschule f\u00fcr Sozialp\u00e4dagogik\" \/>\n<meta property=\"og:description\" content=\"\u00dcber uns Die H\u00f6here Fachschule f\u00fcr Sozialp\u00e4dagogik Luzern (hsl) ist eine privatrechtlich getragene Institution. Die hsl ist von Bund und Kantonen anerkannt und \u00fcberregional ausgerichtet. Sie entstand 1959 als Heimhelferinnenkurs und entwickelte sich kontinuierlich zur heute bestehenden H\u00f6heren Fachschule f\u00fcr Sozialp\u00e4dagogik. Bis Ende 2002 war der Verband Christlicher Institutionen vci Tr\u00e4ger der hsl. Dieser fusionierte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/fr\/listings\/curaviva-hsl-hoehere-fachschule-fuer-sozialpaedagogik\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-14T15:42:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/3D504D3835-w-532.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/3D504D3835-w-532.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/curaviva-hsl-hoehere-fachschule-fuer-sozialpaedagogik\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/curaviva-hsl-hoehere-fachschule-fuer-sozialpaedagogik\\\/\",\"name\":\"Curaviva Hsl - H\u00f6here Fachschule f\u00fcr Sozialp\u00e4dagogik - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#website\"},\"datePublished\":\"2020-09-09T20:52:33+00:00\",\"dateModified\":\"2020-10-14T15:42:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/curaviva-hsl-hoehere-fachschule-fuer-sozialpaedagogik\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/curaviva-hsl-hoehere-fachschule-fuer-sozialpaedagogik\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/curaviva-hsl-hoehere-fachschule-fuer-sozialpaedagogik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Curaviva Hsl &#8211; H\u00f6here Fachschule f\u00fcr Sozialp\u00e4dagogik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Curaviva Hsl - H\u00f6here Fachschule f\u00fcr Sozialp\u00e4dagogik - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/fr\/listings\/curaviva-hsl-hoehere-fachschule-fuer-sozialpaedagogik\/","og_locale":"fr_FR","og_type":"article","og_title":"Curaviva Hsl - H\u00f6here Fachschule f\u00fcr Sozialp\u00e4dagogik","og_description":"\u00dcber uns Die H\u00f6here Fachschule f\u00fcr Sozialp\u00e4dagogik Luzern (hsl) ist eine privatrechtlich getragene Institution. Die hsl ist von Bund und Kantonen anerkannt und \u00fcberregional ausgerichtet. Sie entstand 1959 als Heimhelferinnenkurs und entwickelte sich kontinuierlich zur heute bestehenden H\u00f6heren Fachschule f\u00fcr Sozialp\u00e4dagogik. Bis Ende 2002 war der Verband Christlicher Institutionen vci Tr\u00e4ger der hsl. Dieser fusionierte [&hellip;]","og_url":"https:\/\/schoolaboo.com\/fr\/listings\/curaviva-hsl-hoehere-fachschule-fuer-sozialpaedagogik\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-10-14T15:42:57+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/3D504D3835-w-532.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/3D504D3835-w-532.jpg","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/fr\/listings\/curaviva-hsl-hoehere-fachschule-fuer-sozialpaedagogik\/","url":"https:\/\/schoolaboo.com\/fr\/listings\/curaviva-hsl-hoehere-fachschule-fuer-sozialpaedagogik\/","name":"Curaviva Hsl - H\u00f6here Fachschule f\u00fcr Sozialp\u00e4dagogik - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/fr\/#website"},"datePublished":"2020-09-09T20:52:33+00:00","dateModified":"2020-10-14T15:42:57+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/fr\/listings\/curaviva-hsl-hoehere-fachschule-fuer-sozialpaedagogik\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/fr\/listings\/curaviva-hsl-hoehere-fachschule-fuer-sozialpaedagogik\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/fr\/listings\/curaviva-hsl-hoehere-fachschule-fuer-sozialpaedagogik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/fr\/angebote\/"},{"@type":"ListItem","position":3,"name":"Curaviva Hsl &#8211; H\u00f6here Fachschule f\u00fcr Sozialp\u00e4dagogik"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/fr\/#website","url":"https:\/\/schoolaboo.com\/fr\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/fr\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/schoolaboo.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job-listings\/20244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/comments?post=20244"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/media?parent=20244"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job_listing_region?post=20244"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job-categories?post=20244"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job-types?post=20244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}