{"id":20041,"date":"2020-09-09T22:53:23","date_gmt":"2020-09-09T20:53:23","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=20041"},"modified":"2020-10-14T21:12:10","modified_gmt":"2020-10-14T19:12:10","slug":"institut-international-notre-dame-du-lac","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/fr\/listings\/institut-international-notre-dame-du-lac\/","title":{"rendered":"Institut International Notre-Dame du Lac"},"content":{"rendered":"<p>Das Internationale Institut Notre Dame du Lac befindet sich in einer gr\u00fcnen Oase auf einem H\u00fcgel in Genf und ist stets bestrebt, <strong>akademische Spitzenleistungen und die Werte des franz\u00f6sischen Bildungssystems zu erreichen.\u00a0<\/strong>Vor allem aber f\u00f6rdern wir die Freude am Lernen.<\/p>\n<p>Indem wir das Lerntempo jedes Einzelnen respektieren, ermutigen wir die Kinder, sich zu entwickeln und ihnen zu erm\u00f6glichen, das Beste aus ihren ersten Schuljahren herauszuholen.\u00a0Unsere Schule begr\u00fc\u00dft Kinder im Alter zwischen 3 und 11 Jahren in gemischten Vorschul- und Grundschulklassen und f\u00f6rdert personalisiertes Mentoring in einem au\u00dfergew\u00f6hnlichen Umfeld.<\/p>\n<p>In den letzten 70 Jahren haben viele Genfer und internationale Jugendliche an unserer Schule Erfolge erzielt.\u00a0Zwischen der\u00a0<strong>klassischen Wissenschaft und der Verbreitung von Wissen mit modernsten Ger\u00e4ten<\/strong>\u00a0legen wir gro\u00dfen Wert auf die Grundlagen:\u00a0<strong>Lesen lernen, sich ausdr\u00fccken, schreiben und z\u00e4hlen.<\/strong><\/p>\n<p><strong>Ab dem Beginn des akademischen Jahres 2017<\/strong>\u00a0wird die Anzahl der Stunden Englischunterricht auf allen Ebenen verdoppelt, wobei auf das Konzept der Koedukation zur\u00fcckgegriffen wird.\u00a0Wir bei Notre-Dame du Lac sind davon \u00fcberzeugt, dass das\u00a0<strong>Erlernen einer Sprache in jungen Jahren<\/strong> , insbesondere durch das Unterrichten eines Fachs, ein hervorragendes Sprungbrett f\u00fcr den Erfolg in der sp\u00e4teren Bildung und die Offenheit f\u00fcr die Welt darstellt.<\/p>\n<h1>Bildungsansatz<\/h1>\n<div id=\"carousel\" class=\"carousel slide\" data-ride=\"carousel\">\n<div class=\"carousel-inner\"><\/div>\n<\/div>\n<p>Der p\u00e4dagogische Ansatz bei Notre Dame du Lac zielt auf die pers\u00f6nliche Erf\u00fcllung im Studium ab.<\/p>\n<p>Die Klassengr\u00f6\u00dfen reichen von 15 bis 20 Sch\u00fclern, was einen wichtigen Ort f\u00fcr die Begleitung und Nachverfolgung jedes einzelnen Sch\u00fclers darstellt.<\/p>\n<p>Das Kind, das im Mittelpunkt seiner Ausbildung steht, bleibt das wichtigste Leitlicht in unserer P\u00e4dagogik.<\/p>\n<h2>Vorschule<\/h2>\n<p>Das Notre Dame du Lac Institut ist bestrebt, ein fruchtbarer Boden f\u00fcr viele erfolgreiche elementare akademische Erfahrungen zu sein.\u00a0Den Lehrern geht es darum, einen Rahmen und eine Organisation von Aktivit\u00e4ten anzubieten, die jedem einzelnen Sch\u00fcler die Autonomie f\u00f6rdern und ihm gleichzeitig die Zeit geben, ihre ersten sozialen Interaktionen zu entwickeln.\u00a0Das Kind, das die Vorschule betritt, wird nach und nach Sch\u00fcler.<\/p>\n<p>Ab dem 4. Lebensjahr wird besonderes Augenmerk auf den Umgang mit dem Bleistift, die kursive Handschrift, die Entdeckung der Nummerierung und die Kontrolle des gesprochenen Ausdrucks gelegt, die die Grundlage f\u00fcr eine perfekte Beherrschung der franz\u00f6sischen Sprache bilden Sprache.<\/p>\n<p>Eine t\u00e4gliche Aneignung der Schriftsprache beginnt ebenfalls.\u00a0Dieser fortschreitende Aufbau von F\u00e4higkeiten im Rhythmus des Kindes setzt sich bis zum Alter von 5 Jahren fort, um die Vorliebe f\u00fcr ein perfektes Erlernen des Lesens und Schreibens an der Schwelle zur Grundschule zu gew\u00e4hrleisten.<\/p>\n<h2>Grundschule<\/h2>\n<p>Die Grundschule begleitet ihre Sch\u00fcler in der Beherrschung der franz\u00f6sischen Sprache in Wort und Schrift, hin zu einer Autonomie des mathematischen Denkens und dem \u00dcben von Fremdsprachen.<\/p>\n<p>Diese Fondationen sind ein wesentliches Sprungbrett f\u00fcr eine erfolgreiche und erf\u00fcllende Skolarit\u00e4t.<\/p>\n<p>Ab dem 6. Lebensjahr strukturieren die Sch\u00fcler ihr Verst\u00e4ndnis durch Lese-Workshops sowie unterhaltsame und herausfordernde mathematische Dispositive.\u00a0Die Lehrer bieten Methoden an, die ihrem Lernen einen echten Sinn geben.<\/p>\n<p>In regelm\u00e4\u00dfigen Abst\u00e4nden werden Bewertungen abgegeben, um die Wissenschaft der Sch\u00fcler zu leiten, ihre Fortschritte hervorzuheben und zu korrekten und individuellen Folgema\u00dfnahmen zu f\u00fchren.<\/p>\n<p>Informationswissenschaftliche Studien und erg\u00e4nzende F\u00e4cher sind unbestreitbare Vorteile bei der \u00d6ffnung zu einem h\u00f6heren Niveau des Allgemeinwissens.<\/p>\n<p>Jede Klasse n\u00e4hrt auf angenehme Weise das Jahr mit Kulturprojekten in Phase des Programms.<\/p>\n<p>Die Sch\u00fcler erwerben Hand in Hand mit unseren Lehrern Kompetenzen in Bezug auf Autonomie und Eigeninitiative in Bezug auf die humanistische Kultur auf dem Weg zu Spitzenleistungen.<\/p>\n<h1>Ein au\u00dfergew\u00f6hnlicher Ort<\/h1>\n<div id=\"carousel\" class=\"carousel slide\" data-ride=\"carousel\">\n<div class=\"carousel-inner\">\n<div class=\"item active\"><\/div>\n<\/div>\n<\/div>\n<p>Direkt aus dem 18. Jahrhundert beherbergt die Boissier-Dom\u00e4ne seit 1946 das Notre Dame International Institute &#8211; insgesamt 70 Jahre!\u00a0Im Herzen dieses privilegierten Raums profitieren Kinder im Alter von 4 bis 11 Jahren vom Charme der B\u00e4ume, der Weite, des Gr\u00fcns und der idealen Lage am Genfer See, die alle von dieser magischen St\u00e4tte geboten werden.<\/p>\n<p>Dieses Universum irgendwo zwischen unserer Zeit und der der Geschichte ist der Grundstein f\u00fcr die Bildung und Lehre, die wir unseren Sch\u00fclern bieten m\u00f6chten: eine reiche Kultur, die in soliden, unbestreitbaren, realen und klaren Grundlagen verankert ist, und die Bereitschaft, zu wachsen und nach vorne zu schauen in die Zukunft, versickert in den Werten des Friedens, des Respekts und der Toleranz, die die ganze Gr\u00f6\u00dfe des Menschen ausmachen.<\/p>\n<p>Unsere Ambitionen lassen sich in wenigen Worten zusammenfassen: Tradition, hohe Standards, Disziplin, Strenge, Respekt und Exzellenz.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Institut International Notre-Dame du Lac Chemin Notre-Dame du Lac, 5 1223 Genf, Schweiz","_company_website":"https:\/\/www.notre-dame-du-lac.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[172],"job-categories":[110,103,229,99],"job-types":[90,5,230],"class_list":{"0":"post-20041","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-genf","6":"job_listing_category-franzoesisches-schulprogramm-baccalaureat","7":"job_listing_category-kindergarten","8":"job_listing_category-vorkindergarten","9":"job_listing_category-primarschule","10":"job_listing_type-kindergarten","11":"job_listing_type-primarschule","12":"job_listing_type-vorkindergarten","14":"job-type-kindergarten-4-6-jahre","15":"job-type-primarschule-7-12jahre","16":"job-type-vorkindergarten"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Institut International Notre-Dame du Lac - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/fr\/listings\/institut-international-notre-dame-du-lac\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Institut International Notre-Dame du Lac\" \/>\n<meta property=\"og:description\" content=\"Das Internationale Institut Notre Dame du Lac befindet sich in einer gr\u00fcnen Oase auf einem H\u00fcgel in Genf und ist stets bestrebt, akademische Spitzenleistungen und die Werte des franz\u00f6sischen Bildungssystems zu erreichen.\u00a0Vor allem aber f\u00f6rdern wir die Freude am Lernen. Indem wir das Lerntempo jedes Einzelnen respektieren, ermutigen wir die Kinder, sich zu entwickeln und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/fr\/listings\/institut-international-notre-dame-du-lac\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-14T19:12:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/Institut-International-Notre-Dame-du-Lac.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/Institut-International-Notre-Dame-du-Lac.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/institut-international-notre-dame-du-lac\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/institut-international-notre-dame-du-lac\\\/\",\"name\":\"Institut International Notre-Dame du Lac - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#website\"},\"datePublished\":\"2020-09-09T20:53:23+00:00\",\"dateModified\":\"2020-10-14T19:12:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/institut-international-notre-dame-du-lac\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/institut-international-notre-dame-du-lac\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/listings\\\/institut-international-notre-dame-du-lac\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Institut International Notre-Dame du Lac\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Institut International Notre-Dame du Lac - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/fr\/listings\/institut-international-notre-dame-du-lac\/","og_locale":"fr_FR","og_type":"article","og_title":"Institut International Notre-Dame du Lac","og_description":"Das Internationale Institut Notre Dame du Lac befindet sich in einer gr\u00fcnen Oase auf einem H\u00fcgel in Genf und ist stets bestrebt, akademische Spitzenleistungen und die Werte des franz\u00f6sischen Bildungssystems zu erreichen.\u00a0Vor allem aber f\u00f6rdern wir die Freude am Lernen. Indem wir das Lerntempo jedes Einzelnen respektieren, ermutigen wir die Kinder, sich zu entwickeln und [&hellip;]","og_url":"https:\/\/schoolaboo.com\/fr\/listings\/institut-international-notre-dame-du-lac\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-10-14T19:12:10+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/Institut-International-Notre-Dame-du-Lac.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/Institut-International-Notre-Dame-du-Lac.jpg","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/fr\/listings\/institut-international-notre-dame-du-lac\/","url":"https:\/\/schoolaboo.com\/fr\/listings\/institut-international-notre-dame-du-lac\/","name":"Institut International Notre-Dame du Lac - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/fr\/#website"},"datePublished":"2020-09-09T20:53:23+00:00","dateModified":"2020-10-14T19:12:10+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/fr\/listings\/institut-international-notre-dame-du-lac\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/fr\/listings\/institut-international-notre-dame-du-lac\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/fr\/listings\/institut-international-notre-dame-du-lac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/fr\/angebote\/"},{"@type":"ListItem","position":3,"name":"Institut International Notre-Dame du Lac"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/fr\/#website","url":"https:\/\/schoolaboo.com\/fr\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/fr\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/schoolaboo.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job-listings\/20041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/comments?post=20041"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/media?parent=20041"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job_listing_region?post=20041"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job-categories?post=20041"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/fr\/wp-json\/wp\/v2\/job-types?post=20041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}