{"id":20217,"date":"2020-09-09T22:52:33","date_gmt":"2020-09-09T20:52:33","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=20217"},"modified":"2020-10-14T20:39:47","modified_gmt":"2020-10-14T18:39:47","slug":"ecole-catholique-du-valentin","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/es\/listings\/ecole-catholique-du-valentin\/","title":{"rendered":"Ecole Catholique du Valentin"},"content":{"rendered":"<p class=\"font_8\">Die \u00c9cole Catholique du Valentin ist eine private gemeinn\u00fctzige Schule, die Kinder aus Kleinkindklassen ohne Diskriminierung aufgrund des sozialen, kulturellen oder religi\u00f6sen Hintergrunds in der Turnhalle willkommen hei\u00dft.<\/p>\n<p class=\"font_8\"><span class=\"inherit-font-size\">Dar\u00fcber hinaus m\u00fcssen Sie mehr dar\u00fcber wissen.<\/span><\/p>\n<p class=\"font_8\">Es implementiert einen globalen, ausdr\u00fccklich Christian Bildungsprojekt und arbeitet in enger Zusammenarbeit mit den Schulen in der Vereinigung der Schweizeren katholische Schulen (ECS) vereint ,\u00a0von denen es ein Mitglied und Unterzeichner der ist\u00a0\u00a0Charta\u00a0.<\/p>\n<p class=\"font_8\"><span class=\"wixGuard\">Dar\u00fcber hinaus m\u00fcssen Sie mehr dar\u00fcber wissen.<\/span><\/p>\n<p class=\"font_8\">Mit dem vielf\u00e4ltigen Angebot an Schulen im Kanton Waadt will sie eine originelle P\u00e4dagogik entwickeln und damit Familien eine echte Bildungsalternative bieten.<\/p>\n<div id=\"comp-ka41w5ki\" class=\"txtNew\" data-packed=\"true\" data-vertical-text=\"false\">\n<h2 class=\"font_2\">Seit 1816 die Wurzeln eines harmonischen Wachstums<\/h2>\n<\/div>\n<div id=\"comp-ka41w5kp\" class=\"style-j4tpwfsd\" data-is-absolute-layout=\"false\">\n<div id=\"comp-ka41w5kpbg\" class=\"style-j4tpwfsdbg\"><\/div>\n<div id=\"comp-ka41w5kpinlineContent\" class=\"style-j4tpwfsdinlineContent\">\n<div id=\"comp-ka41w5kpinlineContent-gridWrapper\" data-mesh-internal=\"true\">\n<div id=\"comp-ka41w5kpinlineContent-gridContainer\" data-mesh-internal=\"true\">\n<div id=\"comp-ka41w5kv\" class=\"txtNew\" data-packed=\"false\" data-vertical-text=\"false\" data-min-height=\"151\">\n<p class=\"font_8\">Die katholische Schule von Valentin (LE VALENTIN) ist eine der \u00e4ltesten Schulen am Place de Lausanne.\u00a0LE VALENTIN wurde 1816 von Marie Rivier gegr\u00fcndet. Seit August 2003 ist LE VALENTIN eine gemeinn\u00fctzige Stiftung und befindet sich im Herzen der Stadt neben der Basilika Notre-Dame.\u00a0Die Gr\u00fcndung der \u00c9cole Catholique du Valentin ist mit der Wiederbelebung des Katholizismus in Lausanne verbunden.\u00a0In der Tat wurde 1816 die katholische Schule von Lausanne geboren.\u00a0Die in der Rue de la Mercerie gegr\u00fcndete katholische Schule von Valentine hatte zu Beginn nur etwa zehn Sch\u00fcler.\u00a0Diese Zahl w\u00e4chst rasant und ist ein klarer Beweis f\u00fcr die Notwendigkeit einer solchen Einrichtung, die in erster Linie Jungen vorbehalten ist.\u00a0Die M\u00e4dchenschule folgte bald im Jahr 1826. Sie wurde 1841 den Schwestern der Darstellung Mariens anvertraut.\u00a0Zwei Jahre sp\u00e4ter waren die Br\u00fcder Maria an der Reihe, die Jungen zu unterrichten.\u00a0Sie werden 40 Jahre sp\u00e4ter zur\u00fcckgerufen und 1914 den Marist Brothers weichen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"comp-ka41w5l2\" class=\"txtNew\" data-packed=\"true\" data-vertical-text=\"false\">\n<h2 class=\"font_2\">Im Stadtzentrum<\/h2>\n<\/div>\n<div id=\"comp-ka41w5lb\" class=\"style-j4tpwfsd\" data-is-absolute-layout=\"false\">\n<div id=\"comp-ka41w5lbbg\" class=\"style-j4tpwfsdbg\"><\/div>\n<div id=\"comp-ka41w5lbinlineContent\" class=\"style-j4tpwfsdinlineContent\">\n<div id=\"comp-ka41w5lbinlineContent-gridWrapper\" data-mesh-internal=\"true\">\n<div id=\"comp-ka41w5lbinlineContent-gridContainer\" data-mesh-internal=\"true\">\n<div id=\"comp-ka41w5lk\" class=\"txtNew\" data-packed=\"false\" data-vertical-text=\"false\" data-min-height=\"151\">\n<p class=\"font_8\">Die Gr\u00fcndung der katholischen Schule von Valentin, die an die Pfarrei Notre-Dame angrenzt, stammt aus dem Jahr 1865. Mitten im Zentrum von Lausanne, leicht zug\u00e4nglich, genie\u00dft LE VALENTIN dennoch eine ruhige Lage und eine g\u00fcnstige Umgebung eine ruhige Studie.\u00a0Die katholische Valentinstagschule hat sich nat\u00fcrlich perfekt an die Daten unserer Zeit angepasst.\u00a0Die Klassen sind seit 1972 gemischt, die Verwaltung und das Lehrpersonal stehen heutzutage unter der Verantwortung von Laien und die Geb\u00e4ude wurden 1995 vollst\u00e4ndig restauriert. Reich an menschlichen und spirituellen Werten, Erbe von 190 Jahren Unterricht durch Qualit\u00e4t, unsere Schule will f\u00fcr alle zug\u00e4nglich sein.<\/p>\n<div id=\"comp-ka41w5m3\" class=\"txtNew\" data-packed=\"true\" data-vertical-text=\"false\"><\/div>\n<div id=\"comp-ka41w70j\" class=\"txtNew\" data-packed=\"false\" data-vertical-text=\"false\" data-min-height=\"75\">\n<p class=\"font_8\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Rue du Valentin 7 1004 Lausanne","_company_website":"https:\/\/www.levalentin.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[],"job-categories":[99,76],"job-types":[5,92],"class_list":{"0":"post-20217","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_category-primarschule","6":"job_listing_category-sekundarstufe_1","7":"job_listing_type-primarschule","8":"job_listing_type-sekundarstufe_1","10":"job-type-primarschule-7-12jahre","11":"job-type-sekundarstufe-1-13-16-jahre"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ecole Catholique du Valentin - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/es\/listings\/ecole-catholique-du-valentin\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecole Catholique du Valentin\" \/>\n<meta property=\"og:description\" content=\"Die \u00c9cole Catholique du Valentin ist eine private gemeinn\u00fctzige Schule, die Kinder aus Kleinkindklassen ohne Diskriminierung aufgrund des sozialen, kulturellen oder religi\u00f6sen Hintergrunds in der Turnhalle willkommen hei\u00dft. Dar\u00fcber hinaus m\u00fcssen Sie mehr dar\u00fcber wissen. Es implementiert einen globalen, ausdr\u00fccklich Christian Bildungsprojekt und arbeitet in enger Zusammenarbeit mit den Schulen in der Vereinigung der Schweizeren [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/es\/listings\/ecole-catholique-du-valentin\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-14T18:39:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/Download-2-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/Download-2-1.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/listings\\\/ecole-catholique-du-valentin\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/listings\\\/ecole-catholique-du-valentin\\\/\",\"name\":\"Ecole Catholique du Valentin - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/#website\"},\"datePublished\":\"2020-09-09T20:52:33+00:00\",\"dateModified\":\"2020-10-14T18:39:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/listings\\\/ecole-catholique-du-valentin\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/es\\\/listings\\\/ecole-catholique-du-valentin\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/listings\\\/ecole-catholique-du-valentin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ecole Catholique du Valentin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ecole Catholique du Valentin - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/es\/listings\/ecole-catholique-du-valentin\/","og_locale":"es_ES","og_type":"article","og_title":"Ecole Catholique du Valentin","og_description":"Die \u00c9cole Catholique du Valentin ist eine private gemeinn\u00fctzige Schule, die Kinder aus Kleinkindklassen ohne Diskriminierung aufgrund des sozialen, kulturellen oder religi\u00f6sen Hintergrunds in der Turnhalle willkommen hei\u00dft. Dar\u00fcber hinaus m\u00fcssen Sie mehr dar\u00fcber wissen. Es implementiert einen globalen, ausdr\u00fccklich Christian Bildungsprojekt und arbeitet in enger Zusammenarbeit mit den Schulen in der Vereinigung der Schweizeren [&hellip;]","og_url":"https:\/\/schoolaboo.com\/es\/listings\/ecole-catholique-du-valentin\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-10-14T18:39:47+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/Download-2-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/Download-2-1.jpg","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/es\/listings\/ecole-catholique-du-valentin\/","url":"https:\/\/schoolaboo.com\/es\/listings\/ecole-catholique-du-valentin\/","name":"Ecole Catholique du Valentin - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/es\/#website"},"datePublished":"2020-09-09T20:52:33+00:00","dateModified":"2020-10-14T18:39:47+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/es\/listings\/ecole-catholique-du-valentin\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/es\/listings\/ecole-catholique-du-valentin\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/es\/listings\/ecole-catholique-du-valentin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/es\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/es\/angebote\/"},{"@type":"ListItem","position":3,"name":"Ecole Catholique du Valentin"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/es\/#website","url":"https:\/\/schoolaboo.com\/es\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/es\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/schoolaboo.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/es\/wp-json\/wp\/v2\/job-listings\/20217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/es\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/es\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/es\/wp-json\/wp\/v2\/comments?post=20217"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/es\/wp-json\/wp\/v2\/media?parent=20217"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/es\/wp-json\/wp\/v2\/job_listing_region?post=20217"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/es\/wp-json\/wp\/v2\/job-categories?post=20217"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/es\/wp-json\/wp\/v2\/job-types?post=20217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}