{"id":19919,"date":"2020-09-09T22:53:52","date_gmt":"2020-09-09T20:53:52","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=19919"},"modified":"2020-10-10T11:03:46","modified_gmt":"2020-10-10T09:03:46","slug":"ecole-medica-sa","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/es\/listings\/ecole-medica-sa\/","title":{"rendered":"Ecole Medica SA"},"content":{"rendered":"<h4><strong>UNSERE AUFGABE<\/strong><\/h4>\n<ul>\n<li>Begr\u00fc\u00dfen und bereiten Sie unsere Auszubildenden und Studenten auf den Erfolg in der gew\u00e4hlten Ausbildung vor.<\/li>\n<li>Ermutigen und motivieren Sie ihr Lernen.<\/li>\n<li>Entwickeln Sie in unseren Auszubildenden und Studenten autonome Arbeit, Vertrauen, Verantwortungsbewusstsein und Respekt.<\/li>\n<li>Tragen Sie zu ihrem beruflichen Erfolg bei.<\/li>\n<li>Bem\u00fchen Sie sich, unsere Auszubildenden oder Studenten in Schwierigkeiten in Zusammenarbeit mit Ausbildern des Unternehmens, gesetzlichen Vertretern und durch zus\u00e4tzliche Kurse zu unterst\u00fctzen.<\/li>\n<li>Wenden Sie die vollst\u00e4ndige Ausbildung strikt gem\u00e4\u00df den von SERI und H + festgelegten Programmen an.<\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><\/p>\n<h4><strong>UNSERE RESSOURCEN<\/strong><\/h4>\n<p>Die M\u00c9DICA School verpflichtet sich:<\/p>\n<ul>\n<li>Stellen Sie qualifizierte, kompetente Lehrer mit einer Haltung der Loyalit\u00e4t, des Respekts und der Gerechtigkeit ein, um eine qualitativ hochwertige Ausbildung zu gew\u00e4hrleisten.<\/li>\n<li>Unterst\u00fctzen Sie die Trainer bei ihren Bem\u00fchungen und geben Sie ihnen die Werkzeuge, die f\u00fcr das ordnungsgem\u00e4\u00dfe Funktionieren ihrer Aktivit\u00e4ten und f\u00fcr ihre kontinuierliche Ausbildung erforderlich sind<\/li>\n<li>Wissen vermitteln, aber auch Know-how und zwischenmenschliche F\u00e4higkeiten.<\/li>\n<li>F\u00f6rderung einer guten Atmosph\u00e4re im Unterricht und des gegenseitigen Respekts gegen\u00fcber Ausbildern, Auszubildenden und Sch\u00fclern.<\/li>\n<\/ul>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Avenue de la Gare 44, 1003 Lausanne, Schweiz","_company_website":"https:\/\/www.ecole-medica.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[],"job-categories":[],"job-types":[],"class_list":["post-19919","job_listing","type-job_listing","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ecole Medica SA - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/es\/listings\/ecole-medica-sa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecole Medica SA\" \/>\n<meta property=\"og:description\" content=\"UNSERE AUFGABE Begr\u00fc\u00dfen und bereiten Sie unsere Auszubildenden und Studenten auf den Erfolg in der gew\u00e4hlten Ausbildung vor. Ermutigen und motivieren Sie ihr Lernen. Entwickeln Sie in unseren Auszubildenden und Studenten autonome Arbeit, Vertrauen, Verantwortungsbewusstsein und Respekt. Tragen Sie zu ihrem beruflichen Erfolg bei. Bem\u00fchen Sie sich, unsere Auszubildenden oder Studenten in Schwierigkeiten in Zusammenarbeit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/es\/listings\/ecole-medica-sa\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-10T09:03:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/eduqua.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/eduqua.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/listings\\\/ecole-medica-sa\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/listings\\\/ecole-medica-sa\\\/\",\"name\":\"Ecole Medica SA - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/#website\"},\"datePublished\":\"2020-09-09T20:53:52+00:00\",\"dateModified\":\"2020-10-10T09:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/listings\\\/ecole-medica-sa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/es\\\/listings\\\/ecole-medica-sa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/listings\\\/ecole-medica-sa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ecole Medica SA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ecole Medica SA - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/es\/listings\/ecole-medica-sa\/","og_locale":"es_ES","og_type":"article","og_title":"Ecole Medica SA","og_description":"UNSERE AUFGABE Begr\u00fc\u00dfen und bereiten Sie unsere Auszubildenden und Studenten auf den Erfolg in der gew\u00e4hlten Ausbildung vor. Ermutigen und motivieren Sie ihr Lernen. Entwickeln Sie in unseren Auszubildenden und Studenten autonome Arbeit, Vertrauen, Verantwortungsbewusstsein und Respekt. Tragen Sie zu ihrem beruflichen Erfolg bei. Bem\u00fchen Sie sich, unsere Auszubildenden oder Studenten in Schwierigkeiten in Zusammenarbeit [&hellip;]","og_url":"https:\/\/schoolaboo.com\/es\/listings\/ecole-medica-sa\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-10-10T09:03:46+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/eduqua.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/eduqua.jpg","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/es\/listings\/ecole-medica-sa\/","url":"https:\/\/schoolaboo.com\/es\/listings\/ecole-medica-sa\/","name":"Ecole Medica SA - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/es\/#website"},"datePublished":"2020-09-09T20:53:52+00:00","dateModified":"2020-10-10T09:03:46+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/es\/listings\/ecole-medica-sa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/es\/listings\/ecole-medica-sa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/es\/listings\/ecole-medica-sa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/es\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/es\/angebote\/"},{"@type":"ListItem","position":3,"name":"Ecole Medica SA"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/es\/#website","url":"https:\/\/schoolaboo.com\/es\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/es\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/schoolaboo.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/es\/wp-json\/wp\/v2\/job-listings\/19919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/es\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/es\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/es\/wp-json\/wp\/v2\/comments?post=19919"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/es\/wp-json\/wp\/v2\/media?parent=19919"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/es\/wp-json\/wp\/v2\/job_listing_region?post=19919"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/es\/wp-json\/wp\/v2\/job-categories?post=19919"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/es\/wp-json\/wp\/v2\/job-types?post=19919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}