{"id":23297,"date":"2020-12-14T13:29:40","date_gmt":"2020-12-14T12:29:40","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=23297"},"modified":"2020-12-14T13:29:40","modified_gmt":"2020-12-14T12:29:40","slug":"tany-fitiavana","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/en\/listings\/tany-fitiavana\/","title":{"rendered":"Tany Fitiavana"},"content":{"rendered":"<div id=\"comp-k8etlplp\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<h3 class=\"font_3\">Leitgedanke<\/h3>\n<\/div>\n<div id=\"comp-k8eub891\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\">\u2015 Kinder speichern Informationen, aber wir m\u00fcssen ebenfalls daran denken, dass sie auch Gef\u00fchle speichern. Ihnen die Freiheit zu geben\u00a0zu denken, zu f\u00fchlen und zu sein &#8211; ist genauso wichtig, wie das Wissen,\u00a0das wir teilen. \u2015<\/p>\n<\/div>\n<div id=\"comp-k8etlpm0\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\"><span class=\"color_30\">Tany Fitiavanas Schl\u00fcsselkonzept ist es, das organische und nat\u00fcrliche Lernen zu unterst\u00fctzen, indem wir einen holistischen Ansatz ehren. Das wird bei uns in allen R\u00e4umen sowie im gesamten Umfeld der Schule ersichtlich sein.<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">In unseren Augen bedeutet organisches Lernen, wenn keine Vorgehensweise vorgeschrieben wird, um ein Problem zu l\u00f6sen oder eine Herausforderung anzugehen. Ziel ist es, der Neugier des Kindes unendlich viel Platz zu lassen, damit diese aufbl\u00fchen kann und die Kinder innovative Wege gehen k\u00f6nnen.<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Kinder fragen oft &#8216;wie&#8217;\u00a0sie die Sachen machen sollen oder &#8216;was&#8217;\u00a0sie dazu brauchen. Anstatt Ihnen unsere L\u00f6sungen zu pr\u00e4sentieren, geben wir ihnen die M\u00f6glichkeit, ihr eigenes Potenzial zu nutzen. W\u00e4hrend sie ihre eigene Kreativit\u00e4t anzapfen, definieren sie von selbst ihr nat\u00fcrliches Lernen.<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Wir glauben durch Fragen wie &#8216;Was meinst du, wie k\u00f6nnte das funktionieren?&#8217;\u00a0oder &#8216;Was brauchen wir deiner Meinung nach, um das m\u00f6glich zu machen?&#8217;\u00a0bef\u00e4higen wir die Kinder ihrer Intuition zu vertrauen und die eigene Vorstellungskraft zu benutzen.<\/span><\/p>\n<\/div>\n<div id=\"comp-k8eujan1\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\">\u2015 In\u00a0unsere Augen gibt es keine kreativen &#8216;Fehler&#8217;. \u2015<\/p>\n<\/div>\n<div id=\"comp-k8euppuk\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\"><span class=\"color_30\">Oft ist es ein Umlernen, das f\u00fcr uns Erwachsene stattfinden muss. Es kann sehr herausfordernd sein, unseren eigenen Werten und Zielen treu zu bleiben, selbst wenn wir die sch\u00f6nsten Lernerfahrungen f\u00fcr die Kinder organisieren. Gleichzeitig k\u00f6nnen wir sie durch unsere eigene Weiterentwicklung inspirieren. Indem wir vorzeigen, wie positiv wir uns Herausforderungen stellen, motivieren wir unsere Mitmenschen, egal ob gross oder klein, nicht aufzugeben und diese ebenfalls zu akzeptieren und gemeinsam anzupacken.<\/span><\/p>\n<\/div>\n<div id=\"comp-k8euqx14\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\">\u2015 Wir brauchen unsere Kinder nicht zu erziehen, sie machen uns sowieso alles nach. \u2015<\/p>\n<p class=\"font_7\">Karl Valentin<\/p>\n<\/div>\n<div id=\"comp-k8eutji6\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\"><span class=\"color_30\">Wir, die Erwachsenen, die am Schulalltag teilnehmen, sind bestrebt, diesen Lernansatz vollst\u00e4ndig zu verk\u00f6rpern und alle unsere Grundwerte zu respektieren und zu pflegen, indem wir unser Denken reflektieren und als Werkzeug f\u00fcr gegenseitige Achtung nutzen. Zudem stehen wir auch jederzeit zur Verf\u00fcgung, um zu helfen, zu unterst\u00fctzen und nat\u00fcrlich um unser Wissen zu teilen.<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Die Gew\u00e4hrung von Autonomie und die M\u00f6glichkeit, mit gleichgesinnten Menschen in einer friedlichen und liebevollen Umgebung zu interagieren, ist die Grundlage f\u00fcr die Erziehung unserer Kinder, welche wir jeden Tag aufs Neue ausleben m\u00f6chten.<\/span><\/p>\n<div id=\"comp-k8g7r04q\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<h3 class=\"font_3\">Frei<\/h3>\n<\/div>\n<div id=\"comp-k8g80rez\" class=\"_3nfU6 ignore-focus\" tabindex=\"-1\" role=\"region\" aria-label=\"Frei\"><\/div>\n<div id=\"comp-k8g7r04u\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\">\u2015 Das Gegenteil von Gehorsamkeit ist die Sch\u00f6pfung. \u2015<\/p>\n<p class=\"font_7\">Whole Beings<\/p>\n<\/div>\n<div id=\"comp-k8g7r04y\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\"><span class=\"color_30\">Es gibt so viele verschiedene Lernmethoden und noch mehr unterschiedliche Interpretationen dieser Techniken.\u00a0Wir versuchen viele nat\u00fcrliche und nachhaltige Lehrmittel zu benutzen und das Lernumfeld so magisch wie m\u00f6glich einzurichten. Sind wir wegen dieser Vorgehensweise eine Steiner Schule? &#8211; Nein, sind wir nicht. Unsere Einstellung zu Bewertungen, wie Noten und Zeugnisse sind \u00e4hnlich, wie die Ansichten der Steiner oder Montessori Schule, aber deswegen folgen wir nicht ihrem ganzen Programm. Wir geben den Kindern die M\u00f6glichkeit, ihre t\u00e4glichen Aktivit\u00e4ten frei von Verpflichtungen und Erwartungen zu w\u00e4hlen. Bedeutet dies, dass wir Erwachsene nur Zuschauer sind? &#8211; Dies k\u00f6nnte nicht weiter von unserer Realit\u00e4t des freien Lernens entfernt sein.<\/span><\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Tany&#8217;s Kernteam und Mitwirkende bieten\u00a0den Kindern f\u00e4cher\u00fcbergreifende Kurse nach Lernplan 21 an. Diese werden mit Absprache ausgew\u00e4hlt und je nach Interesse der Schulgemeinschaft gestalltet. Die Kinder k\u00f6nnen sich dann selbst\u00e4ndig f\u00fcr die Kurse verpflichten. Durch das gemeinsame Planen und Teilen\u00a0der Verantwortung, st\u00e4rken wir ihr Selbstvertrauen und die verschiedenen Kompetenzen des Lehrplans 21 werden kontinuirlich abgedeckt und ge\u00fcbt.<\/span><\/p>\n<\/div>\n<div id=\"comp-k8g7r056\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\">\u2015 Lernen ist Leben, ohne Trennung oder Unterscheidung.\u00a0 Ein Schulprogramm, das nicht in eine Kiste passt, kann nicht auf eine einzige Theorie beschr\u00e4nkt werden.\u00a0\u2015<\/p>\n<p class=\"font_7\">Whole Beings<\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Von dem Moment an, in dem ein Kind geboren wird, wendet es das Prinzip des \u201aFreien Lernens\u2018 an. Es entwickelt sich weiter durch das Leben selbst und verarbeitet neu Erlerntes mit jedem Atemzug. Es lernt selbstst\u00e4ndig zu laufen, zu sprechen und durch Geist, K\u00f6rper und Seele mit der Aussenwelt zu interagieren. Diese Entwicklungsphasen sind Teil vom Leben und Kinder erleben diese durch das Spielen, Beobachten, Imitieren, Versuchen, Scheitern und schlussendlich durch das Gelingen. In unserer Schule lassen wir sie diese erfolgreiche Reise fortsetzen, indem wir keine Grenze zwischen Lern- und Spielzeit setzen, weil das f\u00fcr uns ein und dasselbe ist. Dadurch wird der\u00a0gesamte erforderliche Schulstoff, durch ihren selbst entworfenen Stundenplan beil\u00e4ufig und in ihrem individuellen Tempo erlernt.<\/span><\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\">\u2015 Das Spiel ist die h\u00f6chste Form der Forschung.\u00a0\u2015<\/p>\n<p class=\"font_7\">Albert Einstein<\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Seth Godin,\u00a0ein US-amerikanischer Autor,\u00a0schrieb in einem seiner vielen grossartigen Artikel\u00a0&#8211; Wir wurden von klein auf zur Gehorsamkeit erzogen. Das Gegenteil von Gehorsamkeit, so sagt man uns, ist Versagen. &#8211; Unsere Schule aber ermutigt\u00a0den furchtlosen Ansatz zu diesem Versagen, denn wir glauben, dass der gleiche Boden, auf dem Fehler gemacht werden, auch der Boden ist, auf dem Wachstum und Erfolge durch unsere unerschrockene Kreativit\u00e4t erbl\u00fchen. Durch unsere Augen navigiert Tany Fitiavana auf zu neuen Ufern.<\/span><\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\">\u2015 Du lernst nicht, indem du Regeln befolgst. Du lernst durch das Tun und Hinfallen.\u00a0\u2015<\/p>\n<p class=\"font_7\">Richard Brason<\/p>\n<div id=\"comp-k8gamrrn\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<h3 class=\"font_3\">Gemeinschaftlich<\/h3>\n<\/div>\n<div id=\"comp-k8gawscr\" class=\"_3nfU6 ignore-focus\" tabindex=\"-1\" role=\"region\" aria-label=\"Gemeinshaftlich\"><\/div>\n<div id=\"comp-k8gamrs4\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\">\u2015 Das ist die Macht der Versammlung: Sie inspiriert uns\u00a0hoffnungsvoller, freudiger und\u00a0nachdenklicher zu sein.\u00a0In einem Wort: Lebendiger. \u2015<\/p>\n<p class=\"font_7\">Alice Walker<\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<\/div>\n<div id=\"comp-k8gamrso\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\"><span class=\"color_30\">Kinder beobachten, wie andere Essen zubereiten, meditieren, sich um den Garten k\u00fcmmern, B\u00fccher lesen, Tageb\u00fccher schreiben, sich die Z\u00e4hne putzen und weiteren t\u00e4glichen Besch\u00e4ftigungen nachgehen, aber auch, wie Mitmenschen Emotionen verarbeiten und mit der Welt interagieren. Es liegt in unserer Natur\u00a0Handlungen zu kopieren, die mit unseren inneren Werten oder unserem derzeitigen emotionalen Zustand \u00fcbereinstimmen.<\/span><\/p>\n<\/div>\n<div id=\"comp-k8gamrt5\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\">\u2015 Je einzigartiger, bunter und mitf\u00fchlender die Lerngemeinschaft f\u00fcr ein Kind ist, desto gr\u00f6sser ist die Chance, sich in die Richtung eines gl\u00fccklichen und erf\u00fcllten Erwachsenenlebens zu entwickeln.\u00a0\u2015<\/p>\n<p class=\"font_7\">Louise<\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">In diesem Sinne wollen wir eine freundliche und liebevolle Gemeinschaft erschaffen, die die Vielfalt und individuelle Einzigartigkeit ehrt und die pers\u00f6nlichen Bed\u00fcrfnisse respektiert. In Tany Fitiavana sind wir alle gleich &#8211; unabh\u00e4ngig davon, ob als Erwachsener, Kind oder Tier: wir begegnen uns immer auf Augenh\u00f6he. Die Kinder haben die Freiheit, der von ihnen gew\u00e4hlten Aktivit\u00e4t nachzugehen, wobei sie unsere Grundwerte und die Grundprinzipien respektieren. Zum Beispiel wird die benutzte Umgebung f\u00fcr das n\u00e4chste Kind oder den n\u00e4chsten Tag so gut es geht sauber und ordentlich hinterlassen, dabei werden die Kinder, falls sie es sich w\u00fcnschen, immer und jederzeit unterst\u00fctzt. Alle unsere R\u00e4ume werden von qualifizierten Erwachsenen in Zusammenarbeit mit den Kindern erschaffen. Diese R\u00e4ume haben ihre Grundregeln, welche den Kindern bei der ersten Benutzung erkl\u00e4rt werden, aber auch zusammen erarbeitet und angepasst werden k\u00f6nnen. Wir sind alle gleichermassen wichtig und sorgen daf\u00fcr, dass wir nur Fussabdr\u00fccke hinterlassen.<\/span><\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\">\u2015 Nimm nur Erinnerungen mit, hinterlasse nichts ausser Fussspuren.\u00a0\u2015<\/p>\n<p class=\"font_7\">Chief Seattle<\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Die Erwachsenen halten den Raum, um dort zu helfen, wo es n\u00f6tig und gefragt ist. Sie helfen dabei\u00a0eine ruhige und sichere Atmosph\u00e4re zu schaffen. Durch die Vielf\u00e4ltigkeit der Gemeinschaft k\u00f6nnen die Erwachsenen diverse Kurse erstellen und eine Vielzahl von Ausfl\u00fcgen und Erfahrungen planen, aus denen die Kinder w\u00e4hlen k\u00f6nnen. Jeder Erwachsene kann sein eigenes Wissen, seine St\u00e4rken und seine erworbenen beruflichen F\u00e4higkeiten nutzen, um eigene Aktivit\u00e4tsm\u00f6glichkeiten f\u00fcr die Kinder zu kreieren. Wir stellen uns einen Ort vor, an dem die Kinder von Tany Fitiavana an verschiedenen Kursen wie Gartenarbeit, Kochen, Theater, T\u00f6pfern, N\u00e4hen und Musik teilnehmen k\u00f6nnen, welche von der ganzen Gemeinschaft erm\u00f6glicht werden.<\/span><\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<div id=\"comp-k8gbpp4d\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<h3 class=\"font_3\">Demokratisch<\/h3>\n<\/div>\n<div id=\"comp-k8gd3itu\" class=\"_3nfU6 ignore-focus\" tabindex=\"-1\" role=\"region\" aria-label=\"Demokratisch\"><\/div>\n<div id=\"comp-k8gbpp4j\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\">\u2015\u00a0Schulen, welche diese Idee unterst\u00fctzen, sind Gemeinschaften\u00a0in denen der Artikel 12 der UN-Konvention \u00fcber die Rechte des Kindes -der besagt, dass Kinder ein Recht auf Mitsprache in Angelegenheiten haben, die sie betreffen-\u00a0vollst\u00e4ndig verwirklicht wird. \u2015<\/p>\n<p class=\"font_7\">EUDEC org.<\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<\/div>\n<div id=\"comp-k8gbpp4o\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\"><span class=\"color_30\">Demokratische Lerngemeinschaften sind alle speziell durch ihre Einzigartigkeit. Dabei teilen sie oft Gemeinsamkeiten, zu diesen geh\u00f6ren immer die folgenden Elemente:<\/span><\/p>\n<\/div>\n<div id=\"comp-k8gbpp4u\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\">KOLLEKTIVE ENTSCHEIDUNGSFINDUNG<\/p>\n<p class=\"font_7\">FESTE GRUNDLAGEN<\/p>\n<p class=\"font_7\">SELBSTGESTEUERTE ENTDECKUNG<\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Daraus wird ersichtlich, dass demokratische Bildung\u00a0bedeutet wie Verantwortung zu teilen. Wie alle demokratischen Schulen f\u00f6rdert Tany Fitiavana diesen Aspekt durch die Organisation von w\u00f6chentlichen Schulversammlungen. Bei diesen Versammlungen k\u00f6nnen alle Mitglieder der Gemeinschaft, unabh\u00e4ngig vom Alter oder Gesellschaftsstatus, gleichberechtigt \u00fcber wichtige Entscheidungen mitbestimmen. Zum Beispiel betreffend Vorschriften, Ausfl\u00fcgen, Projekten, m\u00f6gliche Verbesserungen, innovativen Ideen und sogar bei der Einstellung von Mitarbeitern. Diese Treffen k\u00f6nnen auch benutzt werden, um Konflikte in einer sicheren und mitf\u00fchlenden Umgebung zu l\u00f6sen. Durch die Anwendung dieser Lernmethode k\u00f6nnen die Kinder frei ausw\u00e4hlen, was sie wann, wie und mit wem lernen wollen. Das bedeutet f\u00fcr die gesamte Lerngemeinschaft, dass wir uns in Achtsamkeit \u00fcben m\u00fcssen, damit unsere Handlungen nicht dieselbe Freiheit bei unseren Mitmenschen einschr\u00e4nkt oder verletzt. Der Schl\u00fcssel f\u00fcr das Gelingen dieser Lernmethode ist, dass alle Erwachsene sowie das ganze Umfeld der Schule die Kinder unterst\u00fctzt ihrer intrinsischen Motivation und ihren Interessen zu folgen. F\u00fcr uns ist es sehr wichtig\u00a0diese Prinzipien \u00fcber Tany Fitiavana hinaus beizubehalten und vollstes Vertrauen in die F\u00e4higkeit des Kindes zu haben, dass es weiss, was es braucht, damit dieser Lernansatz wirklich erfolgreich sein kann.\u00a0 In der heutigen Zeit kann dieses Vertrauen eine Herausforderung sein, aber es ist und wird, sowohl f\u00fcr das Kind und seine Familie als auch zur St\u00e4rkung des Selbstwertgef\u00fchls, sehr wertvoll sein.<\/span><\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\">\u2015 Respekt erzeugt Respekt. Vertrauen schafft Vertrauen. Mitgef\u00fchl ruft Mitgef\u00fchl hervor.<\/p>\n<p class=\"font_7\">Toleranz geb\u00e4rt Toleranz. Zuh\u00f6ren verleitet zum Zuh\u00f6ren.\u00a0\u2015<\/p>\n<p class=\"font_7\">EUDEC org.<\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Die erste demokratische Schule, welche noch existiert, ist Summerhill in Suffolk, England. Sie wurde 1921 von A.S. Neill gegr\u00fcndet.\u00a0Seine Vision war es, dass eine Schule f\u00fcr das Kind gemacht werden sollte, und nicht umgekehrt. Heute gibt es viele demokratische Schulen. Man findet sie in Brasilien, Europa und von Israel bis Thailand \u00fcber die ganze Welt verteilt. Obwohl unterschiedliche Strukturen verwendet werden, f\u00f6rdern sie alle die gleiche Idee &#8211; Jeder kann gleichberechtigt mitbestimmen, welche Lernziele verfolgt werden und wie die Zusammenarbeit in der Gemeinschaft stattfindet. &#8211; Das Ziel ist es, den Kindern ein tiefes Verst\u00e4ndnis von Gleichheit und Gerechtigkeit zu vermitteln.<\/span><\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\">\u2015 Ein demokratischer Ansatz bedeutet, dass wir unsere Mitmenschen so unterst\u00fctzen, dass sie unabh\u00e4ngig denken und unter anderem Informationen, Wissen und Technologie nutzen k\u00f6nnen, um ihre eigenen Schlussfolgerungen zu ziehen.\u00a0\u2015<\/p>\n<p class=\"font_7\">Linda Darling-Hammond<\/p>\n<div id=\"comp-kdeg3x5c\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<h3 class=\"font_3\">Unser\u00a0Angebot<\/h3>\n<h3 class=\"font_3\"><\/h3>\n<h3 class=\"font_3\"><span class=\"color_30\">|\u00a0<\/span>SPIELGRUPPE\u00a0<span class=\"color_30\">|<\/span>\u00a0KINDERGARTEN\u00a0<span class=\"color_30\">|<\/span>\u00a0PRIMARSCHULE\u00a0<span class=\"color_30\">|<\/span>\u00a0OBERSTUFE\u00a0<span class=\"color_30\">|<\/span><\/h3>\n<\/div>\n<div id=\"comp-kdeg3x5p\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\"><span class=\"color_30\">Unsere Schule bietet ab dem Schuljahr 2020\/21\u00a0einen Betreuungsplatz f\u00fcr alle Altersgruppen an. Eine Spielgruppe ist auf Anfrage verf\u00fcgbar (Pl\u00e4tze begrenzt). Unser Kernteam deckt Kindergarten, Primarschule und Oberstufe ab.<\/span><\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">|\u00a0<\/span>BILINGUAL\u00a0<span class=\"color_30\">|<\/span><\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Tany Fitiavana ist ebenfalls eine zweisprachige Privatschule und integriert die Sprache Englisch durch das Leben\u00a0in\u00a0einer\u00a0vielf\u00e4ltigen\u00a0Gemeinschaft\u00a0spielerisch\u00a0in\u00a0den\u00a0Alltag\u00a0mit\u00a0ein.\u00a0Dadurch\u00a0wird\u00a0die\u00a0Zweitsprache<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">automatisch und ohne aufzufallen akzeptiert und verschmilzt als Teil des normalen Schulumfelds.<\/span><\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">|\u00a0<\/span>GEMEINSCHAFTSORIENTIERT\u00a0<span class=\"color_30\">|<\/span><\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\">\u2015 Tany Fitiavana sch\u00e4tzt und integriert die positiven Ver\u00e4nderungen des &#8220;Lehrplans 21&#8221; und bereichert diese, indem sie eine starke Gemeinschaft von Eltern, Familienmitgliedern und Freunden in den Lernprozess miteinbezieht. Ihre Zusammenarbeit bildet eine sehr wichtige Basis im Konzept unserer Schule. \u2015<\/p>\n<p class=\"font_7\">Tany Fitiavana<\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Wir wollen Familien aus allen Lebens- und Einkommensbereichen eine Schuloption anbieten.<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Insbesonders den Familien, die auf der Suche nach einem alternativen und nachhaltigen Lernkonzept sind, welches sie als wichtigen Bestandteil der Ausbildung ihrer Kinder miteinbezieht.<\/span><\/p>\n<\/div>\n<div id=\"comp-kdeg3x60\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\"><span class=\"color_30\">In unseren Augen k\u00f6nnen wir von einer gemeinschaftlichen Lernumgebung nur profitieren. Durch dieses Konzept k\u00f6nnen wir nicht nur niedrigere, sich nach dem Einkommen der Eltern richtende Schulgeb\u00fchren anbieten, sondern geben der Familie auch die M\u00f6glichkeit Teil der Lerngemeinschaft ihres Kindes zu sein.<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">F\u00fcr den Familienbeitrag pro Kind und f\u00fcr weitere Details bez\u00fcglich den Stundenpl\u00e4nen kannst\u00a0du uns jederzeit kontaktieren oder auf\u00a0<a href=\"https:\/\/www.tanyfitiavana.ch\/dokumente\" target=\"_self\" rel=\"noopener noreferrer\">Dokumente<\/a>\u00a0finden.<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Um unsere wundersch\u00f6ne Zusammenarbeit mit den Familien zu erm\u00f6glichen, bieten wir verschiedene interne Schulungen f\u00fcr alle Mitglieder an, die in verschiedenen Formen an unserem Schulalltag teilnehmen. Diese werden von spezialisierten Fachleuten geleitet, um uns die neusten Studien, Grundlagen und das praktische Verst\u00e4ndnis \u00fcber das freie Lernen sowie den demokratischen und holistischen Ansatz zur Bildung zu vermitteln und regelm\u00e4ssig aufzufrischen.<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">\u00a0<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Ebenso ist es f\u00fcr uns sehr wichtig, auch wenn wir nicht rechtlich dazu verpflichtet sind, dass alle Bezugspersonen im Alltag der Schule an einem Kinder-Nothelferkurs teilnehmen.<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Unsere Aufgabe ist es zu gew\u00e4hrleisten, dass wir uns gemeinsam und zielorientiert weiterentwickeln, damit wir den Kindern jederzeit die besten Voraussetzungen und ein sicheres Fundament anbieten k\u00f6nnen.<\/span><\/p>\n<\/div>\n<div id=\"comp-kdeg3x6b\" class=\"_2TxBB\" title=\"Lebenshof Hof Narr\">\n<div class=\"_2yXCL\" data-testid=\"linkElement\">\n<div class=\"_1ShVK\"><\/div>\n<\/div>\n<\/div>\n<div id=\"comp-kdehsdzz\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<h3 class=\"font_3\">Standort<\/h3>\n<h3 class=\"font_3\"><span class=\"color_30\">|\u00a0<\/span>Wolfhagstrasse 2, 8194 H\u00fcntwangen\u00a0<span class=\"color_30\">|<\/span><\/h3>\n<\/div>\n<div id=\"comp-kdehzbyz\" class=\"_3nfU6 ignore-focus\" tabindex=\"-1\" role=\"region\" aria-label=\"Standort\"><\/div>\n<div id=\"comp-kdehse0d\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\">\u2015\u00a0Leidenschaft entsteht, wenn wir uns als Kinder die H\u00e4nde in der Erde schmutzig machen; durch die grasfleckigen \u00c4rmel wandert sie ins Herz. Wenn wir die Umweltbewegung und die Umwelt retten wollen, dann m\u00fcssen wir auch und vor allem eine gef\u00e4hrdete Spezies retten: das Kind in der Natur.\u00a0\u2015<\/p>\n<p class=\"font_7\">Das letzte Kind im Wald von Richard Louv<\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Wir stellten uns eine Immobilie im Kanton Z\u00fcrich, mit hellen und lichtdurchfluteten R\u00e4umen inmitten der Natur vor. Einen Ort, an welchem die\u00a0Kinder wirklich frei sein k\u00f6nnten und ein\u00a0solcher\u00a0Standort ist uns zur Verf\u00fcgung gestellt worden.\u00a0<\/span><span class=\"color_30\">Wir sind sehr dankbar f\u00fcr den Gl\u00fccksgriff mit dem grossz\u00fcgigen Schulgeb\u00e4ude in H\u00fcntwangen und seiner gr\u00fcnen\u00a0Umgebung.<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Als wir vor kurzer Zeit ein\u00a0Teammeeting abhielten, in welchem wir uns f\u00fcr ein m\u00f6gliches Schulobjekt entscheiden sollten, haben wir lange die verschiedenen Eckpunkte besprochen, die f\u00fcr die Eltern normalerweise interessant w\u00e4ren. Wie Anfahrtsweg, zentrale Umgebung, Gewerben\u00e4he etc. Mit dieser Methode liess sich aber keine Entscheidung treffen, denn wir erhielten R\u00fcckmeldungen von Familien aus dem ganzem Kanton Z\u00fcrich, sowie von den Nachbarskantonen. F\u00fcr welche Familien sollten wir uns also entscheiden und kann eine solche Entscheidung \u00fcberhaupt fair getroffen werden?<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Nach langer \u00dcberlegung \u00e4nderten wir unsere Vorgehensweise und hoffen nun, dass die Familien unsere Beweggr\u00fcnde nachvollziehen und unterst\u00fctzen k\u00f6nnen. Denn wir begannen die Liegenschaften aus der Sicht des Kindes und in Verbindung mit unserem freien Lernkonzept zu betrachten.<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Wichtig ist, dass die Kinder die M\u00f6glichkeit haben\u00a0nahe gelegene W\u00e4lder, Fl\u00fcsse und B\u00e4che zu Fuss zu erreichen. Ebenfalls ist das &#8220;Kind in der Natur&#8221; eines der wichtigsten T\u00fcren zur Welt der Wunder. Es passiert in der Natur, dass ein Kind das Wunder des Selbstvertrauens und der Widerstandsf\u00e4higkeit findet und vielen weiteren Wundern begegnet.<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Zudem ist f\u00fcr uns nicht nur das freie Lernkonzept relevant, sondern auch die physische Freiheit, beim Austoben,\u00a0den Zauber zu sp\u00fcren, wenn man mit der nat\u00fcrlichen Umgebung in Verbindung tritt und diese aktiv erforscht.<\/span><\/p>\n<\/div>\n<div id=\"comp-kdehse0o\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\">\u2015 Wenn Kinder mit der Natur in Kontakt kommen, offenbaren sie ihre St\u00e4rken. \u2015<\/p>\n<p class=\"font_7\">Maria Montessori<\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\">Ki<span class=\"color_30\">nder wollen Raum, um sich zu entwickeln und eigenst\u00e4ndig ihren Projekten nachgehen zu k\u00f6nnen und genau aus diesen Gr\u00fcnden ist H\u00fcntwangen perfekt. Zudem ist die Liegenschaft, f\u00fcr die meisten mit uns in Verbindung stehenden Familien, in einer Zeit von +\/\u2015 30min erreichbar und mit einem Fahrweg von 20-30 min in die Stadt Z\u00fcrich, liegt es immernoch zentrumsnah.\u00a0<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Gerne wollen wir Fahrgemeinschaften unter den Familien und mit den Lehrern erm\u00f6glichen und unterst\u00fctzen.<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Eine weitere M\u00f6glichkeit in der Zukunft k\u00f6nnte ein Schulbus darstellen.<\/span><\/p>\n<p class=\"font_7\"><span class=\"wixGuard\">\u200b<\/span><\/p>\n<p class=\"font_7\"><span class=\"color_30\">Die Tany-Schule\u00a0erwartet euch in einer gr\u00fcnen und wundersch\u00f6nen Umgebung, mit eigener Turnhalle und Sportplatz. \u00dcberzeugt euch\u00a0bei einem geplanten Aufnahmegespr\u00e4ch\u00a0pers\u00f6nlich von unserer Liegenschaft.<\/span><\/p>\n<div id=\"comp-k8hqbhrz\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<h3 class=\"font_3\">Empfehlungen<\/h3>\n<\/div>\n<div id=\"comp-k8hqbhs9\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\"><span class=\"color_30\">Wir sind allen Pionieren dankbar, die verschiedene alternative Lernmethoden eingef\u00fchrt haben, wie beispielsweise die demokratische Sudbury Valley School, die bereits seit \u00fcber 50 Jahren erfolgreich besteht. Hier findest du\u00a0eine kurze von uns zusammengestellte Liste mit\u00a0informativem\u00a0Material\u00a0\u00fcber verschiedene alternative Schulen, wissenschaftliche Forschungen, Erfahrungen und Studien, die von vielen renommierten Psychologen, Soziologen, Kinder\u00e4rzten, Lehrern und vor allem von Eltern und Kindern geteilt und unterst\u00fctzt werden.<\/span><\/p>\n<\/div>\n<div id=\"comp-k8hqbhse\" class=\"_1Z_nJ\" data-testid=\"richTextElement\">\n<p class=\"font_7\">\u2015\u00a0Die Zukunft wird den Naturverbundenen geh\u00f6ren &#8211; den Individuen, Familien, Unternehmen und Politikern, die ein tieferes Verst\u00e4ndnis f\u00fcr die transformative Kraft der nat\u00fcrlichen Welt entwickeln und die das Virtuelle mit dem Realen in Einklang bringen. Je mehr hightech wir werden, desto mehr Natur brauchen wir.\u00a0\u2015<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Wolfhagstrasse 2, 8194 H\u00fcntwangen, Schweiz","_company_website":"https:\/\/www.tanyfitiavana.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[153],"job-categories":[103,99,76],"job-types":[90,5,92],"class_list":{"0":"post-23297","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-zuerich","6":"job_listing_category-kindergarten","7":"job_listing_category-primarschule","8":"job_listing_category-sekundarstufe_1","9":"job_listing_type-kindergarten","10":"job_listing_type-primarschule","11":"job_listing_type-sekundarstufe_1","13":"job-type-kindergarten-4-6-jahre","14":"job-type-primarschule-7-12jahre","15":"job-type-sekundarstufe-1-13-16-jahre"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tany Fitiavana - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/en\/listings\/tany-fitiavana\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tany Fitiavana\" \/>\n<meta property=\"og:description\" content=\"Leitgedanke \u2015 Kinder speichern Informationen, aber wir m\u00fcssen ebenfalls daran denken, dass sie auch Gef\u00fchle speichern. Ihnen die Freiheit zu geben\u00a0zu denken, zu f\u00fchlen und zu sein &#8211; ist genauso wichtig, wie das Wissen,\u00a0das wir teilen. \u2015 Tany Fitiavanas Schl\u00fcsselkonzept ist es, das organische und nat\u00fcrliche Lernen zu unterst\u00fctzen, indem wir einen holistischen Ansatz ehren. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/en\/listings\/tany-fitiavana\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/Download-3-2.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/Download-3-2.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/tany-fitiavana\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/tany-fitiavana\\\/\",\"name\":\"Tany Fitiavana - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\"},\"datePublished\":\"2020-12-14T12:29:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/tany-fitiavana\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/tany-fitiavana\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/tany-fitiavana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tany Fitiavana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tany Fitiavana - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/en\/listings\/tany-fitiavana\/","og_locale":"en_US","og_type":"article","og_title":"Tany Fitiavana","og_description":"Leitgedanke \u2015 Kinder speichern Informationen, aber wir m\u00fcssen ebenfalls daran denken, dass sie auch Gef\u00fchle speichern. Ihnen die Freiheit zu geben\u00a0zu denken, zu f\u00fchlen und zu sein &#8211; ist genauso wichtig, wie das Wissen,\u00a0das wir teilen. \u2015 Tany Fitiavanas Schl\u00fcsselkonzept ist es, das organische und nat\u00fcrliche Lernen zu unterst\u00fctzen, indem wir einen holistischen Ansatz ehren. [&hellip;]","og_url":"https:\/\/schoolaboo.com\/en\/listings\/tany-fitiavana\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","og_image":[{"url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/Download-3-2.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/Download-3-2.jpg","twitter_misc":{"Est. reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/en\/listings\/tany-fitiavana\/","url":"https:\/\/schoolaboo.com\/en\/listings\/tany-fitiavana\/","name":"Tany Fitiavana - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/en\/#website"},"datePublished":"2020-12-14T12:29:40+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/en\/listings\/tany-fitiavana\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/en\/listings\/tany-fitiavana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/en\/listings\/tany-fitiavana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/en\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/en\/angebote\/"},{"@type":"ListItem","position":3,"name":"Tany Fitiavana"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/en\/#website","url":"https:\/\/schoolaboo.com\/en\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/en\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings\/23297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/comments?post=23297"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/media?parent=23297"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job_listing_region?post=23297"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-categories?post=23297"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-types?post=23297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}