{"id":23221,"date":"2020-12-11T22:49:28","date_gmt":"2020-12-11T21:49:28","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=23221"},"modified":"2020-12-14T13:04:59","modified_gmt":"2020-12-14T12:04:59","slug":"wings-school","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/en\/listings\/wings-school\/","title":{"rendered":"Wings School"},"content":{"rendered":"<ul class=\"list-unstyled list-regular-lined\">\n<li>Wir bieten ein sicheres Umfeld und sorgen f\u00fcr das Wohlergehen der Kinder. Das Kind soll sich aufgehoben, respektiert und sicher f\u00fchlen und Vertrauen in die Betreu\u00adungspersonen und die Gemeinschaft aufbauen k\u00f6nnen.<\/li>\n<li>Uns ist eine ausgewogene F\u00f6rderung in allen Entwick\u00adlungsbereichen mittels verschiedenen Methoden wichtig, welche das Kind stimulierend und motivierend einbe\u00adziehen und ihm ein breites Entdeckungs\u00ad und Lern\u00adspektrum erm\u00f6glichen.<\/li>\n<li>Die Kinder haben bei uns die M\u00f6glichkeit Erfahrun\u00adgen zu sammeln, welche sie in ihrer Selbstst\u00e4ndigkeit, Selbstvertrauen, Verantwortungsbewusstsein und ihrer Entscheidungsf\u00e4higkeit gezielt st\u00e4rken.<\/li>\n<li>Wir legen Wert auf gegenseitigen Respekt, Wertsch\u00e4tzung, R\u00fccksichtnahme und Achtung vor dem Leben und der Umwelt. In einem nicht diskriminierenden Umfeld wird jedem Kind dieselbe Aufmerksamkeit entgegengebracht, unabh\u00e4ngig von Nationalit\u00e4t, Religion, sozialer Schicht, individuellem Entwicklungsstand etc.<\/li>\n<li>Beide Sprachen Deutsch und Englisch sind gleichwertig und werden den Kindern in allen F\u00e4chern und Alltags\u00adsituationen vermittelt.<\/li>\n<li>In Zusammenarbeit mit den Eltern bereiten wir das Kind darauf vor, in die \u00f6ffentliche Schule oder andere Privat\u00adschulen\/International Schools \u00abauszufliegen\u00bb.<\/li>\n<\/ul>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Priorit\u00e4t f\u00fcr die\u00a0<strong>Krippenkinder<\/strong>\u00a0ist, ihnen die\u00a0<strong>erstklassige Betreuung und Aufmerksamkeit<\/strong>\u00a0zukommen zu lassen. Dazu bringen wir eine grosse Anzahl Spielzeuge, ausgew\u00e4hlte B\u00fccher, Spiele, Musik und Bewegung ein.<\/p>\n<p>Kinder verf\u00fcgen \u00fcber ein enormes Lernpotenzial und sie sind bereit und begierig, die Welt zu entdecken. Sie setzen sich mit einer grossen Anzahl von Dingen auseinander, stellen konstant Fragen und m\u00f6chten eine f\u00fcr sie verst\u00e4nd\u00adliche Antwort.<\/p>\n<p>Den Kindern wollen wir ein\u00a0<strong>sicheres, abwechslungsreiches und interessantes Umfeld<\/strong>\u00a0bieten. In einem organisierten Rahmen sollen sie spielerisch einen m\u00f6glichst breiten \u00dcberblick \u00fcber die\u00a0<strong>verschiedensten Aspekte des Lebens<\/strong>\u00a0gewinnen, und ihre eigene\u00a0<strong>Pers\u00f6nlichkeit entfalten<\/strong>\u00a0k\u00f6nnen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Sie sollen in einer\u00a0<strong>zweisprachigen Umgebung<\/strong>, deutsch und englisch, betreut werden. Dazu haben wir ausgebildete Betreuerinnen deutscher\u00ad und englischer vorzugsweise Muttersprache engagiert.<\/p>\n<p>Den\u00a0<strong>Eltern<\/strong>\u00a0wollen wir die M\u00f6glichkeit bieten, ihrer\u00a0<strong>Berufs\u00adt\u00e4tigkeit nachgehen<\/strong>\u00a0zu k\u00f6nnen, mit der Gewissheit, dass ihr Kind w\u00e4hrend dieser Zeit nicht nur in guten H\u00e4nden ist, sondern auch entsprechend seinen Neigungen und Bed\u00fcrfnissen gef\u00f6rdert wird.<\/p>\n<p>Da die Gr\u00fcnder der Wings School selbst berufst\u00e4tige Eltern sind und ihr Kind in die Obhut dieser Institution geben, besteht ein pers\u00f6nliches Interesse, das Beste anzubieten.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3 class=\"m-t-none\">Krippenpersonal<\/h3>\n<p>Die Krippengruppen werden je von einer deutsch \u2013 oder englischsprachi\u00adgen\u00a0<strong>Kleinkinderzieherin<\/strong>\u00a0zusammen mit einer Lehrfrau und einer Praktikantin betreut. Auf jeder Gruppe werden beide Sprachen gesprochen.<\/p>\n<ul class=\"list-regular-wide\">\n<li>Krippenleiterin (anerkannt)<\/li>\n<li>Kleinkinderzieherinnen oder Fachfrau Betreuung Richtung Kind (anerkannt), deutsch sprechend<\/li>\n<li>Kleinkinderzieherinnen Fachfrau Betreuung oder anerkannt (anerkannt oder gleichwertig), englisch sprechend<\/li>\n<li>Fachfrau Betreuung Richtung Kind in Ausbildung<\/li>\n<li>Praktikantinnen<\/li>\n<\/ul>\n<p><strong>K\u00fcche &amp; Hauswirtschaft<\/strong><br \/>\nQualifizierte K\u00f6chin, Koch in Ausbildung, Raumpflegerin, Praktikantin<\/p>\n<p>Alle MitarbeiterInnen besuchen einen Erste\u00adHilfe\u00adKurs sowie einen Feuerbek\u00e4mpfungskurs.<\/p>\n<blockquote><p>Die Wings School h\u00e4lt die gesetzlichen Vorgaben des SKV, Volksschulamtes und der entsprechenden Schweizer Beh\u00f6rde betreffend Arbeitszeit, Ferien, Sal\u00e4re, Ausbildung und Weiterbildung der Mitarbeiter ein.<\/p><\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h5 class=\"pre-header\">PROGRAMM<\/h5>\n<h3 class=\"h1\">Das Krippen Wochenprogramm f\u00f6rdert die Kinder in allen Entwicklungsbereichen und in beiden Sprachen.<\/h3>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p class=\"text-center\">Dies ist nur ein grober Ablauf unserer Tagesroutine.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3 class=\"m-t-none\">Morgenstunden<\/h3>\n<p>7.30 \u2013 8.50 Ankunft, Fr\u00fchst\u00fcck und Vorbereitung<\/p>\n<p>In dieser Zeit haben die Kinder die Gelegenheit etwas zu essen, falls sie vor 8.30 ankommen, und anschliessend im Spielzimmer zu spielen.<\/p>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3 class=\"m-t-none\">Vormittag<\/h3>\n<p>9.00 \u2013 11.30 Spielzeit<\/p>\n<p>Verschiedene gef\u00fchrte und von den Betreuerinnen vorbe\u00adreitete Aktivit\u00e4ten, wie Morgenkreis, Kleingruppenarbeit, Individuelle F\u00f6rderung, Ausfl\u00fcge, Freispiel\u2026<\/p>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3 class=\"m-t-none\">Mittagsstunden<\/h3>\n<p>11.30 \u2013 14.00 Mittagessen, Ausruhen<\/p>\n<p>Jeden Tag wird ein warmes Essen in unserer K\u00fcche frisch zubereitet. Die Mahlzeiten sind ausgewogen (z. B. Teigwaren, Fleisch, Salat und Gem\u00fcse) und werden zu Beginn der Woche den Eltern mittels Men\u00fcplan mitgeteilt.<\/p>\n<p>Nach dem Mittag\u00adessen findet eine Ruhepause statt, h\u00f6ren sich Geschichten oder schauen B\u00fccher an.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3 class=\"m-t-none\">Vogelnest<\/h3>\n<p>13.30 \u2013 15.00 Vogelnest<\/p>\n<p>F\u00fcr die Krippenkinder, welche \u00fcber drei Jahre alt sind, findet ein Treffen mit gleichaltrigen statt.<\/p>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3 class=\"m-t-none\">z\u2019Vieri<\/h3>\n<p>15.30 \u2013 16.15 z\u2019Vieri<\/p>\n<p>Um 16.00 ist grunds\u00e4tzlich der Tag in der Krippe zu Ende. Kinder die sich l\u00e4nger in der Kinderkrippe aufhalten, treffen sich zu einem kleinen Imbiss (Fr\u00fcchte) um 17.30 Uhr.<\/p>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3 class=\"m-t-none\">Tagesabschluss<\/h3>\n<p>17.30 \u2013 18.30 Spielen, Aufr\u00e4umen<\/p>\n<p>Gegen 18.00 Uhr treffen die Kinder Vorbereitungen, den Tag in der Kinderkrippe zu beenden. Sie werden helfen aufzur\u00e4umen, spielen zusammen mit anderen Grup\u00adpen, bis sie von den Eltern abgeholt werden.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h5 class=\"pre-header\">LERNSTOFF DER KINDERKRIPPE<\/h5>\n<h2 class=\"h1\">Sprache, Sport, Mathematik &amp; Wissenschaft, Musik, Tanz, Theater, Ausfl\u00fcge, Kunst, basteln<\/h2>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Am Anfang jedes Monats\/Themas wird eine\u00a0<strong>detaillierte \u00dcbersicht des Lehrstoffes<\/strong>\u00a0in der Kinderkrippe vorbereitet, der auch den Eltern zug\u00e4nglich ist, damit sie einen \u00dcberblick \u00fcber die Themen und Lernziele haben, mit denen sich die Kinder auseinan\u00addersetzen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3>Sprache<\/h3>\n<p>Die Kinder werden sowohl in\u00a0<strong>Englisch<\/strong>\u00a0als auch in\u00a0<strong>Deutsch<\/strong>\u00a0unterrichtet. Dies setzt einen bewussten Umgang mit der Sprache und klare Regeln voraus. Unser Personal spricht konsequent in nur einer Sprache mit dem Kind, somit wird verhindert, dass das Kind die Sprachen vermischt.<\/p>\n<p>Zur\u00a0<strong>Sprachf\u00f6rderung<\/strong>\u00a0geh\u00f6rt unter anderem Aufbau des Wortschatzes, Phonologische Bewusstheit entwickeln, Ein\u00adf\u00fchrung in die Buchstabenwelt, die Sprache verstehen und selber korrekt anwenden, \u00dcbung der Aussprache etc.<\/p>\n<h3>Kunst &amp; Basteln<\/h3>\n<p>Das Ziel der\u00a0<strong>Kunstf\u00e4cher<\/strong>\u00a0ist es, die Kinder ihre\u00a0<strong>Kreativi\u00adt\u00e4t<\/strong>\u00a0ausleben zu lassen und die Gesetze der \u00c4sthetik zu verstehen (Farben, Formen). Die Kinder sollen mit Farben, Knetmasse, Hammer, N\u00e4geln, Schrauben, Scheren, Papier, Karton, Leim, Klebefilz etc. experimentieren k\u00f6nnen und sie werden so in neue Handwerkstechniken eingef\u00fchrt.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3>Spielen draussen<\/h3>\n<p>Es ist uns ein grosses Anliegen, den Kindern\u00a0<strong>viel Zeit im Frei\u00aden<\/strong>\u00a0zu erm\u00f6glichen. Da wir keinen eigenen Garten haben, suchen wir wenn m\u00f6glich t\u00e4glich, jedoch mindestens 3\u00admal in der Woche die umliegenden Spielpl\u00e4tze und Parks auf.<\/p>\n<h3>Musik, Tanz &amp; Theater<\/h3>\n<p>Ein wichtiger Teil des Lernens ist die Musik. Wir singen regelm\u00e4ssig, spielen mit verschiedenen Instrumenten und vertiefen\u00a0<strong>K\u00f6rper\u00ad und Bewegungserfahrungen<\/strong>\u00a0mittels Rhythmik und Tanz. Auch Rollenspiele haben einen festen Platz in unserem Lehrplan.<\/p>\n<h3>Ausfl\u00fcge<\/h3>\n<p>Pro Jahr sind\u00a0<strong>mehrere Ganz\u00ad oder Halbtagesausfl\u00fcge<\/strong>\u00a0ge\u00adplant. In vielen F\u00e4llen beziehen sich diese Ausfl\u00fcge auf die gerade aktuellen Unterrichtsthemen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h5 class=\"pre-header\">ELTERNANL\u00c4SSE<\/h5>\n<h2 class=\"h1\">Im Interesse des Kindes ist eine gute Zusammenarbeit zwischen Eltern und Lehrpersonen wichtig<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3>Elternabend<\/h3>\n<p>Die Eltern werden von den jeweiligen Gruppen zum Elternabend eingeladen. Die Eltern haben die M\u00f6glichkeit die Betreuerinnen und andere Eltern kennenzulernen und sie erhalten Informationen \u00fcber den Alltag der Kinder.<\/p>\n<h3>Elterngespr\u00e4che<\/h3>\n<p>Einmal im Jahr wird ein Standortgespr\u00e4ch durchgef\u00fchrt. Dies findet jeweils im Fr\u00fchling statt.<\/p>\n<h3>Wings\u00adParty<\/h3>\n<p>Im Sommer sind die Wings School Familien zum\u00a0<strong>Grillfest<\/strong>\u00a0eingeladen. So k\u00f6nnen sich die Lehrerinnen\/Erzieherinnen und die Eltern auf einer pers\u00f6nlichen Ebene kennenlernen.<\/p>\n<h3>R\u00e4benliechtli<\/h3>\n<p>Jedes Jahr laden das Krippen\u00ad und Kindergartenteam die Wings School Familien zu einem Umzug durch das Quartier mit anschliessendem Ap\u00e9ro ein.<\/p>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Der Unterricht basiert auf dem\u00a0<strong>Lehrplan 21 f\u00fcr den Kindergarten<\/strong>. Die Kinder werden vielf\u00e4ltig und spielerisch in allen Entwicklungsbereichen gef\u00f6rdert, um mit den besten Voraussetzungen in die eigentliche Schule eintreten zu k\u00f6nnen.<\/p>\n<p>Kinder verf\u00fcgen \u00fcber ein enormes Lernpotenzial und sie sind bereit und begierig, die Welt zu entdecken. Sie setzen sich mit einer grossen Anzahl von Dingen auseinander, stellen konstant Fragen und m\u00f6chten eine f\u00fcr sie verst\u00e4nd\u00adliche Antwort.<\/p>\n<p>Den Kindern wollen wir ein\u00a0<strong>sicheres, abwechslungsreiches und interessantes Umfeld<\/strong>\u00a0bieten. In einem organisierten Rahmen sollen sie spielerisch einen m\u00f6glichst breiten \u00dcberblick \u00fcber die verschiedensten Aspekte des Lebens gewinnen, und ihre\u00a0<strong>eigene Pers\u00f6nlichkeit entfalten<\/strong>\u00a0k\u00f6nnen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Sie sollen in einer\u00a0<strong>zweisprachigen Umgebung<\/strong>, deutsch und englisch, betreut werden. Dazu haben wir ausgebildete\u00a0<strong>Kinderg\u00e4rtnerinnen\u00a0<\/strong>deutscher\u00ad und englischer vorzugsweise Muttersprache engagiert.<\/p>\n<p>Den\u00a0<strong>Eltern<\/strong>\u00a0wollen wir die M\u00f6glichkeit bieten, ihrer\u00a0<strong>Berufs\u00adt\u00e4tigkeit nachgehen<\/strong>\u00a0zu k\u00f6nnen, mit der Gewissheit, dass ihr Kind w\u00e4hrend dieser Zeit nicht nur in guten H\u00e4nden ist, sondern auch entsprechend seinen Neigungen und Bed\u00fcrfnissen gef\u00f6rdert wird.<\/p>\n<p>Da die Gr\u00fcnder der Wings School selbst berufst\u00e4tige Eltern sind und ihr Kind in die Obhut dieser Institution geben, besteht ein pers\u00f6nliches Interesse, das Beste anzubieten.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_single_image wpb_content_element vc_align_left\">\n<figure class=\"wpb_wrapper vc_figure\">\n<div class=\"vc_single_image-wrapper vc_box_border_grey\"><\/div>\n<\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3 class=\"m-t-none\">Personal Kindergarten<\/h3>\n<p>Die\u00a0<strong>Kindergartengruppen<\/strong>\u00a0werden von je einer Englisch und einer Deutsch sprechenden Kinderg\u00e4rtnerin geleitet, gemeinsam mit einer Praktikantin oder Lernende.<\/p>\n<ul class=\"list-regular-wide\">\n<li>Schulleiterin (EDK anerkannt)<\/li>\n<li>Kinderg\u00e4rtnerinnen (mit schweizerisch anerkanntem Diplom oder gleichwertig), deutsch &amp; englisch sprechend<\/li>\n<li>Praktikantinnen oder Lernende<\/li>\n<\/ul>\n<p><strong>K\u00fcche und Hauswirtschaft<\/strong><br \/>\nQualifizierte K\u00f6chin, Koch in Ausbildung, Raumpflegerin, Praktikantin<\/p>\n<p>Alle MitarbeiterInnen besuchen einen Erste\u00adHilfe\u00adKurs sowie einen Feuerbek\u00e4mpfungskurs.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h5 class=\"pre-header\">PROGRAMM<\/h5>\n<h3 class=\"h1\">Das Kindergarten-Wochenprogramm f\u00f6rdert die Kinder in allen Entwicklungsbereichen und in beiden Sprachen.<\/h3>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Das Wochenprogramm im Kindergarten ist so angelegt, dass es\u00a0<strong>alle Kinder in allen Entwicklungsbereichen<\/strong>\u00a0und in beiden Sprachen in der Gruppe und\u00a0<strong>individuell gef\u00f6rdert<\/strong>\u00a0werden. Dies ist nur ein grober Ablauf unserer Tagesroutine.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3 class=\"m-t-none\">Morgenstunden<\/h3>\n<p>7.30 \u2013 8.50 Ankunft, Fr\u00fchst\u00fcck und Vorbereitung<\/p>\n<p>In dieser Zeit haben die Kinder die Gelegenheit etwas zu essen, falls sie vor 8.30 ankommen, und anschliessend im Kindergartenzimmer zu spielen.<\/p>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3 class=\"m-t-none\">Vormittag<\/h3>\n<p>9.00 \u2013 11.30 Unterrichtszeit<\/p>\n<p>Verschiedene gef\u00fchrte und von den Lehrpersonen vorbe\u00adreitete Aktivit\u00e4ten, wie Morgenkreis, Kleingruppenarbeit, Individuelle F\u00f6rderung, Ausfl\u00fcge, Freispiel\u2026<\/p>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3 class=\"m-t-none\">Mittagsstunden<\/h3>\n<p>11.30 \u2013 14.00 Mittagessen, Ausruhen<\/p>\n<p>Jeden Tag wird ein warmes Essen in unserer K\u00fcche frisch zubereitet. Die Mahlzeiten sind ausgewogen (z. B. Teigwaren, Fleisch, Salat und Gem\u00fcse) und werden zu Beginn der Woche den Eltern mittels Men\u00fcplan mitgeteilt.<\/p>\n<p>Nach dem Mittag\u00adessen findet eine Ruhepause statt, h\u00f6ren sich Geschichten oder schauen B\u00fccher an.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3 class=\"m-t-none\">z\u2019Vieri<\/h3>\n<p>15.30 \u2013 16.15 z\u2019Vieri<\/p>\n<p>Um 16.15 ist grunds\u00e4tzlich der Schultag f\u00fcr das erste Kindergartenjahr und f\u00fcr das zweite am 16:45 Uhr zu Ende. Kinder die den Kindergarten l\u00e4nger besuchen, besch\u00e4ftigen sich mit dem Freispiel.<\/p>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3 class=\"m-t-none\">Tagesabschluss<\/h3>\n<p>17.30 \u2013 18.30 Spielen, Aufr\u00e4umen<\/p>\n<p>Gegen 18.00 Uhr treffen die Kinder Vorbereitungen, den Tag im Kindergarten zu beenden. Sie werden helfen aufzur\u00e4umen, spielen zusammen mit anderen Grup\u00adpen, bis sie von den Eltern abgeholt werden.<\/p>\n<\/div>\n<\/div>\n<div class=\"wpb_images_carousel wpb_content_element vc_clearfix\">\n<div class=\"wpb_wrapper\">\n<div id=\"vc_images-carousel-1-1605300008\" class=\"vc_slide vc_images_carousel vc_build\" data-ride=\"vc_carousel\" data-wrap=\"true\" data-interval=\"5000\" data-auto-height=\"yes\" data-mode=\"horizontal\" data-partial=\"false\" data-per-view=\"1\" data-hide-on-end=\"false\">\n<div class=\"vc_carousel-inner\">\n<div class=\"vc_carousel-slideline\">\n<div class=\"vc_carousel-slideline-inner\">\n<div class=\"vc_item vc_active\">\n<div class=\"vc_inner\"><\/div>\n<\/div>\n<div class=\"vc_item\">\n<div class=\"vc_inner\"><\/div>\n<\/div>\n<div class=\"vc_item\">\n<div class=\"vc_inner\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h5 class=\"pre-header\">LERNSTOFF IM KINDERGARTEN<\/h5>\n<h2 class=\"h1\">Sprache, Sport, Mathematik &amp; Wissenschaft, Musik, Tanz, Theater, Ausfl\u00fcge, Kunst, basteln<\/h2>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Am Anfang jedes Monats\/Themas wird eine\u00a0<strong>detaillierte \u00dcbersicht des Lehrstoffes<\/strong>\u00a0im Kindergarten vorbereitet, der auch den Eltern zug\u00e4nglich ist, damit sie einen \u00dcberblick \u00fcber die Themen und Lernziele haben, mit denen sich die Kinder auseinan\u00addersetzen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3>M\u00f6gliche Themen<\/h3>\n<ul>\n<li>Soziales Verhalten (Ich und meine Klasse, Familie, Kulturen, Menschen, Kooperation und Konfliktbew\u00e4lti\u00adgung, etc.)<\/li>\n<li>Geographie und Umwelt (Kontinente &amp; Meere, L\u00e4nder, St\u00e4dte, Wetter, etc.)<\/li>\n<li>Zahnpflege, Nahrungsmittel und Kochen<\/li>\n<li>Der menschliche K\u00f6rper<\/li>\n<li>Tiere, Pflanzen und Naturzusammenh\u00e4nge<\/li>\n<li>Sicherheit und Gefahr (Gifte, Feuer, Strassen)<\/li>\n<li>Emotionen (Gef\u00fchle, Eigentum, Respekt, Geduld, Anerkennung)<\/li>\n<\/ul>\n<h3>Sprache<\/h3>\n<p>Die Kinder werden sowohl in\u00a0<strong>Englisch<\/strong>\u00a0als auch in\u00a0<strong>Deutsch<\/strong>\u00a0unterrichtet. Dies setzt einen bewussten Umgang mit der Sprache und klare Regeln voraus. Unser Personal spricht konsequent in nur einer Sprache mit dem Kind, somit wird verhindert, dass das Kind die Sprachen vermischt.<\/p>\n<p>Zur\u00a0<strong>Sprachf\u00f6rderung<\/strong>\u00a0geh\u00f6rt unter anderem Aufbau des Wortschatzes, Phonologische Bewusstheit entwickeln, Ein\u00adf\u00fchrung in die Buchstabenwelt, die Sprache verstehen und selber korrekt anwenden, \u00dcbung der Aussprache etc.<\/p>\n<h3>Kunst &amp; Basteln<\/h3>\n<p>Das Ziel der\u00a0<strong>Kunstf\u00e4cher<\/strong>\u00a0ist es, die Kinder ihre\u00a0<strong>Kreativi\u00adt\u00e4t<\/strong>\u00a0ausleben zu lassen und die Gesetze der \u00c4sthetik zu verstehen (Farben, Formen). Die Kinder sollen mit Farben, Knetmasse, Hammer, N\u00e4geln, Schrauben, Scheren, Papier, Karton, Leim, Klebefilz etc. experimentieren k\u00f6nnen und sie werden so in neue Handwerkstechniken eingef\u00fchrt.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3>Sport<\/h3>\n<p>Einmal pro Woche steht uns die grosse Turnhalle des Schul\u00adhauses Rebh\u00fcgel zur Verf\u00fcgung.<\/p>\n<p>Es ist uns ein grosses Anliegen, den Kindern\u00a0<strong>viel Zeit im Frei\u00aden<\/strong>\u00a0zu erm\u00f6glichen. Da wir keinen eigenen Garten haben, suchen wir wenn m\u00f6glich t\u00e4glich, jedoch mindestens 3\u00admal in der Woche die umliegenden Spielpl\u00e4tze und Parks auf.<\/p>\n<h3>Musik, Tanz &amp; Theater<\/h3>\n<p>Ein wichtiger Teil des Lernens ist die Musik. Wir singen regelm\u00e4ssig, spielen mit verschiedenen Instrumenten und vertiefen\u00a0<strong>K\u00f6rper\u00ad und Bewegungserfahrungen<\/strong>\u00a0mittels Rhythmik und Tanz. Auch Rollenspiele haben einen festen Platz in unserem Lehrplan.<\/p>\n<h3>Mathematik &amp; Wissenschaften<\/h3>\n<p>Die wissenschaftlichen Themen f\u00fchren die Kinder in die Grundbegriffe von Mathematik, Physik und Chemie ein. Un\u00adser Ziel ist es, die\u00a0<strong>Kinder neugierig zu machen<\/strong>, sie mit Freu\u00adde und Faszination\u00a0<strong>experimentieren<\/strong>\u00a0zu lassen. Sie haben die M\u00f6glichkeit, selbst kleine Experimente durchzuf\u00fchren, dar\u00fcber nachzudenken, Probleme zu l\u00f6sen und das Gelern\u00adte umzusetzen. Sie lernen unter anderem die folgenden Konzepte kennen: Gewichte, Geschwindigkeit, Licht, T\u00f6ne, Gr\u00f6ssen, Mengen, Zahlen, Rechenoperationen etc. Zus\u00e4tz\u00adlich lernen die Kinder den Umgang mit dem Computer.<\/p>\n<h3>Ausfl\u00fcge<\/h3>\n<p>Pro Jahr sind\u00a0<strong>mehrere Ganz\u00ad oder Halbtagesausfl\u00fcge<\/strong>\u00a0ge\u00adplant. In vielen F\u00e4llen beziehen sich diese Ausfl\u00fcge auf die gerade aktuellen Unterrichtsthemen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h5 class=\"pre-header\">ELTERNANL\u00c4SSE<\/h5>\n<h2 class=\"h1\">Im Interesse des Kindes ist eine gute Zusammenarbeit zwischen Eltern und Lehrpersonen wichtig<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3>Wings\u00adParty<\/h3>\n<p>Im Sommer sind die Wings School Familien zum\u00a0<strong>Grillfest<\/strong>\u00a0eingeladen. So k\u00f6nnen sich die Lehrerinnen\/Erzieherinnen und die Eltern auf einer pers\u00f6nlichen Ebene kennenlernen.<\/p>\n<h3>Elternabend<\/h3>\n<p>Zu Beginn des Schuljahres werden die Eltern von den jeweiligen Klassenlehrerinnen zum Elternabend eingeladen. Die Eltern haben die M\u00f6glichkeit die Lehrerinnen\/Erziehe\u00adrinnen und andere Eltern kennenzulernen und sie erhalten Informationen \u00fcber die Pl\u00e4ne der Klassen.<\/p>\n<h3>Elterngespr\u00e4che<\/h3>\n<p>Es werden pro Kinderkrippenjahr jeweils\u00a0<strong>zwei Elterngespr\u00e4che<\/strong>\u00a0durchgef\u00fchrt. Zu Beginn des Schuljahres werden die Eltern nach den ersten drei Monate f\u00fcr ein Gespr\u00e4ch eingeladen und danach nach sechs Monaten.<\/p>\n<h3>R\u00e4benliechtli<\/h3>\n<p>Jedes Jahr laden das Krippen\u00ad und Kindergartenteam die Wings School Familien zu einem Umzug durch das Quartier mit anschliessendem Ap\u00e9ro ein.<\/p>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Der\u00a0<strong>Kids Club ist ein Hort<\/strong>\u00a0f\u00fcr diejenigen Kinder, welche bereits die Schule besuchen. Der Hort wird den Kindern angeboten im Alter von 5-12 Jahren.\u00a0 Wir setzen unsere Priorit\u00e4ten in hoch qualitativer Betreuung und altersentsprechende Tagesgestaltung ein. In unserem Kids Club haben die Kinder die M\u00f6glichkeit\u00a0<strong>die englische Sprache zu vertiefen<\/strong>\u00a0oder neu zu lernen, denn er wird von einer englischsprechenden Leitung gef\u00fchrt.<\/p>\n<p>Neben der\u00a0<strong>Hausaufgabenhilfe<\/strong>\u00a0werden auch allt\u00e4glich\u00a0<strong>abwechslungsreiche Aktivit\u00e4ten<\/strong>, wie Z.B Bastelarbeiten, anregende Auftr\u00e4ge, um schulische Leistungen zu unterst\u00fctzen, verschiedene Aktivit\u00e4ten und Spiele, Geschichten, Teilnahme an unterschiedlichen Projekten und unz\u00e4hlige Spazierg\u00e4nge durchgef\u00fchrt.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Das wir die Betreuungsqualit\u00e4t hochhalten und individuelle Begleitung umsetzten k\u00f6nnen haben wir eine maximale Anzahl von zehn Kindern pro Tag.<\/p>\n<p>Ebenfalls ist uns eine\u00a0<strong>gesunde Ern\u00e4hrung<\/strong>\u00a0wichtig, unsere Qualifizierte K\u00f6chin zusammen mit ihrem Team, versorgen die Kinder mit ausgewogenen und gesunden Essen. Sie achten sich auf eine Saisonale K\u00fcche und Intoleranzen der Kinder.<\/p>\n<p><strong>Der Hort beginnt um 12:00 Uhr<\/strong>, die Kinder haben auch die M\u00f6glichkeit sp\u00e4ter dazu zu kommen oder nur unsere Mittagtisch von 12:00 bis 14:00 Uhr zu besuchen, die T\u00fcren werden t\u00e4glich um 18:30 Uhr geschlossen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Eichstrasse 29, 8045 Z\u00fcrich, Schweiz","_company_website":"https:\/\/www.wingsschool.ch\/de\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[153],"job-categories":[103,229],"job-types":[90,230],"class_list":{"0":"post-23221","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-zuerich","6":"job_listing_category-kindergarten","7":"job_listing_category-vorkindergarten","8":"job_listing_type-kindergarten","9":"job_listing_type-vorkindergarten","11":"job-type-kindergarten-4-6-jahre","12":"job-type-vorkindergarten"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Wings School - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/en\/listings\/wings-school\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wings School\" \/>\n<meta property=\"og:description\" content=\"Wir bieten ein sicheres Umfeld und sorgen f\u00fcr das Wohlergehen der Kinder. Das Kind soll sich aufgehoben, respektiert und sicher f\u00fchlen und Vertrauen in die Betreu\u00adungspersonen und die Gemeinschaft aufbauen k\u00f6nnen. Uns ist eine ausgewogene F\u00f6rderung in allen Entwick\u00adlungsbereichen mittels verschiedenen Methoden wichtig, welche das Kind stimulierend und motivierend einbe\u00adziehen und ihm ein breites Entdeckungs\u00ad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/en\/listings\/wings-school\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-14T12:04:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/Download-8-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/Download-8-1.png\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/wings-school\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/wings-school\\\/\",\"name\":\"Wings School - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\"},\"datePublished\":\"2020-12-11T21:49:28+00:00\",\"dateModified\":\"2020-12-14T12:04:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/wings-school\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/wings-school\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/wings-school\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wings School\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wings School - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/en\/listings\/wings-school\/","og_locale":"en_US","og_type":"article","og_title":"Wings School","og_description":"Wir bieten ein sicheres Umfeld und sorgen f\u00fcr das Wohlergehen der Kinder. Das Kind soll sich aufgehoben, respektiert und sicher f\u00fchlen und Vertrauen in die Betreu\u00adungspersonen und die Gemeinschaft aufbauen k\u00f6nnen. Uns ist eine ausgewogene F\u00f6rderung in allen Entwick\u00adlungsbereichen mittels verschiedenen Methoden wichtig, welche das Kind stimulierend und motivierend einbe\u00adziehen und ihm ein breites Entdeckungs\u00ad [&hellip;]","og_url":"https:\/\/schoolaboo.com\/en\/listings\/wings-school\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-12-14T12:04:59+00:00","og_image":[{"url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/Download-8-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/Download-8-1.png","twitter_misc":{"Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/en\/listings\/wings-school\/","url":"https:\/\/schoolaboo.com\/en\/listings\/wings-school\/","name":"Wings School - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/en\/#website"},"datePublished":"2020-12-11T21:49:28+00:00","dateModified":"2020-12-14T12:04:59+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/en\/listings\/wings-school\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/en\/listings\/wings-school\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/en\/listings\/wings-school\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/en\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/en\/angebote\/"},{"@type":"ListItem","position":3,"name":"Wings School"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/en\/#website","url":"https:\/\/schoolaboo.com\/en\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/en\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings\/23221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/comments?post=23221"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/media?parent=23221"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job_listing_region?post=23221"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-categories?post=23221"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-types?post=23221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}