{"id":22890,"date":"2020-11-06T10:38:07","date_gmt":"2020-11-06T09:38:07","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=22890"},"modified":"2020-11-06T10:38:07","modified_gmt":"2020-11-06T09:38:07","slug":"hso-wirtschaftsschule-schweiz-ag-rapperswil","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/en\/listings\/hso-wirtschaftsschule-schweiz-ag-rapperswil\/","title":{"rendered":"HSO Wirtschaftsschule Schweiz AG Rapperswil"},"content":{"rendered":"<h1 class=\"page-header\">HSO. Seit 1954<\/h1>\n<div class=\"region region-content\">\n<section id=\"block-system-main\" class=\"block block-system clearfix\">\n<div class=\"node node-page view-mode-full\">\n<div class=\"row\">\n<div class=\"col-sm-12 \">\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><strong>Die HSO-Philosophie<\/strong><\/p>\n<ul>\n<li>\u00abWitercho mit HSO\u00bb ist unser Daseinszweck im Hier und Jetzt<\/li>\n<li>\u00abWitercho mit HSO\u00bb ist unser Begleiter bei all unserem Wirken und Tun<\/li>\n<li>\u00abWitercho mit HSO\u00bb ist unsere Antwort an die Menschen, die im Leben weiterkommen wollen<\/li>\n<li>\u00abWitercho mit HSO\u00bb wird zum Statement im Kommunikations-Mix unserer Bildungsangebote<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3><strong>Unsere Vision<\/strong><\/h3>\n<p>Wir bilden Menschen von heute f\u00fcr die Zukunft von morgen.<\/p>\n<ul>\n<li>Wir leisten einen substanziellen und nachhaltigen Beitrag zur Wissensbildung unserer Gesellschaft.<\/li>\n<li>Wir sind der f\u00fchrende private Bildungsanbieter f\u00fcr Wirtschafts- und Informatiklehrg\u00e4nge in der Schweiz.<\/li>\n<li>Wir sind als privater Bildungsanbieter erste Wahl, wenn es um praxis- und handlungsorientierte Aus- und Weiterbildungen geht.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3><strong>Unsere Mission<\/strong><\/h3>\n<p>Wir bringen Menschen weiter.<\/p>\n<ul>\n<li>Wir f\u00f6rdern Menschen durch Bildung darin, in der Gesellschaft einen Beitrag zu leisten, unabh\u00e4ngig wo sie im Leben stehen.<\/li>\n<li>Wir unterst\u00fctzen Menschen beim lebenslangen Lernen und bringen sie durch unsere Bildungsangebote in ihrem privaten und beruflichen Umfeld weiter.<\/li>\n<li>Wir setzen konsequent auf wirtschafts-, praxis- und handlungsorientierte\u00a0\u00a0 Bildungsangebote und f\u00f6rdern stufengerecht die entsprechenden Fach-, Sozial- und Selbstkompetenzen.<\/li>\n<\/ul>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Die HSO verf\u00fcgte 2020 \u00fcber 3\u2019800 Studierende und einen Lehrk\u00f6rper mit 450 Mitarbeitenden und Dozenten. Die Aus- und Weiterbildung umfasst 40 verschiedene Lehrg\u00e4nge. Diese reichen von eidgen\u00f6ssischen Diplomen und Nachdiplomen \u00fcber europ\u00e4isch anerkannte Bachelorprogramme bis hin zu global akkreditierten Masterprogrammen. Dazu geh\u00f6ren die kaufm\u00e4nnische Grundausbildung und verschiedene Berufspr\u00fcfungen bis zur\u00a0H\u00f6heren Fachschule\u00a0und\u00a0Fachhochschule, sowie weiterf\u00fchrende Studien bis zum Executive Master of Business Administration (EMBA).<\/p>\n<\/div>\n<h2><span id=\"Bildungsg\u00e4nge\" class=\"mw-headline\">Bildungsg\u00e4nge<\/span><\/h2>\n<p>Die Lehrg\u00e4nge sind strukturiert in KV College, Handelsschule, Kaderschule und Marketingschule. Die einzelnen Bildungslehrg\u00e4nge wurden 2013 neu pr\u00e4zisiert und wie folgt umrissen:<\/p>\n<ul>\n<li>Das HSO KV College ist eine kaufm\u00e4nnische Berufsfach- und Maturit\u00e4tsschule f\u00fcr Einsteiger.<\/li>\n<li>Die HSO Handelsschule soll kaufm\u00e4nnische Zusatzbildung vermitteln.<\/li>\n<li>Die HSO Kaderschule soll Handlungs- und Entscheidungskompetenz vermitteln.<\/li>\n<li>Die HSO Executive Business School dient der Managementbildung.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Gl\u00e4rnischstrasse 8, 8640 Rapperswil-Jona, Schweiz","_company_website":"https:\/\/www.hso.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[159],"job-categories":[252,141,114,226,102],"job-types":[93,228],"class_list":{"0":"post-22890","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-st-gallen","6":"job_listing_category-berufsmatura","7":"job_listing_category-brueckenangebot","8":"job_listing_category-fachmittelschule","9":"job_listing_category-hoehere-fachschule","10":"job_listing_category-sekundarstufe_2","11":"job_listing_type-sekundarstufe_2","12":"job_listing_type-tertiaerausbildung","14":"job-type-sekundarstufe-2-16-19-jahre","15":"job-type-tertiarausbildung"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>HSO Wirtschaftsschule Schweiz AG Rapperswil - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/en\/listings\/hso-wirtschaftsschule-schweiz-ag-rapperswil\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HSO Wirtschaftsschule Schweiz AG Rapperswil\" \/>\n<meta property=\"og:description\" content=\"HSO. Seit 1954 Die HSO-Philosophie \u00abWitercho mit HSO\u00bb ist unser Daseinszweck im Hier und Jetzt \u00abWitercho mit HSO\u00bb ist unser Begleiter bei all unserem Wirken und Tun \u00abWitercho mit HSO\u00bb ist unsere Antwort an die Menschen, die im Leben weiterkommen wollen \u00abWitercho mit HSO\u00bb wird zum Statement im Kommunikations-Mix unserer Bildungsangebote &nbsp; Unsere Vision Wir [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/en\/listings\/hso-wirtschaftsschule-schweiz-ag-rapperswil\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/hso_logo-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/hso_logo-1.png\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/hso-wirtschaftsschule-schweiz-ag-rapperswil\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/hso-wirtschaftsschule-schweiz-ag-rapperswil\\\/\",\"name\":\"HSO Wirtschaftsschule Schweiz AG Rapperswil - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\"},\"datePublished\":\"2020-11-06T09:38:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/hso-wirtschaftsschule-schweiz-ag-rapperswil\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/hso-wirtschaftsschule-schweiz-ag-rapperswil\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/hso-wirtschaftsschule-schweiz-ag-rapperswil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HSO Wirtschaftsschule Schweiz AG Rapperswil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"HSO Wirtschaftsschule Schweiz AG Rapperswil - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/en\/listings\/hso-wirtschaftsschule-schweiz-ag-rapperswil\/","og_locale":"en_US","og_type":"article","og_title":"HSO Wirtschaftsschule Schweiz AG Rapperswil","og_description":"HSO. Seit 1954 Die HSO-Philosophie \u00abWitercho mit HSO\u00bb ist unser Daseinszweck im Hier und Jetzt \u00abWitercho mit HSO\u00bb ist unser Begleiter bei all unserem Wirken und Tun \u00abWitercho mit HSO\u00bb ist unsere Antwort an die Menschen, die im Leben weiterkommen wollen \u00abWitercho mit HSO\u00bb wird zum Statement im Kommunikations-Mix unserer Bildungsangebote &nbsp; Unsere Vision Wir [&hellip;]","og_url":"https:\/\/schoolaboo.com\/en\/listings\/hso-wirtschaftsschule-schweiz-ag-rapperswil\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/hso_logo-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/hso_logo-1.png","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/en\/listings\/hso-wirtschaftsschule-schweiz-ag-rapperswil\/","url":"https:\/\/schoolaboo.com\/en\/listings\/hso-wirtschaftsschule-schweiz-ag-rapperswil\/","name":"HSO Wirtschaftsschule Schweiz AG Rapperswil - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/en\/#website"},"datePublished":"2020-11-06T09:38:07+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/en\/listings\/hso-wirtschaftsschule-schweiz-ag-rapperswil\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/en\/listings\/hso-wirtschaftsschule-schweiz-ag-rapperswil\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/en\/listings\/hso-wirtschaftsschule-schweiz-ag-rapperswil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/en\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/en\/angebote\/"},{"@type":"ListItem","position":3,"name":"HSO Wirtschaftsschule Schweiz AG Rapperswil"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/en\/#website","url":"https:\/\/schoolaboo.com\/en\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/en\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings\/22890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/comments?post=22890"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/media?parent=22890"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job_listing_region?post=22890"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-categories?post=22890"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-types?post=22890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}