{"id":22480,"date":"2020-11-06T12:28:55","date_gmt":"2020-11-06T11:28:55","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=22480"},"modified":"2020-12-22T11:15:22","modified_gmt":"2020-12-22T10:15:22","slug":"sol-schule-fuer-offenes-lernen","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/en\/listings\/sol-schule-fuer-offenes-lernen\/","title":{"rendered":"SOL Schule f\u00fcr Offenes Lernen"},"content":{"rendered":"<div class=\"article\">\n<div class=\"article-content\">\n<div class=\"RichTextElement\">\n<div>\n<p><span style=\"font-size: 2.25rem;\">Was wollen wir<\/span><\/p>\n<\/div>\n<div class=\"collection-navigation text-navigation\">\n<div class=\"next-page\"><\/div>\n<\/div>\n<div class=\"article\">\n<div class=\"article-content\">\n<div class=\"RichTextElement\">\n<div>\n<div class=\"first callout-container\">\n<div class=\"callout\">\n<div class=\"callout-content\">\n<div class=\"pagelet untitled i1 o last-item\">\n<div class=\"pagelet-body\">\n<div class=\"ImageElement\">\n<div class=\"photo\">\n<div><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.offeneslernen.ch\/_Media\/p1000917_med.jpeg\" alt=\"P1000917\" width=\"200\" height=\"150\" \/><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Warum eine andere Schule? In der SOL Schule f\u00fcr Offenes Lernen haben sich\u00a0LehrerInnen und Eltern zusammengefunden, weil sie Anspr\u00fcche und\u00a0\u00dcberzeugungen haben.<\/p>\n<p>Anspr\u00fcche: Die Schule soll die Bed\u00fcrfnisse und F\u00e4higkeiten der Sch\u00fclerInnen\u00a0ernst nehmen.<br \/>\n\u00dcberzeugungen: Eine Schule, die anders ist als die bestehenden, die sich vom\u00a0\u201cNormalen\u201d und \u201cSelbstverst\u00e4ndlichen\u201d, von der Behauptung, wie es in der\u00a0Schule immer gewesen sei und deshalb immer sein werde, l\u00f6st und\u00a0p\u00e4dagogische Ideale konsequent umsetzt &#8211; eine solche Schule ist n\u00f6tig, ist\u00a0m\u00f6glich und wird Erfolg haben.<\/p>\n<p><strong>Eine menschenfreundliche Schule f\u00fcr die Gegenwart\u00a0<\/strong><\/p>\n<p>Schulzeit ist Lebenszeit. Sch\u00fcler und Sch\u00fclerinnen sind nicht nur zuk\u00fcnftige\u00a0Erwachsene, die lernen m\u00fcssen, was sie sp\u00e4ter n\u00f6tig haben werden. Sie sind\u00a0vollwertige Menschen, die ein Recht haben auf eine erf\u00fcllte Kindheit und\u00a0Jugendzeit. Die Schule nimmt darin einen breiten Platz ein. Sie muss den<br \/>\nHeranwachsenden eine sinnvolle Gestaltung ihres jetzigen Lebens\u00a0erm\u00f6glichen, sie ernst nehmen in ihren Bed\u00fcrfnissen; ihre Sinne, ihre Gef\u00fchle,\u00a0ihren Verstand und ihren K\u00f6rper ansprechen und sich entfalten lassen. Das ist\u00a0die Voraussetzung daf\u00fcr, dass die Sch\u00fclerInnen die selbstverst\u00e4ndlichen<br \/>\nKulturtechniken (Sprache, Lesen, Schreiben, Rechnen, Naturwissenschaften,\u00a0Fremdsprachen, Umgang mit Computer und Internet) erwerben k\u00f6nnen.<\/p>\n<p><strong>Eine Schule, welche die Pers\u00f6nlichkeit der Kinder und Jugendlichen achtet<\/strong><\/p>\n<p>Kinder und Jugendliche haben das grundlegende Recht, ernst genommen zu\u00a0werden, ihre Bed\u00fcrfnisse wahrzunehmen, \u00fcber ihre Lebensgestaltung selbst zu\u00a0entscheiden. Zu ihren Rechten geh\u00f6rt aber auch dasjenige auf Geborgenheit,\u00a0auf speziellen Schutz vor \u00e4usserem Druck und vor den Anspr\u00fcchen aller<br \/>\nm\u00f6glichen Moden, seien es kommerzielle oder p\u00e4dagogische. Wir widersetzen\u00a0uns der trendigen Forderung, die Menschen m\u00fcssten auf die (st\u00e4ndig\u00a0wechselnden) Bed\u00fcrfnisse der Wirtschaft hin ausgerichtet werden, sondern\u00a0halten am alten humanistischen Ideal der Pers\u00f6nlichkeitsentfaltung fest. Jedes\u00a0einzelne Kind, jede und jeder Jugendliche wird in seiner Eigenart geachtet und\u00a0unterst\u00fctzt. Gelingt uns das, k\u00f6nnen die Kinder und Jugendlichen auch\u00a0Achtung vor ihren Mitmenschen und der gesamten Mitwelt entwickeln.<\/p>\n<p><strong>Eine Schule f\u00fcr die Gestaltung der Zukunft<\/strong><\/p>\n<p>Indem die Schule der Entfaltung der Pers\u00f6nlichkeit, der eigenverantwortlichen\u00a0Lebensgestaltung und dem Respekt f\u00fcr die Gemeinschaft Priorit\u00e4t einr\u00e4umt,\u00a0bereitet sie die Kinder und Jugendlichen genau auf die Anforderungen vor, die\u00a0in der gegenw\u00e4rtigen und zuk\u00fcnftigen Gesellschaft auf sie zukommen:<br \/>\nSelbst\u00e4ndigkeit, Teamf\u00e4higkeit, Flexibilit\u00e4t, die Lust am Weiterlernen, die\u00a0F\u00e4higkeit, sich mit der Realit\u00e4t auseinanderzusetzen, und die Bereitschaft,\u00a0soziale und oekologische Verantwortung zu \u00fcbernehmen. Unsere Schule\u00a0unterst\u00fctzt die Sch\u00fclerInnen darin, die F\u00e4higkeiten zu entwickeln, um\u00a0n\u00fctzliche Mitglieder der Gesellschaft zu werden. Das schliesst auch ein: die\u00a0Gesellschaft nach ihren Bed\u00fcrfnissen und in Respekt vor den Bed\u00fcrfnissen\u00a0ihrer Mitwelt zu gestalten.<\/p>\n<\/div>\n<\/div>\n<h2 class=\"title\"><span class=\"in\">Wer sind wir<\/span><\/h2>\n<div class=\"collection-navigation text-navigation\">\n<div class=\"next-page\"><\/div>\n<\/div>\n<div class=\"article\">\n<div class=\"article-content\">\n<div class=\"RichTextElement\">\n<div>\n<div class=\"first callout-container\">\n<div class=\"callout\">\n<div class=\"callout-content\">\n<div class=\"pagelet untitled i1 o last-item\">\n<div class=\"pagelet-body\">\n<div class=\"ImageElement\">\n<div class=\"photo\">\n<div><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.offeneslernen.ch\/_Media\/schulfoto3_med.jpeg\" alt=\"Schulfoto3\" width=\"200\" height=\"133\" \/><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Die SOL Schule f\u00fcr Offenes Lernen ist aus der Freien Volksschule Basel (FVB)\u00a0hervorgegangen. Diese wurde 1982 gegr\u00fcndet. 1999 hat das LehrerInnenteam\u00a0mit einer Mehrheit der Eltern nach internen Konflikten die Schulgemeinschaft\u00a0in Pratteln, seit 2000 in Liestal, neu aufgebaut. Die SOL ist also eine neue\u00a0Schule mit zwanzigj\u00e4hriger Erfahrung.<\/p>\n<p>Die SOL umfasst die gesamte Volksschule, 1. bis 10. Klasse. Sie f\u00fchrt keine\u00a0Jahrgangsklassen, sondern funktioniert als Gesamtschule und erinnert darin\u00a0etwas an die alten Dorfschulen.<\/p>\n<p>Nicht f\u00fcr jedes Kind resp. Jugendlichen ist die SOL die richtige Schule. Vor der\u00a0Aufnahme ist eine genaue Bed\u00fcrfnisabkl\u00e4rung n\u00f6tig. Die Schule steht aber\u00a0grunds\u00e4tzlich allen offen und verzichtet bewusst auf Selektion und Noten. Mit\u00a0ihrer Struktur als Gesamtschule und dem reformp\u00e4dagogischen Ansatz, der\u00a0die Sch\u00fclerInnen in ihren je eigenen F\u00e4higkeiten und Besonderheiten ernst\u00a0nimmt, erweist sie sich f\u00fcr die unterschiedlichsten Kinder und Jugendlichen als\u00a0ideal. Besonders begabte Sch\u00fclerInnen k\u00f6nnen hier \u2013 genauso wie\u00a0Sch\u00fclerInnen mit bestimmten Schwierigkeiten \u2013 in ihrem eigenen Tempo\u00a0lernen. Die Schule kann dank ihrem besonderen Konzept auf die\u00a0verschiedensten individuellen Bed\u00fcrfnisse eingehen.<\/p>\n<p>Ganz nat\u00fcrlich bew\u00e4hrt sich das Konzept auch zur Integration geistig und\u00a0k\u00f6rperlich behinderter Kinder. Die Schule hat damit grosse Erfahrung und\u00a0beste Erfolge auszuweisen. F\u00fcr die sogenannt \u201cnormalen\u201d Sch\u00fclerInnen erweist\u00a0sich das Zusammenleben mit Behinderten als in vielerlei Hinsicht sehr\u00a0f\u00f6rderlich.<\/p>\n<p>Die SOL orientiert sich konsequent an den anspruchsvollen Leitzielen des\u00a0staatlichen Lehrplans und vermittelt neben Haltungen und grundlegenden\u00a0F\u00e4higkeiten die f\u00fcr unsere Gesellschaft notwendigen Kulturtechniken. Sie h\u00e4lt\u00a0sich aber nicht im Detail an die staatlichen Stoffpl\u00e4ne, da sie gerade das<br \/>\nUnterrichten mit Stoffdruck und nach starren \u00e4usseren Vorgaben f\u00fcr\u00a0unp\u00e4dagogisch und f\u00fcr sch\u00e4dlich h\u00e4lt f\u00fcr die Entwicklung der Pers\u00f6nlichkeit\u00a0und der Lernlust. Die Schule untersteht der Aufsicht durch das\u00a0Basellandschaftliche Amt f\u00fcr Volksschulen, das an ihr auch schon eine ihrer\u00a0ersten Schulevaluationen durchgef\u00fchrt hat.<\/p>\n<div class=\"not-first-item callout-container\">\n<div class=\"callout\">\n<div class=\"callout-content\">\n<div class=\"pagelet untitled i1 o last-item\">\n<div class=\"pagelet-body\">\n<div class=\"ImageElement\">\n<div class=\"photo\">\n<div><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.offeneslernen.ch\/_Media\/schulfoto1_med.jpeg\" alt=\"Schulfoto1\" width=\"200\" height=\"133\" \/><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Die Erfahrung zeigt, dass sich unsere Sch\u00fclerInnen in den weiterf\u00fchrenden\u00a0Ausbildungsg\u00e4ngen, sei es eine Diplomschule, ein Gymnasium oder eine\u00a0Berufslehre, bew\u00e4hren. Sie zeichnen sich dort durch \u00fcberdurchschnittliches\u00a0Interesse, Selbst\u00e4ndigkeit, Verantwortungsgef\u00fchl und Selbstbewusstsein aus.<br \/>\nWer aus unserer Schule kommt, ist bestimmt nicht lernm\u00fcde und hat nicht den\u00a0\u201cVerleider\u201d.<br \/>\nDas LehrerInnen-Team besteht aus Fachkr\u00e4ften aller Schulstufen sowie\u00a0verschiedener Bereiche (Begabungsf\u00f6rderung, Theaterp\u00e4dagogik,\u00a0Sozialp\u00e4dagogik, Legasthenietherapie, Psychotherapie, Heilp\u00e4dagogik). Die\u00a0LehrerInnen setzen ihre F\u00e4higkeiten und Erfahrungen aus den verschiedensten<br \/>\nBereichen in unserer Schule um. Gemeinsam werden an den w\u00f6chentlichen\u00a0Sitzungen und den regelm\u00e4ssigen\u00a0Weiterbildungen die Entwicklung der Sch\u00fclerInnen besprochen, neue Ideen\u00a0entwickelt und umgesetzt und das Schulkonzept verfeinert.<\/p>\n<p>Als nicht-staatliche Schule tragen wir alle Kosten selbst. Die Schule finanziert\u00a0sich \u00fcber Schulgelder, die den finanziellen Verh\u00e4ltnissen der Eltern angepasst\u00a0sind. Es ist uns wichtig, die Schulkosten sozial abzustufen und solidarisch zu\u00a0tragen. Der individuelle Schulbeitrag wird in einem Gespr\u00e4ch vereinbart. Von\u00a0den Eltern wird zudem ideelle und praktische Mitarbeit im Rahmen ihrer\u00a0M\u00f6glichkeiten erwartet.<\/p>\n<p>Zur Zeit bilden 60 Sch\u00fclerInnen zusammen mit 16 fest angestellten LehrerInnen und MitarbeiterInnen\u00a0(die sich in 13 Stellen teilen) die Schulgemeinschaft. Es besteht eine rege\u00a0Nachfrage nach Pl\u00e4tzen, doch k\u00f6nnen wir nicht alle InteressentInnen\u00a0aufnehmen. Die Schule soll klein bleiben, damit die pers\u00f6nlichen\u00a0Beziehungen weiterhin im Zentrum stehen k\u00f6nnen.<\/p>\n<\/div>\n<h2 class=\"title\"><span class=\"in\">Wie machen wir Schule<\/span><\/h2>\n<div class=\"collection-navigation text-navigation\">\n<div class=\"next-page\"><\/div>\n<\/div>\n<div class=\"article\">\n<div class=\"article-content\">\n<div class=\"RichTextElement\">\n<div>\n<div class=\"first callout-container\">\n<div class=\"callout\">\n<div class=\"callout-content\">\n<div class=\"pagelet untitled i1 o last-item\">\n<div class=\"pagelet-body\">\n<div class=\"ImageElement\">\n<div class=\"photo\">\n<div><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.offeneslernen.ch\/_Media\/unterricht1_med.jpeg\" alt=\"Unterricht1\" width=\"200\" height=\"150\" \/><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Reformp\u00e4dagogik<\/strong><\/p>\n<p>Wir respektieren die individuelle Eigenart jedes Menschen, also auch unserer\u00a0Sch\u00fclerInnen. Sie sollen sich ihre Welt selbst erobern und sie gestalten. Wir\u00a0betreiben eine P\u00e4dagogik der Erfolgserlebnisse. Wenn sich Kinder und\u00a0Jugendliche an ihren Erfolgen st\u00e4rken, k\u00f6nnen sie auch mit Misserfolgen\u00a0besser umgehen.<\/p>\n<p>Uns inspiriert die Reformp\u00e4dagogik von verschiedenen\u00a0P\u00e4dagoginnen, wie z.B. C\u00e9lestin Freinet sowie die humanistische\u00a0Psychologie von Carl Rogers, die alle auf \u00e4hnlichen Grundlagen aufbauen, und\u00a0ihre Weiterentwicklungen. Im Speziellen lassen wir die Ideen der Freinet-Bewegung in unseren Schulalltag einfliessen und stehen im Austausch mit\u00a0LehrerInnen und ihren Klassen, die an den verschiedensten Schulen die\u00a0Freinet-P\u00e4dagogik weiterentwickeln.<\/p>\n<p>Unser Interesse gilt der weiteren Entwicklung des Schulwesens insgesamt.\u00a0Alternativschulen beziehen ihre Berechtigung auch aus dem Ausmass, in dem\u00a0sie die Regelschule befruchten k\u00f6nnen. Daher sind wir aktiv in der\u00a0Schulentwicklung und der LehrerInnenfortbildung t\u00e4tig.<\/p>\n<p><strong>Offener Unterricht<\/strong><\/p>\n<p>Der offene Unterricht bietet Kindern und Jugendlichen die geeignete\u00a0Umgebung, in der sie sie selbst sein k\u00f6nnen und sich auf ihre je eigene Weise\u00a0und in ihrem individuellen Tempo entwickeln. Speziellen Wert legen wir auf\u00a0individuelle Entdeckung, unmittelbare Erfahrung und sch\u00f6pferische Arbeit.<\/p>\n<p>K\u00fcnstliche Trennungen von Spiel und Arbeit oder von verschiedenen F\u00e4chern\u00a0werden aufgehoben. Sie sollen sich erg\u00e4nzen und nicht konkurrenzieren. Die\u00a0Schulr\u00e4ume sind als Ateliers mit unterschiedlichem Inhalt eingerichtet und\u00a0bieten reichlich anregendes Material f\u00fcr Entdeckungen und Erfahrungen. So<br \/>\nk\u00f6nnen im Mathematik-Atelier Erfahrungen gesammelt werden zu Gewichten,\u00a0Mengen, Zahlenreihen, Gleichungen etc. Weitere Ateliers stehen zur Zeit zur\u00a0Verf\u00fcgung f\u00fcr Sprache und Schreiben, Franz\u00f6sisch, Englisch, Naturkunde,\u00a0Musik und Theater, Geographie und Geschichte, Werken und Gestalten sowie\u00a0N\u00e4hen. Nach den Bed\u00fcrfnissen der Sch\u00fclerInnen und der Gemeinschaft<br \/>\nentstehen weitere Ateliers und sogenannte Clubs (Arbeitsgemeinschaften von\u00a0Sch\u00fclerInnen), die sich zusammen mit einer Lehrperson mit speziellen Themen\u00a0auseinandersetzen.<\/p>\n<p><strong>Soziales Lernen<\/strong><\/p>\n<p>Soziales Lernen findet statt, wenn unterschiedliche Menschen gemeinsam t\u00e4tig\u00a0sind und sich um Respekt f\u00fcr jedes Individuum, aber auch f\u00fcr die\u00a0Gemeinschaft bem\u00fchen. Wir sind eine Gesamtschule mit Kindern und\u00a0Jugendlichen von 6 bis 17 Jahren. Sch\u00fclerInnen mit den verschiedensten<br \/>\nF\u00e4higkeiten geh\u00f6ren zu unserer Schulgemeinschaft und werden nicht k\u00fcnstlich\u00a0auseinander dividiert.<\/p>\n<p>Die Kinder und Jugendlichen \u00fcbernehmen Verantwortung f\u00fcr die\u00a0Gemeinschaft. Die verschiedenen Aufgaben \u2013 Morgenessen und Zn\u00fcni\u00a0bereitstellen, Mittagessen kochen, Schulkonferenz leiten, Bibliothek betreuen,\u00a0Putzplan erstellen, Post bringen resp. abholen und vieles mehr \u2013 sind einer<br \/>\nSch\u00fclerin, einem Sch\u00fcler oder einer kleinen Gruppe zugeteilt. JedeR kann so\u00a0mit der \u00dcbernahme von Verantwortung den Lebensraum Schule aktiv\u00a0mitgestalten und somit ein gutes Selbstwertgef\u00fchl entwickeln.<\/p>\n<p><strong>Inklusion<\/strong><\/p>\n<p>Das Konzept der Schule macht es m\u00f6glich, dass Kinder und Jugendliche mit\u00a0unterschiedlicher Begabung und Pers\u00f6nlichkeit miteinander, aneinander und\u00a0durch einander lernen k\u00f6nnen. Konsequenterweise integrieren wir auch ein bis\u00a0drei geistig oder k\u00f6rperlich behinderte Kinder und Jugendliche &#8211; mit viel\u00a0Erfolg. Weil keine starren Lernprogramme in Jahrgangsklassen mit<br \/>\neinheitlichem Anspruchsniveau durchgearbeitet werden m\u00fcssen, befinden sich\u00a0die Sch\u00fclerInnen mit besonderen Begabungen und die behinderten\u00a0Sch\u00fclerInnen nicht fortw\u00e4hrend in einem Sonderstatus als diejenigen, welche\u00a0st\u00e4ndig unterfordert sind, oder als diejenigen, welche die Lernziele ohnehin\u00a0nicht erreichen.<\/p>\n<p>Auch die behinderten Kinder und Jugendlichen beteiligen sich an den\u00a0Schulaktivit\u00e4ten, Lagern, Ausfl\u00fcgen, Schulproduktionen. Durch ihre Integration\u00a0in den Schulalltag, die von einer Fachperson unterst\u00fctzt wird, gewinnen sie ein\u00a0doppeltes Selbstbewusstsein: Sie werden sich einerseits ihrer Behinderung\u00a0bewusst und lernen sich andererseits in einer Welt der Nicht-Behinderten\u00a0behaupten. Diese Form der Inklusion ist f\u00fcr alle Sch\u00fclerInnen wertvoll. Sie\u00a0verst\u00e4rkt den Impuls zur gegenseitigen Achtung und Hilfsbereitschaft und das\u00a0Bewusstsein daf\u00fcr, dass alle Menschen ihre eigenen Begabungen und\u00a0Schw\u00e4chen haben.<\/p>\n<p><strong>Schule ohne Not(en)<\/strong><\/p>\n<p>Einen Menschen akzeptieren heisst auch anerkennen, dass er seinen eigenen\u00a0Rhythmus hat. Eine Selektion mit Noten oder \u00dcbertrittsbedingungen vermeiden\u00a0wir bewusst. Wir wollen positive Erfahrungen beim Lernen vermitteln. Die SOL\u00a0arbeitet seit jeher mit Portofolios. Die Sch\u00fclerInnen legen deshalb eine<br \/>\nDokumentation an dar\u00fcber, was sie gelernt und geschaffen haben. Wir f\u00f6rdern\u00a0das Lernen aus Freude und Eigeninteresse und lehnen Notendruck und\u00a0Leistungsmessung an starren Kriterien ab. Dadurch m\u00fcssen wir uns bei den\u00a0Lerninhalten auch nicht auf das beschr\u00e4nken, was messbar und benotbar ist.<br \/>\nWir unterliegen also nicht der Banalisierung der Inhalte, wie sie f\u00fcr Schulen,\u00a0welche Selektion mittels Noten betreiben, typisch ist.<\/p>\n<p>Wir beraten die \u00e4lteren Sch\u00fclerInnen in der Berufswahl, erm\u00f6glichen Praktika\u00a0und ziehen ehemalige Sch\u00fclerInnen bei, die von ihren Erfahrungen nach der\u00a0obligatorischen Schulzeit berichten. Die Sch\u00fclerInnen werden bei Bedarf darin\u00a0unterst\u00fctzt, sich die n\u00f6tigen F\u00e4higkeiten zu erwerben, die sie f\u00fcr den \u00dcbertritt\u00a0in die anschliessenden Ausbildungsg\u00e4nge ben\u00f6tigen. Die Erfahrung zeigt, dass<br \/>\nunsere Sch\u00fclerInnen sich in den nachobligatorischen Ausbildungen bew\u00e4hren\u00a0und von den Ausbildungsverantwortlichen gesch\u00e4tzt werden.<\/p>\n<p><strong>Einbezug der Eltern<\/strong><\/p>\n<p>Unsere Schule lebt nicht nur vom Engagement der LehrerInnen und\u00a0Sch\u00fclerInnen, sondern auch von dem der Eltern. Eine grundlegende Qualit\u00e4t\u00a0von Schule besteht zwar darin, dass Kinder und Jugendliche in einen\u00a0Erfahrungsbereich treten, der \u00fcber denjenigen der eigenen Familie\u00a0hinausreicht. Trotzdem sollen die Eltern aus dem Lebensbereich Schule nicht\u00a0ausgeschlossen sein. Ihre Mithilfe ist in verschiedensten Bereichen gefragt.\u00a0H\u00e4ufige Gespr\u00e4che der LehrerInnen mit den Eltern helfen, die Bed\u00fcrfnisse der\u00a0Kinder und Jugendlichen genauer zu erfassen und ihre Unterst\u00fctzung zu\u00a0koordinieren. Regelm\u00e4ssig finden Elternabende zur Information und zu\u00a0gemeinsamer Fortbildung statt. Das Ideal ist eine Schule f\u00fcr alle, in der alle\u00a0ihre F\u00e4higkeiten und Kenntnisse einbringen und alle lernen und sich\u00a0weiterentwickeln k\u00f6nnen.<\/p>\n<p><strong>Naturarzt<\/strong><\/p>\n<p>Die SOL arbeitet mit einem Naturarzt zusammen. Die Kinder und\u00a0Jugendlichen k\u00f6nnen selbst bestimmen, in Absprache mit ihren Eltern, wann\u00a0sie Unterst\u00fctzung durch Hom\u00f6opathie in\u00a0Anspruch nehmen. Die Beratung findet in der Schule statt. Mit dieser ganzheitlichen\u00a0Praxis haben wir sehr gute Erfahrungen gemacht.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Benzburweg 18, 4410 Liestal, Schweiz","_company_website":"http:\/\/www.offeneslernen.ch\/kontakt\/stiftung-offenes-lernen.html","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[158,414],"job-categories":[141,99,76],"job-types":[5,92],"class_list":{"0":"post-22480","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-basel-land","6":"job_listing_region-basel-stadt-land","7":"job_listing_category-brueckenangebot","8":"job_listing_category-primarschule","9":"job_listing_category-sekundarstufe_1","10":"job_listing_type-primarschule","11":"job_listing_type-sekundarstufe_1","13":"job-type-primarschule-7-12jahre","14":"job-type-sekundarstufe-1-13-16-jahre"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SOL Schule f\u00fcr Offenes Lernen - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/en\/listings\/sol-schule-fuer-offenes-lernen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SOL Schule f\u00fcr Offenes Lernen\" \/>\n<meta property=\"og:description\" content=\"Was wollen wir Warum eine andere Schule? In der SOL Schule f\u00fcr Offenes Lernen haben sich\u00a0LehrerInnen und Eltern zusammengefunden, weil sie Anspr\u00fcche und\u00a0\u00dcberzeugungen haben. Anspr\u00fcche: Die Schule soll die Bed\u00fcrfnisse und F\u00e4higkeiten der Sch\u00fclerInnen\u00a0ernst nehmen. \u00dcberzeugungen: Eine Schule, die anders ist als die bestehenden, die sich vom\u00a0\u201cNormalen\u201d und \u201cSelbstverst\u00e4ndlichen\u201d, von der Behauptung, wie es in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/en\/listings\/sol-schule-fuer-offenes-lernen\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-22T10:15:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/Download-3.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/Download-3.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/sol-schule-fuer-offenes-lernen\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/sol-schule-fuer-offenes-lernen\\\/\",\"name\":\"SOL Schule f\u00fcr Offenes Lernen - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/sol-schule-fuer-offenes-lernen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/sol-schule-fuer-offenes-lernen\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.offeneslernen.ch\\\/_Media\\\/p1000917_med.jpeg\",\"datePublished\":\"2020-11-06T11:28:55+00:00\",\"dateModified\":\"2020-12-22T10:15:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/sol-schule-fuer-offenes-lernen\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/sol-schule-fuer-offenes-lernen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/sol-schule-fuer-offenes-lernen\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.offeneslernen.ch\\\/_Media\\\/p1000917_med.jpeg\",\"contentUrl\":\"http:\\\/\\\/www.offeneslernen.ch\\\/_Media\\\/p1000917_med.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/sol-schule-fuer-offenes-lernen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SOL Schule f\u00fcr Offenes Lernen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SOL Schule f\u00fcr Offenes Lernen - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/en\/listings\/sol-schule-fuer-offenes-lernen\/","og_locale":"en_US","og_type":"article","og_title":"SOL Schule f\u00fcr Offenes Lernen","og_description":"Was wollen wir Warum eine andere Schule? In der SOL Schule f\u00fcr Offenes Lernen haben sich\u00a0LehrerInnen und Eltern zusammengefunden, weil sie Anspr\u00fcche und\u00a0\u00dcberzeugungen haben. Anspr\u00fcche: Die Schule soll die Bed\u00fcrfnisse und F\u00e4higkeiten der Sch\u00fclerInnen\u00a0ernst nehmen. \u00dcberzeugungen: Eine Schule, die anders ist als die bestehenden, die sich vom\u00a0\u201cNormalen\u201d und \u201cSelbstverst\u00e4ndlichen\u201d, von der Behauptung, wie es in [&hellip;]","og_url":"https:\/\/schoolaboo.com\/en\/listings\/sol-schule-fuer-offenes-lernen\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-12-22T10:15:22+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/Download-3.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/Download-3.jpg","twitter_misc":{"Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/en\/listings\/sol-schule-fuer-offenes-lernen\/","url":"https:\/\/schoolaboo.com\/en\/listings\/sol-schule-fuer-offenes-lernen\/","name":"SOL Schule f\u00fcr Offenes Lernen - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoolaboo.com\/en\/listings\/sol-schule-fuer-offenes-lernen\/#primaryimage"},"image":{"@id":"https:\/\/schoolaboo.com\/en\/listings\/sol-schule-fuer-offenes-lernen\/#primaryimage"},"thumbnailUrl":"http:\/\/www.offeneslernen.ch\/_Media\/p1000917_med.jpeg","datePublished":"2020-11-06T11:28:55+00:00","dateModified":"2020-12-22T10:15:22+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/en\/listings\/sol-schule-fuer-offenes-lernen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/en\/listings\/sol-schule-fuer-offenes-lernen\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/schoolaboo.com\/en\/listings\/sol-schule-fuer-offenes-lernen\/#primaryimage","url":"http:\/\/www.offeneslernen.ch\/_Media\/p1000917_med.jpeg","contentUrl":"http:\/\/www.offeneslernen.ch\/_Media\/p1000917_med.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/en\/listings\/sol-schule-fuer-offenes-lernen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/en\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/en\/angebote\/"},{"@type":"ListItem","position":3,"name":"SOL Schule f\u00fcr Offenes Lernen"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/en\/#website","url":"https:\/\/schoolaboo.com\/en\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/en\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings\/22480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/comments?post=22480"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/media?parent=22480"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job_listing_region?post=22480"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-categories?post=22480"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-types?post=22480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}