{"id":22068,"date":"2021-04-02T17:49:11","date_gmt":"2021-04-02T15:49:11","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=22068"},"modified":"2026-04-24T13:39:39","modified_gmt":"2026-04-24T11:39:39","slug":"freie-schule-zuerich","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/en\/listings\/freie-schule-zuerich\/","title":{"rendered":"Freie Schule Z\u00fcrich"},"content":{"rendered":"<h1><span style=\"font-size: 3rem;\"><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-31845 size-full\" src=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/04\/fsz_logo_zusatz_seit_1874_RGB.jpg\" alt=\"\" width=\"1959\" height=\"1251\" srcset=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/04\/fsz_logo_zusatz_seit_1874_RGB.jpg 1959w, https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/04\/fsz_logo_zusatz_seit_1874_RGB-500x319.jpg 500w, https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/04\/fsz_logo_zusatz_seit_1874_RGB-1500x958.jpg 1500w, https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/04\/fsz_logo_zusatz_seit_1874_RGB-768x490.jpg 768w, https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/04\/fsz_logo_zusatz_seit_1874_RGB-1536x981.jpg 1536w, https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/04\/fsz_logo_zusatz_seit_1874_RGB-450x287.jpg 450w, https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/04\/fsz_logo_zusatz_seit_1874_RGB-1253x800.jpg 1253w\" sizes=\"auto, (max-width: 1959px) 100vw, 1959px\" \/><\/span><\/span><\/h1>\n<h1><\/h1>\n<hr class=\"clear\" \/>\n<h1><span style=\"font-size: 3rem;\">Frei \u2013 aber nicht wertfrei. Die Schule f\u00fcr Kopf, Hand und Herz.<br \/>\n<\/span><\/h1>\n<div class=\"field field--name-field-paragraph field--type-entity-reference-revisions field--label-hidden field--items\">\n<div class=\"field--item\">\n<div class=\"row\">\n<div class=\"col-sm-12 col-md-9\">\n<div class=\"container-mit-verbindungslinie\">\n<div class=\"row row-eq-height-xs verbindungslinie-last\">\n<div class=\"col-xs-12 col-rest col-eq-height-middle\">\n<div class=\"field field--name-field-text field--type-text-long field--label-hidden field--item\">\n<p>Ob Primarschule, \u00dcbergangsklasse, Sekundarschule, 10. Schuljahr oder Kleinklasse \u2013 das Angebot der Freien Schule Z\u00fcrich holt die Sch\u00fclerinnen und Sch\u00fcler dort ab, wo sie stehen. Vor der Aufnahme versuchen wir die Bed\u00fcrfnisse des Kindes zu eruieren. Was braucht das Kind, um sich optimal zu entwickeln? Wo braucht es gezielte F\u00f6rderung? Welcher Schultyp passt?<br \/>\nUnser Team von rund 60 Lehrpersonen unterrichtet zurzeit rund 400 Sch\u00fclerinnen und Sch\u00fcler in 24 Klassen. Unsere Schule ist eine nicht gewinnorientierte Privatschule und orientiert sich an christlichen Werten. Sie steht allen unabh\u00e4ngig ihrer Religionszugeh\u00f6rigkeit offen. Bewusst pflegen wir gemeinsame Erlebnisse und Rituale \u2013 im Unterricht und im Schulalltag. Wir pflegen eine Kultur des \u00abHinschauens\u00bb. Selbst\u00e4ndiges Lernen f\u00f6rdern wir, indem wir Verantwortung \u00fcbertragen.<br \/>\nBesuchen Sie uns an einem Informationsabend oder kommen Sie zu einem Gespr\u00e4ch vorbei. Wir freuen uns, Sie pers\u00f6nlich kennenzulernen.<\/p>\n<p><span style=\"font-size: 3rem;\">Primarschule<br \/>\n<\/span><span style=\"color: inherit; font-family: inherit; font-size: inherit;\">Unser Angebot auf der Primarstufe beginnt ab der 5. Klasse. In \u00fcberschaubaren Klassen werden die Sch\u00fclerinnen und Sch\u00fcler auf die Sekundarschule oder aufs Gymnasium vorbereitet. Mit modernen Arbeitstechniken lernen sie den Umgang mit Leistung und profitieren von betreutem Lernen. Das Wichtigste zur Primarschule in K\u00fcrze:<\/span><\/p>\n<\/div>\n<div class=\"field field--name-field-paragraph field--type-entity-reference-revisions field--label-hidden field--items\">\n<div class=\"field--item\">\n<div class=\"row sb-paragraph-mit-abstand wysiwyg-content\">\n<div class=\"col-sm-12 col-md-6\">\n<ul>\n<li>Die Primarschule ist eine Tagesschule in Z\u00fcrich mit betreutem Mittagstisch.<\/li>\n<li>Die Sch\u00fclerinnen und Sch\u00fcler \u00fcbernehmen Verantwortung innerhalb der Klassengemeinschaft.<\/li>\n<li>Die Kinder profitieren vom Angebot der Hausaufgabenbetreuung.<\/li>\n<li>Die optimale Vorbereitung aufs Langzeitgymnasium oder die Sekundarstufen A oder B ist das Ziel der Primarstufe.<\/li>\n<\/ul>\n<p>In der Primarschule legen wir Wert auf<\/p>\n<ul>\n<li>eine gezielte F\u00f6rderung in einem angenehmen Lernumfeld<\/li>\n<li>die Pflege von Ritualen<\/li>\n<li>\u00fcberschaubare Klassen und klare Strukturen<\/li>\n<li>eine w\u00f6chentlich gepflegte Feedback-Kultur durch Arbeit mit dem Lernjournal<\/li>\n<\/ul>\n<h1>Sekundarschule<\/h1>\n<div class=\"field field--name-field-paragraph field--type-entity-reference-revisions field--label-hidden field--items\">\n<div class=\"field--item\">\n<div class=\"row sb-paragraph-mit-abstand wysiwyg-content\">\n<div class=\"col-sm-12 col-md-6\">\n<p>Vielseitige\u00a0Angebote erwarten unsere Lernenden auf der Sekundarstufe. Ausgehend vom\u00a0kantonalen Lehrplan, geh\u00f6ren\u00a0das Training von Arbeits- und\u00a0Lerntechniken ebenso\u00a0zum Unterricht wie musische F\u00e4cher. Wir\u00a0f\u00fchren unsere Sekundarsch\u00fclerinnen und -sch\u00fcler strukturiert ans selbstorganisierte\u00a0Lernen heran. Raum dazu\u00a0bieten unsere\u00a0<strong>Lernlandschaften<\/strong>.<\/p>\n<p>Wir bieten die Sekundarstufe A an f\u00fcr Sch\u00fclerinnen und Sch\u00fcler, die ein h\u00f6heres Arbeitstempo bevorzugen und sich auf die Mittelschule oder eine Lehre mit Berufs- oder eine Fachmittelschule vorbereiten m\u00f6chten. Die Sekundarstufe B eignet sich f\u00fcr Jugendliche, die den Schulstoff in \u00fcberschaubaren Einheiten aufnehmen, als Vorbereitung auf das 10. Schuljahr oder eine Berufslehre. Das Wichtigste zu den beiden Sekundarstufen in K\u00fcrze:<\/p>\n<h2>Sekundarstufe A<\/h2>\n<p>Sie richtet sich an Sch\u00fclerinnen und Sch\u00fcler, die<\/p>\n<ul>\n<li>leistungsorientiert arbeiten wollen und gezielte Unterst\u00fctzung suchen<\/li>\n<li>sich gerne mit abstrakten Fragestellungen auseinandersetzen und ein h\u00f6heres Arbeitstempo sch\u00e4tzen<\/li>\n<li>sp\u00e4ter das Gymnasium oder die Fachmittelschule besuchen oder eine anspruchsvolle Berufslehre, eventuell mit Berufsmittelschule, absolvieren m\u00f6chten<\/li>\n<\/ul>\n<p>Die Sch\u00fclerinnen und Sch\u00fcler der Sekundarstufe A werden in der Regel auf der Kompetenzstufe I unterrichtet.<\/p>\n<p>Wir bieten individuelle Vorbereitungskurse f\u00fcr Jugendliche an, die die Aufnahmepr\u00fcfung an eine Mittelschule bestehen m\u00f6chten.<\/p>\n<p>In der Sekundarstufe A setzen wir auf<\/p>\n<ul>\n<li>eine f\u00f6rderliche Lernatmosph\u00e4re mit starken Lernbeziehungen zu den Lehrpersonen<\/li>\n<li>die gezielte F\u00f6rderung von Lern- und Aufgabentechniken<\/li>\n<li>F\u00fchrung zu selbstorganisiertem Lernen<\/li>\n<li>Vorbereitung auf Aufnahmepr\u00fcfungen an die Mittelschule, Berufsmittelschule oder eine anspruchsvolle Berufslehre<\/li>\n<li>\u00fcberschaubare Klassengr\u00f6sssen (die Fokusklassen sind in der Regel etwas gr\u00f6sser)<\/li>\n<li>die Pflege von Ritualen im Schulalltag<\/li>\n<\/ul>\n<p class=\"ohnemtop\">Die Lerninhalte und Lernziele der Sekundarschule richten sich nach den kantonalen Richtlinien. Neben den Grundlagenf\u00e4chern bieten wir musische und gestalterische Kurse an. Als wichtiger Bestandteil ist die Berufswahl in den Unterricht integriert.<\/p>\n<h2>Sekundarstufe A, Fokus Mittelschule<\/h2>\n<p>F\u00fcr besonders leistungsstarke Sch\u00fclerinnen und Sch\u00fcler mit einem durchgehend guten Arbeits-, Lern- und Sozialverhalten f\u00fchren wir im Schulhaus Kreuzstrasse Klassen mit dem\u00a0<strong>Fokus Mittelschule<\/strong>. Diese Jugendlichen haben beim \u00dcbertritt aus der 6. Klasse der Primarstufe in den beiden F\u00e4chern Deutsch und Mathematik je mindestens die Note 5. .<\/p>\n<h2>Sekundarstufe B<\/h2>\n<p>Sie richtet sich an Sch\u00fclerinnen und Sch\u00fcler, die<\/p>\n<ul>\n<li>eine Berufslehre machen oder ein 10. Schuljahr besuchen wollen<\/li>\n<li>gerne in kleinen und \u00fcberschaubaren Einheiten arbeiten<\/li>\n<li>mehr Unterst\u00fctzung beim Lernen ben\u00f6tigen<\/li>\n<\/ul>\n<p>Die Sch\u00fclerinnen und Sch\u00fcle der Sekundarstufe B werden in der Regel auf der Kompetenzstufe II unterrichtet.<\/p>\n<p>In der Sekundarstufe B setzen wir auf<\/p>\n<ul>\n<li>besonders starke Lernbeziehungen und eine starke F\u00fchrung durch die Klassenlehrperson.<\/li>\n<li>die gezielte F\u00f6rderung von Lern- und Arbeitstechniken<\/li>\n<li>individuelles Coaching f\u00fcr den \u00dcbertritt den Antritt einer Berufslehre oder den \u00dcbertritt in ein 10. Schuljahr<\/li>\n<li>\u00fcberschaubare Klassengr\u00f6sse<\/li>\n<\/ul>\n<p>Aufgrund guter Leistungen und einer positiven Gesamtbeurteilung einer Sch\u00fclerin oder eines Sch\u00fclers im entsprechenden Fach kann ein Wechsel der Kompetenzstufe zu Beginn eines neuen Semesters vollzogen werden. Die Umstufung erfolgt innerhalb der Klasse, es findet kein Klassenwechsel statt.<\/p>\n<p>Die Lerninhalte und Lernziele der Sekundarschule richten sich nach den kantonalen Richtlinien. Neben den Grundlagenf\u00e4chern bieten wir Kurse im k\u00fcnstlerischen, handwerklichen und sportlichen Bereich an. Als wichtiger Bestandteil ist die Berufswahl in den Unterricht integriert.<\/p>\n<h2>Kleinklasse<\/h2>\n<div class=\"field field--name-field-paragraph field--type-entity-reference-revisions field--label-hidden field--items\">\n<div class=\"field--item\">\n<div class=\"row sb-paragraph-mit-abstand wysiwyg-content\">\n<div class=\"col-sm-12 col-md-6\">\n<p>Die Sekundarstufen-Kleinklasse ist konzipiert f\u00fcr Sch\u00fclerinnen und Sch\u00fcler im 7. bis 9. Schuljahr, die aufgrund ihrer speziellen p\u00e4dagogischen Bed\u00fcrfnisse auf individuelle F\u00f6rderung und eine kleine Klasse angewiesen sind. Das Wichtigste zu der Sekundarstufen-Kleinklasse in K\u00fcrze:<\/p>\n<ul>\n<li>Grundlagenf\u00e4cher (Deutsch, Franz\u00f6sisch, Englisch, Mathematik) in kleinen Klassen mit maximal 6 Jugendlichen, \u00fcbrige F\u00e4cher in parallelen Regelklassen<\/li>\n<li>Unterricht auf dem Niveau der Sekundarstufe A und B<\/li>\n<li>Unterrichtsform sorgt f\u00fcr eine vollumf\u00e4ngliche soziale Integration<\/li>\n<\/ul>\n<p>In der Sekundarstufen-Kleinklasse setzen wir auf<\/p>\n<ul>\n<li>intensive individuelle F\u00f6rderung<\/li>\n<li>aktive Auseinandersetzung mit den eigenen St\u00e4rken<\/li>\n<li>den Aufbau eines positiven Selbstbildes in einer anregenden Lernumgebung<\/li>\n<\/ul>\n<p>Die Lernziele und Lerninhalte richten sich grunds\u00e4tzlich nach den kantonalen Richtlinien.<\/p>\n<h1>10. Schuljahr<\/h1>\n<div class=\"field field--name-field-paragraph field--type-entity-reference-revisions field--label-hidden field--items\">\n<div class=\"field--item\">\n<div class=\"row sb-paragraph-mit-abstand wysiwyg-content\">\n<div class=\"col-sm-12 col-md-6\">\n<p>Sekundarschule \u2013 und was dann? Das 10. Schuljahr ist das Br\u00fcckenangebot zwischen der Sekundarstufe und einer weiterf\u00fchrenden Schule oder einer Berufslehre.<\/p>\n<h2 id=\"re\">Reflexions- und Entscheidungsjahr (R+E)<\/h2>\n<p>Das Reflexions- und Entscheidungsjahr bietet die optimale schulische Vorbereitung auf die Aufnahmepr\u00fcfung an eine Mittelschule oder der beruflichen Orientierung.<\/p>\n<p>Das R+E richtet sich an Lernende, die<\/p>\n<ul>\n<li>die Sekundarstufe A abgeschlossen haben<\/li>\n<li>die Aufnahmepr\u00fcfung an eine Mittelschule anstreben<\/li>\n<li>sich die Option f\u00fcr den \u00dcbertritt nach dem 1. Semester in die 1. Klasse der hauseigenen Fachmittelschule offen halten m\u00f6chten<\/li>\n<li>sich auf eine anspruchsvolle Lehre eventuell mit Berufsmittelschule vorbereiten m\u00f6chten<\/li>\n<li>die Entscheidung \u00fcber ihre Berufswahl erst nach der obligatorischen Schulzeit treffen wollen<\/li>\n<\/ul>\n<p>Das p\u00e4dagogische Konzept des Reflexions- und Entscheidungsjahrs setzt auf<\/p>\n<ul>\n<li>Doppellektionen von 80 Minuten f\u00fcr mehr Lernerfolge<\/li>\n<li>Inputlektionen und Scholastikum (Lernatelier) f\u00fcr selbstverantwortetes Lernen<\/li>\n<li>die F\u00f6rderung von Kompetenzerwerb, Selbst- und Mitverantwortung<\/li>\n<\/ul>\n<p>Die Unterrichtsinhalte sind auf die Lernziele und die Stundentafel der 1. Klasse der Fachmittelschule ausgerichtet. Diese umfassen nebst den Grundlagenf\u00e4chern auch Informatik, Kommunikation, Musik, Bildnerisches Gestalten, Religion und Sport.<\/p>\n<\/div>\n<h1>\u00dcbergangsklasse<\/h1>\n<div class=\"field field--name-field-paragraph field--type-entity-reference-revisions field--label-hidden field--items\">\n<div class=\"field--item\">\n<div class=\"row sb-paragraph-mit-abstand wysiwyg-content\">\n<div class=\"col-sm-12 col-md-6\">\n<p>Die Entwicklung der Sch\u00fclerinnen und Sch\u00fcler verl\u00e4uft in der Phase der Mittelstufe sehr individuell. Die \u00dcbergangsklasse bietet im Anschluss an die 6. Primarklasse die M\u00f6glichkeit eines Jahres der Reife und der Festigung f\u00fcr Lernende, die aufgrund ihrer Lernbiografie ein weiteres Jahr der Vertiefung des Primarschulstoffes und\/oder der pers\u00f6nlichen Entwicklung ben\u00f6tigen. Das Wichtigste zum \u00dcbergangsjahr in K\u00fcrze:<\/p>\n<h2>Vorbereitung auf die Sekundarstufe<\/h2>\n<p>Das \u00dcbergangsjahr ist ein Br\u00fcckenangebot zwischen der Primar- und der Sekundarstufe und dient als 7. Schuljahr. Das Angebot ist eine Zwischenl\u00f6sung f\u00fcr Sch\u00fclerinnen und Sch\u00fcler der 6. Primarklasse, die aufgrund ihrer Lernbiografie ein weiteres Jahr der Festigung des Primarschulstoffes und\/oder der pers\u00f6nlichen Entwicklung ben\u00f6tigen. Vielf\u00e4ltige Lehr- und Lernformen werden gezielt eingesetzt: gemeinsames und selbst\u00e4ndiges Lernen, die Reflexion des Lernens im Lernjournal und das Gestalten von Projekten. Die \u00dcbergangsklasse ist f\u00fcr Kinder, die motiviert und leistungswillig sind. Sie m\u00f6chten ihr Selbstvertrauen und ihre Selbstwirksamkeit f\u00f6rdern.<\/p>\n<p>In der \u00dcbergangsklasse legen wir Wert auf<\/p>\n<ul>\n<li>eine gezielte Vorbereitung auf die Sekundarstufe mit eigens daf\u00fcr konzipierten Lehrmitteln<\/li>\n<li>betreute Arbeits- und Lerntechnikstunden innerhalb des Unterrichts<\/li>\n<li>eine w\u00f6chentlich gepflegte Feedback-Kultur durch die Arbeit mit dem Lernjournal<\/li>\n<li>die Pflege von Ritualen im Schulalltag<\/li>\n<li>\u00fcberschaubaren Klassengr\u00f6ssen<\/li>\n<li>eine bew\u00e4hrte Tagesschul-Struktur mit gemeinsamem Mittagessen und einem Angebot f\u00fcr Hausaufgabenbetreuung im Anschluss an den Unterricht<\/li>\n<\/ul>\n<h1>Fachmittelschule (FMS)<\/h1>\n<div class=\"field field--name-field-paragraph field--type-entity-reference-revisions field--label-hidden field--items\">\n<div class=\"field--item\">\n<div class=\"row sb-paragraph-mit-abstand wysiwyg-content\">\n<div class=\"col-sm-12 col-md-6\">\n<p>Unsere Fachmittelschule ist eine von drei Fachmittelschulen im Kanton Z\u00fcrich. Sie ist eine schweizerisch anerkannte Mittelschule und bereitet Sch\u00fclerinnen und Sch\u00fcler auf ein Studium an einer Fachhochschule oder der p\u00e4dagogischen Hochschule oder auf eine Ausbildung an einer H\u00f6heren Fachschule vor.<\/p>\n<p>Die FMS richtet sich an Sch\u00fclerinnen und Sch\u00fcler, die<\/p>\n<ul>\n<li>eine umfassende Allgemeinbildung auf Mittelschulstufe m\u00f6chten.<\/li>\n<li>eine Ausbildung an einer Fachhochschule oder an einer H\u00f6heren Fachschule anstreben.<\/li>\n<li>die Berufsfindungs-Phase noch nicht abgeschlossen haben.<\/li>\n<\/ul>\n<p>Die Fachmittelschule dauert drei Jahre und wird mit dem Fachmittelschulausweis abgeschlossen. Im zweiten Basisjahren entscheiden sich die Sch\u00fclerinnen und Sch\u00fcler f\u00fcr eines der vier Profile<\/p>\n<ul>\n<li>P\u00e4dagogik*<\/li>\n<li>Kommunikation und Information<\/li>\n<li>Soziales<\/li>\n<li>Gesundheit und Naturwissenschaften<\/li>\n<\/ul>\n<p>Im vierten Ausbildungsjahr (Praktikumsjahr) kann die Fachmatur und damit der direkte Zugang zu den Fachhochschulen erlangt werden.<\/p>\n<p>* Die Fachmaturit\u00e4t P\u00e4dagogik erlaubt den direkten Zugang zur p\u00e4dagogischen Hochschule.<\/p>\n<p>Wir setzen in der Fachmittelschule auf<\/p>\n<ul>\n<li>die Ausbildung umfassender Kompetenzen, Schnuppertage, Orientierungspraktika, Sprachaufenthalte, selbstst\u00e4ndige Arbeiten, Projektwochen<\/li>\n<li>lernen nach den neusten p\u00e4dagogischen Erkenntnissen<\/li>\n<li>anschlussf\u00e4hige Abschl\u00fcsse (Fachmittelschulausweis oder Fachmaturit\u00e4t)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Waldmannstrasse 9, 8001 Z\u00fcrich, Schweiz","_company_website":"https:\/\/www.fsz.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[153],"job-categories":[141,114,253,99,76,102,115],"job-types":[5,92,93],"class_list":{"0":"post-22068","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-zuerich","6":"job_listing_category-brueckenangebot","7":"job_listing_category-fachmittelschule","8":"job_listing_category-nachhilfe","9":"job_listing_category-primarschule","10":"job_listing_category-sekundarstufe_1","11":"job_listing_category-sekundarstufe_2","12":"job_listing_category-tagesschule","13":"job_listing_type-primarschule","14":"job_listing_type-sekundarstufe_1","15":"job_listing_type-sekundarstufe_2","17":"job-type-primarschule-7-12jahre","18":"job-type-sekundarstufe-1-13-16-jahre","19":"job-type-sekundarstufe-2-16-19-jahre"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Freie Schule Z\u00fcrich - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/en\/listings\/freie-schule-zuerich\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Freie Schule Z\u00fcrich\" \/>\n<meta property=\"og:description\" content=\"Frei \u2013 aber nicht wertfrei. Die Schule f\u00fcr Kopf, Hand und Herz. Ob Primarschule, \u00dcbergangsklasse, Sekundarschule, 10. Schuljahr oder Kleinklasse \u2013 das Angebot der Freien Schule Z\u00fcrich holt die Sch\u00fclerinnen und Sch\u00fcler dort ab, wo sie stehen. Vor der Aufnahme versuchen wir die Bed\u00fcrfnisse des Kindes zu eruieren. Was braucht das Kind, um sich optimal [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/en\/listings\/freie-schule-zuerich\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-24T11:39:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/Freie_Evangelische_Schule_Zuerich.svg.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/Freie_Evangelische_Schule_Zuerich.svg.png\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/freie-schule-zuerich\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/freie-schule-zuerich\\\/\",\"name\":\"Freie Schule Z\u00fcrich - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/freie-schule-zuerich\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/freie-schule-zuerich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/fsz_logo_zusatz_seit_1874_RGB.jpg\",\"datePublished\":\"2021-04-02T15:49:11+00:00\",\"dateModified\":\"2026-04-24T11:39:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/freie-schule-zuerich\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/freie-schule-zuerich\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/freie-schule-zuerich\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/fsz_logo_zusatz_seit_1874_RGB.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/fsz_logo_zusatz_seit_1874_RGB.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/freie-schule-zuerich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Freie Schule Z\u00fcrich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Freie Schule Z\u00fcrich - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/en\/listings\/freie-schule-zuerich\/","og_locale":"en_US","og_type":"article","og_title":"Freie Schule Z\u00fcrich","og_description":"Frei \u2013 aber nicht wertfrei. Die Schule f\u00fcr Kopf, Hand und Herz. Ob Primarschule, \u00dcbergangsklasse, Sekundarschule, 10. Schuljahr oder Kleinklasse \u2013 das Angebot der Freien Schule Z\u00fcrich holt die Sch\u00fclerinnen und Sch\u00fcler dort ab, wo sie stehen. Vor der Aufnahme versuchen wir die Bed\u00fcrfnisse des Kindes zu eruieren. Was braucht das Kind, um sich optimal [&hellip;]","og_url":"https:\/\/schoolaboo.com\/en\/listings\/freie-schule-zuerich\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2026-04-24T11:39:39+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/Freie_Evangelische_Schule_Zuerich.svg.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/Freie_Evangelische_Schule_Zuerich.svg.png","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/en\/listings\/freie-schule-zuerich\/","url":"https:\/\/schoolaboo.com\/en\/listings\/freie-schule-zuerich\/","name":"Freie Schule Z\u00fcrich - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoolaboo.com\/en\/listings\/freie-schule-zuerich\/#primaryimage"},"image":{"@id":"https:\/\/schoolaboo.com\/en\/listings\/freie-schule-zuerich\/#primaryimage"},"thumbnailUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/04\/fsz_logo_zusatz_seit_1874_RGB.jpg","datePublished":"2021-04-02T15:49:11+00:00","dateModified":"2026-04-24T11:39:39+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/en\/listings\/freie-schule-zuerich\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/en\/listings\/freie-schule-zuerich\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/schoolaboo.com\/en\/listings\/freie-schule-zuerich\/#primaryimage","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/04\/fsz_logo_zusatz_seit_1874_RGB.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/04\/fsz_logo_zusatz_seit_1874_RGB.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/en\/listings\/freie-schule-zuerich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/en\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/en\/angebote\/"},{"@type":"ListItem","position":3,"name":"Freie Schule Z\u00fcrich"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/en\/#website","url":"https:\/\/schoolaboo.com\/en\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/en\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings\/22068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/comments?post=22068"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/media?parent=22068"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job_listing_region?post=22068"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-categories?post=22068"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-types?post=22068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}