{"id":21575,"date":"2020-11-02T21:21:24","date_gmt":"2020-11-02T20:21:24","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=21575"},"modified":"2020-11-02T21:21:24","modified_gmt":"2020-11-02T20:21:24","slug":"hso","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/en\/listings\/hso\/","title":{"rendered":"HSO"},"content":{"rendered":"<h1 class=\"page-header\">HSO. Seit 1954<\/h1>\n<div class=\"region region-content\">\n<section id=\"block-system-main\" class=\"block block-system clearfix\">\n<div class=\"node node-page view-mode-full\">\n<div class=\"row\">\n<div class=\"col-sm-12 \">\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><strong>Die HSO-Philosophie<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>\u00abWitercho mit HSO\u00bb ist unser Daseinszweck im Hier und Jetzt<\/li>\n<li>\u00abWitercho mit HSO\u00bb ist unser Begleiter bei all unserem Wirken und Tun<\/li>\n<li>\u00abWitercho mit HSO\u00bb ist unsere Antwort an die Menschen, die im Leben weiterkommen wollen<\/li>\n<li>\u00abWitercho mit HSO\u00bb wird zum Statement im Kommunikations-Mix unserer Bildungsangebote<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3><strong>Unsere Vision<\/strong><\/h3>\n<p>Wir bilden Menschen von heute f\u00fcr die Zukunft von morgen.<\/p>\n<ul>\n<li>Wir leisten einen substanziellen und nachhaltigen Beitrag zur Wissensbildung unserer Gesellschaft.<\/li>\n<li>Wir sind der f\u00fchrende private Bildungsanbieter f\u00fcr Wirtschafts- und Informatiklehrg\u00e4nge in der Schweiz.<\/li>\n<li>Wir sind als privater Bildungsanbieter erste Wahl, wenn es um praxis- und handlungsorientierte Aus- und Weiterbildungen geht.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3><strong>Unsere Mission<\/strong><\/h3>\n<p>Wir bringen Menschen weiter.<\/p>\n<ul>\n<li>Wir f\u00f6rdern Menschen durch Bildung darin, in der Gesellschaft einen Beitrag zu leisten, unabh\u00e4ngig wo sie im Leben stehen.<\/li>\n<li>Wir unterst\u00fctzen Menschen beim lebenslangen Lernen und bringen sie durch unsere Bildungsangebote in ihrem privaten und beruflichen Umfeld weiter.<\/li>\n<li>Wir setzen konsequent auf wirtschafts-, praxis- und handlungsorientierte\u00a0\u00a0 Bildungsangebote und f\u00f6rdern stufengerecht die entsprechenden Fach-, Sozial- und Selbstkompetenzen.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<\/div>\n<h3><strong>Unser Leitbild\u00a0<\/strong><\/h3>\n<p>Bildung heisst Verantwortung in der Gemeinschaft \u00fcbernehmen!<\/p>\n<p>Unser Leitbild steht f\u00fcr einen ganzheitlichen Ansatz der Unternehmensf\u00fchrung, kollektiv getragen durch die Mitwirkung aller Mitarbeitenden.<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<div class=\"table-responsive\">\n<table border=\"0\" cellspacing=\"1\" cellpadding=\"1\">\n<tbody>\n<tr>\n<td colspan=\"2\" rowspan=\"1\">Unsere Verantwortung im eigenen\u00a0<strong>Unternehmen<\/strong>!<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/unternehmen_1.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/unternehmen_2.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/unternehmen_3.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<\/tr>\n<tr>\n<td class=\"rtecenter\">Wir sind ein agiles Unternehmen und setzen dabei auf ein angemessenes Verh\u00e4ltnis zwischen Kontinuit\u00e4t und Innovation.<\/td>\n<td class=\"rtecenter\">Wir fokussieren sowohl strategisch wie operativ auf eine nachhaltige und wertsch\u00f6pfende Unternehmensf\u00fchrung, im Interesse der Mitarbeitenden und Aktion\u00e4re.<\/td>\n<td class=\"rtecenter\">Wir \u00fcbernehmen in unserem Unternehmen im Interesse aller Anspruchsgruppen die Verantwortung f\u00fcr unser Wirken und Tun.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">\n<hr \/>\n<p>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" rowspan=\"1\">Unsere Verantwortung gegen\u00fcber unseren\u00a0<strong>Mitarbeitenden<\/strong>!<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/mitarbeiter_1.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/mitarbeiter_2.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/mitarbeiter_3.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<\/tr>\n<tr>\n<td class=\"rtecenter\">Wir f\u00fchlen uns dem Wohl unserer Mitarbeitenden verpflichtet und sorgen f\u00fcr ein angemessenes Arbeitsumfeld.<\/td>\n<td class=\"rtecenter\">Wir f\u00f6rdern einerseits unsere Mitarbeitenden in ihrer pers\u00f6nlichen und beruflichen Weiterentwicklung und achten dabei auf Chancengleichheit.<\/td>\n<td>\n<p class=\"rtecenter\">Wir fordern andererseits von unseren Mitarbeitenden empathisch, kompetent, engagiert und motiviert ihren Aufgaben nachzugehen.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">\n<hr \/>\n<p>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">Unsere Verantwortung gegen\u00fcber unseren\u00a0<strong>Studierenden<\/strong>!<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/studierende_1.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/studierende_2.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/studierende_3.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<\/tr>\n<tr>\n<td class=\"rtecenter\">Wir sorgen mit unseren Bildungsangeboten f\u00fcr ein spannendes, praxis- und transferorientiertes Lernumfeld.<\/td>\n<td class=\"rtecenter\">Wir f\u00f6rdern und unterst\u00fctzen unsere Studierenden bei ihrer Bildungskarriere und bringen sie pers\u00f6nlich und beruflich weiter.<\/td>\n<td>\n<p class=\"rtecenter\">\u00a0Wir fordern bei unseren Studierenden die Eigenverantwortung ein, sich f\u00fcr das angestrebte Bildungsziel engagiert einzusetzen.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">\n<hr \/>\n<p>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">Unsere Verantwortung gegen\u00fcber unseren\u00a0<strong>Dozierenden<\/strong>!<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td class=\"rtecenter\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/dozierende_1.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td class=\"rtecenter\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/dozierende_2.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/dozierende_person.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<\/tr>\n<tr>\n<td class=\"rtecenter\">Wir stellen unseren Dozierenden f\u00fcr die Ausgestaltung spannender Lektionen eine moderne und zeitgem\u00e4sse Infrastruktur zur Verf\u00fcgung.<\/td>\n<td class=\"rtecenter\">Wir unterst\u00fctzen unsere Dozierenden sowohl in der methodisch-didaktischen wie auch in der handlungs- und praxisorientierten Entwicklung von Bildungsinhalten.<\/td>\n<td class=\"rtecenter\">Wir fordern von unseren Dozierenden eine menschliche, begeisternde, engagierte und professionelle Einstellung bei ihrem Wirken und Tun.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">\n<hr \/>\n<p>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">Unsere Verantwortung gegen\u00fcber unseren\u00a0<strong>Lieferanten<\/strong>!<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/lieferant_personaussen.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/lieferant_person.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/lieferant_personaussen_0.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<\/tr>\n<tr>\n<td class=\"rtecenter\">Wir verhalten uns gegen\u00fcber unseren Lieferanten fair, transparent und verbindlich und setzen auf eine nachhaltige und langfristige Partnerschaft.<\/td>\n<td class=\"rtecenter\">Wir achten bei der Wahl unserer Lieferanten auf Qualit\u00e4t und setzen auf eine nachhaltige und langfristige Partnerschaft.<\/td>\n<td class=\"rtecenter\">Wir erwarten von unseren Lieferanten, dass sie uns im gleichen Sinn einsch\u00e4tzen und die Zusammenarbeit pflegen.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">\n<hr \/>\n<p>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" rowspan=\"1\">Unsere Verantwortung gegen\u00fcber unseren\u00a0<strong>Bildungspartnern<\/strong>!<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/bildungspartner_1.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<p>&nbsp;<\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/bildungspartner_2.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<p>&nbsp;<\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/bildungspartner_3.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<p>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"rtecenter\">Wir verhalten uns gegen\u00fcber unseren Bildungspartnern wie Verb\u00e4nden, Organisationen der Arbeit, kantonalen \u00c4mter und dem Bund jederzeit kooperativ und setzen auf eine nachhaltige Zusammenarbeit.<\/p>\n<\/td>\n<td>\n<p class=\"rtecenter\">Wir bringen uns kooperativ und mit Engagement bei allen relevanten Gruppierungen ein und pflegen dabei einen l\u00f6sungsorientierten Ansatz.<\/p>\n<\/td>\n<td>\n<p class=\"rtecenter\">Wir fordern von unseren Bildungspartner eine transparente, sachliche und kooperative Grundhaltung, im Interesse einer gemeinschaftlichen und qualitativ hochstehenden Bildungslandschaft.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">\n<hr \/>\n<p>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">Unsere Verantwortung gegen\u00fcber unserer\u00a0<strong>Gesellschaft<\/strong>!<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td class=\"rtecenter\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/gesellschaft_1.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/gesellschaft_people.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/gesellschaft_schweiz.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<\/tr>\n<tr>\n<td class=\"rtecenter\">Wir setzen uns in der Gesellschaft f\u00fcr die demokratischen und verfassungsrechtlichen Grundwerte der Schweiz ein.<\/td>\n<td class=\"rtecenter\">Wir \u00fcbernehmen als Bildungsanbieter in unserer\u00a0 Gesellschaft eine wichtige Mitverantwortung und sind uns der Stellung auch umfassend bewusst.<\/td>\n<td class=\"rtecenter\">Wir fordern von allen Mitgliedern unserer Gesellschaft einen kollektiven Beitrag f\u00fcr eine nachhaltige Weiterentwicklung der Schweiz.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">\n<hr \/>\n<p>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">Unsere Verantwortung gegen\u00fcber unserer\u00a0<strong>Umwelt<\/strong>!<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/erde.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/umwelt_blume.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/umwelt_erdekreis.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<\/tr>\n<tr>\n<td class=\"rtecenter\">Wir setzen uns verantwortungsvoll f\u00fcr einen schonenden und nachhaltigen Umgang mit den weltweit vorhandenen Umweltressourcen ein.<\/td>\n<td class=\"rtecenter\">Wir arbeiten kontinuierlich daran, unseren Bezug an Umweltressourcen zu reduzieren oder wo immer m\u00f6glich durch neutrale Alternativen komplett zu ersetzen.<\/td>\n<td class=\"rtecenter\">Wir erwarten von unseren Anspruchsgruppen, dass sie sich ebenfalls f\u00fcr einen nachhaltigen Umgang mit den vorhandenen Umweltressourcen einsetzen.<\/td>\n<\/tr>\n<tr>\n<td class=\"rtecenter\"><\/td>\n<td class=\"rtecenter\"><\/td>\n<td class=\"rtecenter\"><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Andreasstrasse 15 CH-8050 Z\u00fcrich-Oerlikon","_company_website":"https:\/\/www.hso.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[153],"job-categories":[],"job-types":[228],"class_list":{"0":"post-21575","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-zuerich","6":"job_listing_type-tertiaerausbildung","8":"job-type-tertiarausbildung"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>HSO - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/en\/listings\/hso\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HSO\" \/>\n<meta property=\"og:description\" content=\"HSO. Seit 1954 Die HSO-Philosophie &nbsp; &nbsp; &nbsp; \u00abWitercho mit HSO\u00bb ist unser Daseinszweck im Hier und Jetzt \u00abWitercho mit HSO\u00bb ist unser Begleiter bei all unserem Wirken und Tun \u00abWitercho mit HSO\u00bb ist unsere Antwort an die Menschen, die im Leben weiterkommen wollen \u00abWitercho mit HSO\u00bb wird zum Statement im Kommunikations-Mix unserer Bildungsangebote &nbsp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/en\/listings\/hso\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/hso_logo.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/hso_logo.png\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/hso\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/hso\\\/\",\"name\":\"HSO - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/hso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/hso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hso.ch\\\/sites\\\/default\\\/files\\\/uploads\\\/unternehmen_1.png\",\"datePublished\":\"2020-11-02T20:21:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/hso\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/hso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/hso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hso.ch\\\/sites\\\/default\\\/files\\\/uploads\\\/unternehmen_1.png\",\"contentUrl\":\"https:\\\/\\\/www.hso.ch\\\/sites\\\/default\\\/files\\\/uploads\\\/unternehmen_1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/hso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HSO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"HSO - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/en\/listings\/hso\/","og_locale":"en_US","og_type":"article","og_title":"HSO","og_description":"HSO. Seit 1954 Die HSO-Philosophie &nbsp; &nbsp; &nbsp; \u00abWitercho mit HSO\u00bb ist unser Daseinszweck im Hier und Jetzt \u00abWitercho mit HSO\u00bb ist unser Begleiter bei all unserem Wirken und Tun \u00abWitercho mit HSO\u00bb ist unsere Antwort an die Menschen, die im Leben weiterkommen wollen \u00abWitercho mit HSO\u00bb wird zum Statement im Kommunikations-Mix unserer Bildungsangebote &nbsp; [&hellip;]","og_url":"https:\/\/schoolaboo.com\/en\/listings\/hso\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/hso_logo.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/hso_logo.png","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/en\/listings\/hso\/","url":"https:\/\/schoolaboo.com\/en\/listings\/hso\/","name":"HSO - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoolaboo.com\/en\/listings\/hso\/#primaryimage"},"image":{"@id":"https:\/\/schoolaboo.com\/en\/listings\/hso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/unternehmen_1.png","datePublished":"2020-11-02T20:21:24+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/en\/listings\/hso\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/en\/listings\/hso\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/schoolaboo.com\/en\/listings\/hso\/#primaryimage","url":"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/unternehmen_1.png","contentUrl":"https:\/\/www.hso.ch\/sites\/default\/files\/uploads\/unternehmen_1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/en\/listings\/hso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/en\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/en\/angebote\/"},{"@type":"ListItem","position":3,"name":"HSO"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/en\/#website","url":"https:\/\/schoolaboo.com\/en\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/en\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings\/21575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/comments?post=21575"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/media?parent=21575"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job_listing_region?post=21575"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-categories?post=21575"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-types?post=21575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}