{"id":20262,"date":"2020-09-09T22:52:33","date_gmt":"2020-09-09T20:52:33","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=20262"},"modified":"2020-12-22T11:15:44","modified_gmt":"2020-12-22T10:15:44","slug":"rudolf-steiner-schule-birseck","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/en\/listings\/rudolf-steiner-schule-birseck\/","title":{"rendered":"Rudolf Steiner Schule Birseck"},"content":{"rendered":"<h2>Kindergarten<\/h2>\n<p class=\"lead\">\u00abAus der Art, wie ein Kind spielt, kann man erahnen, wie es seine Lebensaufgabe ergreifen wird.\u00bb Rudolf Steiner<\/p>\n<p class=\"text\">Oft sind es die einfachen Spiel- und Baumaterialien, welche die reiche Phantasie der Kinder ansprechen und sie zu kreativem Empfinden und Handeln bewegen. Sie k\u00f6nnen frei ihr Spiel gestalten und werden nicht durch Vorgefertigtes gebunden. Das freie Spiel im Hause wie auch draussen wird von uns als wichtiger Bestandteil des kindlichen Lebens angesehen. Hierdurch werden die Phantasie- und Willensausbildung, dazu die Sinnesorgane (Tastsinn, Geruchssinn, Sehsinn, Gleichgewichtssinn &#8230;) und das Koordinationsverm\u00f6gen angeregt. Im gemeinschaftlichen Spiel entwickeln sich in selbstverst\u00e4ndlicher Weise soziale F\u00e4higkeiten und emotionale Sicherheit. Durch einen rhythmisch gegliederten Tages-, Wochen- und von den Festen gepr\u00e4gten Jahresablauf werden die Voraussetzungen f\u00fcr eine gesunde Entwicklung geschaffen.<\/p>\n<p class=\"text\">Welche Erfahrungen kann ein Kind machen, wenn es miterlebt und mittut, wie aus dem Korn das Mehl, aus diesem der Teig und aus dem Teig wiederum das Brot f\u00fcr die gemeinsame Fr\u00fchst\u00fccksmahlzeit entsteht!<\/p>\n<p class=\"text\">M\u00e4rchen- und Geschichtenerz\u00e4hlen, auch Puppenspiele f\u00f6rdern die seelische Regsamkeit und Phantasie. Jeder Mensch ist ein K\u00fcnstler. Wir f\u00f6rdern den \u2039K\u00fcnstler\u203a im Kind, indem wir mit Musik, rhythmischen Spielen, Eurythmie, dem Malen mit Wasserfarben und vielen anderen Bet\u00e4tigungsm\u00f6glichkeiten Freude wecken.<\/p>\n<p class=\"text\">In gemeinsamer und verantwortungsvoller Zusammenarbeit zwischen Eltern, P\u00e4dagogen und weiteren qualifizierten Begleitern sind alle Bem\u00fchungen darauf gerichtet, die Kr\u00e4fte der Kinder zu entwickeln und zu pflegen, welche sie sp\u00e4ter durch das ganze Leben tragen werden. Kinder lernen am Leben f\u00fcr das Leben!<\/p>\n<div class=\"row\">\n<div class=\"col-xs-12\"><\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-xs-12\">\n<div id=\"section-18354\" class=\"container-section\">\n<div class=\"element\">\n<h2 class=\"text\">Unterstufe<\/h2>\n<p class=\"lead\">\u00abDas Kind in Ehrfurcht aufnehmen, in Liebe erziehen und in Freiheit entlassen.\u00bb Rudolf Steiner<\/p>\n<p class=\"text\">Die Zeit in der Unterstufe ist ein Lernen mit allen Sinnen. Die Pflege der Sinne und k\u00fcnstlerisch gestalteter Unterricht sind die Grundlagen f\u00fcr die Lernerfahrungen in der sich bildenden Klassengemeinschaft. Es wird mit starken Bildern gearbeitet, sowohl im k\u00fcnstlerischen als auch im sprachlichen Bereich. Diese Bilder regen die Fantasie der Kinder an und st\u00e4rken \u2013 neben den kognitiven F\u00e4higkeiten \u2013 das Gef\u00fchls- und Willensleben.<\/p>\n<p class=\"text\">Ein strukturierter Tages-, Wochen- und Jahresablauf ist f\u00fcr eine gesunde Entwicklung wichtig, und so wird grosser Wert auf den Rhythmus des gesamten Unterrichts gelegt. Wiederkehrende Elemente im Grossen wie im Kleinen geben Struktur und Sicherheit. Jeden Morgen begr\u00fcssen die Klassenlehrerinnen und Klassenlehrer ihre Kinder um 8 Uhr im Klassenzimmer. Gemeinsam beginnen sie den Tag mit Sprache, Musik, Bewegung und Rhythmus.<\/p>\n<p class=\"text\">Von der ersten bis zur achten Klasse werden die Sch\u00fclerinnen und Sch\u00fcler von ihrem Klassenlehrer oder ihrer Klassenlehrerin begleitet. Es gibt kein Sitzenbleiben und keine Noten. Die Lehrer schreiben individuelle, differenzierte Entwicklungsberichte. Der Unterricht gliedert sich in Epochen- und Fachunterricht.<\/p>\n<h2>Mittelstufe<\/h2>\n<p class=\"lead\">\u00abBei der Erziehung muss man etwas aus dem Menschen herausbringen und nicht in ihn hinein.\u00bb Friedrich Fr\u00f6bel<\/p>\n<p class=\"text\">In der Mittelstufe beginnt der Aufbruch in die eigene Identit\u00e4t. Es ist f\u00fcr die Sch\u00fclerinnen und Sch\u00fcler eine fordernde und turbulente Zeitspanne, die von uns Erwachsenen Gelassenheit, Verst\u00e4ndnis und auch viel Humor verlangt. Jugendliche fragen zu Recht nach Kausalit\u00e4ten und legen dieses Verst\u00e4ndnis einem neuen Lernverhalten zugrunde. Dabei ist der Prozess, durch den eine Erkenntnis im Lernen errungen wird, f\u00fcr das \u2039lernen-Lernen\u203a so wichtig wie das Ergebnis. Reflektion und Selbstreflektion gilt es zu erarbeiten.<\/p>\n<p class=\"text\">Es ist f\u00fcr junge Menschen wichtig, selbstst\u00e4ndig handeln zu lernen, zu verstehen, dass Ansichten oft verschieden sein k\u00f6nnen und dennoch jede Einzelne berechtigt ist; zu sp\u00fcren, dass man aktzeptiert wird, wie man ist &#8211; dass dem eigenen Tun und Lassen aber auch Grenzen gesetzt sind. Die Naturwissenschaften entwickeln sich von der ersten Menschen- und Tierkunde in der 4. Klasse \u00fcber die Pflanzen- und Gesteinskunde bis zur Ern\u00e4hrungslehre und Astronomie in der 7. Klasse. Ein Beispiel f\u00fcr aufbauenden Unterricht: Von der Himmels- und Heimatkunde in der 4. Klasse geht es in der 5. Klasse weiter zur Geographie der Schweiz, Europas und in der 8. Klasse zur geographischen Differenzierung der gesamten Erde. In der 6. Klasse beginnt die Physik und in der siebten Klasse die Chemie. In der 8. Klasse kommt die Anatomie hinzu.<\/p>\n<p class=\"text\">Soziale Prozesse und die Klassengemeinschaft werden durch zahlreiche Unternehmungen, wie Klassenfahrten, Theaterspiel, soziale Projekte, usw. entscheidend gef\u00f6rdert. Ab der 6. Klasse finden verst\u00e4rkt Projektarbeiten sowohl f\u00fcr den einzelnen Sch\u00fcler als auch f\u00fcr Gruppen zu Themen aus den verschiedenen Epochen statt. Dazu geh\u00f6rt eine schriftliche Ausarbeitung\/Folio wie auch eine m\u00fcndliche Darstellung des Themas. Projektarbeiten der Mittelstufe: Buchvorstellungen, tierkundliche Referate, pflanzenkundliche Referate, Biografiearbeiten einschliesslich Portfolio und Pr\u00e4sentation vor Publikum in der 8. Klasse.<\/p>\n<h2>10. bis 12. Klasse<\/h2>\n<p class=\"lead\">Das Konzept der Steiner-Schulen f\u00fcr die Klassen 10 bis 12 heisst Integrative Mittelschule (IMS).<\/p>\n<p class=\"text\">Durch eine breite, vielseitige Allgemeinbildung mit praxisorientiertem Lernen gewinnen die Jugendlichen einen weiten Horizont f\u00fcr ihr Leben. Interdisziplin\u00e4res Urteilsverm\u00f6gen und Einf\u00fchlungsverm\u00f6gen sind die F\u00e4higkeiten, auf die es ankommt in einer immer komplexeren Lebenswelt.<\/p>\n<p class=\"text\">In der bewegten Schweizer Bildungslandschaft ist es uns sehr wichtig, unseren Sch\u00fclerinnen und Sch\u00fclern umfassende und ad\u00e4quate schulische Abschlussm\u00f6glichkeiten anzubieten und dadurch die notwendigen Anschl\u00fcsse an terti\u00e4re Ausbildungen zu gew\u00e4hrleisten.<\/p>\n<p class=\"text\">Mit dem IMS-F Abschluss haben wir ein Instrument geschaffen, dass den Zugang zu h\u00f6heren Fachschulen und Fachhochschulen erm\u00f6glicht. Im\u00a0Kompass\u00a0finden Sie alle Details zu diesen Fragen.<\/p>\n<p class=\"text\">Die \u00dcbertritte an die Gymnasien der Kantone Basel-Stadt und Basel-Landschaft sind im Rahmen von Vereinbarungen zwischen den Rudolf Steiner Schulen der Region Basel und den Kantonen geregelt.\u00a0Die entsprechenden Regelungen k\u00f6nnen Sie hier nachlesen.<\/p>\n<p class=\"text\">Diejenigen Sch\u00fclerinnen und Sch\u00fcler, die auf eine FMS wechseln m\u00f6chten, um dort die Fachmaturit\u00e4t zu erwerben, haben ebenfalls entsprechende M\u00f6glichkeiten. Die Steinerschulen Region Basel haben auch hier eine\u00a0Vereinbarung\u00a0mit den Kantonen abgeschlossen.<\/p>\n<div id=\"section-28410\" class=\"container-section\">\n<h2>Die Rudolf Steiner Schule Birseck<\/h2>\n<p class=\"lead\">\u00abWenn wir die Menschen nur nehmen, wie sie sind, machen wir sie schlechter. Wenn wir sie behandeln, als w\u00e4ren sie, was sie sein sollen, so bringen wir sie dahin, wohin sie zu bringen sind.\u00bb \u00a0Goethe<\/p>\n<p>500 Sch\u00fclerinnen und Sch\u00fcler gehen t\u00e4glich in das langgestreckte Geb\u00e4ude der Rudolf Steiner Schule Birseck gegen\u00fcber vom Bahnhof Aesch. Die Idee, neben der Basler Schule eine weitere Rudolf Steiner Schule ins Leben zu rufen, wurde <strong>1977<\/strong>\u00a0geboren. Der damalige gesellschaftliche Aufbruch liess bei vielen Eltern den Wunsch wachsen, ihren Kindern ganzheitlichen Unterricht zu erm\u00f6glichen. Eine Schule vom Kindergarten bis zur 12. Klasse aufzubauen, war das Ziel des kleinen Gr\u00fcndungskollegiums. Es geschah der Gl\u00fccksfall, dass auf Dugginger Boden ein altes Fabrikgeb\u00e4ude zu kaufen war. Jedes Jahr stiess eine neue erste Klasse zur Schulgemeinschaft. Im Winter\u00a0<strong>1984\/85<\/strong>\u00a0konnte in der ehemaligen Seidenspinnereifabrik der Umbau beginnen. Ein Jahr sp\u00e4ter zogen die ersten Klassen ein.\u00a0<strong>1988<\/strong>\u00a0war schliesslich die ganze Schule unter einem Dach vereinigt.\u00a0<strong>1996<\/strong>\u00a0ging die sp\u00e4ter entstandene Rudolf Steiner Schule Arlesheim in der Birseckschule auf.<\/p>\n<p>Die ehemalige Fabrik wurde zu einer Schule mit Turnhalle, Laborr\u00e4umen, Schulgarten, Theatersaal und mehreren Kinderg\u00e4rten umgebaut. Als Schule in freier Tr\u00e4gerschaft muss all das, wie auch der Schulbetrieb gr\u00f6sstenteils aus eigenen Mitteln finanziert werden \u2013 ein Kraftakt der Elternschaft. Wochenendeins\u00e4tze im Garten und Schulhaus, Engagement in vielen Arbeitskreisen pr\u00e4gen mit den Geist der Schule. Wer ihn kennenlernen m\u00f6chte, kann neben den vielen k\u00fcnstlerischen Anl\u00e4ssen den j\u00e4hrlichen Herbstmarkt oder das jeweils einem Land gewidmete Maifest besuchen.<\/p>\n<p>\u00abErziehung ist Beziehung\u00bb, dieses Losungswort heutiger P\u00e4dagogik und die Tatsache, dass jede Sch\u00fclerin, jeder Sch\u00fcler mehr und mehr eine individuelle Zuwendung braucht, pr\u00e4gen die p\u00e4dagogischen Ziele der Schule. Dieser Herausforderung m\u00f6chte die Birseckschule weiter treu bleiben und entwickelt deshalb neue Formen der p\u00e4dagogischen Begleitung \u2013 wie Portfolioarbeiten in der Oberstufe, wo ein Sch\u00fcler mit einem Lehrer im Gespr\u00e4ch ist, bis zu klassen\u00fcbergreifenden k\u00fcnstlerischen Grossproduktionen. Aus diesem Grund stehen weitere Ausbauschritte an.<\/p>\n<p>Schule bedeutet, die Heranwachsenden f\u00fcr den Zugriff auf die eigene Pers\u00f6nlichkeit zu bef\u00e4higen, dass aus Erziehung schliesslich Selbsterziehung, aus Selbstbehauptung, Selbstfindung wird. Schule bedeutet, das Hineinfinden in das Gewebe der Gesellschaft vorzubereiten. In diesem Sinne ist der fr\u00fchere \u00a0Zweck des Hauses \u2013 den Seidenfaden zu verweben \u2013 nicht weit vom heutigen Schulleben entfernt.<\/p>\n<\/div>\n<div id=\"section-28411\" class=\"container-section\">\n<hr \/>\n<h2>Das Kollegium<\/h2>\n<p class=\"lead\">\u00abZur Erziehung eines Kindes braucht es ein ganzes Dorf.\u00bb \u00a0Afrikanisches Sprichwort<\/p>\n<p class=\"text\">\u00dcber 80 Lehrerinnen und Lehrer unterrichten an der Rudolf Steiner Schule Birseck. So verschieden ihr fachlicher Hintergrund ist, es vereinigt sie das anthroposophische Menschenbild, nach dem jeder Mensch mit ureigenen Impulsen seine Biografie auf der Erde angetreten hat. Den Sch\u00fclerinnen und Sch\u00fclern dabei zu helfen, an diese vorgeburtlichen Entschl\u00fcsse anzukn\u00fcpfen, geh\u00f6rt zum Kern anthroposophischer P\u00e4dagogik.<\/p>\n<p class=\"text\">Die Lehrerbildung auf der Grundlage der Rudolf Steiner P\u00e4dagogik setzt sich mit den theoretischen und praktischen Grundlagen der allgemeinen Erziehungswissenschaft und der Waldorfp\u00e4dagogik sowie deren philosophischen, anthropologischen, wissenschaftstheoretisch-methodischen und historischen Hintergr\u00fcnden auseinander. Leitmotiv dabei ist es, durch ein innovatives, an der Entwicklung des Kindes orientiertes Lehrerbildungsmodell Reformen und Entwicklungen in der Schulpraxis anzuregen. Damit leistet sie einen Beitrag zur Entwicklung aller Schulen in freier Tr\u00e4gerschaft, die immer auch Impulsgeber f\u00fcr das \u00f6ffentliche Schulsystem waren.<\/p>\n<p class=\"text\">Viele im staatlichen Schulwesen in j\u00fcngerer Zeit realisierte Prinzipien sind traditionell in der<br \/>\nRudolf Steiner Schule praktiziert worden.<\/p>\n<p class=\"text\"><strong>Beispiele:<\/strong><\/p>\n<p class=\"text\">\u00bb \u00a0\u00a0F\u00e4cher\u00fcbergreifendes Lernen<br \/>\n\u00bb \u00a0\u00a0Praktisches Lernen<br \/>\n\u00bb \u00a0 Integrative Lernformen<br \/>\n\u00bb \u00a0 Fremdsprachenunterricht ab der 1. Klasse<br \/>\n\u00bb \u00a0 Neue Formen der Leistungsbewertung<br \/>\n\u00bb \u00a0 Gr\u00f6ssere Lerneinheiten<br \/>\n\u00bb \u00a0 \u00dcberwindung des 45-Minuten-Taktes<br \/>\n\u00bb \u00a0 Kein Sitzenbleiben<br \/>\n\u00bb \u00a0 Ausbildung k\u00fcnstlerisch-sch\u00f6pferischer Kreativit\u00e4t<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Rudolf Steiner Schule Birseck Apfelseestrasse 1, 4147 Aesch","_company_website":"https:\/\/www.steinerschule-birseck.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[158,414],"job-categories":[132,103,99,140,76,102],"job-types":[90,5,92,93],"class_list":{"0":"post-20262","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-basel-land","6":"job_listing_region-basel-stadt-land","7":"job_listing_category-gymnasium","8":"job_listing_category-kindergarten","9":"job_listing_category-primarschule","10":"job_listing_category-schweizer-maturitaet","11":"job_listing_category-sekundarstufe_1","12":"job_listing_category-sekundarstufe_2","13":"job_listing_type-kindergarten","14":"job_listing_type-primarschule","15":"job_listing_type-sekundarstufe_1","16":"job_listing_type-sekundarstufe_2","18":"job-type-kindergarten-4-6-jahre","19":"job-type-primarschule-7-12jahre","20":"job-type-sekundarstufe-1-13-16-jahre","21":"job-type-sekundarstufe-2-16-19-jahre"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rudolf Steiner Schule Birseck - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/en\/listings\/rudolf-steiner-schule-birseck\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rudolf Steiner Schule Birseck\" \/>\n<meta property=\"og:description\" content=\"Kindergarten \u00abAus der Art, wie ein Kind spielt, kann man erahnen, wie es seine Lebensaufgabe ergreifen wird.\u00bb Rudolf Steiner Oft sind es die einfachen Spiel- und Baumaterialien, welche die reiche Phantasie der Kinder ansprechen und sie zu kreativem Empfinden und Handeln bewegen. Sie k\u00f6nnen frei ihr Spiel gestalten und werden nicht durch Vorgefertigtes gebunden. Das [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/en\/listings\/rudolf-steiner-schule-birseck\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-22T10:15:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/schulefront_schmal.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/schulefront_schmal.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/rudolf-steiner-schule-birseck\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/rudolf-steiner-schule-birseck\\\/\",\"name\":\"Rudolf Steiner Schule Birseck - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\"},\"datePublished\":\"2020-09-09T20:52:33+00:00\",\"dateModified\":\"2020-12-22T10:15:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/rudolf-steiner-schule-birseck\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/rudolf-steiner-schule-birseck\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/rudolf-steiner-schule-birseck\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rudolf Steiner Schule Birseck\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rudolf Steiner Schule Birseck - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/en\/listings\/rudolf-steiner-schule-birseck\/","og_locale":"en_US","og_type":"article","og_title":"Rudolf Steiner Schule Birseck","og_description":"Kindergarten \u00abAus der Art, wie ein Kind spielt, kann man erahnen, wie es seine Lebensaufgabe ergreifen wird.\u00bb Rudolf Steiner Oft sind es die einfachen Spiel- und Baumaterialien, welche die reiche Phantasie der Kinder ansprechen und sie zu kreativem Empfinden und Handeln bewegen. Sie k\u00f6nnen frei ihr Spiel gestalten und werden nicht durch Vorgefertigtes gebunden. Das [&hellip;]","og_url":"https:\/\/schoolaboo.com\/en\/listings\/rudolf-steiner-schule-birseck\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-12-22T10:15:44+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/schulefront_schmal.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/schulefront_schmal.jpg","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/en\/listings\/rudolf-steiner-schule-birseck\/","url":"https:\/\/schoolaboo.com\/en\/listings\/rudolf-steiner-schule-birseck\/","name":"Rudolf Steiner Schule Birseck - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/en\/#website"},"datePublished":"2020-09-09T20:52:33+00:00","dateModified":"2020-12-22T10:15:44+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/en\/listings\/rudolf-steiner-schule-birseck\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/en\/listings\/rudolf-steiner-schule-birseck\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/en\/listings\/rudolf-steiner-schule-birseck\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/en\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/en\/angebote\/"},{"@type":"ListItem","position":3,"name":"Rudolf Steiner Schule Birseck"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/en\/#website","url":"https:\/\/schoolaboo.com\/en\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/en\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings\/20262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/comments?post=20262"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/media?parent=20262"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job_listing_region?post=20262"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-categories?post=20262"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-types?post=20262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}