{"id":20242,"date":"2020-09-09T22:52:33","date_gmt":"2020-09-09T20:52:33","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=20242"},"modified":"2020-10-14T17:42:16","modified_gmt":"2020-10-14T15:42:16","slug":"curaviva-hfg-hoehere-fachschule-fuer-gemeindeanimation","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/en\/listings\/curaviva-hfg-hoehere-fachschule-fuer-gemeindeanimation\/","title":{"rendered":"Curaviva hfg &#8211; H\u00f6here Fachschule f\u00fcr Gemeindeanimation"},"content":{"rendered":"<div class=\"container struktur title\">\n<header>\n<p class=\"context-label\">H\u00f6here Fachschule f\u00fcr Gemeindeanimation<\/p>\n<h1 class=\"wwsticky-stick-to\">Am Puls \u2013 Im Dialog<\/h1>\n<\/header>\n<\/div>\n<div class=\"container struktur\">\n<section class=\" modulecontainer module curavivasnippet \">\n<div class=\"row\">\n<div class=\"col-6\">\n<article class=\"modulecontainer-item curavivasnippet item \">\n<div class=\"snippet-content\">\n<div class=\"snippettext\">\n<p>Curaviva hfg bietet den Ausbildungsgang f\u00fcr angehende Gemeindeanimator*innen\u00a0an. Die berufsbegleitende 3- oder 4-j\u00e4hrige Ausbildung orientiert sich an den Zielen, Arbeitsweisen und Methoden der Gemeinwesenarbeit und der soziokulturellen Animation sowie der Erwachsenenbildung.<\/p>\n<p>Gemeindeanimator*innen\u00a0sind praxisnah ausgebildete Profis* und arbeiten f\u00fcr private und \u00f6ffentliche Tr\u00e4gerschaften wie politische Gemeinden, Kirchgemeinden, Institutionen der offenen Kinder- und Jugendarbeit, Organisationen im Bereich Alter, Quartiervereinigungen oder andere soziale Einrichtungen.<\/p>\n<div class=\"container struktur title\">\n<header>\n<h1 class=\"wwsticky-stick-to\">Gemeindeanimation: Ein Beruf am Puls<\/h1>\n<\/header>\n<\/div>\n<div class=\"container struktur\">\n<p>Gemeindeanimator*innen\u00a0f\u00f6rdern den sozialen Zusammenhalt der Bev\u00f6lkerung sowie die Verbesserung der Lebensqualit\u00e4t in Bezug auf das soziale und kulturelle Zusammenleben in der Gemeinde oder im Quartier.<\/p>\n<h3><a id=\"T\u00e4tigkeiten\" name=\"tatigkeiten-0\"><\/a>T\u00e4tigkeiten<\/h3>\n<p>Sie setzen sich f\u00fcr bessere Lebensbedingungen der Bev\u00f6lkerung, insbesondere jene sozial benachteiligter Gruppen ein und f\u00f6rdern die Partizipation.<\/p>\n<p>Gemeindeanimator*innen\u00a0arbeiten gemeinwesen- und sozialraumorientiert. Das heisst, sie orientieren sich bei ihrer Arbeit stark an den Interessen und am Willen der Menschen vor Ort . Sie unterst\u00fctzen Eigeninitiativen und Aktivit\u00e4ten zur Selbsthilfe und konzentrierensich auf die Ressourcen der Bev\u00f6lkerung .<\/p>\n<p>Gemeindeanimator*innen stellen Kontakte her, pflegen Netzwerke, vermitteln zwischen lokalen Akteuren, Fachstellen, Milieus, Altersgruppen, Profis und Freiwilligen, vernetzen diese miteinander und f\u00f6rdern den Dialog zwischen verschiedenen Interessengruppen.<\/p>\n<h3><a id=\"Arbeitsorte\" name=\"arbeitsorte-1\"><\/a>M\u00f6gliche Arbeitsorte<\/h3>\n<p>Gemeindeanimator*innen\u00a0arbeiten an Begegnungsorten:<\/p>\n<ul>\n<li>Kultur-, Gemeinschafts- und Seniorenzentren<\/li>\n<li>Quartier- oder Jugendtreffs<\/li>\n<li>betreute Spielpl\u00e4tze<\/li>\n<li>Pr\u00e4ventions-, Asyl- und Arbeitslosenprojekte<\/li>\n<li>Interkulturelle Projekte<\/li>\n<li>ausserschulische Bildungsarbeit<\/li>\n<li>mobile Kinder- und Jugendarbeit<\/li>\n<li>Gassenarbeit<\/li>\n<\/ul>\n<div class=\"container struktur title\">\n<header>\n<h1 class=\"wwsticky-stick-to\">\u00dcber uns<\/h1>\n<\/header>\n<\/div>\n<div class=\"container struktur\">\n<p>Die H\u00f6here Fachschule f\u00fcr Gemeindeanimation\u00a0hfg bietet seit August 2016 den neuen Ausbildungsgang zur Gemeindeanimator\/-in\u00a0an. Die hfg ist\u00a0Teil des Gesch\u00e4ftsbereichs Bildung von CURAVIVA Schweiz.<\/p>\n<p>Der Bildungsbereich von CURAVIVA Schweiz ist eduQua und ISO zertifiziert.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"CURAVIVA hfg Abendweg 1 Luzern 6","_company_website":"","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[162],"job-categories":[226],"job-types":[228],"class_list":{"0":"post-20242","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-luzern","6":"job_listing_category-hoehere-fachschule","7":"job_listing_type-tertiaerausbildung","9":"job-type-tertiarausbildung"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Curaviva hfg - H\u00f6here Fachschule f\u00fcr Gemeindeanimation - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/en\/listings\/curaviva-hfg-hoehere-fachschule-fuer-gemeindeanimation\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curaviva hfg - H\u00f6here Fachschule f\u00fcr Gemeindeanimation\" \/>\n<meta property=\"og:description\" content=\"H\u00f6here Fachschule f\u00fcr Gemeindeanimation Am Puls \u2013 Im Dialog Curaviva hfg bietet den Ausbildungsgang f\u00fcr angehende Gemeindeanimator*innen\u00a0an. Die berufsbegleitende 3- oder 4-j\u00e4hrige Ausbildung orientiert sich an den Zielen, Arbeitsweisen und Methoden der Gemeinwesenarbeit und der soziokulturellen Animation sowie der Erwachsenenbildung. Gemeindeanimator*innen\u00a0sind praxisnah ausgebildete Profis* und arbeiten f\u00fcr private und \u00f6ffentliche Tr\u00e4gerschaften wie politische Gemeinden, Kirchgemeinden, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/en\/listings\/curaviva-hfg-hoehere-fachschule-fuer-gemeindeanimation\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-14T15:42:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/Download-2-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/Download-2-1.png\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/curaviva-hfg-hoehere-fachschule-fuer-gemeindeanimation\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/curaviva-hfg-hoehere-fachschule-fuer-gemeindeanimation\\\/\",\"name\":\"Curaviva hfg - H\u00f6here Fachschule f\u00fcr Gemeindeanimation - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\"},\"datePublished\":\"2020-09-09T20:52:33+00:00\",\"dateModified\":\"2020-10-14T15:42:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/curaviva-hfg-hoehere-fachschule-fuer-gemeindeanimation\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/curaviva-hfg-hoehere-fachschule-fuer-gemeindeanimation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/curaviva-hfg-hoehere-fachschule-fuer-gemeindeanimation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Curaviva hfg &#8211; H\u00f6here Fachschule f\u00fcr Gemeindeanimation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Curaviva hfg - H\u00f6here Fachschule f\u00fcr Gemeindeanimation - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/en\/listings\/curaviva-hfg-hoehere-fachschule-fuer-gemeindeanimation\/","og_locale":"en_US","og_type":"article","og_title":"Curaviva hfg - H\u00f6here Fachschule f\u00fcr Gemeindeanimation","og_description":"H\u00f6here Fachschule f\u00fcr Gemeindeanimation Am Puls \u2013 Im Dialog Curaviva hfg bietet den Ausbildungsgang f\u00fcr angehende Gemeindeanimator*innen\u00a0an. Die berufsbegleitende 3- oder 4-j\u00e4hrige Ausbildung orientiert sich an den Zielen, Arbeitsweisen und Methoden der Gemeinwesenarbeit und der soziokulturellen Animation sowie der Erwachsenenbildung. Gemeindeanimator*innen\u00a0sind praxisnah ausgebildete Profis* und arbeiten f\u00fcr private und \u00f6ffentliche Tr\u00e4gerschaften wie politische Gemeinden, Kirchgemeinden, [&hellip;]","og_url":"https:\/\/schoolaboo.com\/en\/listings\/curaviva-hfg-hoehere-fachschule-fuer-gemeindeanimation\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-10-14T15:42:16+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/Download-2-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/Download-2-1.png","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/en\/listings\/curaviva-hfg-hoehere-fachschule-fuer-gemeindeanimation\/","url":"https:\/\/schoolaboo.com\/en\/listings\/curaviva-hfg-hoehere-fachschule-fuer-gemeindeanimation\/","name":"Curaviva hfg - H\u00f6here Fachschule f\u00fcr Gemeindeanimation - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/en\/#website"},"datePublished":"2020-09-09T20:52:33+00:00","dateModified":"2020-10-14T15:42:16+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/en\/listings\/curaviva-hfg-hoehere-fachschule-fuer-gemeindeanimation\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/en\/listings\/curaviva-hfg-hoehere-fachschule-fuer-gemeindeanimation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/en\/listings\/curaviva-hfg-hoehere-fachschule-fuer-gemeindeanimation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/en\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/en\/angebote\/"},{"@type":"ListItem","position":3,"name":"Curaviva hfg &#8211; H\u00f6here Fachschule f\u00fcr Gemeindeanimation"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/en\/#website","url":"https:\/\/schoolaboo.com\/en\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/en\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings\/20242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/comments?post=20242"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/media?parent=20242"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job_listing_region?post=20242"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-categories?post=20242"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-types?post=20242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}