{"id":20142,"date":"2020-09-09T22:52:34","date_gmt":"2020-09-09T20:52:34","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=20142"},"modified":"2020-10-14T22:58:08","modified_gmt":"2020-10-14T20:58:08","slug":"ibz-schulen-ag-winterthur","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/en\/listings\/ibz-schulen-ag-winterthur\/","title":{"rendered":"IBZ Schulen AG &#8211; Winterthur"},"content":{"rendered":"<div id=\"section-96814\" class=\"container-section\">\n<h2><strong>IBZ \u2013 DIE SCHWEIZER SCHULE F\u00dcR TECHNIK UND MANAGEMENT<\/strong><\/h2>\n<\/div>\n<div id=\"section-96817\" class=\"container-section\">\n<p>Erfahren Sie mehr zu den \u00fcber 30 Lehrg\u00e4ngen in den Bereichen\u00a0Bau- und Geb\u00e4udetechnik,\u00a0Elektrotechnik,\u00a0Informatik,\u00a0Maschinenbau,\u00a0Kunststofftechnik,\u00a0Betriebstechnik,\u00a0Logistik,\u00a0Qualit\u00e4tsmanagement\u00a0sowie\u00a0Management\u00a0oder informieren Sie sich \u00fcber einen unserer\u00a0Kurse. Wir w\u00fcnschen viel Spass beim Durchklicken und stehen f\u00fcr Fragen oder eine pers\u00f6nliche Beratung gerne zur Verf\u00fcgung.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div id=\"section-96818\" class=\"container-section\">\n<h3><strong>INFOVERANSTALTUNGEN<\/strong><\/h3>\n<p><strong>INFOABENDE<\/strong><br \/>\nWir f\u00fchren regelm\u00e4ssig\u00a0<strong>Infoabende\u00a0<\/strong>durch, jeweils abends von 18.00 bis 20.00 Uhr. Dabei stellen wir Ihnen die IBZ und unsere Lehrg\u00e4nge vor. Ein Schulleiter beantwortet dabei gerne Ihre Fragen.<\/p>\n<p><strong>OPEN HOUSE<\/strong><br \/>\nDaneben haben Sie die M\u00f6glichkeit, an ausgew\u00e4hlten Daten eine\u00a0<strong>OPEN HOUSE Infoveranstaltung mit Ausstellung und Ap\u00e9ro<\/strong>\u00a0in Aarau, Bern, Zug oder Z\u00fcrich zu besuchen. Im Ausstellungsbereich stehen Ihnen die Schulleiter aus s\u00e4mtlichen Fachbereichen f\u00fcr Ihre Fragen zur Verf\u00fcgung und pr\u00e4sentieren Ihnen die verschiedenen Lehrg\u00e4nge. Es findet mehrmals eine Kurzvorstellung der IBZ statt und ein Ap\u00e9ro-Buffet sorgt f\u00fcr die kleine St\u00e4rkung zwischendurch.<\/p>\n<p><strong>SCHNUPPERTAG<\/strong><br \/>\nSind Sie auf der Suche nach einer Lehrstelle zum\/zur Informatiker\/-in EFZ? Dann besuchen Sie unseren\u00a0<strong>Schnuppertag Informatiker\/-in EFZ.\u00a0<\/strong>Hier erfahren Sie mehr zur Ausbildung zum\/zur Informatiker\/-in bei der IBZ und k\u00f6nnen in verschiedenen Workshops gleich selber die T\u00e4tigkeiten einer Informatikerin bzw. eines Informatikers kennenlernen. Der Schnuppertag dauert von 09.30 bis 15.30 Uhr, das Mittagessen ist dabei.<\/p>\n<\/div>\n<div class=\"container content\">\n<div class=\"row\">\n<div class=\"col-md-12\">\n<div id=\"section-70010\" class=\"container-section\">\n<p>Die Schweizer Schule f\u00fcr Technik und Management ist f\u00fchrend in der beruflichen Aus- und Weiterbildung im technischen Bereich. Sie wurde 1945 gegr\u00fcndet und ist seit 1972 eine eidgen\u00f6ssisch anerkannte H\u00f6here Fachschule. Seit 2007 geh\u00f6rt die IBZ zur ipso Bildung und ist somit Teil der gr\u00f6ssten privaten Anbieterin von Aus- und Weiterbildungen in der Nordwestschweiz. 2014 wurde die Zuger Techniker- und Informationsschule zti in die IBZ integriert.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>VIELSEITIG<\/strong><\/h3>\n<p>Das Schulungsangebot der IBZ umfasst ein breites Spektrum von berufsbegleitenden Studieng\u00e4ngen auf den Stufen H\u00f6here Berufsbildung, H\u00f6here Fachschule und Nachdiplomstudien sowie vollzeitliche Berufsausbildungen im Bereich Informatik und zahlreiche Kurse.<\/p>\n<h3><strong>PRAXISORIENTIERT<\/strong><\/h3>\n<p>Ausbildungen und Weiterbildungen der IBZ orientieren sich an den Bed\u00fcrfnissen der Praxis. Die Lehrg\u00e4nge sind so gestaltet, dass sie berufsbegleitend neben einem 100%-Pensum absolviert werden k\u00f6nnen. Gelerntes kann sofort im Alltag umgesetzt werden \u2013 so profitieren auch die Betriebe vom neuen Wissen.<\/p>\n<h3><strong>QUALIFIZIERT<\/strong><\/h3>\n<p>An der IBZ unterrichten \u00fcber 400 qualifizierte und erfahrene Dozenten und Dozentinnen aus der Wirtschaft und dem Bildungsbereich. Sie tragen mit ihrem wissenschaftlichen Know-how und ihrem Praxiswissen wesentlich dazu bei, dass die Studierenden ihr angestrebtes Bildungsziel erreichen.<\/p>\n<h3><strong>ZEITGEM\u00c4SS<\/strong><\/h3>\n<p>Modernste Unterrichtsmethoden und Lerntechniken, ein flexibler, modularer Studienaufbau und bewusste Praxisn\u00e4he unterst\u00fctzen den Lernerfolg der Studierenden. Die IBZ legt Wert auf einen effizienten Wissenstransfer. Das Angebot wird laufend verbessert und den Anforderungen der Praxis angepasst.<\/p>\n<h3><strong>ERFOLGREICH<\/strong><\/h3>\n<p>Die IBZ bringt Menschen weiter: Die Erfolgsquote unserer Absolvierenden bei den Abschlusspr\u00fcfungen ist \u00fcberdurchschnittlich hoch. Auf dem Arbeitsmarkt sind sie gefragte Leute.<\/p>\n<h3><strong>ZERTIFIZIERT<\/strong><\/h3>\n<p>Die IBZ ist nach ISO 29900 zertifiziert, dem Qualit\u00e4tsmanagementsystem f\u00fcr die Aus- und Weiterbildungsbranche.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"IBZ Schulen AG Standort Winterthur c\/o Berufsschule Winterthur T\u00f6sstalstrasse 26 | CH-8400 Winterthur","_company_website":"https:\/\/www.ibz.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[153],"job-categories":[],"job-types":[93,228],"class_list":{"0":"post-20142","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-zuerich","6":"job_listing_type-sekundarstufe_2","7":"job_listing_type-tertiaerausbildung","9":"job-type-sekundarstufe-2-16-19-jahre","10":"job-type-tertiarausbildung"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>IBZ Schulen AG - Winterthur - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/en\/listings\/ibz-schulen-ag-winterthur\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IBZ Schulen AG - Winterthur\" \/>\n<meta property=\"og:description\" content=\"IBZ \u2013 DIE SCHWEIZER SCHULE F\u00dcR TECHNIK UND MANAGEMENT Erfahren Sie mehr zu den \u00fcber 30 Lehrg\u00e4ngen in den Bereichen\u00a0Bau- und Geb\u00e4udetechnik,\u00a0Elektrotechnik,\u00a0Informatik,\u00a0Maschinenbau,\u00a0Kunststofftechnik,\u00a0Betriebstechnik,\u00a0Logistik,\u00a0Qualit\u00e4tsmanagement\u00a0sowie\u00a0Management\u00a0oder informieren Sie sich \u00fcber einen unserer\u00a0Kurse. Wir w\u00fcnschen viel Spass beim Durchklicken und stehen f\u00fcr Fragen oder eine pers\u00f6nliche Beratung gerne zur Verf\u00fcgung. &nbsp; INFOVERANSTALTUNGEN INFOABENDE Wir f\u00fchren regelm\u00e4ssig\u00a0Infoabende\u00a0durch, jeweils abends von 18.00 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/en\/listings\/ibz-schulen-ag-winterthur\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-14T20:58:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/IBZ_Logo-5.svg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/IBZ_Logo-5.svg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/ibz-schulen-ag-winterthur\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/ibz-schulen-ag-winterthur\\\/\",\"name\":\"IBZ Schulen AG - Winterthur - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\"},\"datePublished\":\"2020-09-09T20:52:34+00:00\",\"dateModified\":\"2020-10-14T20:58:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/ibz-schulen-ag-winterthur\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/ibz-schulen-ag-winterthur\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/ibz-schulen-ag-winterthur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IBZ Schulen AG &#8211; Winterthur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"IBZ Schulen AG - Winterthur - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/en\/listings\/ibz-schulen-ag-winterthur\/","og_locale":"en_US","og_type":"article","og_title":"IBZ Schulen AG - Winterthur","og_description":"IBZ \u2013 DIE SCHWEIZER SCHULE F\u00dcR TECHNIK UND MANAGEMENT Erfahren Sie mehr zu den \u00fcber 30 Lehrg\u00e4ngen in den Bereichen\u00a0Bau- und Geb\u00e4udetechnik,\u00a0Elektrotechnik,\u00a0Informatik,\u00a0Maschinenbau,\u00a0Kunststofftechnik,\u00a0Betriebstechnik,\u00a0Logistik,\u00a0Qualit\u00e4tsmanagement\u00a0sowie\u00a0Management\u00a0oder informieren Sie sich \u00fcber einen unserer\u00a0Kurse. Wir w\u00fcnschen viel Spass beim Durchklicken und stehen f\u00fcr Fragen oder eine pers\u00f6nliche Beratung gerne zur Verf\u00fcgung. &nbsp; INFOVERANSTALTUNGEN INFOABENDE Wir f\u00fchren regelm\u00e4ssig\u00a0Infoabende\u00a0durch, jeweils abends von 18.00 [&hellip;]","og_url":"https:\/\/schoolaboo.com\/en\/listings\/ibz-schulen-ag-winterthur\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-10-14T20:58:08+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/IBZ_Logo-5.svg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/IBZ_Logo-5.svg","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/en\/listings\/ibz-schulen-ag-winterthur\/","url":"https:\/\/schoolaboo.com\/en\/listings\/ibz-schulen-ag-winterthur\/","name":"IBZ Schulen AG - Winterthur - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/en\/#website"},"datePublished":"2020-09-09T20:52:34+00:00","dateModified":"2020-10-14T20:58:08+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/en\/listings\/ibz-schulen-ag-winterthur\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/en\/listings\/ibz-schulen-ag-winterthur\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/en\/listings\/ibz-schulen-ag-winterthur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/en\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/en\/angebote\/"},{"@type":"ListItem","position":3,"name":"IBZ Schulen AG &#8211; Winterthur"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/en\/#website","url":"https:\/\/schoolaboo.com\/en\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/en\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings\/20142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/comments?post=20142"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/media?parent=20142"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job_listing_region?post=20142"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-categories?post=20142"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-types?post=20142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}