{"id":19896,"date":"2020-09-09T22:53:52","date_gmt":"2020-09-09T20:53:52","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=19896"},"modified":"2020-10-13T15:05:52","modified_gmt":"2020-10-13T13:05:52","slug":"cta-istituto-interlingue-sa","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/en\/listings\/cta-istituto-interlingue-sa\/","title":{"rendered":"CTA Istituto Interlingue SA"},"content":{"rendered":"<p>Seit seiner Gr\u00fcndung im Jahre 1985, hat sich das CTA Istituto Interlingue f\u00fcr die Sprachausbildung in Tessiner Unternehmen eingesetzt. Viele Tessiner Firmen und Banken haben seitdem von unserer Erfahrung auf diesem Sektor profitiert. Wir bieten Kurse auf allen Sprachstufen an, die individuell den Bed\u00fcrfnissen des Kunden\/der Firma angepasst sind. Es besteht auch die M\u00f6glichkeit, Vorbereitungskurse auf international anerkannte Diplome\/Pr\u00fcfungen durchzuf\u00fchren<\/p>\n<p>Unsere Angebote gelten f\u00fcr Einzelpersonen oder Kleingruppen.<\/p>\n<p>Die vorwiegend verlangten Sprachen sind Englisch, Italienisch, Franz\u00f6sisch und Deutsch, aber auf Anfrage k\u00f6nnen wir auch andere Sprachkurse anbieten.<\/p>\n<p>Alle unsere Mitarbeiter sind Muttersprachler die \u00fcber eine ausgezeichnete Ausbildung in ihrer Sprache verf\u00fcgen und Erfahrung im Unterricht von Erwachsenen haben (z.B. SVEB-Zertifikat oder gleichwertig).<\/p>\n<p>&nbsp;<\/p>\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><strong>\u00dcberbr\u00fcckungsausbildung: Kurse f\u00fcr Jugendliche und Erwachsene.<\/strong><br \/>\nDank der \u00dcberbr\u00fcckungsausbildung \u00a0k\u00f6nnen Sie sich in einem einzigen Schuljahr alle Kenntnisse und F\u00e4higkeiten aneignen, die im nationalen und internationalen Arbeitsmarkt, in der allgemeinen Gesch\u00e4ftswelt und \u00a0f\u00fcr praktische B\u00fcroarbeiten ben\u00f6tigt werden.<br \/>\nF\u00fcr Jugendliche bieten wir<strong>\u00a0im Bereich der \u00dcberbr\u00fcckungsausbildung 3 Formationsm\u00f6glichkeiten an<\/strong> um ein Maximum an pers\u00f6nlicher Gestaltung des Studiums zu erm\u00f6glichen.<\/p>\n<\/div>\n<p>F\u00fcr alle Schulf\u00e4cher und Studienbereiche bieten wir Privatstunden oder Kleingruppenunterricht an, die darauf hinzielen, etwaige Wissensl\u00fccken der Teilnehmer zu f\u00fcllen.<br \/>\nDas Unterrichtsprogramm ist f\u00fcr jedes Bildungsniveau gedacht und st\u00fctzt sich auf die wirklichen, individuellen Erfordernisse der Studenten.<br \/>\nWir bieten maximale Verf\u00fcgbarkeit und Flexibilit\u00e4t was die Uhrzeit des Unterrichts betrifft.<br \/>\nDer Unterricht kann auch ausserhalb des Schulsitzes durchgef\u00fchrt werden.<br \/>\nDie Kurse werden w\u00e4hrend des ganzen Schuljahres durchgef\u00fchrt \u00a0(nach dem Unterricht).<br \/>\nW\u00e4hrend dem Sommer organisieren wir Intensiv-Nachhilfekurse von 2 oder mehr Wochen.<\/p>\n<\/div>\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Seit 1985 \u00fcbersetzen wir alle Arten von Texten: Artikel, Jahresrapporte, B\u00fccher, Diplom- und Forschungsarbeiten, Prospekte, Kataloge, Vertr\u00e4ge, Urteile und verschiedene Texte im \u00f6ffentlichen und privaten \u00a0Sektor.<\/p>\n<p>Unsere professionellen \u00dcbersetzungen sind von hoher Qualit\u00e4t und k\u00f6nnen von und in den weltweit meist verbreiteten Sprachen gemacht werden. Die Ausf\u00fchrung der Arbeit ist genau und p\u00fcnktlich und unsere Preise sind g\u00fcnstig und konkurrenzf\u00e4hig.<\/p>\n<p>Ausserdem bieten wir Dolmetscherdienste an (Konferenz-, Konsekutiv- und Simultan\u00fcbersetzungen).<\/p>\n<p>Wir verf\u00fcgen \u00fcber professionelle Dolmetscher, die bereit sind, f\u00fcr unsere Kunden auch im Ausland zu \u00fcbersetzen (Konferenz-, Konsekutiv- und Simultan\u00fcbersetzungen).<\/p>\n<p>Es ist ausserdem m\u00f6glich Texte (auch Handgeschriebene), in derselben Sprache zu korrigieren in der diese verfasst oder \u00fcbersetzt worden sind.<\/p>\n<\/div>\n<\/div>\n<p>Als Erg\u00e4nzung zu den Sprachkursen, organisieren wir seit 1985 Sprachaufenthalte in der Schweiz und im Ausland.<br \/>\nIm Laufe der Jahre haben wir ausgezeichnete Kontakte mit einigen ausl\u00e4ndischen Schulen entwickelt, die unseren Sch\u00fclern die meisten Vorteile und die besten Resultate garantieren, vor allem in Bezug auf die offiziellen Pr\u00fcfungen der Cambridge University und des Goethe Instituts.<br \/>\nWir wenden dabei direkt und absolut transparent die Originalpreise<br \/>\nder jeweiligen, ausl\u00e4ndischen Schulen an.<br \/>\nWir verfolgen die Ergebnisse unserer Sch\u00fcler mittels regelm\u00e4ssigen<br \/>\nBerichten die wir von den Schulen erhalten.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Via Monte Boglia 4, 6900 Lugano (CH)","_company_website":"http:\/\/www.interlingue.ch\/de\/sprachaufenthalte","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[152],"job-categories":[],"job-types":[],"class_list":["post-19896","job_listing","type-job_listing","status-publish","hentry","job_listing_region-tessin"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CTA Istituto Interlingue SA - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/en\/listings\/cta-istituto-interlingue-sa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CTA Istituto Interlingue SA\" \/>\n<meta property=\"og:description\" content=\"Seit seiner Gr\u00fcndung im Jahre 1985, hat sich das CTA Istituto Interlingue f\u00fcr die Sprachausbildung in Tessiner Unternehmen eingesetzt. Viele Tessiner Firmen und Banken haben seitdem von unserer Erfahrung auf diesem Sektor profitiert. Wir bieten Kurse auf allen Sprachstufen an, die individuell den Bed\u00fcrfnissen des Kunden\/der Firma angepasst sind. Es besteht auch die M\u00f6glichkeit, Vorbereitungskurse [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/en\/listings\/cta-istituto-interlingue-sa\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-13T13:05:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/Download.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/Download.png\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/cta-istituto-interlingue-sa\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/cta-istituto-interlingue-sa\\\/\",\"name\":\"CTA Istituto Interlingue SA - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\"},\"datePublished\":\"2020-09-09T20:53:52+00:00\",\"dateModified\":\"2020-10-13T13:05:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/cta-istituto-interlingue-sa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/cta-istituto-interlingue-sa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/listings\\\/cta-istituto-interlingue-sa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CTA Istituto Interlingue SA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CTA Istituto Interlingue SA - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/en\/listings\/cta-istituto-interlingue-sa\/","og_locale":"en_US","og_type":"article","og_title":"CTA Istituto Interlingue SA","og_description":"Seit seiner Gr\u00fcndung im Jahre 1985, hat sich das CTA Istituto Interlingue f\u00fcr die Sprachausbildung in Tessiner Unternehmen eingesetzt. Viele Tessiner Firmen und Banken haben seitdem von unserer Erfahrung auf diesem Sektor profitiert. Wir bieten Kurse auf allen Sprachstufen an, die individuell den Bed\u00fcrfnissen des Kunden\/der Firma angepasst sind. Es besteht auch die M\u00f6glichkeit, Vorbereitungskurse [&hellip;]","og_url":"https:\/\/schoolaboo.com\/en\/listings\/cta-istituto-interlingue-sa\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-10-13T13:05:52+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/Download.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/07\/Download.png","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/en\/listings\/cta-istituto-interlingue-sa\/","url":"https:\/\/schoolaboo.com\/en\/listings\/cta-istituto-interlingue-sa\/","name":"CTA Istituto Interlingue SA - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/en\/#website"},"datePublished":"2020-09-09T20:53:52+00:00","dateModified":"2020-10-13T13:05:52+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/en\/listings\/cta-istituto-interlingue-sa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/en\/listings\/cta-istituto-interlingue-sa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/en\/listings\/cta-istituto-interlingue-sa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/en\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/en\/angebote\/"},{"@type":"ListItem","position":3,"name":"CTA Istituto Interlingue SA"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/en\/#website","url":"https:\/\/schoolaboo.com\/en\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/en\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings\/19896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/comments?post=19896"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/media?parent=19896"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job_listing_region?post=19896"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-categories?post=19896"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/en\/wp-json\/wp\/v2\/job-types?post=19896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}