{"id":23441,"date":"2020-12-14T17:08:22","date_gmt":"2020-12-14T16:08:22","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=23441"},"modified":"2020-12-22T11:15:20","modified_gmt":"2020-12-22T10:15:20","slug":"hws-huber-widemann-schule-ag-bewegung-und-gesundheit","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/de\/listings\/hws-huber-widemann-schule-ag-bewegung-und-gesundheit\/","title":{"rendered":"HWS Huber Widemann Schule AG Bewegung und Gesundheit"},"content":{"rendered":"<div class=\"grid__item grid__item--columns-2 grid__item--white\">\n<div class=\"box ckeditor-table\">\n<div class=\"text-long\">\n<p>Wir engagieren uns f\u00fcr Ihre Zukunft: Mit 1&#8217;000 Lernenden und Studierenden ist die HWS Huber Widemann Schule in der Nordwestschweiz die Nummer 1 f\u00fcr Aus- und Weiterbildungen in den Bereichen Bewegung und Gesundheit, Medizin und Naturheilkunde. Unsere Lehrpersonen kommen aus der Praxis und lehren f\u00fcr die Praxis. Die HWS ist bekannt als renommierte Privatschule und hat einen\u00a0ausgezeichnet Ruf &#8211; seit bald 150 Jahren.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"grid__item grid__item--columns-2 grid__item--white\">\n<div class=\"box ckeditor-table\">\n<div class=\"text-long\">\n<p>Die HWS ist Teil von ipso!, eines der f\u00fchrenden Bildungsunternehmen in der Deutschschweiz.<\/p>\n<p>ipso! bietet insgesamt \u00fcber 120 verschiedene Bildungsprogramme in den Bereichen Wirtschaft, Sprachen, Informatik, Technik, Gesundheit und Management an. Dieses Bildungsportfolio geh\u00f6rt zu den umfassendsten in der privaten Schweizer Bildung.<\/p>\n<p>An den ipso! Schulen absolvieren zurzeit \u00fcber 5000 Sch\u00fcler, Lernende und Studierende eine Aus- oder Weiterbildung, wobei das umfangreiche Bildungsangebot vom Fr\u00fch-Kindergarten bis zur Managementbildung reicht. \u00dcber 1000 Lehrpersonen und Dozierende stehen an unseren elf Standorten im Einsatz und rund 130 Mitarbeitende arbeiten im Gruppen- und Bildungsmanagement.<\/p>\n<\/div>\n<div class=\"grid__item grid__item--columns-2 grid__item--white\">\n<div class=\"box ckeditor-table\">\n<div class=\"text-long\">\n<p>Wir bieten zeitgem\u00e4sse und praxisnahe Aus- und Weiterbildungen in den Bereichen Medizin, Bewegung und\u00a0Gesundheit sowie in Naturheilkunde an. Die HWS Huber Widemann Schule ist bekannt als renommierte Privatschule und hat einen ausgezeichneten Ruf &#8211; seit bald 150 Jahren.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"grid__item grid__item--columns-2 grid__item--white\">\n<div class=\"box ckeditor-table\">\n<div class=\"text-long\">\n<p>Wir sind zudem die offzielle Berufsfachschule der Kantone Basel-Stadt und Baselland f\u00fcr folgende EFZ Ausbildungen: Medizinische Praxisassistent\/-innen, Dentalassistent\/-innen, Fachleute Bewegungs- und Gesundheitsf\u00f6rderung sowie B\u00fchnent\u00e4nzer\/-innen.<\/p>\n<\/div>\n<div class=\"beg-course-quickview-section__area\">\n<div class=\"beg-course-quickview-section__area-name\">Lehrg\u00e4nge Bewegung und Gesundheit<\/div>\n<div class=\"beg-course-quickview-section__area-courses\">\n<ul class=\"ul\">\n<li class=\"list-item list-item--no-padding\"><a href=\"https:\/\/www.hws.ch\/angebote\/bewegungspaedagogin-bewegungspaedagoge\" hreflang=\"de\">Dipl. Bewegungs\u00adp\u00e4dagogin \/ Bewegungs\u00adp\u00e4dagoge HF (in Vorbereitung)<\/a><\/li>\n<li class=\"list-item list-item--no-padding\"><a href=\"https:\/\/www.hws.ch\/angebote\/experteexpertin-bewegungs-und-gesundheitsfoerderung-mit-eidg-diplom\" hreflang=\"de\">Experte\/Expertin Bewegungs- und Gesundheits\u00adf\u00f6rderung mit eidg. Diplom<\/a><\/li>\n<li class=\"list-item list-item--no-padding\"><a href=\"https:\/\/www.hws.ch\/angebote\/fitness-und-bewegungstrainerin\" hreflang=\"de\">Fitness- und Bewegungstrainer\/-in<\/a><\/li>\n<li class=\"list-item list-item--no-padding\"><a href=\"https:\/\/www.hws.ch\/angebote\/fitnessclub-manager\" hreflang=\"de\">Fitnessclub Manager\/-in<\/a><\/li>\n<li class=\"list-item list-item--no-padding\"><a href=\"https:\/\/www.hws.ch\/angebote\/marketing-und-sales-manager\" hreflang=\"de\">Marketing und Sales Manager\/-in<\/a><\/li>\n<li class=\"list-item list-item--no-padding\"><a href=\"https:\/\/www.hws.ch\/angebote\/medizinischer-fitnesstrainer\" hreflang=\"de\">Medizinische\/r Fitnesstrainer\/-in<\/a><\/li>\n<li class=\"list-item list-item--no-padding\"><a href=\"https:\/\/www.hws.ch\/angebote\/modulpruefungstermine-spezialistin-bewegungs-und-gesundheitsfoerderung-mit-eidg\" hreflang=\"de\">Modulpr\u00fcfungstermine Spezialist\/-in Bewegungs- und Gesundheitsf\u00f6rderung mit eidg. Fachausweis<\/a><\/li>\n<li class=\"list-item list-item--no-padding\"><a href=\"https:\/\/www.hws.ch\/angebote\/spezialistin-bewegungs-und-gesundheitsfoerderung-mit-eidg-fachausweis-fuer-fachleute\" hreflang=\"de\">Spezialist\/-in Bewegungs- und Gesundheits\u00adf\u00f6rderung mit eidg. Fachausweis f\u00fcr Fachleute Bewegungs- und Gesundheits\u00adf\u00f6rderung EFZ<\/a><\/li>\n<li class=\"list-item list-item--no-padding\"><a href=\"https:\/\/www.hws.ch\/angebote\/spezialistin-bewegungs-und-gesundheitsfoerderung-mit-eidg-fachausweis-fuer-fitness-und\" hreflang=\"de\">Spezialist\/-in Bewegungs- und Gesundheits\u00adf\u00f6rderung mit eidg. Fachausweis f\u00fcr Fitness- und Bewegungs\u00adtrainer\/-in HWS<\/a><\/li>\n<li class=\"list-item list-item--no-padding\"><a href=\"https:\/\/www.hws.ch\/angebote\/trainerin-bewegungs-und-gesundheitsfoerderung-mit-branchenzertifikat-fuer-fitness-und\" hreflang=\"de\">Trainer\/-in Bewegungs- und Gesundheits\u00adf\u00f6rderung mit Branchen\u00adzertifikat f\u00fcr Fitness- und Bewegungs\u00adtrainer\/-innen<\/a><\/li>\n<li class=\"list-item list-item--no-padding\"><a href=\"https:\/\/www.hws.ch\/angebote\/trainer-bewegungs-und-gesundheitsfoerderung-mit-branchenzertifikat-fuer-fachleute\" hreflang=\"de\">Trainer\/-in Bewegungs- und Gesundheitsf\u00f6rderung mit Branchenzertifikat f\u00fcr Fachleute Bewegungs- und Gesundheitsf\u00f6rderung EFZ<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"beg-course-quickview-section__area\">\n<div class=\"beg-course-quickview-section__area-name\">Weitere Angebote<\/div>\n<div class=\"beg-course-quickview-section__area-courses\">\n<ul class=\"ul\">\n<li class=\"list-item list-item--no-padding\"><a href=\"https:\/\/www.hws.ch\/angebote\/ernaehrungscoach\" hreflang=\"de\">Ern\u00e4hrungscoach<\/a><\/li>\n<li class=\"list-item list-item--no-padding\"><a href=\"https:\/\/www.hws.ch\/angebote\/gesundheitsfoerderung-und-lebensstilintervention\" hreflang=\"de\">Gesundheitsf\u00f6rderung und Lebensstilintervention<\/a><\/li>\n<li class=\"list-item list-item--no-padding\"><a href=\"https:\/\/www.hws.ch\/angebote\/klassische-massage\" hreflang=\"de\">Klassische Massage<\/a><\/li>\n<li class=\"list-item list-item--no-padding\"><a href=\"https:\/\/www.hws.ch\/angebote\/kursleiter-koerperarbeit-schwangerschaft-geburt-und-rueckbildung\" hreflang=\"de\">Kursleiter\/-in K\u00f6rperarbeit &#8211; Schwangerschaft, Geburt und R\u00fcckbildung<\/a><\/li>\n<li class=\"list-item list-item--no-padding\"><a href=\"https:\/\/www.hws.ch\/angebote\/kursleiterin-mit-svebzertifikat\" hreflang=\"de\">Kursleiter\/-in mit SVEB-Zertifikat<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"HWS Huber Widemann Schule AG Eulerstrasse 55 CH-4051 Basel","_company_website":"https:\/\/www.hws.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[158,414],"job-categories":[114,102,271,251],"job-types":[93,228],"class_list":{"0":"post-23441","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-basel-land","6":"job_listing_region-basel-stadt-land","7":"job_listing_category-fachmittelschule","8":"job_listing_category-sekundarstufe_2","9":"job_listing_category-technik","10":"job_listing_category-weiterbildung","11":"job_listing_type-sekundarstufe_2","12":"job_listing_type-tertiaerausbildung","14":"job-type-sekundarstufe-2-16-19-jahre","15":"job-type-tertiaerausbildung"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>HWS Huber Widemann Schule AG Bewegung und Gesundheit - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/de\/listings\/hws-huber-widemann-schule-ag-bewegung-und-gesundheit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HWS Huber Widemann Schule AG Bewegung und Gesundheit\" \/>\n<meta property=\"og:description\" content=\"Wir engagieren uns f\u00fcr Ihre Zukunft: Mit 1&#8217;000 Lernenden und Studierenden ist die HWS Huber Widemann Schule in der Nordwestschweiz die Nummer 1 f\u00fcr Aus- und Weiterbildungen in den Bereichen Bewegung und Gesundheit, Medizin und Naturheilkunde. Unsere Lehrpersonen kommen aus der Praxis und lehren f\u00fcr die Praxis. Die HWS ist bekannt als renommierte Privatschule und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/de\/listings\/hws-huber-widemann-schule-ag-bewegung-und-gesundheit\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-22T10:15:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/Download-2-7.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/Download-2-7.png\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/hws-huber-widemann-schule-ag-bewegung-und-gesundheit\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/hws-huber-widemann-schule-ag-bewegung-und-gesundheit\\\/\",\"name\":\"HWS Huber Widemann Schule AG Bewegung und Gesundheit - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#website\"},\"datePublished\":\"2020-12-14T16:08:22+00:00\",\"dateModified\":\"2020-12-22T10:15:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/hws-huber-widemann-schule-ag-bewegung-und-gesundheit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/hws-huber-widemann-schule-ag-bewegung-und-gesundheit\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/hws-huber-widemann-schule-ag-bewegung-und-gesundheit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HWS Huber Widemann Schule AG Bewegung und Gesundheit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"HWS Huber Widemann Schule AG Bewegung und Gesundheit - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/de\/listings\/hws-huber-widemann-schule-ag-bewegung-und-gesundheit\/","og_locale":"de_DE","og_type":"article","og_title":"HWS Huber Widemann Schule AG Bewegung und Gesundheit","og_description":"Wir engagieren uns f\u00fcr Ihre Zukunft: Mit 1&#8217;000 Lernenden und Studierenden ist die HWS Huber Widemann Schule in der Nordwestschweiz die Nummer 1 f\u00fcr Aus- und Weiterbildungen in den Bereichen Bewegung und Gesundheit, Medizin und Naturheilkunde. Unsere Lehrpersonen kommen aus der Praxis und lehren f\u00fcr die Praxis. Die HWS ist bekannt als renommierte Privatschule und [&hellip;]","og_url":"https:\/\/schoolaboo.com\/de\/listings\/hws-huber-widemann-schule-ag-bewegung-und-gesundheit\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2020-12-22T10:15:20+00:00","og_image":[{"url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/Download-2-7.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/Download-2-7.png","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/de\/listings\/hws-huber-widemann-schule-ag-bewegung-und-gesundheit\/","url":"https:\/\/schoolaboo.com\/de\/listings\/hws-huber-widemann-schule-ag-bewegung-und-gesundheit\/","name":"HWS Huber Widemann Schule AG Bewegung und Gesundheit - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/de\/#website"},"datePublished":"2020-12-14T16:08:22+00:00","dateModified":"2020-12-22T10:15:20+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/de\/listings\/hws-huber-widemann-schule-ag-bewegung-und-gesundheit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/de\/listings\/hws-huber-widemann-schule-ag-bewegung-und-gesundheit\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/de\/listings\/hws-huber-widemann-schule-ag-bewegung-und-gesundheit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/de\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/de\/angebote\/"},{"@type":"ListItem","position":3,"name":"HWS Huber Widemann Schule AG Bewegung und Gesundheit"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/de\/#website","url":"https:\/\/schoolaboo.com\/de\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/de\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/schoolaboo.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-listings\/23441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/comments?post=23441"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/media?parent=23441"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job_listing_region?post=23441"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-categories?post=23441"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-types?post=23441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}