{"id":23192,"date":"2020-12-11T10:15:11","date_gmt":"2020-12-11T09:15:11","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=23192"},"modified":"2020-12-11T10:15:11","modified_gmt":"2020-12-11T09:15:11","slug":"montessori-kinderhaus-meggen","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-meggen\/","title":{"rendered":"Montessori Kinderhaus Meggen"},"content":{"rendered":"<header class=\"frame-header\">\n<h1 class=\"element-header \">Allgemeine Informationen<\/h1>\n<\/header>\n<h3>Schulort:<\/h3>\n<p>Huobmattstrasse 6, 6045 Meggen<\/p>\n<p>(Bus Nr. 24, Haltestelle Huob)<\/p>\n<h3>Unterrichtszeiten:<\/h3>\n<p>Montag-Freitag: 7:45 &#8211; 11:30 Uhr<\/p>\n<p>Im Sommer \u00a02016 wurde in unmittelbarer N\u00e4he eine neue Kindergartenst\u00e4tte (Kita Matz) er\u00f6ffnet. F\u00fcr Kinder welche eine Mittags\/Nachmittags Betreuung brauchen, gibt es das Angebot vom Kita Personal abgeholt zu werden.<\/p>\n<h3>Englisch:<\/h3>\n<p>Englisch wird mit allen Kindern spielerisch eingef\u00fchrt. Kinder, die kein Deutsch\/Schweizerdeutsch beherrschen werden vorerst nicht in der englischen Sprache gef\u00f6rdert, sondern werden zun\u00e4chst regelm\u00e4ssig und auf humorvolle Weise in Deutsch\/Schweizerdeutsch angesprochen.<\/p>\n<h3>Schulferien:<\/h3>\n<p>Der Ferienplan entspricht grunds\u00e4tzlich der Ferienordnung der \u00f6ffentlichen Schulen von Luzern. Die genauen Daten werden jeweils bei Schulbeginn bekanntgegeben. Wochenendbr\u00fccken sind m\u00f6glich.<\/p>\n<h3>Schulbesuch:<\/h3>\n<p>Es wird ein regelm\u00e4ssiger Schulbesuch erwartet. Selbstverst\u00e4ndlich haben famili\u00e4re Anliegen Vorrang.<\/p>\n<h3>Schulalter:<\/h3>\n<p>Das Mindestalter betr\u00e4gt 2 \u00bd Jahre. Das beste Eintrittsalter liegt zwischen 2 \u00bd und 4 \u00bd Jahren. Das Kind sollte mit Vorteil bis zum \u00dcbertritt in die Primarschule im Kinderhaus bleiben.<\/p>\n<h3>Schulleitung:<\/h3>\n<p>Das Kinderhaus wird von Joanna Morgowicz geleitet.<\/p>\n<p>&nbsp;<\/p>\n<h3>Besuchstermine:<\/h3>\n<p>Bevor Sie Ihr Kind definitiv anmelden, empfehlen wir Ihnen, mit uns einen Besuchstermin zu vereinbaren, damit Sie sich bei uns ohne Ihr Kind unverbindlich umsehen k\u00f6nnen. Aufgrund Ihrer Anmeldung und sofern es noch Pl\u00e4tze frei hat, werden Sie zu einem Besuch mit Ihrem Kind ins Kinderhaus eingeladen.<\/p>\n<h3>Eltern:<\/h3>\n<p>Drei bis viermal j\u00e4hrlich finden Elternabende bez. Veranstaltungen f\u00fcr Eltern und Beziehungspersonen statt. Einmal pro Jahr werden die Eltern jedes Kindes zu einem pers\u00f6nliche Gespr\u00e4ch mit den Lehrerinnen eingeladen.<\/p>\n<p>&nbsp;<\/p>\n<header class=\"frame-header\">\n<h1 class=\"element-header \">Montessori-P\u00e4dagogik<\/h1>\n<\/header>\n<div>\n<p>Die Montessori-P\u00e4dagogik, heute in vielen L\u00e4ndern bekannt, ist eng verbunden mit dem Lebensweg der Frau, die dieser P\u00e4dagogik den Namen gab.<\/p>\n<p>Maria Montessori (1879-1952) promovierte als erste italienische Frau 1896 zum Doktor der Medizin. 1904 wurde sie Dozentin f\u00fcr Anthropologie. Ber\u00fchmt wurde sie durch ihre T\u00e4tigkeit als Erzieherin.<\/p>\n<p>Dr. Montessori hatte eine geniale Begabung zu beobachten und die Beobachtungen zu deuten. Sie entwickelte Lernmethoden, die ganz auf die Bed\u00fcrfnisse der Kinder zugeschnitten und heute mehr denn je anerkannt und gesch\u00e4tzt werden.<\/p>\n<p>Die Methode basiert auf der Tatsache, dass Kinder am besten selbst\u00e4ndig lernen. Jedes Kind ist mit dem Trieb ausgestattet, alles zu untersuchen und mit dem Drang, seine Umwelt zu entdecken. Das Kind ist von Natur aus aktiv, lernt durch T\u00e4tigkeiten und entwickelt dadurch sich und seine Pers\u00f6nlichkeit.<\/p>\n<p>Nach neuesten Erkenntnissen sind die Jahre von drei bis sechs das aufnahmef\u00e4higste Alter eines Kindes. Die in dieser Zeit feststellbare Lernintensit\u00e4t kehrt in sp\u00e4teren Jahren selten zur\u00fcck. Montessori ist eine Erziehungsmethode, in der jedes Kind in seinem individuellen Wesen respektiert wird, sich bewusst von den Erwachsenen und den \u00fcbrigen Kindern unterscheidet und die Freuden der Freundschaft in einer spontanen Gesellschaft entdeckt.<\/p>\n<header class=\"frame-header\">\n<h1 class=\"element-header \">Unsere Ziele &#8211; Was bekommt das Kind<\/h1>\n<\/header>\n<div>\n<p>Das Kind braucht Ordnung in Raum und Zeit, um f\u00e4hig zu werden, darin seine innere Ordnung aufbauen zu k\u00f6nnen. Durch individuelle Hilfe soll das Kind bef\u00e4higt werden, sich durch eigene Kraft zu entwickeln, Einsichten zu erwerben und unabh\u00e4ngig zu werden. Das Lernen nimmt das Kind als ein gl\u00fcckliches und freudiges Erlebnis mit sich. Die Freiheit, sich alleine oder mit anderen zu besch\u00e4ftigen, bereitet ihm Freude und l\u00e4sst ihm eine positive Einstellung gegen\u00fcber den Mitmenschen (ausserhalb der eigenen Familie), der Gemeinschaft in der Schule und dar\u00fcber hinaus entwickeln.<\/p>\n<\/div>\n<div>\n<p>Durch das Anbieten einer Umgebung, die geeignet ist, die Bed\u00fcrfnisse des Kindes zu befriedigen, kommt das Kind zur Selbst\u00e4ndigkeit, Selbstdisziplin und einer grossen Entdeckungsfreude.<\/p>\n<\/div>\n<div><\/div>\n<div>\n<p>Zur erfolgreichen Montessori-Erziehung braucht es zweit wesentliche Komponenten, die sich gegenseitig erg\u00e4nzen: Die Unterst\u00fctzung durch die Eltern und dieser Arbeit voll zugetane Lehrpersonen.<\/p>\n<\/div>\n<div><\/div>\n<div>\n<p>Das Kind ist das eigentliche Zentrum der Klasse, nicht die Lehrperson, Ihre Aufgabe soll es sein, dem Kind Anreiz f\u00fcrs Leben zu geben, aber es in der Entwicklung frei zu lassen:<\/p>\n<\/div>\n<blockquote>\n<div>\n<p>Hilf mir, es selbst zu tun!<\/p>\n<\/div>\n<div>\n<p>M. Montessori<\/p>\n<\/div>\n<\/blockquote>\n<div>\n<p>Durch Elternabende, Arbeitsabende, Sitzungen, Kinderhausbesuche und Besprechungen nehmen Lehrerinnen und Eltern regelm\u00e4ssig Kontakt auf. Diese Begegnungen, zusammen mit dem Gespr\u00e4ch \u00fcber Erziehung und deren Methoden, vertiefen das Vertrauen und lassen ein gegenseitigen Verst\u00e4ndnis aufkommen, das voll der Entwicklung des Kindes zugute kommt.<\/p>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Huobmattstrasse 6, 6045 Meggen","_company_website":"https:\/\/www.montessori-meggen.ch\/de\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[162],"job-categories":[103,229],"job-types":[90,230],"class_list":{"0":"post-23192","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-luzern","6":"job_listing_category-kindergarten","7":"job_listing_category-vorkindergarten","8":"job_listing_type-kindergarten","9":"job_listing_type-vorkindergarten","11":"job-type-kindergarten-4-6-jahre","12":"job-type-vorkindergarten"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Montessori Kinderhaus Meggen - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-meggen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Montessori Kinderhaus Meggen\" \/>\n<meta property=\"og:description\" content=\"Allgemeine Informationen Schulort: Huobmattstrasse 6, 6045 Meggen (Bus Nr. 24, Haltestelle Huob) Unterrichtszeiten: Montag-Freitag: 7:45 &#8211; 11:30 Uhr Im Sommer \u00a02016 wurde in unmittelbarer N\u00e4he eine neue Kindergartenst\u00e4tte (Kita Matz) er\u00f6ffnet. F\u00fcr Kinder welche eine Mittags\/Nachmittags Betreuung brauchen, gibt es das Angebot vom Kita Personal abgeholt zu werden. Englisch: Englisch wird mit allen Kindern spielerisch [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-meggen\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/logo-montessori-meggen.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/logo-montessori-meggen.png\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/montessori-kinderhaus-meggen\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/montessori-kinderhaus-meggen\\\/\",\"name\":\"Montessori Kinderhaus Meggen - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#website\"},\"datePublished\":\"2020-12-11T09:15:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/montessori-kinderhaus-meggen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/montessori-kinderhaus-meggen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/montessori-kinderhaus-meggen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Montessori Kinderhaus Meggen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Montessori Kinderhaus Meggen - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-meggen\/","og_locale":"de_DE","og_type":"article","og_title":"Montessori Kinderhaus Meggen","og_description":"Allgemeine Informationen Schulort: Huobmattstrasse 6, 6045 Meggen (Bus Nr. 24, Haltestelle Huob) Unterrichtszeiten: Montag-Freitag: 7:45 &#8211; 11:30 Uhr Im Sommer \u00a02016 wurde in unmittelbarer N\u00e4he eine neue Kindergartenst\u00e4tte (Kita Matz) er\u00f6ffnet. F\u00fcr Kinder welche eine Mittags\/Nachmittags Betreuung brauchen, gibt es das Angebot vom Kita Personal abgeholt zu werden. Englisch: Englisch wird mit allen Kindern spielerisch [&hellip;]","og_url":"https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-meggen\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","og_image":[{"url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/logo-montessori-meggen.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2020\/11\/logo-montessori-meggen.png","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-meggen\/","url":"https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-meggen\/","name":"Montessori Kinderhaus Meggen - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/de\/#website"},"datePublished":"2020-12-11T09:15:11+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-meggen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-meggen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-meggen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/de\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/de\/angebote\/"},{"@type":"ListItem","position":3,"name":"Montessori Kinderhaus Meggen"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/de\/#website","url":"https:\/\/schoolaboo.com\/de\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/de\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/schoolaboo.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-listings\/23192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/comments?post=23192"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/media?parent=23192"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job_listing_region?post=23192"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-categories?post=23192"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-types?post=23192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}