{"id":22845,"date":"2020-11-06T09:26:46","date_gmt":"2020-11-06T08:26:46","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=22845"},"modified":"2020-11-06T09:26:46","modified_gmt":"2020-11-06T08:26:46","slug":"shw-schule-fuer-handel-und-wirtschaft","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/de\/listings\/shw-schule-fuer-handel-und-wirtschaft\/","title":{"rendered":"SHW Schule f\u00fcr Handel und Wirtschaft"},"content":{"rendered":"<div id=\"c1100\" class=\"csc-default\">\n<div class=\"csc-header csc-header-n1\">\n<h1 class=\"csc-firstHeader\">KV-AUSBILDUNG WINTERTHUR (KT. Z\u00dcRICH)<\/h1>\n<\/div>\n<\/div>\n<div id=\"c1299\" class=\"csc-default\">\n<p class=\"bodytext\">KV-Ausbildung Winterthur (Kanton Z\u00fcrich) \u2013 Die SWS bietet folgende schulische KV-Ausbildung an:<\/p>\n<ul class=\"maincontent-list\">\n<li>\u201eKaufmann \/ Kauffrau mit eidgen\u00f6ssischem F\u00e4higkeitszeugnis Profil B und E\u201c. In 3 Jahren erreichen Sie (inkl. 1 Jahr Praktikum) Ihren eidgen\u00f6ssischen Lehrabschluss.<\/li>\n<\/ul>\n<ul class=\"maincontent-list\">\n<li>Alternativ ist es auch m\u00f6glich, ein &#8222;1-j\u00e4hriges kaufm\u00e4nnisches 10. Schuljahr&#8220; zu absolvieren.<\/li>\n<\/ul>\n<\/div>\n<div id=\"c1099\" class=\"csc-default\">\n<div class=\"csc-header csc-header-n9\">\n<h2>Kaufmann\/-frau (KV) EFZ Profil B\/E<\/h2>\n<\/div>\n<div class=\"csc-textpic csc-textpic-left csc-textpic-below\">\n<div class=\"csc-textpic-text\">\n<p class=\"bodytext\">Jugendliche, die eine fundierte und umfassende kaufm\u00e4nnische Ausbildung durchlaufen wollen, absolvieren an unserer KV-Schule die KV-Ausbildung Kaufmann\/-frau (\u201eKV-Lehre\u201c) EFZ Profil B\/E<\/p>\n<\/div>\n<div class=\"csc-header csc-header-n10\">\n<h2>Kaufm\u00e4nnisches 10. Schuljahr<\/h2>\n<\/div>\n<div class=\"csc-textpic csc-textpic-left csc-textpic-below\">\n<div class=\"csc-textpic-text\">\n<p class=\"bodytext\">Das Br\u00fcckenangebot &#8222;Kaufm\u00e4nnisches 10. Schuljahr&#8220; ist konzipiert f\u00fcr Jugendliche, die sich nach der obligatorischen Schulzeit noch nicht endg\u00fcltig auf ihren weiteren Berufs- oder Bildungsweg haben festlegen k\u00f6nnen oder noch keine geeignete Lehrstelle gefunden haben.<\/p>\n<\/div>\n<div class=\"csc-header csc-header-n10\"><\/div>\n<div class=\"csc-textpic csc-textpic-left csc-textpic-below\">\n<div class=\"csc-textpic-text\">\n<div id=\"c1104\" class=\"csc-default\">\n<div class=\"csc-header csc-header-n1\">\n<h1 class=\"csc-firstHeader\">HANDELSSCHULE VSH WINTERTHUR (KT. Z\u00dcRICH)<\/h1>\n<\/div>\n<\/div>\n<div id=\"c1108\" class=\"csc-default\">\n<p class=\"bodytext\">Berufsbegleitende Handelsschule in Winterthur (Kanton Z\u00fcrich) an den SWS Schulen f\u00fcr Wirtschaft und Sprachen: Die Handelsschule der SWS erm\u00f6glicht Ihnen den erfolgreichen Einstieg ins B\u00fcro. In zwei aufeinander aufbauenden Lehrg\u00e4ngen erlangen Sie das schweizweit anerkannte Handelsdiplom VSH, das in den Kernkompetenzen dem KV-Lehrabschluss E-Profil entspricht:<\/p>\n<ul class=\"maincontent-list\">\n<li>In einem ersten Schritt besuchen Sie das B\u00fcrofachdiplom inkl. ECDL-Zertifikat.<\/li>\n<li>In einem zweiten Schritt erweitern Sie das dabei erlangte Basiswissen mit erweiterten kaufm\u00e4nnischen Kenntnissen und nehmen das Handelsdiplom VSH \u2013 Ihren Schl\u00fcssel f\u00fcr mehr Verantwortung im B\u00fcro \u2013 in Angriff.<\/li>\n<\/ul>\n<p class=\"bodytext\">Die Diplome des VSH (Verband Schweizerischer Handelsschulen) sind schweizweit anerkannt.<\/p>\n<\/div>\n<div id=\"c1241\" class=\"csc-default\">\n<div class=\"csc-textpic csc-textpic-left csc-textpic-below\">\n<div class=\"csc-textpic-text\">\n<h3><b><br \/>\nB\u00fcrofachdiplom inkl. ECDL-Zertifikat<br \/>\n<\/b><\/h3>\n<p class=\"bodytext\">Der Abschluss B\u00fcrofachdiplom inkl. ECDL-Zertifikat entspricht in den Kernkompetenzen (ohne Fremdsprachen) der KV-Ausbildung mit EFZ (eidg. F\u00e4higkeitszeugnis) B-Profil.<\/p>\n<\/div>\n<div class=\"csc-textpic-imagewrap csc-textpic-single-image\"><a title=\"buerofachdiplom\" href=\"http:\/\/www.sws-weiterbildung.ch\/de\/buerofachdiplom.html\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"http:\/\/www.sws-weiterbildung.ch\/uploads\/pics\/buerofachdiplom_winterthur_01.jpg\" alt=\"buerofachdiplom-winterthur\" width=\"360\" height=\"284\" border=\"0\" \/><\/a><\/div>\n<\/div>\n<div class=\"csc-textpic-clear\"><\/div>\n<\/div>\n<div id=\"c1240\" class=\"csc-default\">\n<div class=\"csc-textpic csc-textpic-left csc-textpic-below\">\n<div class=\"csc-textpic-text\">\n<h3><b><br \/>\nHandelsdiplom VSH, dipl. Kauffrau \/ Kaufmann VSH<\/b><\/h3>\n<p class=\"bodytext\">Der Abschluss Handelsdiplom VSH stimmt in den Kernkompetenzen (ohne Fremdsprachen) mit der KV-Ausbildung mit EFZ (eidg. F\u00e4higkeitszeugnis) E-Profil \u00fcberein. Nach erfolgreichem Abschluss der Ausbildung tragen die Absolventinnen und Absolventen neu den gesch\u00fctzten Titel \u00abDiplomiete(r) Kauffrau VSH \/ Kaufmann VSH\u00bb.<\/p>\n<\/div>\n<div class=\"csc-textpic-imagewrap csc-textpic-single-image\"><a title=\"handelsdiplom\" href=\"http:\/\/www.sws-weiterbildung.ch\/de\/handelsdiplom.html\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"http:\/\/www.sws-weiterbildung.ch\/uploads\/pics\/handelsschule2_01.jpg\" alt=\"handelsdiplom-winterthur\" width=\"800\" height=\"630\" border=\"0\" \/><\/a><\/div>\n<\/div>\n<div class=\"csc-textpic-clear\"><\/div>\n<\/div>\n<div id=\"c1736\" class=\"csc-default\">\n<div class=\"csc-header csc-header-n10\">\n<h2>Handelsschule Vollzeit<\/h2>\n<\/div>\n<p class=\"bodytext\">Neben der berufsbegleitenden Handelsschule bietet die SWS auch eine Handelsschule in einer Vollzeit-Variante an (\u201eHandelsschule Vollzeit\u201c). Diese ist in die KV-Ausbildung integriert<\/p>\n<\/div>\n<div id=\"header\" class=\"header-content\">\n<div id=\"logo-wrapper\" class=\"logo-wrapper\">\n<div id=\"logo\"><a href=\"http:\/\/www.sws-weiterbildung.ch\/\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.sws-weiterbildung.ch\/fileadmin\/bilder-design\/logo.jpg\" alt=\"sws\" width=\"254\" height=\"65\" \/><\/a><\/div>\n<div class=\"header-nav\">\n<div class=\"h-nav clearfix\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"inner-wrap\">\n<div id=\"content\">\n<div id=\"subnavigation\">\n<div id=\"kontakt\">\n<div id=\"c193\" class=\"csc-default\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div id=\"references\">\n<div id=\"c1313\" class=\"csc-default\">\n<p class=\"bodytext\">\n<\/div>\n<\/div>\n<\/div>\n<div id=\"maincontent\">\n<div id=\"c1102\" class=\"csc-default\">\n<div class=\"csc-header csc-header-n1\">\n<h1 class=\"csc-firstHeader\">KADERSCHULE WINTERTHUR (KT. Z\u00dcRICH)<\/h1>\n<\/div>\n<\/div>\n<div id=\"c1229\" class=\"csc-default\">\n<p class=\"bodytext\">Die SWS-Kaderschule in Winterthur bei Z\u00fcrich ist eine der f\u00fchrenden privaten Wirtschaftsschulen in den Regionen Z\u00fcrich und Ostschweiz. Sie setzt seit ihrer Gr\u00fcndung vor 40 Jahren konsequent auf praxisorientierte Wirtschaftsbildung und erh\u00f6ht die beruflichen Perspektiven der Absolventen merklich.<\/p>\n<\/div>\n<div id=\"c1325\" class=\"csc-default\">\n<div class=\"csc-header csc-header-n3\">\n<h2><\/h2>\n<\/div>\n<\/div>\n<div id=\"c1328\" class=\"csc-default\">\n<div class=\"csc-header csc-header-n4\"><\/div>\n<\/div>\n<div id=\"c1331\" class=\"csc-default\">\n<div class=\"csc-header csc-header-n7\">\n<h5><\/h5>\n<\/div>\n<p class=\"bodytext\">\n<\/div>\n<div id=\"c1230\" class=\"csc-default\">\n<div class=\"csc-header csc-header-n8\">\n<h5>Management<\/h5>\n<\/div>\n<div class=\"csc-textpic csc-textpic-left csc-textpic-below\">\n<div class=\"csc-textpic-text\">\n<p class=\"bodytext\"><b>Management Zertifikat SVF<\/b><\/p>\n<p class=\"bodytext\">Diese Ausbildung f\u00fchrt Sie in die Grundlagen des Managements ein. Ihre Kenntnisse werden mit betriebswirtschaftlichem und methodischem Know-how angereichert und Ihre Fachkompetenzen erweitert mit dem Ziel, Aufgaben im Management wahrzunehmen. Der Lehrgang ist nach den Richtlinien der SVF (Schweizerische Vereinigung f\u00fcr F\u00fchrungsausbildung) aufgebaut.<\/p>\n<\/div>\n<div class=\"csc-textpic-imagewrap csc-textpic-single-image\"><a title=\"Management Zertifikat SVF\" href=\"http:\/\/www.sws-weiterbildung.ch\/de\/management.html\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"http:\/\/www.sws-weiterbildung.ch\/uploads\/pics\/01_PICT_FOR_LINK.jpg\" alt=\"\" width=\"800\" height=\"630\" border=\"0\" \/><\/a><\/div>\n<\/div>\n<div class=\"csc-textpic-clear\"><\/div>\n<\/div>\n<div id=\"c1248\" class=\"csc-default\">\n<div class=\"csc-textpic csc-textpic-left csc-textpic-below\">\n<div class=\"csc-textpic-text\">\n<p class=\"bodytext\"><b>H\u00f6heres Wirtschaftsdiplom (HWD) VSK<\/b><\/p>\n<p class=\"bodytext\">Das H\u00f6here Wirtschaftsdiplom VSK (Verband Schweizer Kaderschulen) ist eine breitgef\u00e4cherte Kaderausbildung. Sie richtet sich an Interessierte mit kaufm\u00e4nnischer Grundausbildung.<\/p>\n<\/div>\n<div class=\"csc-textpic-imagewrap csc-textpic-single-image\"><a title=\"HWD VSK Dipl. Wirtschaftsfachmann\/-fachfrau\" href=\"http:\/\/www.sws-weiterbildung.ch\/de\/hoeheres-wirtschaftsdiplom.html\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"http:\/\/www.sws-weiterbildung.ch\/uploads\/pics\/02_PICT_FOR_LINK.jpg\" alt=\"\" width=\"800\" height=\"630\" border=\"0\" \/><\/a><\/div>\n<\/div>\n<div class=\"csc-textpic-clear\"><\/div>\n<\/div>\n<div id=\"c1321\" class=\"csc-default\">\n<div class=\"csc-textpic csc-textpic-left csc-textpic-below\">\n<div class=\"csc-textpic-text\">\n<p class=\"bodytext\"><b>Technische(r) Kaufmann\/-frau mit eidg. FA<\/b><\/p>\n<p class=\"bodytext\">Als Bindeglied von Technik und Betriebswirtschaft werden Sie zu einem gefragten Ansprechpartner. Technische Kaufleute finden in der Praxis beispielsweise Einsatz als Eink\u00e4ufer, im Kundendienst, als technische Berater, als Verkaufs- oder gar als Gesch\u00e4ftsleiter. Diese Ausbildung eignet sich f\u00fcr Interessierte mit technischer Grundausbildung.<\/p>\n<\/div>\n<div class=\"csc-textpic-imagewrap csc-textpic-single-image\"><a title=\"Leadership Zertifikat SVF\" href=\"http:\/\/www.sws-weiterbildung.ch\/de\/technischer-kaufmann.html\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"http:\/\/www.sws-weiterbildung.ch\/uploads\/pics\/03.jpg\" alt=\"\" width=\"800\" height=\"630\" border=\"0\" \/><\/a><\/div>\n<\/div>\n<div class=\"csc-textpic-clear\"><\/div>\n<\/div>\n<div id=\"c1322\" class=\"csc-default\">\n<div class=\"csc-textpic csc-textpic-left csc-textpic-below\">\n<div class=\"csc-textpic-text\">\n<p class=\"bodytext\"><b>Betriebswirtschafter\/in VSK<\/b><\/p>\n<p class=\"bodytext\">Diese Ausbildung bef\u00e4higt Sie, eine anspruchsvolle F\u00fchrungsposition wahrzunehmen oder kleine bis mittlere Unternehmen selbst\u00e4ndig zu f\u00fchren.<\/p>\n<\/div>\n<div class=\"csc-textpic-imagewrap csc-textpic-single-image\"><a title=\"Leadership Zertifikat SVF\" href=\"http:\/\/www.sws-weiterbildung.ch\/de\/betriebswirtschafter.html\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"http:\/\/www.sws-weiterbildung.ch\/uploads\/pics\/04.jpg\" alt=\"\" width=\"800\" height=\"630\" border=\"0\" \/><\/a><\/div>\n<\/div>\n<div class=\"csc-textpic-clear\"><\/div>\n<\/div>\n<div id=\"c1250\" class=\"csc-default\">\n<div class=\"csc-header csc-header-n13\">\n<h5>Personal und Leadership<\/h5>\n<\/div>\n<div class=\"csc-textpic csc-textpic-left csc-textpic-below\">\n<div class=\"csc-textpic-text\">\n<p class=\"bodytext\"><b>Leadership Zertifikat SVF<\/b><\/p>\n<p class=\"bodytext\">Der Lehrgang Leadership SVF (Schweizerische Vereinigung f\u00fcr F\u00fchrungsausbildung) schafft die Basis, in einem Team F\u00fchrungsaufgaben zu \u00fcbernehmen und effizient zu l\u00f6sen. Sie lernen, Ihre Erfahrungen und Einstellungen sowie Ihr eigenes Verhalten kritisch zu hinterfragen.<\/p>\n<\/div>\n<div class=\"csc-textpic-imagewrap csc-textpic-single-image\"><a title=\"Leadership Zertifikat SVF\" href=\"http:\/\/www.sws-weiterbildung.ch\/de\/leadership.html\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"http:\/\/www.sws-weiterbildung.ch\/uploads\/pics\/05_PICT_FOR_LINK_01.jpg\" alt=\"\" width=\"800\" height=\"630\" border=\"0\" \/><\/a><\/div>\n<\/div>\n<div class=\"csc-textpic-clear\"><\/div>\n<\/div>\n<div id=\"c1251\" class=\"csc-default\">\n<div class=\"csc-textpic csc-textpic-left csc-textpic-below\">\n<div class=\"csc-textpic-text\">\n<p class=\"bodytext\"><b>F\u00fchrungsfachmann\/-frau mit eidg. Fachausweis<\/b><\/p>\n<p class=\"bodytext\">F\u00fchrung wird heute als eine Kombination von Leadership (Aspekte der Mitarbeiterf\u00fchrung) und Management (Aspekte der Unternehmensf\u00fchrung) verstanden. Dieses Wissen wird Ihnen in drei modular aufgebauten Lehrg\u00e4ngen vermittelt.<\/p>\n<\/div>\n<div class=\"csc-textpic-imagewrap csc-textpic-single-image\"><a title=\"F\u00fchrungsfachmann\/-frau mit eidg. Fachausweis\" href=\"http:\/\/www.sws-weiterbildung.ch\/de\/fuehrungsfachmann.html\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"http:\/\/www.sws-weiterbildung.ch\/uploads\/pics\/06_PICT_FOR_LINK_01.jpg\" alt=\"\" width=\"800\" height=\"630\" border=\"0\" \/><\/a><\/div>\n<\/div>\n<div class=\"csc-textpic-clear\"><\/div>\n<\/div>\n<div id=\"c1252\" class=\"csc-default\">\n<div class=\"csc-textpic csc-textpic-left csc-textpic-below\">\n<div class=\"csc-textpic-text\">\n<p class=\"bodytext\"><b>Personalassistent\/Personalassistentin VSK HRSE<\/b><\/p>\n<p class=\"bodytext\">Diese Weiterbildung richtet sich an Interessierte, die den Einstieg ins Personalmanagement planen oder ihre in der Berufspraxis erworbenen Kenntnisse vertiefen m\u00f6chten. (HRSE = Human Resources Swiss Exams, VSK = Verband Schweizerischer Kaderschulen)<\/p>\n<\/div>\n<div class=\"csc-textpic-imagewrap csc-textpic-single-image\"><a title=\"Personalassistent\/Personalassistentin VSK HRSE\" href=\"http:\/\/www.sws-weiterbildung.ch\/de\/personalassistentin.html\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"http:\/\/www.sws-weiterbildung.ch\/uploads\/pics\/07_PICT_FOR_LINK_01.jpg\" alt=\"\" width=\"800\" height=\"630\" border=\"0\" \/><\/a><\/div>\n<\/div>\n<div class=\"csc-textpic-clear\"><\/div>\n<\/div>\n<div id=\"c1323\" class=\"csc-default\">\n<div class=\"csc-textpic csc-textpic-left csc-textpic-below\">\n<div class=\"csc-textpic-text\">\n<p class=\"bodytext\"><b>HR-Fachmann\/-frau mit eidg. Fachausweis<\/b><\/p>\n<p class=\"bodytext\">Die Ausbildung HR-Fachmann\/-frau mit eidg. Fachausweis erm\u00f6glicht es den Teilnehmenden, die Gesch\u00e4ftsleitung im Personalmanagement tatkr\u00e4ftig und gewinnbringend zu unterst\u00fctzen. Die entscheidenden Aufgaben des Personalmanagements k\u00f6nnen nach erfolgreichem Abschluss der Ausbildung selbst\u00e4ndig erf\u00fcllt werden.<\/p>\n<\/div>\n<div class=\"csc-textpic-imagewrap csc-textpic-single-image\"><a title=\"Arzt-\/Spitalsekret\u00e4r\/-in\" href=\"http:\/\/www.sws-weiterbildung.ch\/de\/hr-fachfrau.html\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"http:\/\/www.sws-weiterbildung.ch\/uploads\/pics\/08.jpg\" alt=\"\" width=\"800\" height=\"630\" border=\"0\" \/><\/a><\/div>\n<\/div>\n<div class=\"csc-textpic-clear\"><\/div>\n<\/div>\n<div id=\"c1234\" class=\"csc-default\">\n<div class=\"csc-header csc-header-n17\">\n<h5>Medizin und Gesundheit<\/h5>\n<\/div>\n<div class=\"csc-textpic csc-textpic-left csc-textpic-below\">\n<div class=\"csc-textpic-text\">\n<p class=\"bodytext\"><b>Arzt-\/Spitalsekret\u00e4r\/-in<\/b><\/p>\n<p class=\"bodytext\">M\u00f6chten Sie Ihr Wissen in medizinischen Belangen, Ihre kaufm\u00e4nnischen Kompetenzen, Ihr Geschick f\u00fcr organisatorische Anliegen und Ihre Freude am Kundenkontakt vereinen? Sind Sie auf der Suche nach einem Lehrgang, der es Ihnen erm\u00f6glicht, einen entsprechenden Job zu finden? In diesem Fall sollten Sie diese Ausbildung genauer unter die Lupe nehmen.\u00a0 Die Lernziele dieses Lehrgangs entsprechen den Richtlinien des Verbandes \u201eH+ Die Spit\u00e4ler der Schweiz\u201c.<\/p>\n<\/div>\n<div id=\"subnavigation\">\n<div id=\"kontakt\">\n<div id=\"c193\" class=\"csc-default\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div id=\"references\">\n<div id=\"c1339\" class=\"csc-default\">\n<div class=\"csc-textpic csc-textpic-center csc-textpic-above\">\n<div class=\"csc-textpic-imagewrap csc-textpic-single-image\"><\/div>\n<\/div>\n<div class=\"csc-textpic-clear\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"maincontent\">\n<div id=\"c1106\" class=\"csc-default\">\n<div class=\"csc-header csc-header-n1\">\n<h1 class=\"csc-firstHeader\">SPRACHEN LERNEN WINTERTHUR (KT. Z\u00dcRICH)<\/h1>\n<\/div>\n<\/div>\n<div id=\"c1105\" class=\"csc-default\">\n<p class=\"bodytext\">Sprachen sind der Schl\u00fcssel zur Welt und die Br\u00fccken zu fremden L\u00e4ndern und Kulturen im Privaten wie im Beruf. Welche Sprache Sie auch immer erlernen wollen, gleich, ob Sie auf:<\/p>\n<ul class=\"maincontent-list\">\n<li>einem Business-Meeting \u00fcberzeugend argumentieren m\u00fcssen,<\/li>\n<li>beim Boule in der Provence mit Leuten aus dem Dorf plaudern,<\/li>\n<li>Pesce auf einem Markt in Napoli kaufen,<\/li>\n<li>Paella nach einem Ritt durch Andalusien geniessen wollen,<\/li>\n<\/ul>\n<p class=\"bodytext\">unsere Schule er\u00f6ffnet Ihnen alle M\u00f6glichkeiten zur erfolgreichen Kommunikation im Bereich der Umgangs- und Fachsprachen.<\/p>\n<\/div>\n<\/div>\n<div class=\"csc-textpic-imagewrap csc-textpic-single-image\"><a title=\"Arzt-\/Spitalsekret\u00e4r\/-in\" href=\"http:\/\/www.sws-weiterbildung.ch\/de\/arztsekretaerin.html\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"http:\/\/www.sws-weiterbildung.ch\/uploads\/pics\/09_PICT_FOR_LINK.jpg\" alt=\"\" width=\"800\" height=\"630\" border=\"0\" \/><\/a><\/div>\n<\/div>\n<div class=\"csc-textpic-clear\"><\/div>\n<\/div>\n<div id=\"c1324\" class=\"csc-default\">\n<div class=\"csc-textpic csc-textpic-left csc-textpic-below\">\n<div class=\"csc-textpic-text\">\n<p class=\"bodytext\"><b>Chefarztsekret\u00e4r\/-in inkl. ECDL-Zertifikat<\/b><\/p>\n<p class=\"bodytext\">Sie unterst\u00fctzen die Chef\u00e4rztin \/ den Chefarzt in organisatorischen und administrativen Aufgaben. Sie erledigen oder delegieren die Korrespondenz und die Terminplanung, f\u00fchren Protokolle, erstellen Pr\u00e4sentationen, organisieren Anl\u00e4sse und erstellen Antr\u00e4ge. Dar\u00fcber hinaus \u00fcbernehmen Sie personelle Aufgaben, organisieren und planen Mitarbeitergespr\u00e4che und sind verantwortlich f\u00fcr das Zeitmanagement.<\/p>\n<\/div>\n<div class=\"csc-textpic-imagewrap csc-textpic-single-image\"><a title=\"Rechnungswesen Grundlagenkurs (Repetitorium)\" href=\"http:\/\/www.sws-weiterbildung.ch\/de\/chefarztsekretaerin.html\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"http:\/\/www.sws-weiterbildung.ch\/uploads\/pics\/chefarztsekretaerin.jpg\" alt=\"\" width=\"800\" height=\"630\" border=\"0\" \/><\/a><\/div>\n<\/div>\n<div class=\"csc-textpic-clear\"><\/div>\n<\/div>\n<div id=\"c1253\" class=\"csc-default\">\n<div class=\"csc-header csc-header-n19\">\n<h5>Finanzen<\/h5>\n<\/div>\n<div class=\"csc-textpic csc-textpic-left csc-textpic-below\">\n<div class=\"csc-textpic-text\">\n<p class=\"bodytext\"><b>Rechnungswesen Grundlagenkurs (Repetitorium)<\/b><\/p>\n<p class=\"bodytext\">Dieser kompakte Buchhaltungskurs vermittelt Ihnen die Grundlagen von Finanzbuchhaltung und Kostenrechnung.<\/p>\n<\/div>\n<div class=\"csc-textpic-imagewrap csc-textpic-single-image\"><a title=\"Rechnungswesen Grundlagenkurs (Repetitorium)\" href=\"http:\/\/www.sws-weiterbildung.ch\/de\/buchhaltungskurs.html\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"http:\/\/www.sws-weiterbildung.ch\/uploads\/pics\/11_PICT_FOR_LINK_01.jpg\" alt=\"\" width=\"800\" height=\"630\" border=\"0\" \/><\/a><\/div>\n<\/div>\n<div class=\"csc-textpic-clear\"><\/div>\n<\/div>\n<div id=\"c1236\" class=\"csc-default\">\n<div class=\"csc-textpic csc-textpic-left csc-textpic-below\">\n<div class=\"csc-textpic-text\">\n<p class=\"bodytext\"><b>Sachbearbeiter\/-in Rechnungswesen VSK<\/b><\/p>\n<p class=\"bodytext\">Es bereitet Ihnen Vergn\u00fcgen zu rechnen und zu buchen? Der Bildungsgang Sachbearbeiter\/-in Rechnungswesen VSK (Verband Schweizerischer Kaderschulen) vertieft Ihre Kompetenzen in Finanzbuchhaltung, Kostenrechnung, Sozialversicherungen, Steuerkunde und Rechtskunde. Dank der ausgepr\u00e4gten Praxisorientierung k\u00f6nnen erfolgreiche Absolventen\/-innen operative T\u00e4tigkeiten in der Finanz- und Betriebsbuchhaltung \u00fcbernehmen. Nach Ihrem Abschluss er\u00f6ffnen sich Ihnen attraktive berufliche Entwicklungsm\u00f6glichkeiten.<\/p>\n<\/div>\n<div class=\"csc-textpic-imagewrap csc-textpic-single-image\"><a title=\"Sachbearbeiter\/-in Rechnungswesen VSK\" href=\"http:\/\/www.sws-weiterbildung.ch\/de\/sachbearbeiter-rechnungswesen.html\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"http:\/\/www.sws-weiterbildung.ch\/uploads\/pics\/12_PICT_FOR_LINK.jpg\" alt=\"\" width=\"800\" height=\"630\" border=\"0\" \/><\/a><\/div>\n<\/div>\n<div class=\"csc-textpic-clear\"><\/div>\n<\/div>\n<div id=\"c1110\" class=\"csc-default\">\n<div class=\"csc-header csc-header-n21\">\n<h2>Erwachsenenbildung<\/h2>\n<\/div>\n<p class=\"bodytext\">Im Rahmen der Erwachsenenbildung k\u00f6nnen Sie sowohl an der SWS-Handelsschule als auch an der SWS-Kaderschule anerkannte berufsbegleitende Lehrg\u00e4nge und Seminare besuchen.<\/p>\n<\/div>\n<div id=\"subnavigation\">\n<div id=\"kontakt\">\n<div id=\"c193\" class=\"csc-default\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div id=\"references\">\n<div id=\"c1765\" class=\"csc-default\">\n<div class=\"csc-textpic-clear\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"maincontent\">\n<div id=\"c23\" class=\"csc-default\">\n<div class=\"csc-header csc-header-n1\">\n<h1 class=\"csc-firstHeader\">\u00dcBER UNS \/ SWS WEITERBILDUNG<\/h1>\n<\/div>\n<\/div>\n<div id=\"c1794\" class=\"csc-default\">\n<p class=\"bodytext\"><span lang=\"DE-CH\">Zugegeben, so ausgelassen wie an dieser Diplomfeier geht es an unserer Schule nicht immer zu und her. Wie \u00fcberall sind Disziplin, Hingabe und harte Arbeit gefordert, um Ziele \u00a0<\/span>zu erreichen. Aber Sie k\u00f6nnen sich darauf verlassen, dass wir Sie auf Ihrem mitunter beschwerlichen Weg auf Schritt und Tritt begleiten. Unsere ebenso kompetenten wie engagierten Mitarbeiter k\u00f6nnen dank ihrer Flexibilit\u00e4t auch auf ganz pers\u00f6nliche Anliegen eingehen und sorgen mit einem freundschaftlichen und wohlwollenden Umgang f\u00fcr ein produktives Lernklima.<\/p>\n<\/div>\n<div id=\"c1793\" class=\"csc-default\">\n<div class=\"csc-textpic csc-textpic-center csc-textpic-above csc-textpic-equalheight\">\n<div class=\"csc-textpic-imagewrap csc-textpic-single-image\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" src=\"http:\/\/www.sws-weiterbildung.ch\/typo3temp\/pics\/1f020955a8.jpg\" alt=\"\" width=\"556\" height=\"400\" border=\"0\" \/><\/div>\n<\/div>\n<div class=\"csc-textpic-clear\"><\/div>\n<\/div>\n<div id=\"c1792\" class=\"csc-default\">\n<p class=\"bodytext\"><span lang=\"DE-CH\">Kurzum: Wir tun alles daf\u00fcr, dass auch Sie bei einer der n\u00e4chsten Diplom\u00fcbergaben Grund zum Jubeln haben.<\/span><\/p>\n<p class=\"bodytext\"><b><span lang=\"DE-CH\">Neben der ausgepr\u00e4gten Kundenorientierung und der freundschaftlichen Atmosph\u00e4re zeichnet sich unsere Schule insbesondere durch die folgenden Punkte aus:<\/span><\/b><\/p>\n<\/div>\n<div id=\"c1342\" class=\"csc-default\">\n<p class=\"bodytext\"><b>Moderne Infrastruktur<\/b><br \/>\nUnsere Kurszimmer im modernen Neubau am Technopark verf\u00fcgen \u00fcber Visualizer, Beamer, Laptops und andere Hilfsmittel, die Computer-R\u00e4ume sind mit PCs der neusten Generation ausger\u00fcstet. Um Informatik- und Sprachkenntnisse zu erweitern, steht allen Lernenden durchgehend ein Workshop zur freien Ben\u00fctzung zur Verf\u00fcgung. Die Pausen verbringen unsere Studierenden vorzugsweise im mit K\u00fcche, f\u00fcnf Mikrowellen, Kaffee- und Snackautomaten ausgestatteten Selbstverpflegungsraum oder auf der \u00fcberaus grossz\u00fcgigen Dachterrasse mit Blick \u00fcber die Stadt.<\/p>\n<p class=\"bodytext\"><b>Konsequent praxisorientiert<\/b><br \/>\nUnserem Motto\u00a0<b>\u201eAus der Praxis \u2013 f\u00fcr die Praxis\u201c<\/b>\u00a0entsprechend haben viele unserer rund 100 Dozenten neben ihrer Lehrt\u00e4tigkeit Management- bzw. Expertenfunktionen in nationalen und internationalen Unternehmungen inne. Auch als Fachleute in Pr\u00fcfungsverb\u00e4nden sind ihre Erfahrung und ihr Know-how sehr gefragt<\/p>\n<p class=\"bodytext\"><b>Qualit\u00e4t &amp; Zertifizierungen<\/b><br \/>\nDie SWS wird jedes Jahr gem\u00e4ss neusten eduQua-Normen gepr\u00fcft und zertifiziert. Als Mitglied in zahlreichen weiteren Verb\u00e4nden (Verband KV Schweiz, VSH Verband Schweizerischer Handelsschulen, VSK Verband Schweizerischer Kaderschulen, Verband Schweizerischer Privatschulen u.a.) unterliegen die Abl\u00e4ufe der SWS einer j\u00e4hrlichen Qualit\u00e4tskontrolle.<\/p>\n<p class=\"bodytext\"><b>Wir vermitteln kaufm\u00e4nnische Stellen<\/b><br \/>\nDurch Kooperationen mit regionalen Unternehmen, Jobportalen und Personalvermittlungen helfen wir Ihnen bei der Jobsuche.<\/p>\n<p class=\"bodytext\"><b>Kursangebot, Lerninhalte und Lehrmethoden<\/b><br \/>\nUnser Kursangebot orientiert sich an den Bed\u00fcrfnissen von Wirtschaft und Gesellschaft. Wir passen unsere Lerninhalte und Lehrmethoden laufend den sich \u00e4ndernden Gegebenheiten an und arbeiten streng zukunftsorientiert. Der Unterricht ist lebendig und abwechslungsreich und nach den modernsten p\u00e4dagogischen Grunds\u00e4tzen gestaltet.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Neuwiesenstrasse 20 8400 Winterthur","_company_website":"http:\/\/www.sws-weiterbildung.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[153],"job-categories":[114,226,102,227],"job-types":[93,228],"class_list":{"0":"post-22845","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-zuerich","6":"job_listing_category-fachmittelschule","7":"job_listing_category-hoehere-fachschule","8":"job_listing_category-sekundarstufe_2","9":"job_listing_category-sprachschule","10":"job_listing_type-sekundarstufe_2","11":"job_listing_type-tertiaerausbildung","13":"job-type-sekundarstufe-2-16-19-jahre","14":"job-type-tertiaerausbildung"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SHW Schule f\u00fcr Handel und Wirtschaft - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/de\/listings\/shw-schule-fuer-handel-und-wirtschaft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SHW Schule f\u00fcr Handel und Wirtschaft\" \/>\n<meta property=\"og:description\" content=\"KV-AUSBILDUNG WINTERTHUR (KT. Z\u00dcRICH) KV-Ausbildung Winterthur (Kanton Z\u00fcrich) \u2013 Die SWS bietet folgende schulische KV-Ausbildung an: \u201eKaufmann \/ Kauffrau mit eidgen\u00f6ssischem F\u00e4higkeitszeugnis Profil B und E\u201c. In 3 Jahren erreichen Sie (inkl. 1 Jahr Praktikum) Ihren eidgen\u00f6ssischen Lehrabschluss. Alternativ ist es auch m\u00f6glich, ein &#8222;1-j\u00e4hriges kaufm\u00e4nnisches 10. Schuljahr&#8220; zu absolvieren. Kaufmann\/-frau (KV) EFZ Profil B\/E [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/de\/listings\/shw-schule-fuer-handel-und-wirtschaft\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/Download-2-2.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/Download-2-2.png\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/shw-schule-fuer-handel-und-wirtschaft\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/shw-schule-fuer-handel-und-wirtschaft\\\/\",\"name\":\"SHW Schule f\u00fcr Handel und Wirtschaft - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/shw-schule-fuer-handel-und-wirtschaft\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/shw-schule-fuer-handel-und-wirtschaft\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.sws-weiterbildung.ch\\\/uploads\\\/pics\\\/buerofachdiplom_winterthur_01.jpg\",\"datePublished\":\"2020-11-06T08:26:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/shw-schule-fuer-handel-und-wirtschaft\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/shw-schule-fuer-handel-und-wirtschaft\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/shw-schule-fuer-handel-und-wirtschaft\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.sws-weiterbildung.ch\\\/uploads\\\/pics\\\/buerofachdiplom_winterthur_01.jpg\",\"contentUrl\":\"http:\\\/\\\/www.sws-weiterbildung.ch\\\/uploads\\\/pics\\\/buerofachdiplom_winterthur_01.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/shw-schule-fuer-handel-und-wirtschaft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SHW Schule f\u00fcr Handel und Wirtschaft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SHW Schule f\u00fcr Handel und Wirtschaft - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/de\/listings\/shw-schule-fuer-handel-und-wirtschaft\/","og_locale":"de_DE","og_type":"article","og_title":"SHW Schule f\u00fcr Handel und Wirtschaft","og_description":"KV-AUSBILDUNG WINTERTHUR (KT. Z\u00dcRICH) KV-Ausbildung Winterthur (Kanton Z\u00fcrich) \u2013 Die SWS bietet folgende schulische KV-Ausbildung an: \u201eKaufmann \/ Kauffrau mit eidgen\u00f6ssischem F\u00e4higkeitszeugnis Profil B und E\u201c. In 3 Jahren erreichen Sie (inkl. 1 Jahr Praktikum) Ihren eidgen\u00f6ssischen Lehrabschluss. Alternativ ist es auch m\u00f6glich, ein &#8222;1-j\u00e4hriges kaufm\u00e4nnisches 10. Schuljahr&#8220; zu absolvieren. Kaufmann\/-frau (KV) EFZ Profil B\/E [&hellip;]","og_url":"https:\/\/schoolaboo.com\/de\/listings\/shw-schule-fuer-handel-und-wirtschaft\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/Download-2-2.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/Download-2-2.png","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/de\/listings\/shw-schule-fuer-handel-und-wirtschaft\/","url":"https:\/\/schoolaboo.com\/de\/listings\/shw-schule-fuer-handel-und-wirtschaft\/","name":"SHW Schule f\u00fcr Handel und Wirtschaft - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoolaboo.com\/de\/listings\/shw-schule-fuer-handel-und-wirtschaft\/#primaryimage"},"image":{"@id":"https:\/\/schoolaboo.com\/de\/listings\/shw-schule-fuer-handel-und-wirtschaft\/#primaryimage"},"thumbnailUrl":"http:\/\/www.sws-weiterbildung.ch\/uploads\/pics\/buerofachdiplom_winterthur_01.jpg","datePublished":"2020-11-06T08:26:46+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/de\/listings\/shw-schule-fuer-handel-und-wirtschaft\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/de\/listings\/shw-schule-fuer-handel-und-wirtschaft\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/schoolaboo.com\/de\/listings\/shw-schule-fuer-handel-und-wirtschaft\/#primaryimage","url":"http:\/\/www.sws-weiterbildung.ch\/uploads\/pics\/buerofachdiplom_winterthur_01.jpg","contentUrl":"http:\/\/www.sws-weiterbildung.ch\/uploads\/pics\/buerofachdiplom_winterthur_01.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/de\/listings\/shw-schule-fuer-handel-und-wirtschaft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/de\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/de\/angebote\/"},{"@type":"ListItem","position":3,"name":"SHW Schule f\u00fcr Handel und Wirtschaft"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/de\/#website","url":"https:\/\/schoolaboo.com\/de\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/de\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/schoolaboo.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-listings\/22845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/comments?post=22845"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/media?parent=22845"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job_listing_region?post=22845"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-categories?post=22845"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-types?post=22845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}