{"id":22642,"date":"2020-11-06T10:50:53","date_gmt":"2020-11-06T09:50:53","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=22642"},"modified":"2020-11-06T10:50:53","modified_gmt":"2020-11-06T09:50:53","slug":"montessori-kinderhaus-siebnen","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-siebnen\/","title":{"rendered":"Montessori Kinderhaus Siebnen"},"content":{"rendered":"<h1>\u00dcBER UNS<\/h1>\n<p>Die Assoziation Montessori Schweiz AM(S) setzt sich f\u00fcr die Unterst\u00fctzung und F\u00f6rderung der Montessori-P\u00e4dagogik in der Schweiz ein. Dar\u00fcber hinaus pflegt sie die in der Schweiz markenrechtlich gesch\u00fctzte Bezeichnung \u201eMontessori\u201c und erteilt Lizenzen zum Gebrauch der Marke.<\/p>\n<p>Die AM(S) ist Mitglied des Schweizer Dachverbandes\u00a0Association Montessori (Switzerland).<\/p>\n<p>Die AM(S) ist der\u00a0AMI (Association Montessori Internationale), der internationalen Dachorganisation mit Sitz in Amsterdam angeschlossen, welche 1929 von Maria Montessori gegr\u00fcndet wurde. Maria Montessori war bis zu ihrem Tod im Jahre 1952 Pr\u00e4sidentin der AMI.<\/p>\n<h1>GRUNDGEDANKEN DER MONTESSORI-P\u00c4DAGOGIK<\/h1>\n<p>Maria Montessori\u00a0hat mit ihrer P\u00e4dagogik, welche kindliche Eigenaktivit\u00e4t und selbstt\u00e4tiges Lernen ins Zentrum stellt, eine einflussreiche internationale Bewegung ins Leben gerufen. In den letzten 100 Jahren entstanden auf allen Kontinenten Schulen und Lerngemeinschaften f\u00fcr Kinder von 0-18 Jahren und Ausbildungsst\u00e4tten f\u00fcr Lehrkr\u00e4fte.<br \/>\n1896 promovierte Maria Montessori zum Doktor der Medizin und wird somit zur ersten \u00c4rztin Italiens. Das zus\u00e4tzliche Studium der Anthropologie, P\u00e4dagogik, Psychologie und Philosophie, vor allem aber ihre minuti\u00f6se Beobachtung der Kinder bilden die Grundlage ihres revolution\u00e4ren, universellen Erziehungskonzeptes. Die Montessori-P\u00e4dagogik erm\u00f6glicht dem Kind die volle Entfaltung seiner Pers\u00f6nlichkeit und ein seiner Entwicklung angepasstes Lernen.<\/p>\n<p>Wichtige Stichworte zur Montessori-P\u00e4dagogik:<\/p>\n<h2>UNABH\u00c4NGIGKEIT<\/h2>\n<p>\u2026 und deren aktive F\u00f6rderung durch Selbstt\u00e4tigkeit ist das Ziel aller Erziehungsbem\u00fchungen Montessoris. Sie fordert f\u00fcr das Kind Raum und Zeit um sich frei zu entwickeln, denn nur aus dem Gef\u00fchl der eigenen Unabh\u00e4ngigkeit geht menschliche W\u00fcrde und wahre Freiheit hervor.<\/p>\n<h2>DIE VORBEREITETE UMGEBUNG<\/h2>\n<p>\u2026erm\u00f6glicht dem Kind Bewegungsfreiheit, Selbst\u00e4ndigkeit und Unabh\u00e4ngigkeit. Sie ist klar strukturiert und voller Lernangebote, die das Kind zu sinnvollem Tun auffordern. Die Vorbereitete Umgebung ist ganz auf die Bed\u00fcrfnisse der Kinder zugeschnitten und unterscheidet sich im Angebot je nach Altersgruppe (0-3 Jahre, 3-6 Jahre, 6-12 Jahre, 12-18 Jahre).<\/p>\n<h2>DAS MONTESSORIMATERIAL<\/h2>\n<p>\u2026 ist integraler Bestandteil der Vorbereiteten Umgebung. Es umfasst die Bereiche \u00dcbungen des praktischen Lebens, Sinnesbildung, Mathematik, Sprache und Kosmische Erziehung. Es ist so konzipiert, dass die Kinder sich nach einer Einf\u00fchrung durch die Lehrperson selbstst\u00e4ndig Wissen und Fertigkeiten erarbeiten k\u00f6nnen.<br \/>\nDas Material bewirkt durch seine innere Ordnung und Isolierung der Schwierigkeiten ein Ordnen des Geistes und ein Erkennen von Zusammenh\u00e4ngen. Es erm\u00f6glicht dieses konzentrierte Sammeln, das Montessori die &#8222;Polarisation der Aufmerksamkeit&#8220; genannt hat.<\/p>\n<h2>DIE POLARISATION DER AUFMERKSAMKEIT<\/h2>\n<p>\u2026ist ein Zustand tiefer Konzentration, welcher durch das Montessori-Material provoziert wird. Geht ein Kind vollst\u00e4ndig in seinem Tun auf, hat dies positive Auswirkungen auf die gesamte Entwicklung seiner Pers\u00f6nlichkeit. Es wird zufrieden und ausgeglichen, f\u00fchlt sich wohl in der Gruppe und eignet sich mit Freude neues Wissen an.<\/p>\n<h2>DIE SENSIBLEN PHASEN<\/h2>\n<p>\u2026 sind Zeitr\u00e4ume besonderer Empf\u00e4nglichkeit und innerer Bereitschaft, einen bestimmten Lern- oder Entwicklungsschritt zu vollziehen. Dieses Ph\u00e4nomen, das die Neurobiologie heute &#8222;Fenster&#8220; nennt, hat Maria Montessori bereits zu Beginn des letzten Jahrhunderts entdeckt. Das Wissen um die sensiblen Phasen birgt eine grosse Chance: Das richtige Angebot zur rechten Zeit garantiert freudvolles, leichtes, rasches, tiefgreifendes Lernen.<\/p>\n<h2>DIE FREIARBEIT<\/h2>\n<p>\u2026ist die praktische p\u00e4dagogische Konsequenz aus Montessoris Grundgedanken. Die Kinder bestimmen selbst, was und wo sie arbeiten wollen, mit wem und wie lange sie arbeiten wollen. Sie \u00fcben dabei das richtige Einsch\u00e4tzen der eigenen F\u00e4higkeiten, Ausdauer und Selbstdisziplin, das Setzen eigener Ziele, Entscheidungskraft und Kooperationsf\u00e4higkeit. Sie \u00fcbernehmen Verantwortung f\u00fcr das eigene Lernen.<\/p>\n<h2>DER \u201eNEUE LEHRER\u201c<\/h2>\n<p>\u2026hat die Rolle eines Helfers, der dem Kind den Weg zur Selbstst\u00e4ndigkeit ebnet, gem\u00e4ss dem Leitsatz \u201eHilf mir, es selbst zu tun\u201c. Der Prozess des Lernens und der Erkenntnis geschieht im Kind, das Kind ist sein eigener Lehrer. Der Erwachsene muss lernen, das Kind zum Lernen hinzuf\u00fchren um sich dann zur\u00fcckzunehmen und letztlich als Beobachter den kindlichen Erkenntnisprozess zu begleiten.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Spielweg 14, 8854 Siebnen, Schweiz","_company_website":"https:\/\/www.montessori-ams.ch\/einrichtungen\/item\/montessori-kinderhaus-siebnen.html","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[166],"job-categories":[103],"job-types":[90],"class_list":{"0":"post-22642","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-schwyz","6":"job_listing_category-kindergarten","7":"job_listing_type-kindergarten","9":"job-type-kindergarten-4-6-jahre"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Montessori Kinderhaus Siebnen - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-siebnen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Montessori Kinderhaus Siebnen\" \/>\n<meta property=\"og:description\" content=\"\u00dcBER UNS Die Assoziation Montessori Schweiz AM(S) setzt sich f\u00fcr die Unterst\u00fctzung und F\u00f6rderung der Montessori-P\u00e4dagogik in der Schweiz ein. Dar\u00fcber hinaus pflegt sie die in der Schweiz markenrechtlich gesch\u00fctzte Bezeichnung \u201eMontessori\u201c und erteilt Lizenzen zum Gebrauch der Marke. Die AM(S) ist Mitglied des Schweizer Dachverbandes\u00a0Association Montessori (Switzerland). Die AM(S) ist der\u00a0AMI (Association Montessori Internationale), [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-siebnen\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/montessori-siebnen_3d28f3293b7e5db927e609a11f5a502c.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/montessori-siebnen_3d28f3293b7e5db927e609a11f5a502c.png\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/montessori-kinderhaus-siebnen\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/montessori-kinderhaus-siebnen\\\/\",\"name\":\"Montessori Kinderhaus Siebnen - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#website\"},\"datePublished\":\"2020-11-06T09:50:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/montessori-kinderhaus-siebnen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/montessori-kinderhaus-siebnen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/montessori-kinderhaus-siebnen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Montessori Kinderhaus Siebnen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Montessori Kinderhaus Siebnen - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-siebnen\/","og_locale":"de_DE","og_type":"article","og_title":"Montessori Kinderhaus Siebnen","og_description":"\u00dcBER UNS Die Assoziation Montessori Schweiz AM(S) setzt sich f\u00fcr die Unterst\u00fctzung und F\u00f6rderung der Montessori-P\u00e4dagogik in der Schweiz ein. Dar\u00fcber hinaus pflegt sie die in der Schweiz markenrechtlich gesch\u00fctzte Bezeichnung \u201eMontessori\u201c und erteilt Lizenzen zum Gebrauch der Marke. Die AM(S) ist Mitglied des Schweizer Dachverbandes\u00a0Association Montessori (Switzerland). Die AM(S) ist der\u00a0AMI (Association Montessori Internationale), [&hellip;]","og_url":"https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-siebnen\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/montessori-siebnen_3d28f3293b7e5db927e609a11f5a502c.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/11\/montessori-siebnen_3d28f3293b7e5db927e609a11f5a502c.png","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-siebnen\/","url":"https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-siebnen\/","name":"Montessori Kinderhaus Siebnen - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/de\/#website"},"datePublished":"2020-11-06T09:50:53+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-siebnen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-siebnen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/de\/listings\/montessori-kinderhaus-siebnen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/de\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/de\/angebote\/"},{"@type":"ListItem","position":3,"name":"Montessori Kinderhaus Siebnen"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/de\/#website","url":"https:\/\/schoolaboo.com\/de\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/de\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/schoolaboo.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-listings\/22642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/comments?post=22642"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/media?parent=22642"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job_listing_region?post=22642"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-categories?post=22642"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-types?post=22642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}