{"id":20899,"date":"2020-11-02T18:07:37","date_gmt":"2020-11-02T17:07:37","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=20899"},"modified":"2020-11-02T18:07:37","modified_gmt":"2020-11-02T17:07:37","slug":"teko-schweizerische-fachschule","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/de\/listings\/teko-schweizerische-fachschule\/","title":{"rendered":"TEKO Schweizerische Fachschule"},"content":{"rendered":"<div class=\"topic-column\">\n<div class=\"topic-headline\">\n<div class=\"accordion-title\">\n<h2>Beschreibung<\/h2>\n<\/div>\n<div class=\"accordion-content-wrapper\">\n<div class=\"accordion-content\">\n<div class=\"b-inbound-wysiwyg inbound-wysiwyg\">\n<p>Die Gaming Industrie w\u00e4chst weltweit enorm. Gr\u00fcnde daf\u00fcr sind unter anderem die hohen Bandbreiten und die neuen mobilen Endger\u00e4te, welche anspruchsvolles Gaming \u00fcberall erm\u00f6glichen. Aber auch Erweiterte Realit\u00e4t (AR) und Virtuelle Realit\u00e4t (VR) werden in Zukunft wichtige Themen sein, nicht nur f\u00fcr die Gaming Industrie aber auch f\u00fcr Betriebe in der Elektronik und im Maschinenbau.<\/p>\n<p>Das Nachdiplomstudium NDS HF Game Design &amp; Simulation richtet sich an ausgebildete Berufsleute aus der Technik oder Wirtschaftsinformatik, die weiterkommen wollen und bereitseinender folgenden Abschl\u00fcsse erlangt haben:<\/p>\n<ul>\n<li>eidg. Fachausweis Informatik<\/li>\n<li>eidg. Fachausweis Medien oder Kommunikation<\/li>\n<li>eidg. Fachausweis Wirtschaftsinformatik<\/li>\n<li>H\u00f6here Fachschule HF<\/li>\n<li>Fachhochschule FH<\/li>\n<\/ul>\n<p>Die Zulassung zu diesem Studiengang ist an gewisse Voraussetzung gekn\u00fcpft. Die Eignung wird in einem Zulassungsgespr\u00e4ch durch die Schulleitung \u00fcberpr\u00fcft.<\/p>\n<h3>Motivation<\/h3>\n<p>Du willst\u00a0neue Kompetenzen in den Zukunftsgebieten 3D-Design, Game Design, Virtuelle Realit\u00e4t, K\u00fcnstliche Intelligenz, Planspiele und Simulation erwerben:<\/p>\n<ul>\n<li>Eigene Spiele entwickeln oder in einer Firma in der Gaming Industrie arbeiten<\/li>\n<li>Simulationen oder Virtuelle Realit\u00e4ten f\u00fcr Betriebe in der Elektronik oder im Maschinenbau entwickeln<\/li>\n<li>Planspiele f\u00fcr die Strategie-Entwicklung mitentwickeln.<\/li>\n<li>Moderne Benutzeroberfl\u00e4chen f\u00fcr neue Systeme gestalten<\/li>\n<\/ul>\n<h3>Fit f\u00fcr neue Herausforderungen<\/h3>\n<p>Das Nachdiplomstudium NDS HF Game Design &amp; Simulation qualifiziert Dich f\u00fcr T\u00e4tigkeiten wie:<\/p>\n<ul>\n<li>Spiele f\u00fcr mobile Endger\u00e4te entwickeln,Logik f\u00fcr Spiele konzipieren, implementieren und einf\u00fchren<\/li>\n<li>Reale und virtuelle Umgebungen und Maschinen mit 3D-Design abbilden<\/li>\n<li>Dynamische und animierte Benutzeroberfl\u00e4chen gestalten<\/li>\n<li>Simulationen f\u00fcr die Industrie entwickeln<\/li>\n<li>Planspiele f\u00fcr Wirtschaftssimulationen konzipieren<\/li>\n<li>Aktoren in Spielen und Simulationen mit k\u00fcnstlicher Intelligenz versehen<\/li>\n<\/ul>\n<h3>Ausbildungsziele<\/h3>\n<ul>\n<li>Du erwirbst\u00a0umfassende Kenntnisse in den Bereichen\u00a0Game-Design,\u00a03D-Design, Programmierung \u00a0und Game Physik, \u00a0Sound Design, UI\/UX Design, K\u00fcnstliche Intelligenz, Virtuelle Realit\u00e4t, Simulationen und Planspiele.<\/li>\n<li>In praxisorientierten Projekt- und Semesterarbeiten wendest Du\u00a0das erworbene Wissen an.<\/li>\n<li>Im eigenen Berufsumfeld kannst Du\u00a0laufend die w\u00e4hrend des Studiums erworbenen Kompetenzen einsetzen.<\/li>\n<\/ul>\n<p>Zusammen mit den im unterrichteten Fachgebiet berufst\u00e4tigen Dozierenden gew\u00e4hrleisten wir, dass die Lerninhalte immer auf die aktuellsten Anforderungen der Berufswelt ausgerichtet sind.<\/p>\n<h3>Dauer und Aufbau<\/h3>\n<p>Der Lehrgang dauert 3\u00a0Semester zu jeweils maximal 20 Wochen.\u00a0Das Nachdiplomstudium NDS HF Game Design &amp; Simulation ist modular aufgebaut und besteht aus drei unabh\u00e4ngigen Nachdiplomkursen (NDK). Jedes NDK dauert ein Semester und wird mit einem pers\u00f6nlichen Portfolio abgeschlossen.<\/p>\n<ul>\n<li>NDK 1: Game Engine &amp; 3D-Design<\/li>\n<li>NDK 2: Game Design, Sound Design, UI\/UX Design, Game Programmierung<\/li>\n<li>NDK 3:\u00a0Gamification, K\u00fcnstliche Intelligenz, Simulation und Planspiele<\/li>\n<\/ul>\n<p>Ein NDK wird mit einem schweizerischen TEKO-Zertifikat abgeschlossen.<\/p>\n<p>Wenn alle NDK erfolgreich absolviert worden sind, kann das Nachdiplomstudium NDS HF Game Design &amp; Simulation mit der Diplomarbeit abgeschlossen werden.<\/p>\n<h3>Varianten<\/h3>\n<p>Damit Du Beruf und Weiterbildung optimal aufeinander abstimmen kannst, w\u00e4hlst Du\u00a0flexibel zwischen Abend- und Tagesschule.<\/p>\n<h4 class=\"label-evening\">Abendschule<\/h4>\n<p class=\"label-evening\">berufsbegleitend mit Unterricht an zwei Abenden<\/p>\n<h4 class=\"label-day\">Tagesschule<\/h4>\n<p class=\"label-day\">berufsbegleitend mit Unterricht an einem ganzen Wochentag<\/p>\n<p>Unterrichtszeiten:<\/p>\n<ul>\n<li>Morgen: 08.00 &#8211; 11.30 Uhr<\/li>\n<li>Nachmittag: 12.30 &#8211; 16.00 bzw. 18.00 Uhr<\/li>\n<li>Abend: 18.30 &#8211; 21.45\u00a0Uhr<\/li>\n<\/ul>\n<p>Welche Varianten wir an den einzelnen Standorten anbieten, siehst Du unter Daten und Kosten.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<h2><\/h2>\n<h2>H\u00f6here Fachschule<\/h2>\n<\/div>\n<div class=\"topic-slides\">\n<div class=\"swiper-container topic-swiper\">\n<div class=\"swiper-wrapper\">\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Maschinenbau<\/h3>\n<p>Entwerfe und konstruiere komplexe Maschinen und Anlagen: von Werkstoffen \u00fcber Maschinenelemente, Baugruppen bis zu Antrieben, Steuerung und Robotik.<\/p>\n<div class=\"controls\">\n<p>6 Semester<\/p>\n<div class=\"icon day\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Elektrotechnik<\/h3>\n<p>Elektrotechnik, Elektronik, Digital- und Mikrocomputertechnik sowie Robotik sind zentrale Elemente der Digitalisierung. Gestalte die Entwicklung mit.<\/p>\n<div class=\"controls\">\n<p>6 Semester<\/p>\n<div class=\"icon day\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Telekommunikation<\/h3>\n<p>Kommunikationsnetze bilden das R\u00fcckgrat der Informationstechnologie. Plane, baue und betreibe diese erfolgreich mit aktuellster Hard- und Software.<\/p>\n<div class=\"controls\">\n<p>6 Semester<\/p>\n<div class=\"icon day\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Informatik Applikationsentwicklung<\/h3>\n<p>Das Programmieren ist Deine Welt. Du willst L\u00f6sungen entwickeln und programmieren, welche in den verschiedensten Bereichen eingesetzt werden k\u00f6nnen.<\/p>\n<div class=\"controls\">\n<p>6 Semester<\/p>\n<div class=\"icon day\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Informatik Systemtechnik<\/h3>\n<p>Alle IT-L\u00f6sungen setzen eine gut funktionierende Infrastruktur voraus. Du willst die daf\u00fcr notwendige Hard- und Software optimal bereitstellen k\u00f6nnen.<\/p>\n<div class=\"controls\">\n<p>6 Semester<\/p>\n<div class=\"icon day\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Bauplanung Architektur<\/h3>\n<p>Von der Idee \u00fcber den Entwurf zum fertigen Geb\u00e4ude: Du strebst ein T\u00e4tigkeit im Hochbau an und willst alle Bereiche des modernen Bauens kennenlernen.<\/p>\n<div class=\"controls\">\n<p>6 Semester<\/p>\n<div class=\"icon day\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Bauplanung Ingenieurbau<\/h3>\n<p>Alles was auf oder in den Boden gebaut wird interessiert Dich: Strassenbau, Spezialtiefbau, Br\u00fcckenbau, Wasserbau, Wasserversorgung und Tunnelbau.<\/p>\n<div class=\"controls\">\n<p>6 Semester<\/p>\n<div class=\"icon day\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Unternehmensprozesse<\/h3>\n<p>Optimale Prozesse in Logistik und Produktion, Kalkulation, Produktionsplanung und -steuerung, Innovation: als Produktionsleiter hast Du das im Griff.<\/p>\n<div class=\"controls\">\n<p>6 Semester<\/p>\n<div class=\"icon day\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Flugzeugtechnik<\/h3>\n<p>Mit dieser Spezialisierung im Rahmen des Maschinenbau-Studiums willst Du die Kernkompetenzen f\u00fcr eine T\u00e4tigeit im Aviatik-Umfeld erwerben.<\/p>\n<div class=\"controls\">\n<p>6 Semester<\/p>\n<div class=\"icon day\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Energie und Umwelt<\/h3>\n<p>Du begleitest Energie- und Umweltprojekte, ber\u00e4tst verschiedene Anspruchsgruppen und analysierst Effizienz, Wirtschaftlichkeit und Vertr\u00e4glichkeit.<\/p>\n<div class=\"controls\">\n<p>6 Semester<\/p>\n<div class=\"icon day\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div class=\"topic-headline\">\n<h2>Nachdiplomstudien NDS<\/h2>\n<\/div>\n<div class=\"topic-slides\">\n<div class=\"swiper-container topic-swiper\">\n<div class=\"swiper-wrapper\">\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Energie und Umwelt<\/h3>\n<p>Du hast eine h\u00f6here technische Ausbildung und willst diese gezielt f\u00fcr eine leitende und beratende Funktion in Energie- und Umweltbereichen erweitern.<\/p>\n<div class=\"controls\">\n<p>4 Semester<\/p>\n<div class=\"icon day\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Applikationsentwicklung<\/h3>\n<p>Basierend auf Deiner h\u00f6heren Ausbildung willst Du Dich in Softwareengineering, IT-Projektmanagement, Datenbanken und Webapplikationen vertiefen.<\/p>\n<div class=\"controls\">\n<p>3 Semester<\/p>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Cyber Security &amp; Privacy<\/h3>\n<p>Datenschutz, Datensicherheit, DevSecOps und IT-Projektmanagement interessieren Dich sehr. Du willst Deine h\u00f6here Ausbildung gezielt erweitern.<\/p>\n<div class=\"controls\">\n<p>3 Semester<\/p>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>IT-Systemtechnik<\/h3>\n<p>Deine h\u00f6here Ausbildung willst Du mit Netzwerktechnik, Netrwerkbetriebssystemen, \u00dcbertragungstechnik und IT-Projektmanagement gezielt erweitern.<\/p>\n<div class=\"controls\">\n<p>3 Semester<\/p>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Game Design und Simulation<\/h3>\n<p>Gamification ist f\u00fcr Dich kein Fremdwort. Eine h\u00f6here Ausbildung bringst Du mit und tauchst ein in die Bereiche Game-Design, 3D, KI und Simulation.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"topic-column\">\n<div class=\"topic-headline\">3 Semester<\/div>\n<\/div>\n<div>\n<p>&nbsp;<\/p>\n<div class=\"content-screen active-screen\">\n<section class=\"page-overview\">\n<div class=\"content\">\n<div class=\"wrapper\">\n<div class=\"topics-wrapper\">\n<div class=\"topic-column\">\n<div class=\"topic-headline\">\n<h2>B\u00fcromanagement und Handelsschule<\/h2>\n<\/div>\n<div class=\"topic-slides\">\n<div class=\"swiper-container topic-swiper\">\n<div class=\"swiper-wrapper\">\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Kauffrau, Kaufmann VSH<\/h3>\n<p>\u00dcbernehme eine zentrale, verantwortungsvolle Rolle in Administration und Sachbearbeitung: vom Kundenkontakt \u00fcber die Organisation bis zur Buchhaltung.<\/p>\n<div class=\"controls\">\n<p>2 Semester<\/p>\n<div class=\"icon day\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon hybrid\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Wirtschaftsfachleute VSK<\/h3>\n<p>Du m\u00f6chtest ein Team in der Administration oder Sachbearbeitung f\u00fchren? Du erwirbst Fach-, Methoden- und Sozialkompetenzen, damit Dir das gut gelingt.<\/p>\n<div class=\"controls\">\n<p>2 Semester<\/p>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"logos\">\n<div class=\"content-screen active-screen\">\n<section class=\"page-overview\">\n<div class=\"content\">\n<div class=\"wrapper\">\n<div class=\"topics-wrapper\">\n<div class=\"topic-column\">\n<div class=\"topic-headline\">\n<h2>H\u00f6here Fachschule<\/h2>\n<\/div>\n<div class=\"topic-slides\">\n<div class=\"swiper-container topic-swiper\">\n<div class=\"swiper-wrapper\">\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Wirtschaftsinformatik<\/h3>\n<p>\u00dcbernimm eine f\u00fchrende Rolle an der Schnittstelle von Betriebswirtschaft und Informatik. Werde Teil der Digitalisierung und gestalte diese mit.<\/p>\n<div class=\"controls\">\n<p>6 Semester<\/p>\n<div class=\"icon day\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon hybrid\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Betriebswirtschafter\/in<\/h3>\n<p>Baue auf Deine kaufm\u00e4nnische Grundausbildung gezielt betriebswirtschaftliche Kompetenzen f\u00fcr eine F\u00fchrungsposition im Dienstleistungsumfeld auf.<\/p>\n<div class=\"controls\">\n<p>6 Semester<\/p>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon day\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Betriebswirtschafter\/in f\u00fcr Technische Kaufleute<\/h3>\n<p>Du hast bereits den TK im Sack? Dann kannst Du den Abschluss zum\/zur Betriebswirtschafter\/in HF in k\u00fcrzerer Zeit erlangen.<\/p>\n<div class=\"controls\">\n<p>3 Semester<\/p>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon day\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"topic-column\">\n<div class=\"topic-headline\">\n<h2>Managementausbildungen<\/h2>\n<\/div>\n<div class=\"topic-slides\">\n<div class=\"swiper-container topic-swiper\">\n<div class=\"swiper-wrapper\">\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Technische Kaufleute berufsbegleitend<\/h3>\n<p>Werde zum Projekt- oder Abteilungsleiter in einem technischen Berufsumfeld. F\u00fchre Mitarbeitende erfolgreich nach betriebswirtschaftlichen Grunds\u00e4tzen.<\/p>\n<div class=\"controls\">\n<p>4 Semester<\/p>\n<div class=\"icon day\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon exam\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Technische Kaufleute Intensivlehrgang<\/h3>\n<p>Werde zum Projekt- oder Abteilungsleiter in einem technischen Berufsumfeld. F\u00fchre Mitarbeitende erfolgreich nach betriebswirtschaftlichen Grunds\u00e4tzen.<\/p>\n<div class=\"controls\">\n<p>2 Semester<\/p>\n<div class=\"icon intensive\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon exam\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>F\u00fchrungsfachperson<\/h3>\n<p>Verfeinere Deine F\u00fchrungskompetenzen, um auch herausfordernde Situationen erfolgreich und zielorientiert mit Deinen Mitarbeitenden zu meistern.<\/p>\n<div class=\"controls\">\n<p>3 Semester<\/p>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon day\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon exam\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"topic-column\">\n<div class=\"topic-headline\">\n<h2>Nachdiplomstudien NDS HF<\/h2>\n<\/div>\n<div class=\"topic-slides\">\n<div class=\"swiper-container topic-swiper\">\n<div class=\"swiper-wrapper\">\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Betriebswirtschaft<\/h3>\n<p>Du hast eine h\u00f6here technische Ausbildung und m\u00f6chtest erfolgreich als Projekt- oder Teamleiter in Deiner Branche weiterkommen.<\/p>\n<div class=\"controls\">\n<p>3 Semester<\/p>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon seminar\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"swiper-slide\">\n<div class=\"slide-content\">\n<h3>Strategische Unternehmensf\u00fchrung<\/h3>\n<p>Mit Deiner technischen und betriebswirtschaftlichen Ausbildung strebst Du eine strategische Funktion in der Abteilungs- oder Gesch\u00e4ftsleitung an.<\/p>\n<div class=\"controls\">\n<p>3 Semester<\/p>\n<div class=\"icon evening\">\n<div class=\"icon-tooltip-wrapper\">\n<div class=\"icon-tooltip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"icon-tooltip\">\n<div class=\"default-intro\">\n<h1>Die Schule<\/h1>\n<p>Zurzeit besuchen \u00fcber 1700 Studentinnen und Studenten einen Lehrgang an der TEKO. \u00dcber 450 Dozentinnen und Dozenten &#8211; die meisten sind im unterrichteten Fachgebiet berufst\u00e4tig &#8211; sichern Dir einen praxisnahen und interessanten Unterricht.<\/p>\n<\/div>\n<div class=\"b-text\">\n<h2>Wer sind wir?<\/h2>\n<p>Die TEKO entstand 1969 als neutrale, unabh\u00e4ngige Fachschule. Die beiden Gr\u00fcnder Josef Bachmann und J\u00f6rg Himmelrich entwickelten bald darauf zus\u00e4tzliche Lehrg\u00e4nge und positionierten die TEKO erfolgreich als eine der ersten H\u00f6heren Fachschulen der Schweiz in der Bildungslandschaft.<\/p>\n<p>Was kannst Du\u00a0bei uns lernen?<\/p>\n<p>In den drei Bereichen Technik, Wirtschaft und Handel steht Dir vom Workshop \u00fcber kaufm\u00e4nnische und betriebswirtschaftliche Lehr\u00adg\u00e4nge bis zu Studien an der H\u00f6heren Fachschule HF und Nachdiplomstudien NDS HF ein breites Aus- und Weiterbildungsangebot offen. Dieses richtet sich in an Berufst\u00e4tige verschiedener Branchen, welche neben ihrer beruflichen T\u00e4tigkeit einen Lehrgang besuchen m\u00f6chten.<\/p>\n<h2>Wie lernst\u00a0Du\u00a0bei uns?<\/h2>\n<p>Das eigentliche Produkt der TEKO ist der Unterricht. Damit wir Dir einen optimalen Lernerfolg sichern k\u00f6nnen, orientieren wir uns an den folgenden Leits\u00e4tzen:<\/p>\n<ul class=\"default-list\">\n<li>Wir bieten Dir eine qualitativ hochstehende, praxisnahe und aktuelle Ausbildung. Der modularisierte Aufbau entspricht den Lernbed\u00fcrfnissen unserer Studierenden.<\/li>\n<li>Wir verbessern die Berufsaussichten unserer Absolventin\u00adnen und Absolventen nachhaltig, indem wir die Kursinhalte stets auf die Bed\u00fcrfnisse des Marktes abstimmen.<\/li>\n<li>Unsere Dozentinnen und Dozenten kommen aus der Praxis. Durch ihre berufliche T\u00e4tigkeit im unterrichteten Fachgebiet sichern wir den Praxisbezug und die Aktualit\u00e4t.<\/li>\n<li>Wir fordern und f\u00f6rdern unsere Kursteilnehmerinnen und Kursteilnehmer mit klar definierten, handlungsorientierten Lernzielen. Dadurch erh\u00f6hen wir ihre Kompetenzen im beruflichen Umfeld nachhaltig.<\/li>\n<li>Die Lehrg\u00e4nge sind intensiv und praxisorientiert. Sie verlangen pers\u00f6nlichen Einsatz, um das gesteckte Ziel zu erreichen.<\/li>\n<li>An Bew\u00e4hrtem halten wir fest, richtungsweisende Marktver\u00e4nderungen und -entwicklungen finden jedoch umgehend Eingang in die Lehrplangestaltung.<\/li>\n<li>Gruppen-, Projekt- und Semesterarbeiten sowie Hausaufgaben und Heimstudium f\u00f6rdern die Festigung der w\u00e4hrend des Unter\u00adrichts erworbenen Kenntnisse.<\/li>\n<li>In jedem Fachbereich durchgef\u00fchrte und benotete Zwi\u00adschen- und Diplompr\u00fcfungen dienen als Lern\u00aderfolgskontrolle sowie als pers\u00f6nlicher Leistungsausweis. Eine klare Promotionsordnung schafft Transparenz.<\/li>\n<li>Die Unterrichtsunterlagen bieten eine ausgewogene Mischung zwischen Theorie, praktischen Beispielen sowie \u00dcbungen. Zudem stellen die Lehrmittel auch im Beruf eine wertvolle Hilfe dar.<\/li>\n<li>Wir verpflichten uns gegen\u00fcber Dir, dass der von Dir besuchte Lehrgang zu Ende gef\u00fchrt wird. In der Regel am gleichen Standort.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Europa-Strasse 18, 8152 Opfikon, Schweiz","_company_website":"https:\/\/www.teko.ch\/","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[153],"job-categories":[226],"job-types":[228],"class_list":{"0":"post-20899","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-zuerich","6":"job_listing_category-hoehere-fachschule","7":"job_listing_type-tertiaerausbildung","9":"job-type-tertiaerausbildung"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>TEKO Schweizerische Fachschule - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/de\/listings\/teko-schweizerische-fachschule\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TEKO Schweizerische Fachschule\" \/>\n<meta property=\"og:description\" content=\"Beschreibung Die Gaming Industrie w\u00e4chst weltweit enorm. Gr\u00fcnde daf\u00fcr sind unter anderem die hohen Bandbreiten und die neuen mobilen Endger\u00e4te, welche anspruchsvolles Gaming \u00fcberall erm\u00f6glichen. Aber auch Erweiterte Realit\u00e4t (AR) und Virtuelle Realit\u00e4t (VR) werden in Zukunft wichtige Themen sein, nicht nur f\u00fcr die Gaming Industrie aber auch f\u00fcr Betriebe in der Elektronik und im [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/de\/listings\/teko-schweizerische-fachschule\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/TEKO-logo-share.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/TEKO-logo-share.png\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/teko-schweizerische-fachschule\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/teko-schweizerische-fachschule\\\/\",\"name\":\"TEKO Schweizerische Fachschule - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#website\"},\"datePublished\":\"2020-11-02T17:07:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/teko-schweizerische-fachschule\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/teko-schweizerische-fachschule\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/teko-schweizerische-fachschule\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TEKO Schweizerische Fachschule\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"TEKO Schweizerische Fachschule - Privatschul Verzeichnis und Beratung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/de\/listings\/teko-schweizerische-fachschule\/","og_locale":"de_DE","og_type":"article","og_title":"TEKO Schweizerische Fachschule","og_description":"Beschreibung Die Gaming Industrie w\u00e4chst weltweit enorm. Gr\u00fcnde daf\u00fcr sind unter anderem die hohen Bandbreiten und die neuen mobilen Endger\u00e4te, welche anspruchsvolles Gaming \u00fcberall erm\u00f6glichen. Aber auch Erweiterte Realit\u00e4t (AR) und Virtuelle Realit\u00e4t (VR) werden in Zukunft wichtige Themen sein, nicht nur f\u00fcr die Gaming Industrie aber auch f\u00fcr Betriebe in der Elektronik und im [&hellip;]","og_url":"https:\/\/schoolaboo.com\/de\/listings\/teko-schweizerische-fachschule\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/TEKO-logo-share.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/10\/TEKO-logo-share.png","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/de\/listings\/teko-schweizerische-fachschule\/","url":"https:\/\/schoolaboo.com\/de\/listings\/teko-schweizerische-fachschule\/","name":"TEKO Schweizerische Fachschule - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/de\/#website"},"datePublished":"2020-11-02T17:07:37+00:00","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/de\/listings\/teko-schweizerische-fachschule\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/de\/listings\/teko-schweizerische-fachschule\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/de\/listings\/teko-schweizerische-fachschule\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/de\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/de\/angebote\/"},{"@type":"ListItem","position":3,"name":"TEKO Schweizerische Fachschule"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/de\/#website","url":"https:\/\/schoolaboo.com\/de\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/de\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/schoolaboo.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-listings\/20899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/comments?post=20899"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/media?parent=20899"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job_listing_region?post=20899"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-categories?post=20899"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-types?post=20899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}