{"id":20195,"date":"2021-06-09T22:52:33","date_gmt":"2021-06-09T20:52:33","guid":{"rendered":"https:\/\/schoolaboo.ch\/?post_type=job_listing&#038;p=20195"},"modified":"2026-04-26T08:39:10","modified_gmt":"2026-04-26T06:39:10","slug":"kits-zweisprachige-tagesschule-und-kindertagesstaette","status":"publish","type":"job_listing","link":"https:\/\/schoolaboo.com\/de\/listings\/kits-zweisprachige-tagesschule-und-kindertagesstaette\/","title":{"rendered":"KiTs Zweisprachige Tagesschule und Kindertagesst\u00e4tte"},"content":{"rendered":"<article class=\"component col-xs-12\">\n<h1><span class=\"alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-29050 size-large\" src=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/06\/Logo-kits-auf-weiss-1500x176.png\" alt=\"\" width=\"1050\" height=\"123\" srcset=\"https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/06\/Logo-kits-auf-weiss-1500x176.png 1500w, https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/06\/Logo-kits-auf-weiss-500x59.png 500w, https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/06\/Logo-kits-auf-weiss-768x90.png 768w, https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/06\/Logo-kits-auf-weiss-1536x181.png 1536w, https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/06\/Logo-kits-auf-weiss-2048x241.png 2048w, https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/06\/Logo-kits-auf-weiss-450x53.png 450w\" sizes=\"auto, (max-width: 1050px) 100vw, 1050px\" \/><\/span><\/h1>\n<div class=\"text-columns\">\n<h3><strong>KiTs &#8211; Zweisprachige Tagesschule<\/strong><\/h3>\n<p><strong>KiTs &#8211; Zweisprachige Tagesschule <\/strong>mit individueller Begabungsf\u00f6rderung (gestartet im Sommer 2005) bietet aufgeweckten Kindern der Primar- und der Sekundarstufe eine Lernumgebung an, die auf ihre Bed\u00fcrfnisse zugeschnitten ist und auf ihren St\u00e4rken aufbaut. Wir sprechen durchschnittlich bis \u00fcberdurchschnittlich begabte sowie zweisprachige Kinder zwischen 2 und 16 Jahren an.<\/p>\n<p><strong>Tagesstruktur:<\/strong><br \/>\nDurch die Vernetzung von Unterricht und Freizeit wird die Schule lebensnah und ganzheitlich. Die gemeinsam verbrachte Freizeit \u00fcber Mittag und die betreuten Randzeiten bieten Raum f\u00fcr soziale Lernprozesse. Die Tagesstruktur soll auch berufst\u00e4tige Eltern entlasten. Nach Absprache k\u00f6nnen auch externe Kinder betreut werden.<\/p>\n<p><strong>Lehrplan:<\/strong><br \/>\nDie\u00a0KiTs &#8211; Zweisprachige Tagesschule\u00a0ist eine vom Erziehungsdepartement des Kantons St.Gallen bewilligte Privatschule. Der Unterricht umfasst den kantonalen Lehrplan. Der Wechsel in die \u00f6ffentliche Schule oder in weiterf\u00fchrende Schulen ist gew\u00e4hrleistet.<\/p>\n<p><strong>F\u00f6rderung:<\/strong><br \/>\nDie kleinen Klassen erm\u00f6glichen es, alle Kinder individuell innerhalb der Gruppe zu f\u00f6rdern. In zus\u00e4tzlichen w\u00f6chentlichen Begabungsf\u00f6rderungslektionen werden spannende Lerngebiete vertieft. Durch selbstst\u00e4ndiges Erforschen und Experimentieren unter Anleitung sowie durch den Austausch und das Festhalten ihrer Erkenntnisse lernen die Kinder ihre Begabungen kennen und entfalten. Der zus\u00e4tzliche F\u00f6rderunterricht wird auch als Pull-Out-Programm f\u00fcr externe Kinder angeboten.<\/p>\n<p><strong>Zweisprachigkeit:<\/strong><br \/>\nDank der t\u00e4glichen deutsch- und englischsprachigen Lernumgebung eignen sich die Kinder eine Zweitsprache gleichsam wie die Muttersprache an.<\/p>\n<p><strong>Unterricht:<\/strong><br \/>\nDer Unterricht ber\u00fccksichtigt die Begabungen, den Entwicklungsstand und das Lerntempo der Kinder. Die Neugier und die Freude am Lernen werden geweckt und das Selbstvertrauen durch die erlebten Erfolge gest\u00e4rkt.<\/p>\n<p><strong>Elternkontakt:<\/strong><br \/>\nF\u00fcr das Wohl der Kinder ist der Austausch zwischen Eltern und Lehrkr\u00e4ften besonders wichtig. Auf Wunsch k\u00f6nnen Eltern auch in Erziehungsfragen auf die fachkundige Unterst\u00fctzung unseres Beratungsteams zur\u00fcckgreifen.<\/p>\n<p><strong>Abkl\u00e4rungen:<\/strong><br \/>\nAuf Anfrage macht unser Beratungsteam Standortbestimmungen und Potenzialanalysen.<\/p>\n<p><strong>Therapien:<\/strong><br \/>\nAufgeweckte Kinder sind in der Lage, allf\u00e4llige Defizite so zu kompensieren, dass diese lang nicht auffallen. Solche Vermeidungsstrategien r\u00e4chen sich leider oft sp\u00e4ter, wenn die Kinder keine Ausweichm\u00f6glichkeiten mehr haben. Auf Wunsch k\u00f6nnen Betroffene mit unserem Beratungsteam arbeiten, damit eine kleine Schw\u00e4che nicht zum Stolperstein wird.<\/p>\n<p><strong>Nachhaltigkeit:<\/strong><br \/>\nDie KiTs leistet durch den kontinuierlichen Einsatz von green care Professional-Reinigungsprodukten einen Beitrag zu Nachhaltigkeit und Sicherheit f\u00fcr Mensch und Umwelt.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/article>\n<article class=\"component col-xs-12\">\n<h3><strong>Die KiTs Kindertagesst\u00e4tte<\/strong><\/h3>\n<div class=\"text-columns\">\n<p>Unsere <strong>KiTs Kindertagesst\u00e4tte in Bronschhofen und Rickenbach<\/strong>\u00a0bieten eine familienerg\u00e4nzende, p\u00e4dagogisch wertvolle Betreuung.<\/p>\n<p><strong>\u00a0F\u00f6rderung:<br \/>\n<\/strong>Wir f\u00f6rdern die Entwicklung jedes einzelnen der uns anvertrauten Kinder und unterst\u00fctzen ihre Entfaltung in sozialer, emotionaler und intellektueller Hinsicht. Die Kinder werden in ihrer Selbst\u00e4ndigkeit gef\u00f6rdert und durch uns begleitet. \u201eWir helfen dir, es selbst zu tun\u201c &#8211; ein Konzept der Hilfe zur Selbsthilfe.<\/p>\n<p><strong>Betreuung und Aktivit\u00e4ten:<\/strong><br \/>\nIn der Kindertagesst\u00e4tte lernen die Kinder mit Gleichaltrigen zu kommunizieren und zu spielen.<br \/>\nEin liebevoller jedoch klarer Umgang mit f\u00fcr jeden geltende Grenzen, sowie eine wohlwollende Atmosph\u00e4re durch Zuwendung hat bei uns einen hohen Stellenwert. Wir bieten den Kindern viele Aktivit\u00e4ten draussen an, z.B. Ausfl\u00fcge im nahe gelegenen Wald.<\/p>\n<p><strong>Unser Betreuungskonzept:<br \/>\n<\/strong>In unseren Kitas betreuen wir Kinder von 3 Monaten bis Kindergarteneintritt und sogar dar\u00fcber hinaus. An jedem Standort f\u00fchren wir eine separate Babygruppe, welche unseren Kleinsten ein ruhiges und bed\u00fcrfnisorientiertes Umfeld bietet. Im Anschluss an die KiTs-Kita-Zeit k\u00f6nnen Ihre Kinder unsere KiTs Tagesschule GmbH in Bronschhofen (Zweisprachige Tagesschule (Deutsch\/Englisch) mit individueller Begabungsf\u00f6rderung von der Basisstufe bis zur Oberstufe und integrierter Tagesstruktur) besuchen.<\/p>\n<p><strong>Elternkontakt:<br \/>\n<\/strong>Der regelm\u00e4ssige Austausch zwischen Eltern und Erziehern erm\u00f6glicht uns eine bestm\u00f6gliche F\u00f6rderung des Kindes.<\/p>\n<p><strong>Unser Bildungskonzept &#8222;elmar&#8220;:<br \/>\n<\/strong>\u201eelmar\u201c steht f\u00fcr elementar und bezeichnet ein Bildungskonzept, welches f\u00fcr den Elementarbereich (Kinder bis ca. 6 Jahre) konzipiert wurde und elementare Bildungsbereiche anregt und unterst\u00fctzt. Dieses erm\u00f6glicht den Kindern einerseits aktives Lernen in Gruppenangeboten innerhalb von Bildungsprojekten und setzt andererseits auf die individuelle Entwicklungsbegleitung des einzelnen Kindes.<\/p>\n<p>Wir achten stets darauf, dass wir uns mit den Kindern viel bewegen, sei es in Gruppenangeboten drinnen oder mit t\u00e4glichen Aktivit\u00e4ten draussen (Spazierg\u00e4nge, Spielplatz, Wald, Garten). Auch durch Werkstattangebote bekommen die Kinder immer wieder neue anregende und herausfordernde Aufgaben.<\/p>\n<p><strong>Unsere R\u00e4umlichkeiten:<br \/>\n<\/strong>Unsere KiTa-R\u00e4ume sind grossz\u00fcgig und hell gestaltet und sollen den Kindern verschiedene, immer wieder wechselnde, Lernangebote bieten. Wir achten darauf, den Bed\u00fcrfnissen der Kinder gerecht zu werden. Deshalb gibt es in den R\u00e4umen R\u00fcckzugsm\u00f6glichkeiten, Bewegungsbereiche und Bereiche die ein konzentriertes Spielen und Lernen erm\u00f6glichen. Die R\u00e4ume sind altersentsprechend und sicher gestaltet.<\/p>\n<p><span style=\"color: #ff00ff;\"><strong><a style=\"color: #ff00ff;\" href=\"https:\/\/my.matterport.com\/show\/?m=NRRjSGTbx3m\">Hier<\/a><\/strong><\/span><strong> k\u00f6nnen Sie die KiTs virtuell erkunden und unsere R\u00e4umlichkeiten kennen lernen.<\/strong><\/p>\n<p>Alle KiTs Kindertagesst\u00e4tten haben einen Garten, welcher die Kinder zum Austoben, Entdecken, Klettern und Spielen einl\u00e4dt. Auch der Wald wird immer wieder als entdeckungsreicher und spannender Natur-Spielraum mit den Kindern besucht.<\/p>\n<p><strong>Fr\u00fch-Englisch:<br \/>\n<\/strong>In der KiTs Kindertagesst\u00e4tte Bronschhofen und Rickenbach bieten wir f\u00fcr Kinder ab zwei Jahren die M\u00f6glichkeit an, in einer separaten English-Playgroup spielerisch eine zweite Sprache zu erlernen. Unsere englischsprachigen Betreuungspersonen arbeiten nach der \u201eImmersion\u201c Methode, was so viel bedeutet wie, Sprachbad. Das heisst, dass die Sprache in Zusammenh\u00e4ngen vermittelt wird. Das Spiel der Kinder wird auf nat\u00fcrliche Weise sprachlich kommentiert, so dass die Handlungen mit der Sprache verkn\u00fcpft werden. Die English-Playgroup findet von Montag \u2013 Freitag jeweils am Morgen statt.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/article>\n","protected":false},"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_promoted":"","_job_location":"Industriestrasse 4 9552 Bronschhofen","_company_website":"https:\/\/www.kits-dayschool.ch","_company_tagline":"","_company_twitter":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job_listing_region":[159],"job-categories":[871,103,229,139,99,76,115],"job-types":[90,5,92,230],"class_list":{"0":"post-20195","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","5":"job_listing_region-st-gallen","6":"job_listing_category-bilingual","7":"job_listing_category-kindergarten","8":"job_listing_category-vorkindergarten","9":"job_listing_category-mehrsprachiger-unterricht","10":"job_listing_category-primarschule","11":"job_listing_category-sekundarstufe_1","12":"job_listing_category-tagesschule","13":"job_listing_type-kindergarten","14":"job_listing_type-primarschule","15":"job_listing_type-sekundarstufe_1","16":"job_listing_type-vorkindergarten","18":"job-type-kindergarten-4-6-jahre","19":"job-type-primarschule-7-12jahre","20":"job-type-sekundarstufe-1-13-16-jahre","21":"job-type-vorkindergarten"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>KiTs Zweisprachige Tagesschule und Kindertagesst\u00e4tte - Privatschul Verzeichnis und Beratung<\/title>\n<meta name=\"description\" content=\"KiT&#039;s Zweisprachige Tagesschule und Kindertagesst\u00e4tte in Bronschhofen Kanton St.Gallen. Individuelle F\u00f6rderung und Betreeung\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolaboo.com\/de\/listings\/kits-zweisprachige-tagesschule-und-kindertagesstaette\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KiTs Zweisprachige Tagesschule und Kindertagesst\u00e4tte\" \/>\n<meta property=\"og:description\" content=\"KiT&#039;s Zweisprachige Tagesschule und Kindertagesst\u00e4tte in Bronschhofen Kanton St.Gallen. Individuelle F\u00f6rderung und Betreeung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolaboo.com\/de\/listings\/kits-zweisprachige-tagesschule-und-kindertagesstaette\/\" \/>\n<meta property=\"og:site_name\" content=\"Privatschul Verzeichnis und Beratung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schoolaboo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-26T06:39:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/Download-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/Download-1.png\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/kits-zweisprachige-tagesschule-und-kindertagesstaette\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/kits-zweisprachige-tagesschule-und-kindertagesstaette\\\/\",\"name\":\"KiTs Zweisprachige Tagesschule und Kindertagesst\u00e4tte - Privatschul Verzeichnis und Beratung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/kits-zweisprachige-tagesschule-und-kindertagesstaette\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/kits-zweisprachige-tagesschule-und-kindertagesstaette\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-kits-auf-weiss-1500x176.png\",\"datePublished\":\"2021-06-09T20:52:33+00:00\",\"dateModified\":\"2026-04-26T06:39:10+00:00\",\"description\":\"KiT's Zweisprachige Tagesschule und Kindertagesst\u00e4tte in Bronschhofen Kanton St.Gallen. Individuelle F\u00f6rderung und Betreeung\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/kits-zweisprachige-tagesschule-und-kindertagesstaette\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/kits-zweisprachige-tagesschule-und-kindertagesstaette\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/kits-zweisprachige-tagesschule-und-kindertagesstaette\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-kits-auf-weiss-1500x176.png\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-kits-auf-weiss-1500x176.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/listings\\\/kits-zweisprachige-tagesschule-und-kindertagesstaette\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/angebote\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"KiTs Zweisprachige Tagesschule und Kindertagesst\u00e4tte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/\",\"name\":\"schoolaboo Schule suchen und finden\",\"description\":\"Privatschule finden und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#organization\",\"name\":\"schoolaboo\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/schoolaboo.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/schoolaboo_Signet_RGB_pos_72dpi.jpg\",\"width\":262,\"height\":86,\"caption\":\"schoolaboo\"},\"image\":{\"@id\":\"https:\\\/\\\/schoolaboo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schoolaboo\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/schoolaboo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"KiTs Zweisprachige Tagesschule und Kindertagesst\u00e4tte - Privatschul Verzeichnis und Beratung","description":"KiT's Zweisprachige Tagesschule und Kindertagesst\u00e4tte in Bronschhofen Kanton St.Gallen. Individuelle F\u00f6rderung und Betreeung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolaboo.com\/de\/listings\/kits-zweisprachige-tagesschule-und-kindertagesstaette\/","og_locale":"de_DE","og_type":"article","og_title":"KiTs Zweisprachige Tagesschule und Kindertagesst\u00e4tte","og_description":"KiT's Zweisprachige Tagesschule und Kindertagesst\u00e4tte in Bronschhofen Kanton St.Gallen. Individuelle F\u00f6rderung und Betreeung","og_url":"https:\/\/schoolaboo.com\/de\/listings\/kits-zweisprachige-tagesschule-und-kindertagesstaette\/","og_site_name":"Privatschul Verzeichnis und Beratung","article_publisher":"https:\/\/www.facebook.com\/schoolaboo","article_modified_time":"2026-04-26T06:39:10+00:00","og_image":[{"url":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/Download-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/schoolaboo.de\/wp-content\/uploads\/2020\/08\/Download-1.png","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolaboo.com\/de\/listings\/kits-zweisprachige-tagesschule-und-kindertagesstaette\/","url":"https:\/\/schoolaboo.com\/de\/listings\/kits-zweisprachige-tagesschule-und-kindertagesstaette\/","name":"KiTs Zweisprachige Tagesschule und Kindertagesst\u00e4tte - Privatschul Verzeichnis und Beratung","isPartOf":{"@id":"https:\/\/schoolaboo.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoolaboo.com\/de\/listings\/kits-zweisprachige-tagesschule-und-kindertagesstaette\/#primaryimage"},"image":{"@id":"https:\/\/schoolaboo.com\/de\/listings\/kits-zweisprachige-tagesschule-und-kindertagesstaette\/#primaryimage"},"thumbnailUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/06\/Logo-kits-auf-weiss-1500x176.png","datePublished":"2021-06-09T20:52:33+00:00","dateModified":"2026-04-26T06:39:10+00:00","description":"KiT's Zweisprachige Tagesschule und Kindertagesst\u00e4tte in Bronschhofen Kanton St.Gallen. Individuelle F\u00f6rderung und Betreeung","breadcrumb":{"@id":"https:\/\/schoolaboo.com\/de\/listings\/kits-zweisprachige-tagesschule-und-kindertagesstaette\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolaboo.com\/de\/listings\/kits-zweisprachige-tagesschule-und-kindertagesstaette\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/schoolaboo.com\/de\/listings\/kits-zweisprachige-tagesschule-und-kindertagesstaette\/#primaryimage","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/06\/Logo-kits-auf-weiss-1500x176.png","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2021\/06\/Logo-kits-auf-weiss-1500x176.png"},{"@type":"BreadcrumbList","@id":"https:\/\/schoolaboo.com\/de\/listings\/kits-zweisprachige-tagesschule-und-kindertagesstaette\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schoolaboo.com\/de\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/schoolaboo.com\/de\/angebote\/"},{"@type":"ListItem","position":3,"name":"KiTs Zweisprachige Tagesschule und Kindertagesst\u00e4tte"}]},{"@type":"WebSite","@id":"https:\/\/schoolaboo.com\/de\/#website","url":"https:\/\/schoolaboo.com\/de\/","name":"schoolaboo Schule suchen und finden","description":"Privatschule finden und vergleichen","publisher":{"@id":"https:\/\/schoolaboo.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolaboo.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/schoolaboo.com\/de\/#organization","name":"schoolaboo","url":"https:\/\/schoolaboo.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/schoolaboo.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","contentUrl":"https:\/\/schoolaboo.com\/wp-content\/uploads\/2025\/04\/schoolaboo_Signet_RGB_pos_72dpi.jpg","width":262,"height":86,"caption":"schoolaboo"},"image":{"@id":"https:\/\/schoolaboo.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schoolaboo","https:\/\/www.linkedin.com\/showcase\/schoolaboo"]}]}},"_links":{"self":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-listings\/20195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/comments?post=20195"}],"wp:attachment":[{"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/media?parent=20195"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job_listing_region?post=20195"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-categories?post=20195"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/schoolaboo.com\/de\/wp-json\/wp\/v2\/job-types?post=20195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}